{"id":82578,"date":"2020-09-27T22:35:08","date_gmt":"2020-09-28T01:35:08","guid":{"rendered":"https:\/\/www.jornalja.com.br\/ambiente\/?p=82578"},"modified":"2020-09-28T10:56:04","modified_gmt":"2020-09-28T13:56:04","slug":"pericia-inedita-conclui-que-158-hectares-desmatados-no-rs-causaram-perdas-de-r-163-milhoes","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/ambiente\/pericia-inedita-conclui-que-158-hectares-desmatados-no-rs-causaram-perdas-de-r-163-milhoes\/","title":{"rendered":"Per\u00edcia in\u00e9dita conclui que 158 hectares desmatados no RS causaram perdas de R$ 16,3 milh\u00f5es"},"content":{"rendered":"<p>Com base em 105 laudos de infra\u00e7\u00e3o emitidos entre setembro passado e este, o Instituto Geral de Per\u00edcias estimou em R$ 16,3 milh\u00f5es o preju\u00edzo ambiental causado com o desmatamento ilegal de 158 hectares de florestas no Rio Grande do Sul, em um ano.<\/p>\n<p>A \u00e1rea devastada corresponde a 205 campos de futebol, e \u00e9 a soma de todos os casos em que houve corte raso, ou seja, toda a vegeta\u00e7\u00e3o foi removida do local.<\/p>\n<p>O valor do preju\u00edzo de R$ 16.340.919,44 foi obtido por uma metodologia de c\u00e1lculo pr\u00f3pria adotada pela se\u00e7\u00e3o de Per\u00edcias Ambientais do IGP.<\/p>\n<p>Nele est\u00e3o inclu\u00eddos os custos dos servi\u00e7os ambientais prestados por esta vegeta\u00e7\u00e3o, como manuten\u00e7\u00e3o do clima, controle da eros\u00e3o e poliniza\u00e7\u00e3o da \u00e1rea.<\/p>\n<p>Para chegar a este valor, foram levados em conta o est\u00e1gio de sucess\u00e3o da vegeta\u00e7\u00e3o (se a floresta estava em desenvolvimento inicial, m\u00e9dio ou avan\u00e7ado), o tipo de uso do solo na regi\u00e3o (se a \u00e1rea afetada era circundada por floresta nativa, se estava em meio a uma lavoura ou perto de um centro urbano) e a exist\u00eancia de restri\u00e7\u00f5es legais para a ocupa\u00e7\u00e3o (\u00e1rea de preserva\u00e7\u00e3o permanente, reserva legal ou unidade de conserva\u00e7\u00e3o, por exemplo).<\/p>\n<p>Os peritos da Se\u00e7\u00e3o utilizam drones e imagens de sat\u00e9lite, al\u00e9m de dados da Secretaria Estadual do Meio Ambiente (Sema), do Instituto de Pesquisas Espaciais (Inpe) e do Cadastro Ambiental Rural (Car).<\/p>\n<p>No\u00a0levantamento, a\u00a0perita criminal Renata Vieira realizou pesquisa de pre\u00e7os no mercado e utilizou o m\u00e9todo proposto pelo perito criminal do IGP\/Santa\u00a0Catarina,\u00a0Jo\u00e3o Pedro Vieira,\u00a0que \u00e9\u00a0espec\u00edfico para per\u00edcia criminal ambiental.<\/p>\n<p>\u201cAl\u00e9m de cumprir\u00a0a Lei de\u00a0Crimes Ambientais (Lei Federal n\u00b0 9.605\/1998), que determina que a per\u00edcia deve indicar o preju\u00edzo causado, para servir como base para o c\u00e1lculo de multa e pagamento de fian\u00e7a,\u00a0o c\u00e1lculo\u00a0tamb\u00e9m\u00a0fornece subs\u00eddios para os processos criminais e c\u00edveis\u201d,\u00a0afirma a perita.<\/p>\n<p>Das 5.382 per\u00edcias realizadas pela Se\u00e7\u00e3o de 2004 a 2019, a maioria \u2013 41%, ou 2.178 \u2013 referiam-se a locais desmatados,\u00a0principalmente no bioma Mata Atl\u00e2ntica.\u00a0A polui\u00e7\u00e3o h\u00eddrica vem em segundo lugar, com 22% dos casos. Nos \u00faltimos sete\u00a0anos, o\u00a0IGP\u00a0recebeu\u00a0em m\u00e9dia 530 solicita\u00e7\u00f5es de per\u00edcia ambiental.<\/p>\n<p>Ranking dos 10 munic\u00edpios com as maiores \u00e1reas desmatadas:<\/p>\n<p>Munic\u00edpio\u00a0 \u00a0\u00c1rea (hectares)\u00a0 Valor (R$)<br \/>\nVacaria\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 14,54\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 1.583.769,72<br \/>\nCaseiros\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 10,97\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 1.345.564,95<br \/>\nLib. Salzano\u00a0 \u00a0 \u00a011,18\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a01.186.468,11<br \/>\nPinhal da Serra 8,96\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a01.145.392,13<br \/>\nSananduva\u00a0 \u00a0 \u00a0 \u00a0 6,45\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 589.808,63<br \/>\nCanela\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 4,37\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 536.167,53<br \/>\nCristal do Sul\u00a0 \u00a0 \u00a03,63\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 386.715,74<br \/>\nRodeio Bonito\u00a0 \u00a02,88\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 309.336,02<br \/>\nPaim Filho\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 1,92\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0168.395,71<br \/>\nIbiraiaras\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a01,32\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0118.007,49<br \/>\n(Com informa\u00e7\u00f5es da Ascom IGP)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com base em 105 laudos de infra\u00e7\u00e3o emitidos entre setembro passado e este, o Instituto Geral de Per\u00edcias estimou em R$ 16,3 milh\u00f5es o preju\u00edzo ambiental causado com o desmatamento ilegal de 158 hectares de florestas no Rio Grande do Sul, em um ano. A \u00e1rea devastada corresponde a 205 campos de futebol, e \u00e9 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":82579,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4],"tags":[16,158,110,51,69,86,113,52,78,38,205],"class_list":["post-82578","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente-geral","tag-ambiente","tag-crimes","tag-crimes-ambientais","tag-desmatamento","tag-floresta","tag-florestas","tag-mata-atlantica","tag-meio-ambiente","tag-poluicao","tag-rio-grande-do-sul","tag-sema"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.jornalja.com.br\/ambiente\/wp-content\/uploads\/sites\/3\/2020\/09\/ambiente-desmatamento-no-rs-igp.jpg","jetpack-related-posts":[{"id":85174,"url":"https:\/\/www.jornalja.com.br\/ambiente\/pecuaria-e-principal-causa-do-desmatamento-na-amazonia-diz-estudo-lancado-na-cop28\/","url_meta":{"origin":82578,"position":0},"title":"Pecu\u00e1ria \u00e9 principal causa do desmatamento na Amaz\u00f4nia, diz estudo lan\u00e7ado na Cop28","author":"da Reda\u00e7\u00e3o","date":"8 de dezembro de 2023","format":false,"excerpt":"Um mapeamento in\u00e9dito do MapBiomas Amaz\u00f4nia, divulgado nesta sexta-feira (8) na 28\u00aa Confer\u00eancia das Na\u00e7\u00f5es Unidas para Mudan\u00e7a do Clima (COP 28), em Dubai, mostra que a pecu\u00e1ria foi o principal vetor de derrubada de vegeta\u00e7\u00e3o na Am\u00e9rica do Sul, no per\u00edodo de 1985 a 2022. O mapeamento\u00a0levou em considera\u00e7\u00e3o\u2026","rel":"","context":"Em &quot;Ambiente J\u00c1-MAT\u00c9RIA&quot;","block_context":{"text":"Ambiente J\u00c1-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/ambiente\/category\/ambiente-geral\/"},"img":{"alt_text":"Foto: Marcello Casal Jr.\/Ag\u00eancia Brasil","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/ambiente\/wp-content\/uploads\/sites\/3\/2023\/12\/pecuaria.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/ambiente\/wp-content\/uploads\/sites\/3\/2023\/12\/pecuaria.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/ambiente\/wp-content\/uploads\/sites\/3\/2023\/12\/pecuaria.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":82058,"url":"https:\/\/www.jornalja.com.br\/ambiente\/mata-atlantica-perdeu-145-mil-hectares-no-primeiro-ano-do-governo-bolsonaro\/","url_meta":{"origin":82578,"position":1},"title":"Mata Atl\u00e2ntica perdeu 14,5 mil hectares no primeiro ano do governo Bolsonaro","author":"da Reda\u00e7\u00e3o","date":"27 de maio de 2020","format":false,"excerpt":"Depois de longo per\u00edodo de redu\u00e7\u00e3o, o desmatamento em \u00e1reas da Mata Atl\u00e2ntica voltou a crescer no \u00faltimo ano, refletindo a orienta\u00e7\u00e3o do governo Bolsonaro, enunciada j\u00e1 na campanha eleitoral, de relaxar as pol\u00edticas de conten\u00e7\u00e3o. Relat\u00f3rio divulgado nesta quarta-feira, 27, mostra que o desmatamento aumentou 27% entre 2018 e\u2026","rel":"","context":"Em &quot;Ambiente J\u00c1-MAT\u00c9RIA&quot;","block_context":{"text":"Ambiente J\u00c1-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/ambiente\/category\/ambiente-geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/ambiente\/wp-content\/uploads\/sites\/3\/2020\/05\/Mata-Atlantica-grafico-desmatamento-1-300x213.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":82545,"url":"https:\/\/www.jornalja.com.br\/ambiente\/nao-pode-ser-acidente-diz-delegado-sobre-fogo-no-pantanal\/","url_meta":{"origin":82578,"position":2},"title":"&#8220;N\u00e3o pode ser acidente&#8221;, diz delegado sobre fogo no Pantanal","author":"da Reda\u00e7\u00e3o","date":"15 de setembro de 2020","format":false,"excerpt":"Ontem (14\/9), a Pol\u00edcia Federal come\u00e7ou a cumprir dez mandados de busca e apreens\u00e3o no Mato Grosso do Sul, em Corumb\u00e1 e Campo Grande, em endere\u00e7os de cinco fazendeiros que teriam se organizado para atear fogo intencionalmente na vegeta\u00e7\u00e3o de suas\u00a0fazendas em \u00e1reas remotas do Pantanal. At\u00e9 a noite, havia\u2026","rel":"","context":"Em &quot;Ambiente J\u00c1-MAT\u00c9RIA&quot;","block_context":{"text":"Ambiente J\u00c1-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/ambiente\/category\/ambiente-geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/ambiente\/wp-content\/uploads\/sites\/3\/2020\/09\/pantanal-mayketoscano-secommt-09-09-2020.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/ambiente\/wp-content\/uploads\/sites\/3\/2020\/09\/pantanal-mayketoscano-secommt-09-09-2020.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/ambiente\/wp-content\/uploads\/sites\/3\/2020\/09\/pantanal-mayketoscano-secommt-09-09-2020.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/ambiente\/wp-content\/uploads\/sites\/3\/2020\/09\/pantanal-mayketoscano-secommt-09-09-2020.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/ambiente\/wp-content\/uploads\/sites\/3\/2020\/09\/pantanal-mayketoscano-secommt-09-09-2020.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":85038,"url":"https:\/\/www.jornalja.com.br\/ambiente\/brasil-perde-15-de-florestas-naturais-em-quase-40-anos-diz-mapbiomas\/","url_meta":{"origin":82578,"position":3},"title":"Brasil perde 15% de florestas naturais em quase 40 anos, diz MapBiomas","author":"Cleber Dioni Tentardini","date":"20 de outubro de 2023","format":false,"excerpt":"Em novo levantamento, a rede MapBiomas constatou que, entre 1985 e 2022, houve redu\u00e7\u00e3o de 15% da \u00e1rea ocupada por florestas naturais no pa\u00eds, passando de 581,6 milh\u00f5es de hectares para 494,1 milh\u00f5es de hectares. O principal fator de devasta\u00e7\u00e3o foi a apropria\u00e7\u00e3o da agropecu\u00e1ria, e os \u00faltimos cinco anos\u2026","rel":"","context":"Em &quot;Ambiente J\u00c1-MAT\u00c9RIA&quot;","block_context":{"text":"Ambiente J\u00c1-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/ambiente\/category\/ambiente-geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/ambiente\/wp-content\/uploads\/sites\/3\/2020\/09\/amazonia-desmatamento-cresce-40.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/ambiente\/wp-content\/uploads\/sites\/3\/2020\/09\/amazonia-desmatamento-cresce-40.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/ambiente\/wp-content\/uploads\/sites\/3\/2020\/09\/amazonia-desmatamento-cresce-40.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/ambiente\/wp-content\/uploads\/sites\/3\/2020\/09\/amazonia-desmatamento-cresce-40.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":77714,"url":"https:\/\/www.jornalja.com.br\/ambiente\/operacao-verde-brasil-multas-na-amazonia-somam-r-36-milhoes\/","url_meta":{"origin":82578,"position":4},"title":"Opera\u00e7\u00e3o Verde Brasil: multas na Amaz\u00f4nia somam R$ 36 milh\u00f5es","author":"da Reda\u00e7\u00e3o","date":"24 de setembro de 2019","format":false,"excerpt":"A Opera\u00e7\u00e3o Verde Brasil contabilizou, no primeiro m\u00eas de opera\u00e7\u00f5es, 112 termos de infra\u00e7\u00e3o aplicados, que totalizam R$ 36,37 milh\u00f5es em multas, de acordo com balan\u00e7o divulgado hoje (23) pelo Minist\u00e9rio da Defesa. Os recursos s\u00e3o destinados ao Tesouro Nacional. As multas foram aplicadas principalmente pelo Instituto Brasileiro do Meio\u2026","rel":"","context":"Em &quot;Ambiente J\u00c1-MAT\u00c9RIA&quot;","block_context":{"text":"Ambiente J\u00c1-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/ambiente\/category\/ambiente-geral\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":76382,"url":"https:\/\/www.jornalja.com.br\/ambiente\/noruega-suspende-r-133-milhoes-para-protecao-da-amazonia\/","url_meta":{"origin":82578,"position":5},"title":"Noruega suspende R$ 133 milh\u00f5es para prote\u00e7\u00e3o da Amaz\u00f4nia","author":"Carlos Matsubara","date":"15 de agosto de 2019","format":false,"excerpt":"O ministro do Clima e Meio Ambiente da Noruega, Ola Elvestuen, anunciou nesta quinta-feira a suspens\u00e3o dos repasses de 300 milh\u00f5es de coroas norueguesas, o equivalente a R$ 133 milh\u00f5es, que seriam destinados ao Fundo Amaz\u00f4nia. Segundo o jornal noruegu\u00eas \"Dagens N\u00e6ringsliv\" (DV), especializado em neg\u00f3cios, o governo local estaria\u2026","rel":"","context":"Em &quot;Ambiente J\u00c1-MAT\u00c9RIA&quot;","block_context":{"text":"Ambiente J\u00c1-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/ambiente\/category\/ambiente-geral\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKnZo-ltU","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/ambiente\/wp-json\/wp\/v2\/posts\/82578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/ambiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/ambiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/ambiente\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/ambiente\/wp-json\/wp\/v2\/comments?post=82578"}],"version-history":[{"count":1,"href":"https:\/\/www.jornalja.com.br\/ambiente\/wp-json\/wp\/v2\/posts\/82578\/revisions"}],"predecessor-version":[{"id":82580,"href":"https:\/\/www.jornalja.com.br\/ambiente\/wp-json\/wp\/v2\/posts\/82578\/revisions\/82580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/ambiente\/wp-json\/wp\/v2\/media\/82579"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/ambiente\/wp-json\/wp\/v2\/media?parent=82578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/ambiente\/wp-json\/wp\/v2\/categories?post=82578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/ambiente\/wp-json\/wp\/v2\/tags?post=82578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}