{"id":1062,"date":"2006-08-07T13:35:25","date_gmt":"2006-08-07T16:35:25","guid":{"rendered":"http:\/\/75.126.185.46\/~jornalja\/?p=1062"},"modified":"2006-08-07T13:35:25","modified_gmt":"2006-08-07T16:35:25","slug":"as-velhas-bicicletas","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/arquivo\/as-velhas-bicicletas\/","title":{"rendered":"As velhas bicicletas"},"content":{"rendered":"<p align=\"justify\">\n<p align=\"justify\"><strong>Marco Aur\u00e9lio Nunes*<\/strong><\/p>\n<p align=\"justify\">Sentado num banco do Parque da Reden\u00e7\u00e3o, na manh\u00e3 de um domingo, assisti ao movimento do Brique. Era f\u00e1cil notar fam\u00edlias passeando sob o sol com o insepar\u00e1vel chimarr\u00e3o, c\u00e3es nas guias e suas crian\u00e7as comendo pipoca ou lambuzadas pelo algod\u00e3o doce. O fluxo de bicicletas era pequeno. Mas um grupo de ciclistas exibindo suas bikes com marchas desfrutava da sombra de \u00e1rvores centen\u00e1rias. Neste momento, retrocedi no tempo. Sem deixar a polui\u00e7\u00e3o visual de cartazes e bandeiras de partidos pol\u00edticos afetar minha mem\u00f3ria, comecei a recordar do Parque da Reden\u00e7\u00e3o h\u00e1 35 anos.<\/p>\n<p align=\"justify\">O Brique n\u00e3o existia oficialmente. Se n\u00e3o estou enganado, consolidou-se no in\u00edcio da d\u00e9cada de 80. Naquela \u00e9poca, ent\u00e3o com dez anos de idade, meu av\u00f4 convidava-me para andar de bicicleta. O rumo era certo. N\u00e3o precisava nem perguntar. O caminho tinha a dire\u00e7\u00e3o da Reden\u00e7\u00e3o. Sa\u00edamos de Teres\u00f3polis sempre ap\u00f3s o almo\u00e7o. A id\u00e9ia era aproveitar ao m\u00e1ximo a tarde de domingo. Antes, por\u00e9m, eu sempre indagava: &#8220;pegou a carteirinha?&#8221;. Tratava-se de uma carteira do Sindicato dos Comerci\u00e1rios. Acontece que, com esse documento, meu av\u00f4 alugava minha bicicleta.<\/p>\n<p align=\"justify\">Depois de escolhida &#8211; geralmente preferia uma de aro 26, apesar da dificuldade para me equilibrar &#8211; pedalava por cerca de uma hora. Meu av\u00f4 observava-me sentado em um banco pr\u00f3ximo do espelho d&#8217;\u00e1gua. Ap\u00f3s devolver a bicicleta locada, atir\u00e1vamos pipoca \u00e0s carpas, and\u00e1vamos de pedalinho, trenzinho e, ainda, visit\u00e1vamos o mini-z\u00f4o. Admir\u00e1vamos os macacos-pregos co\u00e7ar a cabe\u00e7a e, logo em seguida, caminh\u00e1vamos pelos recantos existentes no parque. Somente depois peg\u00e1vamos o \u00f4nibus para irmos embora. Chegava em casa exausto, mas aproveitava tudo o que a Reden\u00e7\u00e3o oferecia em termos de divertimento.<\/p>\n<p align=\"justify\">Quando lembro de tudo isso fico refletindo: como seria hoje a Reden\u00e7\u00e3o se ainda houvesse as velhas bicicletas para loca\u00e7\u00e3o? Sei, algu\u00e9m me disse, &#8220;parece que acabaram com as bicicletas porque estavam sendo furtadas e, al\u00e9m disso, pessoas acostumadas a caminhar pelas trilhas do parque reclamavam muito!&#8221;. \u00c9, os princ\u00edpios mudaram e a viol\u00eancia cresceu assustadoramente. Imagine hoje algu\u00e9m chegar na Reden\u00e7\u00e3o e alugar uma bicicleta apenas portando um documento sindical! Aposto que em menos de duas semanas n\u00e3o haveria mais bicicletas para locar. Por isso, quem seria louco de enfrentar um processo licitat\u00f3rio com esse prop\u00f3sito se, atualmente, esse servi\u00e7o de lazer fosse de interesse da Prefeitura?<\/p>\n<p align=\"justify\">Sem garantias de ressarcimento do preju\u00edzo e, tamb\u00e9m, de seguran\u00e7a, isso n\u00e3o seria poss\u00edvel. Mas que saudade das velhas bicicletas! Ser\u00e1 que n\u00e3o h\u00e1 uma maneira delas retornarem? Pessoas como eu, que moram num apartamento pequeno e sem condi\u00e7\u00f5es de guardar uma bicicleta, creio, gostariam de ter essa op\u00e7\u00e3o nos finais de semana, apesar de tudo. Ah! esqueci dos que possuem bicicletas! Porto Alegre n\u00e3o se compara, por exemplo, com cidades da Holanda, que t\u00eam o tr\u00e2nsito adaptado ao tr\u00e1fego das bicicletas. Mas, no Bom Fim, j\u00e1 existem as ciclovias. O ciclista pode chegar tranq\u00fcilo na Reden\u00e7\u00e3o. N\u00e3o vamos perder o glamour! A Capital dos ga\u00fachos merece mais charme. Antigamente se ouvia o som do trenzinho, agora n\u00e3o mais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marco Aur\u00e9lio Nunes* Sentado num banco do Parque da Reden\u00e7\u00e3o, na manh\u00e3 de um domingo, assisti ao movimento do Brique. Era f\u00e1cil notar fam\u00edlias passeando sob o sol com o insepar\u00e1vel chimarr\u00e3o, c\u00e3es nas guias e suas crian\u00e7as comendo pipoca ou lambuzadas pelo algod\u00e3o doce. O fluxo de bicicletas era pequeno. Mas um grupo de [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1062","post","type-post","status-publish","format-standard","hentry","category-analiseopiniao"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":1280,"url":"https:\/\/www.jornalja.com.br\/arquivo\/o-menino-que-se-tornou-brizola\/","url_meta":{"origin":1062,"position":0},"title":"O Menino que se Tornou Brizola","author":"da Reda\u00e7\u00e3o","date":"28 de julho de 2008","format":false,"excerpt":"Autor: Cleber Dioni A vida de Leonel Brizola, com \u00eanfase para os primeiros anos em Porto Alegre, at\u00e9 o ex\u00edlio no Uruguai e a volta, quinze anos depois. \u00a0\"...\u00c9ramos todos jovens e nos identific\u00e1vamos com aquela massa an\u00f4nima a percorrer as ruas de Porto Alegre, gritando 'Get\u00falio', 'Get\u00falio' e empunhando\u2026","rel":"","context":"Em &quot;Livros&quot;","block_context":{"text":"Livros","link":"https:\/\/www.jornalja.com.br\/arquivo\/category\/livros\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/wp-content\/uploads\/2008\/07\/brizola.gif?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbQjBd-h8","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/1062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=1062"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/1062\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=1062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=1062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=1062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}