{"id":11854,"date":"2012-03-21T10:42:38","date_gmt":"2012-03-21T13:42:38","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=11854"},"modified":"2012-03-21T10:42:38","modified_gmt":"2012-03-21T13:42:38","slug":"a-escrita-segundo-joao-gilberto-noll","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/arquivo\/a-escrita-segundo-joao-gilberto-noll\/","title":{"rendered":"A escrita segundo Jo\u00e3o Gilberto Noll"},"content":{"rendered":"<p>O escr<a href=\"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/2012\/03\/DSC00044.jpg\"><img decoding=\"async\" class=\"alignleft size-thumbnail wp-image-11855\" title=\"DSC00044\" src=\"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/2012\/03\/DSC00044-150x112.jpg\" alt=\"\" width=\"150\" height=\"112\" \/><\/a>itor ga\u00facho Jo\u00e3o Gilberto Noll tem uma produ\u00e7\u00e3o liter\u00e1ria ampla e variada, multig\u00eanero. Ganhou v\u00e1rios pr\u00eamios e algumas de suas obras foram adaptadas para o cinema, casos, por exemplo, do conto <em>Alguma coisa urgente<\/em><em>mente<\/em> (que virou <em>Nunca fomos t\u00e3o felizes<\/em>, na vers\u00e3o de Murilo Salles, 1984), e do romance <em>Harmada<\/em>, cuja transposi\u00e7\u00e3o para a tela, em 2003, marcou a volta, ap\u00f3s um intervalo de 20 anos, do veterano diretor Maurice Capovilla.<br \/>\nMas h\u00e1 em Noll tamb\u00e9m o lado professor que o levou \u2013 ministrando oficinas liter\u00e1rias e aulas sobre literatura brasileira \u2013 a peregrinar entre a Universidade Federal do Rio de Janeiro, Porto Alegre, e Berkeley, Calif\u00f3rnia, ou a fazer confer\u00eancias em Madri e Londres, onde seus livros foram traduzidos.<br \/>\n\u00c9 este Noll que o p\u00fablico poder\u00e1 novamente tomar contato atrav\u00e9s do curso <em>A escrita, labor e liberdade<\/em>, que ele dar\u00e1, a partir desta quarta-feira (21\/03), no StudioClio (rua Jos\u00e9 do Patroc\u00ednio, 698). Nele, ao longo de 15 encontros, falar\u00e1 sobre aspectos concernentes a literatura contempor\u00e2nea.<br \/>\nEm seu apartamento, na Rua Fernando Machado, centro de Porto Alegre, Noll resume as principais abordagens do curso que, fundamentalmente, gira em torno do tema da cria\u00e7\u00e3o liter\u00e1ria: \u201ca escrita n\u00e3o \u00e9 uma abstra\u00e7\u00e3o e, tamb\u00e9m, n\u00e3o \u00e9 um mapa tra\u00e7ado de antem\u00e3o. Quando escrevo nunca sei como a hist\u00f3ria vai terminar. Trata-se de uma pr\u00e1xis que se alimenta do pr\u00f3prio ato de escrever, e \u00e9 isso que quero passar para as pessoas\u201d.<br \/>\n<a href=\"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/2012\/03\/DSC00048.jpg\"><img decoding=\"async\" class=\"alignleft size-thumbnail wp-image-11856\" title=\"DSC00048\" src=\"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/2012\/03\/DSC00048-e1332337180279-150x202.jpg\" alt=\"\" width=\"150\" height=\"202\" \/><\/a>Noll, enquanto contador de hist\u00f3rias pode parecer um s\u00e1dico. Pode come\u00e7ar um conto com um singelo \u201ca abelha ronda a flor\u201d, em <em>Domingo sem n\u00e9ctar<\/em>, ou \u201cele afundou os p\u00e9s brancos no jardim das cam\u00e9lias\u201d, em <em>Ele era de Berkeley<\/em>, para depois conduzir o leitor por caminhos sinistros, m\u00f3rbidos, \u00e0s vezes sanguin\u00e1rios, mesmo que as cenas descritas sejam apenas met\u00e1foras: \u201cgosto deste casamento entre a delicadeza e a brutalidade. Esta dualidade est\u00e1 em todos os meus livros\u201d, comenta o escritor.<br \/>\nEscrita inspirada atrav\u00e9s de puls\u00f5es, num universo onde se cruzam as influ\u00eancias de Marx, Freud, Sartre, Marcuse, Noll considera os diferentes tipos de crises existenciais como molas propulsoras para o ato criativo, da\u00ed a persist\u00eancia em construir personagens que parecem condenados a viver a beira da ru\u00edna, sob o fio da navalha: \u201ceu n\u00e3o consigo ver um personagem solar na literatura. O que existe s\u00e3o momentos solares. Por isso associo o ato de criar a crise. Escrever para escapar do vazio. Talvez seja um pouco da nossa heran\u00e7a crist\u00e3, pois da dor voc\u00ea emerge, cresce\u201d, explica.<br \/>\nEm 2011, Noll \u2013 convidado a participar do evento liter\u00e1rio &#8220;A Cidade a Travessa: poesia dos lugares&#8221;, na Casa Fernando Pessoa, em Lisboa \u2013, tornou-se o primeiro escritor a dormir no quarto onde poeta portugu\u00eas viveu seus \u00faltimos 15 anos de vida. Experi\u00eancia, segundo Noll, ao mesmo tempo m\u00f3rbida e in\u00f3cua \u2013 \u201cn\u00e3o senti absolutamente nada\u201d, revelou \u2013 que dever\u00e1 resultar num livro coletivo, reunindo textos de outros escritores que tamb\u00e9m passaram pela ins\u00f3lita experi\u00eancia.<br \/>\nNoll, como prefaciou David Treece (do Kings College London, tradutor de suas obras para o ingl\u00eas), \u201cdestaca-se no meio da conformidade uma voz disposta a enunciar um sentimento de insufici\u00eancia diante do real, a certeza de que a potencialidade humana est\u00e1 travada e de que seus desdobramentos poss\u00edveis n\u00e3o foram esgotados\u201d.<br \/>\nPor Francisco Ribeiro<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O escritor ga\u00facho Jo\u00e3o Gilberto Noll tem uma produ\u00e7\u00e3o liter\u00e1ria ampla e variada, multig\u00eanero. Ganhou v\u00e1rios pr\u00eamios e algumas de suas obras foram adaptadas para o cinema, casos, por exemplo, do conto Alguma coisa urgentemente (que virou Nunca fomos t\u00e3o felizes, na vers\u00e3o de Murilo Salles, 1984), e do romance Harmada, cuja transposi\u00e7\u00e3o para a [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[1432],"class_list":["post-11854","post","type-post","status-publish","format-standard","hentry","category-materiasecundaria","tag-gilberto-noll"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbQjBd-35c","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/11854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=11854"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/11854\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=11854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=11854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=11854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}