{"id":12217,"date":"2013-07-21T13:19:33","date_gmt":"2013-07-21T16:19:33","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=12217"},"modified":"2013-07-21T13:19:33","modified_gmt":"2013-07-21T16:19:33","slug":"novo-escandalo-bota-mensalao-no-chinelo","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/arquivo\/novo-escandalo-bota-mensalao-no-chinelo\/","title":{"rendered":"Novo esc\u00e2ndalo bota mensal\u00e3o no chinelo"},"content":{"rendered":"<p>O novo esc\u00e2ndalo, deflagrado pelas confiss\u00f5es da Siemens ao CADE, vai fazer o chamado &#8220;mensal\u00e3o&#8221; parecer uma coisa de amadores.<br \/>\nA empresa alem\u00e3, acossada pelas investiga\u00e7\u00f5es iniciadas em 2008, fez um acordo para ter suas penalidades reduzidas e entregou um esquema de corrup\u00e7\u00e3o que remonta a mais de 20 anos e envolve licita\u00e7\u00f5es em projetos de energia el\u00e9trica e trens urbanos em v\u00e1rios Estados. S\u00f3 em S\u00e3o Paulo, a fraude na licita\u00e7\u00e3o do metr\u00f4 desviou mais de R$ 50 milh\u00f5es (quase o valor total do Mensal\u00e3o).<br \/>\nO esc\u00e2ndalo come\u00e7ou a ser conhecido h\u00e1 uma semana, por uma reportagem da Folha de S\u00e3o Paulo. Nos dias seguintes foi detalhado pelo jornal Valor Econ\u00f4mico e neste fim de semana foi destaque da revista Isto\u00c9. Governos do PSDB s\u00e3o os principais implicados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O novo esc\u00e2ndalo, deflagrado pelas confiss\u00f5es da Siemens ao CADE, vai fazer o chamado &#8220;mensal\u00e3o&#8221; parecer uma coisa de amadores. A empresa alem\u00e3, acossada pelas investiga\u00e7\u00f5es iniciadas em 2008, fez um acordo para ter suas penalidades reduzidas e entregou um esquema de corrup\u00e7\u00e3o que remonta a mais de 20 anos e envolve licita\u00e7\u00f5es em projetos [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[1487,359,1488,1489,1490],"class_list":["post-12217","post","type-post","status-publish","format-standard","hentry","category-x-categorias-velhas","tag-caso-ceee","tag-corrupcao","tag-empresas-corruptoras","tag-metro-de-sao-paulo","tag-patrimonio-publico"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbQjBd-3b3","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/12217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=12217"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/12217\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=12217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=12217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=12217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}