{"id":12224,"date":"2013-07-21T22:53:49","date_gmt":"2013-07-22T01:53:49","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=12224"},"modified":"2013-07-21T22:53:49","modified_gmt":"2013-07-22T01:53:49","slug":"cpi-foi-primeira-a-apontar-corruptores","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/arquivo\/cpi-foi-primeira-a-apontar-corruptores\/","title":{"rendered":"CPI foi primeira a apontar corruptores"},"content":{"rendered":"<p>A fraude contra a CEEE, denunciada pela ent\u00e3o secret\u00e1ria de Minas e Energia do Rio Grande do Sul, Dilma Rousseff, \u00a0 foi alvo de uma Comiss\u00e3o Parlamentar de Inqu\u00e9rito na Assembl\u00e9ia do RS, em 1995. Tumultuada, a CPI s\u00f3 foi concluida no ano seguinte, mas foi a primeira no pa\u00eds que apontou as empresas que promoveram a corrup\u00e7\u00e3o de funcion\u00e1rios p\u00fablicos. Com detalhes a CPI revelou como agentes das empresas, organizadas em dois cons\u00f3rcios, agiam, alguns com tr\u00e2nsito livre dentro da companhia.<br \/>\nA CPI, que teve como relator o deputado Pepe Vargas, deu origem a uma A\u00e7\u00e3o Civil P\u00fablica, ajuizada em 1996\u00a0 pelo Minist\u00e9rio P\u00fablico que estimou em R$ 79 milh\u00f5es o preju\u00edzo \u00e0 estatal de energia. Houve fraude no edital, na licita\u00e7\u00e3o e nos contratos, segundo o MP.\u00a0 O processo j\u00e1 tem mais de 110 volumes e ainda est\u00e1 em primeira inst\u00e2ncia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A fraude contra a CEEE, denunciada pela ent\u00e3o secret\u00e1ria de Minas e Energia do Rio Grande do Sul, Dilma Rousseff, \u00a0 foi alvo de uma Comiss\u00e3o Parlamentar de Inqu\u00e9rito na Assembl\u00e9ia do RS, em 1995. Tumultuada, a CPI s\u00f3 foi concluida no ano seguinte, mas foi a primeira no pa\u00eds que apontou as empresas que [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[701,1493,359,1494],"class_list":["post-12224","post","type-post","status-publish","format-standard","hentry","category-x-categorias-velhas","tag-caso-rigotto","tag-caso-siemens","tag-corrupcao","tag-fraude-a-ceee"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":1280,"url":"https:\/\/www.jornalja.com.br\/arquivo\/o-menino-que-se-tornou-brizola\/","url_meta":{"origin":12224,"position":0},"title":"O Menino que se Tornou Brizola","author":"da Reda\u00e7\u00e3o","date":"28 de julho de 2008","format":false,"excerpt":"Autor: Cleber Dioni A vida de Leonel Brizola, com \u00eanfase para os primeiros anos em Porto Alegre, at\u00e9 o ex\u00edlio no Uruguai e a volta, quinze anos depois. \u00a0\"...\u00c9ramos todos jovens e nos identific\u00e1vamos com aquela massa an\u00f4nima a percorrer as ruas de Porto Alegre, gritando 'Get\u00falio', 'Get\u00falio' e empunhando\u2026","rel":"","context":"Em &quot;Livros&quot;","block_context":{"text":"Livros","link":"https:\/\/www.jornalja.com.br\/arquivo\/category\/livros\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/wp-content\/uploads\/2008\/07\/brizola.gif?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbQjBd-3ba","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/12224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=12224"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/12224\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=12224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=12224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=12224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}