{"id":12237,"date":"2013-07-24T19:58:30","date_gmt":"2013-07-24T22:58:30","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=12237"},"modified":"2013-07-24T19:58:30","modified_gmt":"2013-07-24T22:58:30","slug":"energia-que-vem-de-fora","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/arquivo\/energia-que-vem-de-fora\/","title":{"rendered":"Energia que vem de fora"},"content":{"rendered":"<p>Se faltasse um argumento para desmontar as teses  separatistas que, vez por outra, ressurgem no Rio Grande do Sul, o caso da energia seria exemplar.<br \/>\nNeste campo vital, a depend\u00eancia dos ga\u00fachos \u00e9 total: todo o petr\u00f3leo, 98% do \u00e1lcool e 60% da energia el\u00e9trica que o Estado precisa vem de fora de suas fronteiras. Na energia el\u00e9trica, \u00e9 mais grave ainda a depend\u00eancia: por ficar na extremidade de um sistema integrado, o RS \u00e9 mais vulner\u00e1vel.<br \/>\nEvidentemente, essa situa\u00e7\u00e3o \u00e9 resultado de um planejamento nacional, que relega ao passado as id\u00e9ias de economia regional aut\u00f4noma e, hoje, n\u00e3o se concebe  que pudesse ser de outra forma.<br \/>\n\u00c9 interessante, por\u00e9m, examinar essa rela\u00e7\u00e3o, porque ela revela algumas fragilidades.<br \/>\nEm 1995, por exemplo, a CEEE gastou  R$ 362 milh\u00f5es na compra de energia  do sistema interligado, valor equivalente a 27% da receita l\u00edquida da companhia. Mantida essa propor\u00e7\u00e3o, pode-se calcular que em 2012 a conta se aproximou de R$ 1 bilh\u00e3o.<br \/>\nEsses dados permitem estimar, que em 40 anos de exist\u00eancia do Sistema Integrado Nacional, o Rio Grande do Sul despendeu mais de 15 bilh\u00f5es de reais.<br \/>\nOutro inconveniente da excessiva depend\u00eancia \u00e9 a amea\u00e7a de apag\u00e3o, por conta de problemas clim\u00e1ticos. As secas frequentes que ocorrem na regi\u00e3o da bacia do Igua\u00e7u, onde se localizam as hidrel\u00e9tricas de Salto Os\u00f3rio e Salto Santiago, s\u00e3o respons\u00e1veis pelos principais transtornos que o Estado enfrenta quanto ao fornecimento de energia.<br \/>\nAs maiores defici\u00eancias, no entanto, decorrem de estrangulamentos na  transmiss\u00e3o e distribui\u00e7\u00e3o. \u00c9 uma situa\u00e7\u00e3o que se tornou cr\u00f4nica ao longo de sucessivos governos. \u00c9 onde est\u00e3o concentrados os investimentos que o atual governo est\u00e1 fazendo com os 2,3 bilh\u00f5es que recebeu de uma antiga pend\u00eancia com o governo federal*.<br \/>\n\u201cAtualmente o sistema de suprimento ao Rio Grande do Sul  opera em cerca de 66% do tempo em n\u00edvel de risco de corte de carga, quando da ocorr\u00eancia de conting\u00eancia simples nos circuitos de transmiss\u00e3o\u201d, diz um relat\u00f3rio.<br \/>\nAl\u00e9m da evas\u00e3o de recursos com a compra de energia, tem as perdas na transmiss\u00e3o a longas dist\u00e2ncias. \u201cA Empresa de Pesquisa Energ\u00e9tica sinaliza para o risco da depend\u00eancia, assim como o Operador Nacional do Sistema\u201d, diz uma nota t\u00e9cnica.<br \/>\n\u201cSucessivos estudos do Operador Nacional do Sistema apontam que, em situa\u00e7\u00e3o hidrol\u00f3gica desfavor\u00e1vel, a perda de alguns circuitos  de 230 kV pode resultar em cortes regionalizados particularmente na fronteira Oeste e Regi\u00e3o Sul do Estado do Rio Grande do Sul\u201d.<br \/>\nQuando o sistema foi integrado, apenas uma linha de 530 kv transportava energia at\u00e9 o  Estado, alcan\u00e7ando a subesta\u00e7\u00e3o de Gravata\u00ed. Hoje a energia chega ao Estado atrav\u00e9s de dois \u201clinh\u00f5es\u201d.  A segunda linha de 500 Kv entrou em funcionamento  em 1987.<br \/>\nN\u00e3o h\u00e1 previs\u00e3o de novas linhas de transmiss\u00e3o para aumentar o interc\u00e2mbio com  o Sistema Interligado Nacional, mas h\u00e1 a previs\u00e3o de uma linha de 500 Kv para conex\u00e3o com o sistema argentino na compra de energia que o Brasil far\u00e1 deste pa\u00eds.<br \/>\nCARENCIA CR\u00d4NICA<br \/>\nPara mover as suas ind\u00fastrias e iluminar suas cidades, o Rio Grande do Sul consome por ano 16 mil MW de energia el\u00e9trica. A capacidade de gera\u00e7\u00e3o instalada  em seu territ\u00f3rio que  chega a 6,5 mil MW*. O restante, mais de dois ter\u00e7os vem de fora, do Sistema Nacional Integrado. Al\u00e9m das perdas, pelo transporte a longa dist\u00e2ncia, essa depend\u00eancia traz inseguran\u00e7a no abastecimento.<br \/>\nN\u00e3o \u00e9 s\u00f3 a depend\u00eancia da energia gerada fora do Estado. Tornou-se cr\u00f4nica falta de investimentos, principalmente em linhas de transmiss\u00e3o, substa\u00e7\u00f5es e rede de distribui\u00e7\u00e3o.<br \/>\nEm certo per\u00edodo, as baixas tarifas eram a causa  da car\u00eancia de investimentos.  Em 1986 a lucratividade da CEEE era 5% deveria ser 12% para atender as necessidades de investimento. Isso d\u00e1 ideia do d\u00e9ficit de invesimentos que foi se acumulando.   Depois, as tarifas  foram atualizadas, mas teve o terremoto da privatiza\u00e7\u00e3o e das causas trabalhistas.  Agora voltaram a ter uma  significativa redu\u00e7\u00e3o.  Qual \u00e9 a situa\u00e7\u00e3o tarif\u00e1ria hoje? <strong>(Revista J\u00c1 Especial Energia &#8211; edi\u00e7\u00f5es tem\u00e1ticas 2013)<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se faltasse um argumento para desmontar as teses separatistas que, vez por outra, ressurgem no Rio Grande do Sul, o caso da energia seria exemplar. Neste campo vital, a depend\u00eancia dos ga\u00fachos \u00e9 total: todo o petr\u00f3leo, 98% do \u00e1lcool e 60% da energia el\u00e9trica que o Estado precisa vem de fora de suas fronteiras. [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[408],"class_list":["post-12237","post","type-post","status-publish","format-standard","hentry","category-x-categorias-velhas","tag-energia"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbQjBd-3bn","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/12237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=12237"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/12237\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=12237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=12237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=12237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}