{"id":15044,"date":"2014-07-14T01:06:23","date_gmt":"2014-07-14T04:06:23","guid":{"rendered":"https:\/\/jornalja.com.br\/?p=15044"},"modified":"2014-07-14T01:06:23","modified_gmt":"2014-07-14T04:06:23","slug":"um-dos-legados-da-copa","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/arquivo\/um-dos-legados-da-copa\/","title":{"rendered":"UM DOS LEGADOS DA COPA"},"content":{"rendered":"<p>Vinte pessoas presas acusadas de planejar a\u00e7\u00f5es terroristas na final da Copa, Esse \u00e9 um dos legados que vai ficar. Est\u00e3o sendo chamadas de &#8220;ativistas&#8221;.<br \/>\nSininho, uma jovem da classe m\u00e9dia, \u00e9 a lider de um radicalismo que n\u00e3o encontra espa\u00e7o para se expressar na a\u00e7\u00e3o pol\u00edtica convencional.<br \/>\nDe repente, sem querer, se colocam a servi\u00e7o de interesses que sequer suspeitam. Ou j\u00e1 est\u00e3o a servi\u00e7o?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vinte pessoas presas acusadas de planejar a\u00e7\u00f5es terroristas na final da Copa, Esse \u00e9 um dos legados que vai ficar. Est\u00e3o sendo chamadas de &#8220;ativistas&#8221;. Sininho, uma jovem da classe m\u00e9dia, \u00e9 a lider de um radicalismo que n\u00e3o encontra espa\u00e7o para se expressar na a\u00e7\u00e3o pol\u00edtica convencional. De repente, sem querer, se colocam a [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-15044","post","type-post","status-publish","format-standard","hentry","category-x-categorias-velhas"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbQjBd-3UE","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/15044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=15044"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/15044\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=15044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=15044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=15044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}