{"id":15279,"date":"2014-07-18T02:28:45","date_gmt":"2014-07-18T05:28:45","guid":{"rendered":"https:\/\/jornalja.com.br\/?p=15279"},"modified":"2014-07-18T02:28:45","modified_gmt":"2014-07-18T05:28:45","slug":"imprensa-licao-da-copa-nao-serviu-para-nada","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/arquivo\/imprensa-licao-da-copa-nao-serviu-para-nada\/","title":{"rendered":"Imprensa: li\u00e7\u00e3o da Copa n\u00e3o serviu para nada"},"content":{"rendered":"<p><em><\/em>A reuni\u00e3o do BRICS esta semana, em Fortaleza, serviu para mais uma demonstra\u00e7\u00e3o da grave crise que vive a imprensa monopolista brasileira.<br \/>\nA cobertura foi p\u00edfia, as an\u00e1lises med\u00edocres, preconceituosas e orquestradas. Todos disseram praticamente a mesma coisa.<br \/>\nO banco, criado pelo Brasil, China, India e \u00c1frica do Sul, como alternativa ao FMI e ao Banco Mundial (dominados pelos Estados Unidos), n\u00e3o passa de \u201cuma ilus\u00e3o de emergentes\u201d.<br \/>\nOs 32 acordos comerciais que a presidente Dilma Rousseff assinou com o presidente chin\u00eas, que podem envolver neg\u00f3cios de 30 bilh\u00f5es, s\u00e3o \u201cmanifesta\u00e7\u00f5es de neo-colonialismo\u201d.<br \/>\nAs manchetes dos principais jornais \u00a0preferiram destacar as pesquisas de inten\u00e7\u00e3o de voto a quatro meses da elei\u00e7\u00e3o, quando a campanha nem come\u00e7ou.<br \/>\nOu, ent\u00e3o, os \u201cn\u00fameros preocupantes da economia\u201d que, na verdade, n\u00e3o trazem novidade nenhuma.<br \/>\nA li\u00e7\u00e3o da Copa do Mundo, quando previu uma cat\u00e1strofe e foi clamorosamente desmentida pela realidade, n\u00e3o serviu para nada.<br \/>\nA imprensa brasileira segue desdenhando dos fatos, quando eles n\u00e3o se encaixam na sua maneira de pensar, no discurso pr\u00e9-pronto que confunde o governo, do qual n\u00e3o gosta, com o pa\u00eds, pelo qual deveria ter mais respeito. (EB)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A reuni\u00e3o do BRICS esta semana, em Fortaleza, serviu para mais uma demonstra\u00e7\u00e3o da grave crise que vive a imprensa monopolista brasileira. A cobertura foi p\u00edfia, as an\u00e1lises med\u00edocres, preconceituosas e orquestradas. Todos disseram praticamente a mesma coisa. O banco, criado pelo Brasil, China, India e \u00c1frica do Sul, como alternativa ao FMI e ao [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[26],"tags":[1764,1765,175],"class_list":["post-15279","post","type-post","status-publish","format-standard","hentry","category-geral","tag-brasilchina","tag-brics","tag-imprensa"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbQjBd-3Yr","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/15279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=15279"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/15279\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=15279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=15279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=15279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}