{"id":18114,"date":"2014-09-23T21:45:18","date_gmt":"2014-09-24T00:45:18","guid":{"rendered":"https:\/\/jornalja.com.br\/?p=18114"},"modified":"2014-09-23T21:45:18","modified_gmt":"2014-09-24T00:45:18","slug":"campanha-deixa-partidos-em-segundo-plano","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/arquivo\/campanha-deixa-partidos-em-segundo-plano\/","title":{"rendered":"Campanha revela desgaste na identidade dos partidos"},"content":{"rendered":"<p>Numa campanha que envolve 32 siglas, os grandes partidos perdem a identidade e, no caleidosc\u00f3pio das composi\u00e7\u00f5es, fazem tanto malabarismo que seus programas quase ficam irreconhec\u00edveis.<br \/>\nNo Rio Grande do Sul, por exemplo, os principais partidos n\u00e3o tem candidatos.<br \/>\nO governador Tarso Genro \u00e9 candidato da Unidade Popular.<br \/>\nAna Am\u00e9lia Lemos, a candidata da Esperan\u00e7a.<br \/>\nE Jos\u00e9 Sartori, do PMDB, \u00a0n\u00e3o deixa por menos: \u00e9 &#8220;o candidato do Rio Grande&#8221;.<br \/>\n\u00c9 uma elei\u00e7\u00e3o de partidos em agonia. O desgaste \u00e9 geral.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Numa campanha que envolve 32 siglas, os grandes partidos perdem a identidade e, no caleidosc\u00f3pio das composi\u00e7\u00f5es, fazem tanto malabarismo que seus programas quase ficam irreconhec\u00edveis. No Rio Grande do Sul, por exemplo, os principais partidos n\u00e3o tem candidatos. O governador Tarso Genro \u00e9 candidato da Unidade Popular. Ana Am\u00e9lia Lemos, a candidata da Esperan\u00e7a. [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[26],"tags":[],"class_list":["post-18114","post","type-post","status-publish","format-standard","hentry","category-geral"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":1280,"url":"https:\/\/www.jornalja.com.br\/arquivo\/o-menino-que-se-tornou-brizola\/","url_meta":{"origin":18114,"position":0},"title":"O Menino que se Tornou Brizola","author":"da Reda\u00e7\u00e3o","date":"28 de julho de 2008","format":false,"excerpt":"Autor: Cleber Dioni A vida de Leonel Brizola, com \u00eanfase para os primeiros anos em Porto Alegre, at\u00e9 o ex\u00edlio no Uruguai e a volta, quinze anos depois. \u00a0\"...\u00c9ramos todos jovens e nos identific\u00e1vamos com aquela massa an\u00f4nima a percorrer as ruas de Porto Alegre, gritando 'Get\u00falio', 'Get\u00falio' e empunhando\u2026","rel":"","context":"Em &quot;Livros&quot;","block_context":{"text":"Livros","link":"https:\/\/www.jornalja.com.br\/arquivo\/category\/livros\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/wp-content\/uploads\/2008\/07\/brizola.gif?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbQjBd-4Ia","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/18114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=18114"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/18114\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=18114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=18114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=18114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}