{"id":19423,"date":"2014-11-11T23:18:29","date_gmt":"2014-11-12T01:18:29","guid":{"rendered":"https:\/\/jornalja.com.br\/?p=19423"},"modified":"2014-11-11T23:18:29","modified_gmt":"2014-11-12T01:18:29","slug":"queda-de-braco-entre-o-pt-e-o-governo-dilma","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/arquivo\/queda-de-braco-entre-o-pt-e-o-governo-dilma\/","title":{"rendered":"Queda de bra\u00e7o entre o PT e o governo Dilma"},"content":{"rendered":"<p><span class=\"assina\">*\u00a0Glauco Peres da Silva<\/span><br \/>\nO segundo mandato da presidente Dilma come\u00e7ou com claros atritos entre ela e seu partido. Na semana passada,\u00a0a presidente correu mostrar-se em posi\u00e7\u00e3o distinta\u00a0do partido em rela\u00e7\u00e3o \u00e0s declara\u00e7\u00f5es do partido sobre alguns temas, dentre eles, regula\u00e7\u00e3o da m\u00eddia. Por outro lado,\u00a0Lula tem buscado participar mais, ao menos explicitamente, deste segundo mandato. Ainda o PT, atrav\u00e9s de seu presidente, declarou que\u00a0a rela\u00e7\u00e3o entre o partido com a presidente precisa se ajustar melhor. Atualmente parece termos, de um lado, Dilma; de outro, Lula e o PT. Dilma teve uma reelei\u00e7\u00e3o bastante apertada, o que a coloca em posi\u00e7\u00e3o mais fr\u00e1gil nas diferentes mesas de negocia\u00e7\u00e3o que participar\u00e1; dentre elas, est\u00e1 a rela\u00e7\u00e3o com o seu partido e o ex-presidente Lula. Por outro lado, o partido acredita que tenha tido uma participa\u00e7\u00e3o fundamental durante a campanha e quer atuar\u00a0mais diretamente\u00a0neste governo.<br \/>\n<span class=\"linhapequena\">\u00a0<\/span><br \/>\nEsta disputa est\u00e1 atualmente concentrada na nomea\u00e7\u00e3o do Ministro da Fazenda. De um lado, Lula seguido pelo PT sugere\u00a0nomes que acalmariam as press\u00f5es\u00a0geradas pelos maus resultados econ\u00f4micos dos \u00faltimos anos, flanco aberto e fartamente explorado pela oposi\u00e7\u00e3o durante a campanha de 2014. Henrique Meirelles e Nelson Barbosa s\u00e3o nomes que, nesta ordem, parecem ser a prefer\u00eancia do ex-presidente Lula. Esta antecipa\u00e7\u00e3o do debate p\u00fablico em torno dos novos ministros acontece, a meu ver, em raz\u00e3o do desempenho econ\u00f4mico do pa\u00eds ter sido bastante abaixo do esperado durante todo o governo Dilma, o que foi altamente contestado pela oposi\u00e7\u00e3o. Luiz Carlos Trabuco, do Bradesco, embora j\u00e1 tenha sido cotado, a esta altura parece j\u00e1 n\u00e3o fazer mais parte dos prov\u00e1veis nomes a ocupar a pasta.<br \/>\n<span class=\"linhapequena\">\u00a0<\/span><br \/>\nPor\u00e9m, a interfer\u00eancia neste minist\u00e9rio n\u00e3o passa apenas pela escolha de um nome-chave para as decis\u00f5es econ\u00f4micas do governo que se inicia. Ela cria ru\u00eddos por outras raz\u00f5es. Cogita-se que a presidente Dilma tinha em mente outros nomes para o minist\u00e9rio, como Alo\u00edzio Mercadante, atualmente na Casa Civil. Sua prefer\u00eancia por um nome mais afim ao partido n\u00e3o seria apenas por uma quest\u00e3o ideol\u00f3gica ou de afinidade em outros \u00e2mbitos, mas tamb\u00e9m em raz\u00e3o dela ser formada em Economia. Um nome com quem tivesse alguma proximidade daria a ela espa\u00e7o para manter o que parece ter\u00a0feito com Mantega ao longo de todo o seu governo anterior: intervir diretamente na condu\u00e7\u00e3o econ\u00f4mica. Adotando um estilo bastante centralizador, sup\u00f5e-se que Dilma sinta-se ainda mais \u00e0 vontade para interferir em um minist\u00e9rio afinado \u00e0 sua forma\u00e7\u00e3o.<br \/>\nOu seja, a escolha deste ministro coloca em choque as duas for\u00e7as presentes neste governo que j\u00e1 iniciam o mandato dividindo-se. Por um lado, a vontade e estilo da presidente Dilma e de outro, as press\u00f5es do PT e do ex-presidente Lula para um governo menos criticado e com uma condu\u00e7\u00e3o econ\u00f4mica mais pr\u00f3xima da observada durante os dois primeiros governos petistas. A presidente tem a caneta. Mas n\u00e3o se sabe se tem a autonomia que apresentou no primeiro governo e que pode acreditar ainda possuir, mesmo depois de uma reelei\u00e7\u00e3o t\u00e3o apertada.<br \/>\n<span class=\"linhapequena\">\u00a0<\/span><br \/>\n<em>*Glauco Peres da Silva: professor de ci\u00eancia pol\u00edtica da Universidade de S\u00e3o Paulo e autor do <a href=\"http:\/\/entrementes.blog.br\/author\/glauco\/\" target=\"_blank\" rel=\"noopener noreferrer\">blog Entrementes<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>*\u00a0Glauco Peres da Silva O segundo mandato da presidente Dilma come\u00e7ou com claros atritos entre ela e seu partido. Na semana passada,\u00a0a presidente correu mostrar-se em posi\u00e7\u00e3o distinta\u00a0do partido em rela\u00e7\u00e3o \u00e0s declara\u00e7\u00f5es do partido sobre alguns temas, dentre eles, regula\u00e7\u00e3o da m\u00eddia. Por outro lado,\u00a0Lula tem buscado participar mais, ao menos explicitamente, deste segundo [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[26],"tags":[],"class_list":["post-19423","post","type-post","status-publish","format-standard","hentry","category-geral"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbQjBd-53h","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/19423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=19423"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/19423\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=19423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=19423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=19423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}