{"id":20106,"date":"2014-12-22T14:34:08","date_gmt":"2014-12-22T16:34:08","guid":{"rendered":"https:\/\/jornalja.com.br\/?p=20106"},"modified":"2014-12-22T14:34:08","modified_gmt":"2014-12-22T16:34:08","slug":"dilma-mantem-graca-forster-em-defesa-pre-sal","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/arquivo\/dilma-mantem-graca-forster-em-defesa-pre-sal\/","title":{"rendered":"Dilma mant\u00e9m Gra\u00e7a Forster em defesa do Pr\u00e9-sal"},"content":{"rendered":"<p><span class=\"assina\">Elmar Bones<\/span><br \/>\nA firmeza com que Dilma Rousseff defendeu mais uma vez a presidente da Petrobras \u00e9 sinal de que ela est\u00e1 consciente do verdadeiro alvo da campanha para envolver Gra\u00e7a Forster nas petrofalcatruas.<br \/>\nS\u00e3o dois alvos na verdade:<br \/>\n&#8211; O modelo de partilha do pr\u00e9-sal, que preserva o controle estatal na explora\u00e7\u00e3o das reservas.<br \/>\n&#8211; \u00a0O programa de conte\u00fado nacional nas obras da Petrobras, que prioriza e incentiva a participa\u00e7\u00e3o das empresas brasileiras nos projetos da Estatal.<br \/>\nA sa\u00edda de Gra\u00e7a Forster abriria caminho para solu\u00e7\u00f5es privativistas, principalmente porque o pr\u00f3ximo presidente do Conselho de Administra\u00e7\u00e3o da Petrobr\u00e1s ser\u00e1, pela regra, o ministro Joaquim Levy.<br \/>\nSeria uma solu\u00e7\u00e3o muito bem vista pela &#8220;comunidade internacional , encampada pela m\u00eddia, apoiada pelos grandes investidores e entusiasticamente aplaudida pela oposi\u00e7\u00e3o.<br \/>\nO c\u00edrculo de ferro se fecharia com o comprometimento das maiores empreiteiras do pais com a corrup\u00e7\u00e3o, que pode atingir o andamento das grandes obras de infraestrutura em andamento no PAC, que s\u00e3o vitais para segurar o crescimento.<br \/>\nEnt\u00e3o \u00e9 \u00a0isso. J\u00e1 que a hip\u00f3tese do impeachment est\u00e1 afastada, por enquanto, \u00a0trata-se de conduzir os fatos para manter o governo na defensiva e obter \u00a0o maior desgaste poss\u00edvel da presidente.<br \/>\nAtingindo-se os fundamentos de sua estrat\u00e9gia, \u00a0vai-se imobilizando o governo e esvaziando-o de seus conte\u00fados, deixando-o reduzido \u00e0s manobras e recuos para se manter de p\u00e9.<br \/>\nNestas circunst\u00e2ncias,o impeachment torna-se desnecess\u00e1rio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elmar Bones A firmeza com que Dilma Rousseff defendeu mais uma vez a presidente da Petrobras \u00e9 sinal de que ela est\u00e1 consciente do verdadeiro alvo da campanha para envolver Gra\u00e7a Forster nas petrofalcatruas. S\u00e3o dois alvos na verdade: &#8211; O modelo de partilha do pr\u00e9-sal, que preserva o controle estatal na explora\u00e7\u00e3o das reservas. [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":20123,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-20106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-x-categorias-velhas"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbQjBd-5ei","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/20106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=20106"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/20106\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=20106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=20106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=20106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}