{"id":20260,"date":"2015-01-15T10:25:45","date_gmt":"2015-01-15T12:25:45","guid":{"rendered":"https:\/\/jornalja.com.br\/?p=20260"},"modified":"2015-01-15T10:25:45","modified_gmt":"2015-01-15T12:25:45","slug":"lava-jato-2-a-campanha","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/arquivo\/lava-jato-2-a-campanha\/","title":{"rendered":"Lava jato 2, a campanha"},"content":{"rendered":"<p>O Brasil s\u00f3 ser\u00e1 uma democracia no dia em que um procurador n\u00e3o possa vir a p\u00fablico acusar algu\u00e9m com base em &#8220;fortes ind\u00edcios&#8221;.<br \/>\nAinda mais quando se tratar de uma institui\u00e7\u00e3o nacional com grande alcance econ\u00f4mica e social no pa\u00eds.<br \/>\nDizer que a corrup\u00e7\u00e3o continuou em 2014 na Petrobras \u00a0com base em &#8220;forte ind\u00edcios&#8221;?.<br \/>\n\u00c9 claro que tem que investigar a fundo. Investigar, n\u00e3o divulgar conjeturas, para obter manchetes.<br \/>\nA crise da Petrobr\u00e1s j\u00e1 tem reflexos negativos em todas as regi\u00f5es brasileiras. \u00c9 uma irresponsabilidade agrav\u00e1-la com base em &#8220;fortes indicios&#8221;.<br \/>\nE se os &#8220;fortes ind\u00edcios&#8221; n\u00e3o se confirmarem? \u00a0 Podem n\u00e3o se confirmar, pois ind\u00edcios, por mais fortes que sejam, n\u00e3o s\u00e3o verdade, fato.<br \/>\nN\u00e3o seria simples e correto investigar primeiro, comprovar depois divulgar?. Quanto tempo levaria? Um m\u00eas, dois, tr\u00eas? O que se perderia com isso?<br \/>\nEssa pressa na divulga\u00e7\u00e3o de informa\u00e7\u00f5es incompleta s\u00f3 se justifica numa campanha, que n\u00e3o pode parar.<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Brasil s\u00f3 ser\u00e1 uma democracia no dia em que um procurador n\u00e3o possa vir a p\u00fablico acusar algu\u00e9m com base em &#8220;fortes ind\u00edcios&#8221;. Ainda mais quando se tratar de uma institui\u00e7\u00e3o nacional com grande alcance econ\u00f4mica e social no pa\u00eds. Dizer que a corrup\u00e7\u00e3o continuou em 2014 na Petrobras \u00a0com base em &#8220;forte ind\u00edcios&#8221;?. [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[26],"tags":[],"class_list":["post-20260","post","type-post","status-publish","format-standard","hentry","category-geral"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbQjBd-5gM","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/20260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=20260"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/20260\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=20260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=20260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=20260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}