{"id":50180,"date":"2017-06-17T06:48:24","date_gmt":"2017-06-17T09:48:24","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=50180"},"modified":"2017-06-17T06:48:24","modified_gmt":"2017-06-17T09:48:24","slug":"entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/arquivo\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\/","title":{"rendered":"Entrevista bomba de Joesley Batista detona Temer e sua turma"},"content":{"rendered":"<div>\n<h3 class=\"m_-3831218568826299426gmail-chamada\"><span class=\"assina\">DIEGO ESCOSTEGUY, da \u00c9POCA<\/span><\/h3>\n<\/div>\n<div>\nNa manh\u00e3 da quinta-feira (15), o empres\u00e1rio\u00a0<a href=\"http:\/\/epoca.globo.com\/tudo-sobre\/noticia\/2017\/05\/joesley-batista.html\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"http:\/\/www.google.com\/url?hl=pt-BR&amp;q=http:\/\/epoca.globo.com\/tudo-sobre\/noticia\/2017\/05\/joesley-batista.html&amp;source=gmail&amp;ust=1497777116452000&amp;usg=AFQjCNHyG6HQlNaOdU81VUBiEvx3Q476DQ\">Joesley Batista<\/a>, um dos donos do grupo J&amp;F, recebeu \u00c9POCA para conceder sua primeira entrevista exclusiva desde que fechou a mais pesada dela\u00e7\u00e3o dos tr\u00eas anos de Lava Jato. Em mais de quatro horas de conversa, precedidas de semanas de intensa negocia\u00e7\u00e3o, Joesley explicou minuciosamente, sempre fazendo refer\u00eancia aos documentos entregues \u00e0 Procuradoria-Geral da Rep\u00fablica, como se tornou o maior comprador de pol\u00edticos do Brasil. Discorreu sobre os motivos que o levaram a gravar o presidente\u00a0<a href=\"http:\/\/epoca.globo.com\/tudo-sobre\/noticia\/2016\/05\/michel-temer.html\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"http:\/\/www.google.com\/url?hl=pt-BR&amp;q=http:\/\/epoca.globo.com\/tudo-sobre\/noticia\/2016\/05\/michel-temer.html&amp;source=gmail&amp;ust=1497777116453000&amp;usg=AFQjCNFbI9UVAPYSs7ekdr0e1NRF9iEQkw\">Michel Temer<\/a>\u00a0e a se oferecer \u00e0 PGR para flagrar crimes em andamento contra a Lava Jato. Atacou o presidente, a quem acusa, com casos e detalhes in\u00e9ditos, de liderar \u201ca maior e mais perigosa organiza\u00e7\u00e3o criminosa do Brasil\u201d \u2013 e de usar a m\u00e1quina do governo para retali\u00e1-lo. Contou como o PT de\u00a0<a href=\"http:\/\/epoca.globo.com\/tudo-sobre\/noticia\/2017\/02\/luiz-inacio-lula-da-silva.html\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"http:\/\/www.google.com\/url?hl=pt-BR&amp;q=http:\/\/epoca.globo.com\/tudo-sobre\/noticia\/2017\/02\/luiz-inacio-lula-da-silva.html&amp;source=gmail&amp;ust=1497777116453000&amp;usg=AFQjCNGoDC_hjCYBFKY_hnmsLBlqfGsPRw\">Lula<\/a>\u00a0\u201cinstitucionalizou\u201d a corrup\u00e7\u00e3o no Brasil e de que modo o PSDB de\u00a0<a href=\"http:\/\/epoca.globo.com\/tudo-sobre\/noticia\/2017\/02\/aecio-neves.html\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"http:\/\/www.google.com\/url?hl=pt-BR&amp;q=http:\/\/epoca.globo.com\/tudo-sobre\/noticia\/2017\/02\/aecio-neves.html&amp;source=gmail&amp;ust=1497777116453000&amp;usg=AFQjCNHMKb7vLktw-ZcqsQ6iyGdqVNMyaQ\">A\u00e9cio Neves<\/a>\u00a0entrou em leil\u00f5es para comprar partidos nas elei\u00e7\u00f5es de 2014. O empres\u00e1rio garante estar arrependido dos crimes que cometeu e se defendeu das acusa\u00e7\u00f5es de que lucrou com a pr\u00f3pria dela\u00e7\u00e3o.<br \/>\nA seguir, os principais trechos da entrevista publicada na edi\u00e7\u00e3o de \u00c9POCA desta semana. Leia as 12 p\u00e1ginas da conversa com Joesley na edi\u00e7\u00e3o que chega \u00e0s\u00a0<strong>bancas<\/strong>\u00a0neste s\u00e1bado (17).<br \/>\n<strong>\u00c9POCA &#8211; Quando o senhor conheceu Temer?<\/strong><br \/>\n<strong>Joesley Batista \u2013\u00a0<\/strong>Conheci Temer atrav\u00e9s do ministro Wagner Rossi, em 2009, 2010. Logo no segundo encontro ele j\u00e1 me deu o celular dele. Da\u00ed em diante passamos a falar. Eu mandava mensagem para ele, ele mandava para mim. De 2010 em diante. Sempre tive rela\u00e7\u00e3o direta. Fui v\u00e1rias vezes ao escrit\u00f3rio da Pra\u00e7a Pan-Americana, fui v\u00e1rias vezes ao escrit\u00f3rio no Itaim, fui v\u00e1rias vezes \u00e0 casa dele em S\u00e3o Paulo, fui alguma vezes ao Jaburu, ele j\u00e1 esteve aqui em casa, ele foi ao meu casamento. Foi inaugurar a f\u00e1brica da Eldorado.<br \/>\n<a href=\"http:\/\/epoca.globo.com\/politica\/expresso\/noticia\/2017\/06\/joesley-batista-esta-no-brasil-e-prestou-novo-depoimento-no-acordo-de-delacao-premiada.html\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"http:\/\/www.google.com\/url?hl=pt-BR&amp;q=http:\/\/epoca.globo.com\/politica\/expresso\/noticia\/2017\/06\/joesley-batista-esta-no-brasil-e-prestou-novo-depoimento-no-acordo-de-delacao-premiada.html&amp;source=gmail&amp;ust=1497777116453000&amp;usg=AFQjCNEJ7IDscNaAxpSrM-yA5jrcfJsjgg\">&gt;&gt;\u00a0Joesley Batista est\u00e1 no Brasil e prestou novo depoimento no acordo de dela\u00e7\u00e3o premiada<\/a><br \/>\n<strong>\u00c9POCA \u2013 Qual, afinal, a natureza da rela\u00e7\u00e3o do senhor com o presidente Temer?<br \/>\nJoesley \u2013\u00a0<\/strong>Nunca foi uma rela\u00e7\u00e3o de amizade. Sempre foi uma rela\u00e7\u00e3o institucional, de um empres\u00e1rio que precisava resolver problemas e via nele a condi\u00e7\u00e3o de resolver problemas. Acho que ele me via como um empres\u00e1rio que poderia financiar as campanhas dele \u2013 e fazer esquemas que renderiam propina. Toda a vida tive total acesso a ele. Ele por vezes me ligava para conversar, me chamava, e eu ia l\u00e1.<br \/>\n<strong>\u00c9POCA \u2013 Conversar sobre pol\u00edtica?<br \/>\nJoesley \u2013<\/strong>\u00a0Ele sempre tinha um assunto espec\u00edfico. Nunca me chamou l\u00e1 para bater papo. Sempre que me chamava, eu sabia que ele ia me pedir alguma coisa ou ele queria alguma informa\u00e7\u00e3o.<br \/>\n<a href=\"http:\/\/epoca.globo.com\/politica\/noticia\/2017\/05\/joesley-batista-o-mais-perigoso-delator.html\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"http:\/\/www.google.com\/url?hl=pt-BR&amp;q=http:\/\/epoca.globo.com\/politica\/noticia\/2017\/05\/joesley-batista-o-mais-perigoso-delator.html&amp;source=gmail&amp;ust=1497777116453000&amp;usg=AFQjCNERhkloPpBwdmSzN41dCY-o8lGtqA\">&gt;&gt;\u00a0Joesley Batista: O mais perigoso delator<\/a><br \/>\n<strong>\u00c9POCA \u2013 Segundo a colabora\u00e7\u00e3o, Temer pediu dinheiro ao senhor j\u00e1 em 2010. \u00c9 isso?<br \/>\nJoesley \u2013<\/strong>\u00a0Isso. Logo no in\u00edcio. Conheci Temer, e esse neg\u00f3cio de dinheiro para campanha aconteceu logo no iniciozinho. O Temer n\u00e3o tem muita cerim\u00f4nia para tratar desse assunto. N\u00e3o \u00e9 um cara cerimonioso com dinheiro.<br \/>\n<strong>\u00c9POCA \u2013 Ele sempre pediu sem algo em troca?<br \/>\nJoesley \u2013<\/strong>\u00a0Sempre estava ligado a alguma coisa ou a algum favor. Raras vezes n\u00e3o. Uma delas foi quando ele pediu os R$ 300 mil para fazer campanha na internet antes do impeachment, preocupado com a imagem dele. Fazia pequenos pedidos. Quando o Wagner saiu, Temer pediu um dinheiro para ele se manter. Tamb\u00e9m pediu para um tal de Milton Ortolon, que est\u00e1 l\u00e1 na nossa colabora\u00e7\u00e3o. Um sujeito que \u00e9 ligado a ele. Pediu para fazermos um mensalinho. Fizemos. Volta e meia fazia pedidos assim. Uma vez ele me chamou para apresentar o Yunes. Disse que o Yunes era amigo dele e para ver se dava para ajudar o Yunes.<br \/>\n<a href=\"http:\/\/epoca.globo.com\/politica\/expresso\/noticia\/2017\/05\/joesley-batista-esta-irritado-com-acusacoes-de-temer.html\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"http:\/\/www.google.com\/url?hl=pt-BR&amp;q=http:\/\/epoca.globo.com\/politica\/expresso\/noticia\/2017\/05\/joesley-batista-esta-irritado-com-acusacoes-de-temer.html&amp;source=gmail&amp;ust=1497777116453000&amp;usg=AFQjCNG8jq_uatSimDtz-0cOqx6BEmDbhw\">&gt;&gt;\u00a0Joesley Batista est\u00e1 irritado com acusa\u00e7\u00f5es de Temer<\/a><br \/>\n<strong>\u00c9POCA \u2013 E ajudou?<br \/>\nJoesley \u2013<\/strong>\u00a0N\u00e3o chegamos a contratar. Teve uma vez tamb\u00e9m que ele me pediu para ver se eu pagava o aluguel do escrit\u00f3rio dele na pra\u00e7a [Pan-Americana, em S\u00e3o Paulo]. Eu desconversei, fiz de conta que n\u00e3o entendi, n\u00e3o ouvi. Ele nunca mais me cobrou.<br \/>\n<strong>\u00c9POCA \u2013 Ele explicava a raz\u00e3o desses pedidos? Por que o senhor deveria pagar?<br \/>\nJoesley \u2013\u00a0<\/strong>O Temer tem esse jeito calmo, esse jeito d\u00f3cil de tratar e coisa. N\u00e3o falava.<br \/>\n<strong>\u00c9POCA \u2013 Ele n\u00e3o deu nenhuma raz\u00e3o?<br \/>\nJoesley \u2013<\/strong>\u00a0N\u00e3o, n\u00e3o ele. H\u00e1 pol\u00edticos que acreditam que pelo simples fato do cargo que ele est\u00e1 ocupando j\u00e1 o habilita a voc\u00ea ficar devendo favores a ele. J\u00e1 o habilita a pedir algo a voc\u00ea de maneira que seja quase uma obriga\u00e7\u00e3o voc\u00ea fazer. Temer \u00e9 assim.<br \/>\n<strong>\u00c9POCA \u2013 O empr\u00e9stimo do jatinho da JBS ao presidente tamb\u00e9m ocorreu dessa maneira?<br \/>\nJoesley \u2013<\/strong>\u00a0N\u00e3o lembro direito. Mas \u00e9 dentro desse contexto: \u201cEu preciso viajar, voc\u00ea tem um avi\u00e3o, me empresta a\u00ed\u201d. Acha que o cargo j\u00e1 o habilita. Sempre pedindo dinheiro. Pediu para o Chalita em 2012, pediu para o grupo dele em 2014.<br \/>\n<strong>\u00c9POCA \u2013 Houve uma briga por dinheiro dentro do PMDB na campanha de 2014, segundo o lobista Ricardo Saud, que est\u00e1 na colabora\u00e7\u00e3o da JBS.<br \/>\nJoesley \u2013<\/strong>\u00a0Ricardinho falava direto com Temer, al\u00e9m de mim. O PT mandou dar um dinheiro para os senadores do PMDB. Acho que R$ 35 milh\u00f5es. O Temer e o Eduardo descobriram e deu uma briga danada. Pediram R$ 15 milh\u00f5es, o Temer reclamou conosco. Demos o dinheiro. Foi a\u00ed que Temer voltou \u00e0 Presid\u00eancia do PMDB, da qual ele havia se ausentado. O Eduardo tamb\u00e9m participou ativamente disso.<br \/>\n<strong>\u00c9POCA \u2013 Como era a rela\u00e7\u00e3o entre Temer e Eduardo Cunha?<br \/>\nJoesley \u2013<\/strong>\u00a0A pessoa a qual o Eduardo se referia como seu superior hier\u00e1rquico sempre foi o Temer. Sempre falando em nome do Temer. Tudo que o Eduardo conseguia resolver sozinho, ele resolvia. Quando ficava dif\u00edcil, levava para o Temer. Essa era a hierarquia. Funcionava assim: primeiro vinha o L\u00facio [o operador L\u00facio\u00a0Funaro]. O que ele n\u00e3o conseguia resolver pedia para o Eduardo. Se o Eduardo n\u00e3o conseguia resolver, envolvia o Michel.<br \/>\n<strong>\u00c9POCA \u2013 Segundo as provas da dela\u00e7\u00e3o da JBS e de outras investiga\u00e7\u00f5es, o senhor pagava constantemente tanto para Eduardo Cunha quanto para L\u00facio Funaro, seja por acertos na C\u00e2mara, seja por acertos na Caixa, entre outros. Quem ficava com o dinheiro?<br \/>\nJoesley \u2013<\/strong>\u00a0Em grande parte do per\u00edodo que convivemos, meu acerto era direto com o L\u00facio. Eu n\u00e3o sei como era o acerto do L\u00facio do Eduardo, tampouco do Eduardo com o Michel. Eu n\u00e3o sei como era a distribui\u00e7\u00e3o entre eles. Eu evitava falar de dinheiro de um com o outro. N\u00e3o sabia como era o acerto entre eles. Depois, comecei a tratar uns neg\u00f3cios direto com o Eduardo. Em 2015, quando ele assumiu a presid\u00eancia da C\u00e2mara. N\u00e3o sei tamb\u00e9m quanto desses acertos iam para o Michel. E com o Michel mesmo eu tamb\u00e9m tratei v\u00e1rias doa\u00e7\u00f5es. Quando eu ia falar de esquema mais estrutural com Michel, ele sempre pedia para falar com o Eduardo. \u201cPresidente, o neg\u00f3cio do Minist\u00e9rio da Agricultura, o neg\u00f3cio dos acertos\u2026\u201d Ele dizia: \u201cJoesley, essa parte financeira toca com o Eduardo e se acerta com o Eduardo\u201d. Ele se envolvia somente nos pequenos favores pessoais ou em disputas internas, como a de 2014.<br \/>\n<strong>\u00c9POCA \u2013 O senhor realmente precisava tanto assim desse grupo de Eduardo Cunha, L\u00facio Funaro e Temer?<br \/>\nJoesley \u2013<\/strong>\u00a0Eles foram crescendo no FI-FGTS, na Caixa, na Agricultura \u2013 todos \u00f3rg\u00e3os onde t\u00ednhamos interesses. Eu morria de medo de eles encamparem o Minist\u00e9rio da Agricultura. Eu sabia que o achaque ia ser grande. Eles tentaram. Gra\u00e7as a Deus, mudou o governo e eles sa\u00edram. O mais relevante foi quando Eduardo tomou a C\u00e2mara. A\u00ed virou CPI para c\u00e1, achaque para l\u00e1. Tinha de tudo. Eduardo sempre deixava claro que o fortalecimento dele era o fortalecimento do grupo da C\u00e2mara e do pr\u00f3prio Michel. Aquele grupo tem o estilo de entrar na sua vida sem ser convidado.<br \/>\n<strong>\u00c9POCA \u2013 Pode dar um exemplo?<br \/>\nJoesley \u2013\u00a0<\/strong>O Eduardo, quando j\u00e1 era presidente da C\u00e2mara, um dia me disse assim: \u201cJoesley, t\u00e3o querendo abrir uma CPI contra a JBS para investigar o BNDES. \u00c9 o seguinte: voc\u00ea me d\u00e1 R$ 5 milh\u00f5es que eu acabo com a CPI\u201d. Falei: \u201cEduardo, pode abrir, n\u00e3o tem problema\u201d. \u201cComo n\u00e3o tem problema? Investigar o BNDES, voc\u00eas.\u201d Falei: \u201cN\u00e3o, n\u00e3o tem problema\u201d. \u201cVoc\u00ea t\u00e1 louco?\u201d Depois de tanto insistir, ele virou bem s\u00e9rio: \u201c\u00c9 s\u00e9rio que n\u00e3o tem problema?\u201d. Eu: \u201c\u00c9 s\u00e9rio\u201d. Ele: \u201cN\u00e3o vai te prejudicar em nada?\u201d. \u201cN\u00e3o, Eduardo.\u201d Ele imediatamente falou assim: \u201cSeu concorrente me paga R$ 5 milh\u00f5es para abrir essa CPI. Se n\u00e3o vai te prejudicar, se n\u00e3o tem problema\u2026 Eu acho que eles me d\u00e3o os R$ 5 milh\u00f5es\u201d. \u201cUai, Eduardo, vai sua consci\u00eancia. Faz o que voc\u00ea achar melhor.\u201d Esse \u00e9 o Eduardo. N\u00e3o paguei e n\u00e3o abriu. N\u00e3o sei se ele foi atr\u00e1s. Esse \u00e9 o exemplo mais bem-acabado da l\u00f3gica dessa Orcrim.<br \/>\n<strong>\u00c9POCA \u2013 Algum outro?<br \/>\nJoesley \u2013<\/strong>\u00a0L\u00facio fazia a mesma coisa. Virava para mim e dizia: \u201cTem um requerimento numa CPI para te convocar. Me d\u00e1 R$ 1 milh\u00e3o que eu barro\u201d. Mas a gente ia ver e descobria que era algum deputado a mando dele que estava fazendo. \u00c9 uma coisa de louco.<br \/>\n<strong>\u00c9POCA \u2013 O senhor n\u00e3o pagou?<br \/>\nJoesley \u2013<\/strong>\u00a0Nesse tipo de coisa, n\u00e3o. Tinha alguns limites. Tinha que tomar cuidado. Essa \u00e9 a maior e mais perigosa organiza\u00e7\u00e3o criminosa deste pa\u00eds. Liderada pelo presidente.<br \/>\n<strong>\u00c9POCA \u2013 O chefe \u00e9 o presidente Temer?<br \/>\nJoesley \u2013<\/strong>\u00a0O Temer \u00e9 o chefe da Orcrim da C\u00e2mara. Temer, Eduardo, Geddel, Henrique, Padilha e Moreira. \u00c9 o grupo deles. Quem n\u00e3o est\u00e1 preso est\u00e1 hoje no Planalto. Essa turma \u00e9 muita perigosa. N\u00e3o pode brigar com eles. Nunca tive coragem de brigar com eles. Por outro lado, se voc\u00ea baixar a guarda, eles n\u00e3o t\u00eam limites. Ent\u00e3o meu conv\u00edvio com eles foi sempre mantendo \u00e0 meia dist\u00e2ncia: nem deixando eles aproximarem demais nem deixando eles longe demais. Para n\u00e3o armar alguma coisa contra mim. A realidade \u00e9 que esse grupo \u00e9 o de mais dif\u00edcil conv\u00edvio que j\u00e1 tive na minha vida. Daquele sujeito que nunca tive coragem de romper, mas tamb\u00e9m morria de medo de me abra\u00e7ar com ele.<br \/>\n<strong>\u00c9POCA \u2013 No decorrer de 2016, o senhor, segundo admite e as provas corroboram, estava pagando pelo sil\u00eancio de Eduardo Cunha e L\u00facio Funaro, ambos j\u00e1 presos na Lava Jato, com quem o senhor tivera acertos na Caixa e na C\u00e2mara. O custo de manter esse sil\u00eancio ficou alto demais? Muito arriscado?<br \/>\nJoesley \u2013<\/strong>\u00a0Virei ref\u00e9m de dois presidi\u00e1rios. Combinei quando j\u00e1 estava claro que eles seriam presos, no ano passado. O Eduardo me pediu R$ 5 milh\u00f5es. Disse que eu devia a ele. N\u00e3o devia, mas como ia brigar com ele? Dez dias depois ele foi preso. Eu tinha perguntado para ele: \u201cSe voc\u00ea for preso, quem \u00e9 a pessoa que posso considerar seu mensageiro?\u201d. Ele disse: \u201cO Altair procura voc\u00eas. Qualquer outra pessoa n\u00e3o atenda\u201d.\u00a0 Passou um m\u00eas, veio o Altair. Meu Deus, como vou dar esse dinheiro para o cara que est\u00e1 preso? A\u00ed o Altair disse que a fam\u00edlia do Eduardo precisava e que ele estaria solto logo, logo. E que o dinheiro duraria at\u00e9 mar\u00e7o deste ano. Fui pagando, em dinheiro vivo, ao longo de 2016. E eu sabia que, quando ele n\u00e3o sa\u00edsse da cadeia, ia mandar recados.<br \/>\n<strong>\u00c9POCA \u2013 E o L\u00facio Funaro?<br \/>\nJoesley \u2013<\/strong>\u00a0Foi parecido. Perguntei para ele quem seria o mensageiro se ele fosse preso. Ele disse que seria um irm\u00e3o dele, o Dante. Depois virou a irm\u00e3. Fomos pagando mesada. O Eduardo sempre dizia: \u201cJoesley, estamos juntos, estamos juntos. N\u00e3o te delato nunca. Eu confio em voc\u00ea. Sei que nunca vai me deixar na m\u00e3o, vai cuidar da minha fam\u00edlia\u201d. L\u00facio era a mesma coisa: \u201cConfio em voc\u00ea, eu posso ir preso porque eu sei que voc\u00ea n\u00e3o vai deixar minha fam\u00edlia mal. N\u00e3o te delato\u201d.<br \/>\n<strong>\u00c9POCA \u2013 E eles cumpriram o acerto, n\u00e3o?<br \/>\nJoesley \u2013\u00a0<\/strong>Sim. Sempre me mandando recados: \u201cVoc\u00ea est\u00e1 cumprindo tudo direitinho. N\u00e3o v\u00e3o te delatar. Podem delatar todo mundo menos voc\u00ea\u201d. Mas n\u00e3o era sustent\u00e1vel. N\u00e3o tinha fim. E toda hora o mensageiro do presidente me procurando para garantir que eu estava mantendo esse sistema.<br \/>\n<strong>\u00c9POCA \u2013 Quem era o mensageiro?<br \/>\nJoesley \u2013\u00a0<\/strong>Geddel. De 15 em 15 dias era uma agonia terr\u00edvel. Sempre querendo saber se estava tudo certo, se ia ter dela\u00e7\u00e3o, se eu estava cuidando dos dois. O presidente estava preocupado. Quem estava incumbido de manter Eduardo e L\u00facio calmos era eu.<br \/>\n<strong>\u00c9POCA \u2013 O ministro Geddel falava em nome do presidente Temer?<br \/>\nJoesley \u2013<\/strong>\u00a0Sem d\u00favida. Depois que o Eduardo foi preso, mantive a interlocu\u00e7\u00e3o desses assuntos via Geddel. O presidente sabia de tudo. Eu informava o presidente por meio do Geddel. E ele sabia que eu estava pagando o L\u00facio e o Eduardo. Quando o Geddel caiu, deixei de ter interlocu\u00e7\u00e3o com o Planalto por um tempo. At\u00e9 por precau\u00e7\u00e3o.\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>DIEGO ESCOSTEGUY, da \u00c9POCA Na manh\u00e3 da quinta-feira (15), o empres\u00e1rio\u00a0Joesley Batista, um dos donos do grupo J&amp;F, recebeu \u00c9POCA para conceder sua primeira entrevista exclusiva desde que fechou a mais pesada dela\u00e7\u00e3o dos tr\u00eas anos de Lava Jato. Em mais de quatro horas de conversa, precedidas de semanas de intensa negocia\u00e7\u00e3o, Joesley explicou minuciosamente, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":48655,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[26],"tags":[],"class_list":["post-50180","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"da Reda\u00e7\u00e3o\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.jornalja.com.br\/arquivo\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Arquivo | Jornal J\u00c1 | Porto Alegre\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Entrevista bomba de Joesley Batista detona Temer e sua turma | Arquivo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.jornalja.com.br\/arquivo\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-06-17T09:48:24+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-06-17T09:48:24+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Entrevista bomba de Joesley Batista detona Temer e sua turma | Arquivo\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\\\/#blogposting\",\"name\":\"Entrevista bomba de Joesley Batista detona Temer e sua turma | Arquivo\",\"headline\":\"Entrevista bomba de Joesley Batista detona Temer e sua turma\",\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/author\\\/daredacao\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":48655},\"datePublished\":\"2017-06-17T06:48:24-03:00\",\"dateModified\":\"2017-06-17T06:48:24-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\\\/#webpage\"},\"articleSection\":\"Geral\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/category\\\/geral\\\/#listItem\",\"name\":\"Geral\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/category\\\/geral\\\/#listItem\",\"position\":2,\"name\":\"Geral\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/category\\\/geral\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\\\/#listItem\",\"name\":\"Entrevista bomba de Joesley Batista detona Temer e sua turma\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\\\/#listItem\",\"position\":3,\"name\":\"Entrevista bomba de Joesley Batista detona Temer e sua turma\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/category\\\/geral\\\/#listItem\",\"name\":\"Geral\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/#organization\",\"name\":\"Jornal J\\u00c1\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/\",\"telephone\":\"+555133307272\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/wp-content\\\/uploads\\\/cards\\\/JAslogan.png\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/author\\\/daredacao\\\/#author\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/author\\\/daredacao\\\/\",\"name\":\"da Reda\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"da Reda\\u00e7\\u00e3o\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\\\/#webpage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\\\/\",\"name\":\"Entrevista bomba de Joesley Batista detona Temer e sua turma | Arquivo\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/author\\\/daredacao\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/author\\\/daredacao\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":48655,\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\\\/#mainImage\"},\"datePublished\":\"2017-06-17T06:48:24-03:00\",\"dateModified\":\"2017-06-17T06:48:24-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/#website\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/\",\"name\":\"Arquivo\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Entrevista bomba de Joesley Batista detona Temer e sua turma | Arquivo","description":"","canonical_url":"https:\/\/www.jornalja.com.br\/arquivo\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.jornalja.com.br\/arquivo\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\/#blogposting","name":"Entrevista bomba de Joesley Batista detona Temer e sua turma | Arquivo","headline":"Entrevista bomba de Joesley Batista detona Temer e sua turma","author":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/author\/daredacao\/#author"},"publisher":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/#organization"},"image":{"@type":"ImageObject","url":48655},"datePublished":"2017-06-17T06:48:24-03:00","dateModified":"2017-06-17T06:48:24-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\/#webpage"},"isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\/#webpage"},"articleSection":"Geral"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornalja.com.br\/arquivo\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo#listItem","position":1,"name":"Home","item":"https:\/\/www.jornalja.com.br\/arquivo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo\/category\/geral\/#listItem","name":"Geral"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo\/category\/geral\/#listItem","position":2,"name":"Geral","item":"https:\/\/www.jornalja.com.br\/arquivo\/category\/geral\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\/#listItem","name":"Entrevista bomba de Joesley Batista detona Temer e sua turma"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\/#listItem","position":3,"name":"Entrevista bomba de Joesley Batista detona Temer e sua turma","previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo\/category\/geral\/#listItem","name":"Geral"}}]},{"@type":"Organization","@id":"https:\/\/www.jornalja.com.br\/arquivo\/#organization","name":"Jornal J\u00c1","description":"Jornal J\u00c1 | Porto Alegre","url":"https:\/\/www.jornalja.com.br\/arquivo\/","telephone":"+555133307272","logo":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/cards\/JAslogan.png","@id":"https:\/\/www.jornalja.com.br\/arquivo\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\/#organizationLogo"},"image":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.jornalja.com.br\/arquivo\/author\/daredacao\/#author","url":"https:\/\/www.jornalja.com.br\/arquivo\/author\/daredacao\/","name":"da Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.jornalja.com.br\/arquivo\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g","width":96,"height":96,"caption":"da Reda\u00e7\u00e3o"}},{"@type":"WebPage","@id":"https:\/\/www.jornalja.com.br\/arquivo\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\/#webpage","url":"https:\/\/www.jornalja.com.br\/arquivo\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\/","name":"Entrevista bomba de Joesley Batista detona Temer e sua turma | Arquivo","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/#website"},"breadcrumb":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\/#breadcrumblist"},"author":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/author\/daredacao\/#author"},"creator":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/author\/daredacao\/#author"},"image":{"@type":"ImageObject","url":48655,"@id":"https:\/\/www.jornalja.com.br\/arquivo\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\/#mainImage"},"datePublished":"2017-06-17T06:48:24-03:00","dateModified":"2017-06-17T06:48:24-03:00"},{"@type":"WebSite","@id":"https:\/\/www.jornalja.com.br\/arquivo\/#website","url":"https:\/\/www.jornalja.com.br\/arquivo\/","name":"Arquivo","description":"Jornal J\u00c1 | Porto Alegre","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Arquivo | Jornal J\u00c1 | Porto Alegre","og:type":"article","og:title":"Entrevista bomba de Joesley Batista detona Temer e sua turma | Arquivo","og:url":"https:\/\/www.jornalja.com.br\/arquivo\/entrevista-bomba-de-joesley-batista-detona-temer-e-sua-turma\/","og:image":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg","og:image:secure_url":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg","article:published_time":"2017-06-17T09:48:24+00:00","article:modified_time":"2017-06-17T09:48:24+00:00","twitter:card":"summary","twitter:title":"Entrevista bomba de Joesley Batista detona Temer e sua turma | Arquivo","twitter:image":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg"},"aioseo_meta_data":{"post_id":"50180","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-20 20:32:00","updated":"2025-07-19 22:17:46","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":13128,"url":"https:\/\/www.jornalja.com.br\/arquivo\/maconha-terra-diz-que-uso-medicinal-e-desculpa\/","url_meta":{"origin":50180,"position":0},"title":"Maconha: Terra diz que uso medicinal \u00e9 desculpa","author":"Patr\u00edcia Marini","date":"4 de junho de 2014","format":false,"excerpt":"A condi\u00e7\u00e3o de pol\u00edtico, em \u00e9poca de campanha de campanha eleitoral, tira for\u00e7a do discurso do m\u00e9dico Osmar Terra contra a legaliza\u00e7\u00e3o da maconha. A tese dele de que a libera\u00e7\u00e3o vai ampliar exponencialmente o consumo \u00e9 discutivel, o consumo \u00e9 corrente. Mas seus alertas quanto aos riscos tem que\u2026","rel":"","context":"Em &quot;X.Categorias velhas&quot;","block_context":{"text":"X.Categorias velhas","link":"https:\/\/www.jornalja.com.br\/arquivo\/category\/x-categorias-velhas\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":13239,"url":"https:\/\/www.jornalja.com.br\/arquivo\/conselho-desdenha-do-plano-diretor\/","url_meta":{"origin":50180,"position":1},"title":"Porto Alegre: Conselho detona Plano Diretor","author":"Patr\u00edcia Marini","date":"25 de maio de 2014","format":false,"excerpt":"Den\u00fancia do arquiteto e \u00a0urbanista Ibir\u00e1 Santos Lucas. Ele diz que os conselheiros est\u00e3o votando com \"enorme irresponsabilidade\". \"Mudam regime com a maior naturalidade,,,regularizam absurdos de constru\u00e7\u00f5es irregulares... \"O CMDUA est\u00e1 flexibilizando a lei do plano diretor, de uma forma impactante na vida da cidade. Mudam regime com a maior\u2026","rel":"","context":"Em &quot;Geral&quot;","block_context":{"text":"Geral","link":"https:\/\/www.jornalja.com.br\/arquivo\/category\/geral\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":13101,"url":"https:\/\/www.jornalja.com.br\/arquivo\/morre-um-guerreiro-do-texto\/","url_meta":{"origin":50180,"position":2},"title":"Morre um guerreiro do texto","author":"Patr\u00edcia Marini","date":"14 de maio de 2014","format":false,"excerpt":"Por Ricardo Kotscho Reproduzido do blog do autor, 11\/5\/2014; t\u00edtulo original \u201cE l\u00e1 se foi o nosso Myltainho, guerreiro do texto\u201d. Mi\u00fado e franzino, meu amigo Myltainho era um valente e inconformado guerreiro na luta contra as injusti\u00e7as sociais, a hipocrisia, as maracutaias, o autoritarismo, a intoler\u00e2ncia, a viol\u00eancia, o\u2026","rel":"","context":"Em &quot;Geral&quot;","block_context":{"text":"Geral","link":"https:\/\/www.jornalja.com.br\/arquivo\/category\/geral\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":14241,"url":"https:\/\/www.jornalja.com.br\/arquivo\/o-guaiba-nas-imagens-poeticas-de-achutti\/","url_meta":{"origin":50180,"position":3},"title":"O Gua\u00edba nas imagens po\u00e9ticas de Achutti","author":"da Reda\u00e7\u00e3o","date":"18 de junho de 2014","format":false,"excerpt":"Em \u201cO Gua\u00edba por Achutti\u201d \u2013 obra financiada via Minist\u00e9rio da Cultura, produ\u00e7\u00e3o executiva de Pedro Longhi, e Fl\u00e1vio Wild como designer \u2013, o fot\u00f3grafo revela a beleza e as mazelas de um espa\u00e7o aqu\u00e1tico de \u00e1guas sempre renovadas, cheio de hist\u00f3rias e lendas como as das cidades que foram\u2026","rel":"","context":"Em &quot;Cultura-Geral&quot;","block_context":{"text":"Cultura-Geral","link":"https:\/\/www.jornalja.com.br\/arquivo\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":13124,"url":"https:\/\/www.jornalja.com.br\/arquivo\/sangue-latino-no-iecine\/","url_meta":{"origin":50180,"position":4},"title":"Sangue latino no IECINE","author":"da Reda\u00e7\u00e3o","date":"18 de maio de 2014","format":false,"excerpt":"Francisco Ribeiro O Instituto Estadual de Cinema (IECINE) tem a frente, desde abril \u00faltimo, um novo diretor, o cineasta colombiano Juan Zapata, 36, que substitui Luiz Alberto Cassol. Radicado h\u00e1 dez anos em Porto Alegre, Zapata tem diante de si o desafio de conduzir at\u00e9 o final do ano um\u2026","rel":"","context":"Em &quot;Cultura-Geral&quot;","block_context":{"text":"Cultura-Geral","link":"https:\/\/www.jornalja.com.br\/arquivo\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":13240,"url":"https:\/\/www.jornalja.com.br\/arquivo\/plano-diretor-estamos-construindo-o-caos\/","url_meta":{"origin":50180,"position":5},"title":"Plano diretor: &quot;Estamos construindo o caos&quot;","author":"Patr\u00edcia Marini","date":"26 de maio de 2014","format":false,"excerpt":"Desabafo que arquiteta Eliana Castilhos, delegada da Regi\u00e3o de Planejamento 1, postou nas redes sociais \u00e9 um testemunho do ambiente que se criou no Conselho do Plano Diretor de Porto Alegre, onde a aprova\u00e7\u00e3o de grandes empreendimentos \u00e9 empurrada guela abaixo dos conselheiros. Ao CMDUA Como delegada da Regi\u00e3o de\u2026","rel":"","context":"Em &quot;Geral&quot;","block_context":{"text":"Geral","link":"https:\/\/www.jornalja.com.br\/arquivo\/category\/geral\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbQjBd-d3m","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/50180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=50180"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/50180\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=50180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=50180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=50180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}