{"id":50871,"date":"2017-07-03T15:44:34","date_gmt":"2017-07-03T18:44:34","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=50871"},"modified":"2017-07-03T15:44:34","modified_gmt":"2017-07-03T18:44:34","slug":"fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/arquivo\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\/","title":{"rendered":"FEE vai \u00e0 Assembleia defender patrim\u00f4nio socioecon\u00f4mico do Estado"},"content":{"rendered":"<p>Passados seis meses da aprova\u00e7\u00e3o do projeto que autoriza a extin\u00e7\u00e3o de funda\u00e7\u00f5es estaduais, servidores da Funda\u00e7\u00e3o de Economia e Estat\u00edstica (FEE) ir\u00e3o ocupar na quinta-feira, 6 de julho, a Tribuna Popular da Assembleia Legislativa do Rio Grande do Sul para falar\u00a0sobre a relev\u00e2ncia da Institui\u00e7\u00e3o para o conhecimento e o planejamento do Estado. Os pronunciamentos ocorrem a partir das 14 horas.<br \/>\nA FEE \u00e9 o principal centro de pesquisas e estudos econ\u00f4micos do Estado. Ganhou uma extens\u00e3o em seu nome em homenagem a Siegfried Emanuel Heuser (1921-1986),\u00a0economista que, na defini\u00e7\u00e3o do ex-senador Pedro Simon, foi &#8220;pioneiro em buscar\u00a0solu\u00e7\u00f5es\u00a0econ\u00f4micas para o crescimento do RS em \u00e9pocas de crise\u201d.<br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Passados seis meses da aprova\u00e7\u00e3o do projeto que autoriza a extin\u00e7\u00e3o de funda\u00e7\u00f5es estaduais, servidores da Funda\u00e7\u00e3o de Economia e Estat\u00edstica (FEE) ir\u00e3o ocupar na quinta-feira, 6 de julho, a Tribuna Popular da Assembleia Legislativa do Rio Grande do Sul para falar\u00a0sobre a relev\u00e2ncia da Institui\u00e7\u00e3o para o conhecimento e o planejamento do Estado. Os [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":50874,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[26],"tags":[],"class_list":["post-50871","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"da Reda\u00e7\u00e3o\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.jornalja.com.br\/arquivo\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Arquivo | Jornal J\u00c1 | Porto Alegre\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"FEE vai \u00e0 Assembleia defender patrim\u00f4nio socioecon\u00f4mico do Estado | Arquivo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.jornalja.com.br\/arquivo\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-07-03T18:44:34+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-07-03T18:44:34+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"FEE vai \u00e0 Assembleia defender patrim\u00f4nio socioecon\u00f4mico do Estado | Arquivo\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\\\/#blogposting\",\"name\":\"FEE vai \\u00e0 Assembleia defender patrim\\u00f4nio socioecon\\u00f4mico do Estado | Arquivo\",\"headline\":\"FEE vai \\u00e0 Assembleia defender patrim\\u00f4nio socioecon\\u00f4mico do Estado\",\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/author\\\/daredacao\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":50874},\"datePublished\":\"2017-07-03T15:44:34-03:00\",\"dateModified\":\"2017-07-03T15:44:34-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\\\/#webpage\"},\"articleSection\":\"Geral\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/category\\\/geral\\\/#listItem\",\"name\":\"Geral\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/category\\\/geral\\\/#listItem\",\"position\":2,\"name\":\"Geral\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/category\\\/geral\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\\\/#listItem\",\"name\":\"FEE vai \\u00e0 Assembleia defender patrim\\u00f4nio socioecon\\u00f4mico do Estado\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\\\/#listItem\",\"position\":3,\"name\":\"FEE vai \\u00e0 Assembleia defender patrim\\u00f4nio socioecon\\u00f4mico do Estado\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/category\\\/geral\\\/#listItem\",\"name\":\"Geral\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/#organization\",\"name\":\"Jornal J\\u00c1\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/\",\"telephone\":\"+555133307272\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/wp-content\\\/uploads\\\/cards\\\/JAslogan.png\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/author\\\/daredacao\\\/#author\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/author\\\/daredacao\\\/\",\"name\":\"da Reda\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"da Reda\\u00e7\\u00e3o\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\\\/#webpage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\\\/\",\"name\":\"FEE vai \\u00e0 Assembleia defender patrim\\u00f4nio socioecon\\u00f4mico do Estado | Arquivo\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/author\\\/daredacao\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/author\\\/daredacao\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":50874,\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\\\/#mainImage\"},\"datePublished\":\"2017-07-03T15:44:34-03:00\",\"dateModified\":\"2017-07-03T15:44:34-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/#website\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/\",\"name\":\"Arquivo\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"FEE vai \u00e0 Assembleia defender patrim\u00f4nio socioecon\u00f4mico do Estado | Arquivo","description":"","canonical_url":"https:\/\/www.jornalja.com.br\/arquivo\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.jornalja.com.br\/arquivo\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\/#blogposting","name":"FEE vai \u00e0 Assembleia defender patrim\u00f4nio socioecon\u00f4mico do Estado | Arquivo","headline":"FEE vai \u00e0 Assembleia defender patrim\u00f4nio socioecon\u00f4mico do Estado","author":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/author\/daredacao\/#author"},"publisher":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/#organization"},"image":{"@type":"ImageObject","url":50874},"datePublished":"2017-07-03T15:44:34-03:00","dateModified":"2017-07-03T15:44:34-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\/#webpage"},"isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\/#webpage"},"articleSection":"Geral"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornalja.com.br\/arquivo\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo#listItem","position":1,"name":"Home","item":"https:\/\/www.jornalja.com.br\/arquivo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo\/category\/geral\/#listItem","name":"Geral"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo\/category\/geral\/#listItem","position":2,"name":"Geral","item":"https:\/\/www.jornalja.com.br\/arquivo\/category\/geral\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\/#listItem","name":"FEE vai \u00e0 Assembleia defender patrim\u00f4nio socioecon\u00f4mico do Estado"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\/#listItem","position":3,"name":"FEE vai \u00e0 Assembleia defender patrim\u00f4nio socioecon\u00f4mico do Estado","previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo\/category\/geral\/#listItem","name":"Geral"}}]},{"@type":"Organization","@id":"https:\/\/www.jornalja.com.br\/arquivo\/#organization","name":"Jornal J\u00c1","description":"Jornal J\u00c1 | Porto Alegre","url":"https:\/\/www.jornalja.com.br\/arquivo\/","telephone":"+555133307272","logo":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/cards\/JAslogan.png","@id":"https:\/\/www.jornalja.com.br\/arquivo\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\/#organizationLogo"},"image":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.jornalja.com.br\/arquivo\/author\/daredacao\/#author","url":"https:\/\/www.jornalja.com.br\/arquivo\/author\/daredacao\/","name":"da Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.jornalja.com.br\/arquivo\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g","width":96,"height":96,"caption":"da Reda\u00e7\u00e3o"}},{"@type":"WebPage","@id":"https:\/\/www.jornalja.com.br\/arquivo\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\/#webpage","url":"https:\/\/www.jornalja.com.br\/arquivo\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\/","name":"FEE vai \u00e0 Assembleia defender patrim\u00f4nio socioecon\u00f4mico do Estado | Arquivo","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/#website"},"breadcrumb":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\/#breadcrumblist"},"author":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/author\/daredacao\/#author"},"creator":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/author\/daredacao\/#author"},"image":{"@type":"ImageObject","url":50874,"@id":"https:\/\/www.jornalja.com.br\/arquivo\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\/#mainImage"},"datePublished":"2017-07-03T15:44:34-03:00","dateModified":"2017-07-03T15:44:34-03:00"},{"@type":"WebSite","@id":"https:\/\/www.jornalja.com.br\/arquivo\/#website","url":"https:\/\/www.jornalja.com.br\/arquivo\/","name":"Arquivo","description":"Jornal J\u00c1 | Porto Alegre","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Arquivo | Jornal J\u00c1 | Porto Alegre","og:type":"article","og:title":"FEE vai \u00e0 Assembleia defender patrim\u00f4nio socioecon\u00f4mico do Estado | Arquivo","og:url":"https:\/\/www.jornalja.com.br\/arquivo\/fee-vai-a-assembleia-defender-patrimonio-socioeconomico-do-estado\/","og:image":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg","og:image:secure_url":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg","article:published_time":"2017-07-03T18:44:34+00:00","article:modified_time":"2017-07-03T18:44:34+00:00","twitter:card":"summary","twitter:title":"FEE vai \u00e0 Assembleia defender patrim\u00f4nio socioecon\u00f4mico do Estado | Arquivo","twitter:image":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg"},"aioseo_meta_data":{"post_id":"50871","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-20 20:30:49","updated":"2025-07-19 22:46:56","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":13124,"url":"https:\/\/www.jornalja.com.br\/arquivo\/sangue-latino-no-iecine\/","url_meta":{"origin":50871,"position":0},"title":"Sangue latino no IECINE","author":"da Reda\u00e7\u00e3o","date":"18 de maio de 2014","format":false,"excerpt":"Francisco Ribeiro O Instituto Estadual de Cinema (IECINE) tem a frente, desde abril \u00faltimo, um novo diretor, o cineasta colombiano Juan Zapata, 36, que substitui Luiz Alberto Cassol. Radicado h\u00e1 dez anos em Porto Alegre, Zapata tem diante de si o desafio de conduzir at\u00e9 o final do ano um\u2026","rel":"","context":"Em &quot;Cultura-Geral&quot;","block_context":{"text":"Cultura-Geral","link":"https:\/\/www.jornalja.com.br\/arquivo\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5440,"url":"https:\/\/www.jornalja.com.br\/arquivo\/casarao-da-venancio-destino-permanece-incerto\/","url_meta":{"origin":50871,"position":1},"title":"Estado ainda n\u00e3o sabe o que fazer com casar\u00e3o abandonado h\u00e1 20 anos","author":"Elmar Bones","date":"6 de julho de 2009","format":false,"excerpt":"O casar\u00e3o amarelo, numa esquina nobre de Porto Alegre (Ven\u00e2ncio Aires com Jo\u00e3o Pessoa), j\u00e1 abrigou uma escola. H\u00e1 duas d\u00e9cadas, pelo menos, est\u00e1 abandonado, porque seu propriet\u00e1rio, o governo do Estado do Rio Grande do Sul, n\u00e3o consegue achar um destino para ele. Planos n\u00e3o faltaram. O governador Ol\u00edvio\u2026","rel":"","context":"Em &quot;X.Categorias velhas&quot;","block_context":{"text":"X.Categorias velhas","link":"https:\/\/www.jornalja.com.br\/arquivo\/category\/x-categorias-velhas\/"},"img":{"alt_text":"geraldo1","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/wp-content\/uploads\/2009\/07\/geraldo1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":12960,"url":"https:\/\/www.jornalja.com.br\/arquivo\/populacao-culpa-empresas-pela-greve-dos-rodoviarios\/","url_meta":{"origin":50871,"position":2},"title":"Popula\u00e7\u00e3o culpa empresas pela greve","author":"Patr\u00edcia Marini","date":"14 de fevereiro de 2014","format":false,"excerpt":"Pesquisa divulgada na edi\u00e7\u00e3o do jornal Metro desta sexta-feira,14, comprova o velho ditado: \u00e9 poss\u00edvel enganar muitos por algum tempo, mas n\u00e3o \u00e9 poss\u00edvel enganar a todos o tempo inteiro. A principal revela\u00e7\u00e3o foi que 59,8% dos entrevistados apontaram as empresas como as principais respons\u00e1veis pela grave e 46% culparam\u2026","rel":"","context":"Em &quot;X.Categorias velhas&quot;","block_context":{"text":"X.Categorias velhas","link":"https:\/\/www.jornalja.com.br\/arquivo\/category\/x-categorias-velhas\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbQjBd-dev","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/50871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=50871"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/50871\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=50871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=50871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=50871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}