{"id":52065,"date":"2017-07-25T10:09:04","date_gmt":"2017-07-25T13:09:04","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=52065"},"modified":"2017-07-25T10:09:04","modified_gmt":"2017-07-25T13:09:04","slug":"monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/arquivo\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\/","title":{"rendered":"Monitoramento de site russo leva pol\u00edcia federal \u00e0 rede de ped\u00f3filos"},"content":{"rendered":"<p>A Pol\u00edcia Federal cumpre nesta ter\u00e7a (25) mandados judiciais em 51 cidades \u00a0na segunda fase da Opera\u00e7\u00e3o Glasnost, que combate a explora\u00e7\u00e3o sexual de crian\u00e7as e compartilhamento de pornografia infantil na internet.<br \/>\nA opera\u00e7\u00e3o foi deflagrada em novembro de 2013, quando foram cumpridos 80 mandados judiciais, entre eles, 30 pris\u00f5es em flagrante por posse de pornografia infantil.<br \/>\nForam ainda identificados e presos diversos abusadores sexuais, bem como resgatadas v\u00edtimas, com idades entre 5 e 9 anos.<br \/>\nDe acordo com a PF, 350 policiais cumprem nesta ter\u00e7a-feira 72 mandados de busca e apreens\u00e3o, tr\u00eas de pris\u00e3o preventiva e dois de condu\u00e7\u00e3o coercitiva.<br \/>\nAs a\u00e7\u00f5es ocorrem em 51 munic\u00edpios do Paran\u00e1, Santa Catarina, Rio Grande do Sul, S\u00e3o Paulo, Rio de Janeiro, Minas Gerais, Goi\u00e1s, Cear\u00e1, Pernambuco, Bahia, Maranh\u00e3o, Piau\u00ed, Par\u00e1 e Sergipe.<br \/>\nA PF informa ainda que a investiga\u00e7\u00e3o teve como base o monitoramento de um site russo.<br \/>\nEle era usado como &#8220;ponto de encontro&#8221; de ped\u00f3filos de v\u00e1rios pa\u00edses. As investiga\u00e7\u00f5es identificaram centenas de usu\u00e1rios, brasileiros e estrangeiros, que compartilhavam pornografia infantil na internet, bem como diversos abusadores sexuais e produtores de pornografia infantil.<br \/>\n&#8220;Os investigados produziam e armazenavam fotos e v\u00eddeos de crian\u00e7as, adolescentes e at\u00e9 mesmo de beb\u00eas com poucos meses de vida, muitos deles sendo abusados sexualmente por adultos, e as enviavam para contatos no Brasil e no exterior&#8221;, diz a nota da PF.<br \/>\nO nome da opera\u00e7\u00e3o, Glasnost, faz refer\u00eancia ao termo russo que significa transpar\u00eancia. A palavra foi escolhida porque a maior parte dos investigados utilizava servidores russos para a divulga\u00e7\u00e3o de imagens de menores na internet e para contatos com outros ped\u00f3filos ao redor do mundo.<br \/>\n(Com informa\u00e7\u00f5es da Agencia Brasil)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Federal cumpre nesta ter\u00e7a (25) mandados judiciais em 51 cidades \u00a0na segunda fase da Opera\u00e7\u00e3o Glasnost, que combate a explora\u00e7\u00e3o sexual de crian\u00e7as e compartilhamento de pornografia infantil na internet. A opera\u00e7\u00e3o foi deflagrada em novembro de 2013, quando foram cumpridos 80 mandados judiciais, entre eles, 30 pris\u00f5es em flagrante por posse de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":52066,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[26],"tags":[],"class_list":["post-52065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"da Reda\u00e7\u00e3o\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.jornalja.com.br\/arquivo\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Arquivo | Jornal J\u00c1 | Porto Alegre\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Monitoramento de site russo leva pol\u00edcia federal \u00e0 rede de ped\u00f3filos | Arquivo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.jornalja.com.br\/arquivo\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-07-25T13:09:04+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-07-25T13:09:04+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Monitoramento de site russo leva pol\u00edcia federal \u00e0 rede de ped\u00f3filos | Arquivo\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\\\/#blogposting\",\"name\":\"Monitoramento de site russo leva pol\\u00edcia federal \\u00e0 rede de ped\\u00f3filos | Arquivo\",\"headline\":\"Monitoramento de site russo leva pol\\u00edcia federal \\u00e0 rede de ped\\u00f3filos\",\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/author\\\/daredacao\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":52066},\"datePublished\":\"2017-07-25T10:09:04-03:00\",\"dateModified\":\"2017-07-25T10:09:04-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\\\/#webpage\"},\"articleSection\":\"Geral\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/category\\\/geral\\\/#listItem\",\"name\":\"Geral\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/category\\\/geral\\\/#listItem\",\"position\":2,\"name\":\"Geral\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/category\\\/geral\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\\\/#listItem\",\"name\":\"Monitoramento de site russo leva pol\\u00edcia federal \\u00e0 rede de ped\\u00f3filos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\\\/#listItem\",\"position\":3,\"name\":\"Monitoramento de site russo leva pol\\u00edcia federal \\u00e0 rede de ped\\u00f3filos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/category\\\/geral\\\/#listItem\",\"name\":\"Geral\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/#organization\",\"name\":\"Jornal J\\u00c1\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/\",\"telephone\":\"+555133307272\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/wp-content\\\/uploads\\\/cards\\\/JAslogan.png\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/author\\\/daredacao\\\/#author\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/author\\\/daredacao\\\/\",\"name\":\"da Reda\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"da Reda\\u00e7\\u00e3o\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\\\/#webpage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\\\/\",\"name\":\"Monitoramento de site russo leva pol\\u00edcia federal \\u00e0 rede de ped\\u00f3filos | Arquivo\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/author\\\/daredacao\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/author\\\/daredacao\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":52066,\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\\\/#mainImage\"},\"datePublished\":\"2017-07-25T10:09:04-03:00\",\"dateModified\":\"2017-07-25T10:09:04-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/#website\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/\",\"name\":\"Arquivo\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Monitoramento de site russo leva pol\u00edcia federal \u00e0 rede de ped\u00f3filos | Arquivo","description":"","canonical_url":"https:\/\/www.jornalja.com.br\/arquivo\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.jornalja.com.br\/arquivo\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\/#blogposting","name":"Monitoramento de site russo leva pol\u00edcia federal \u00e0 rede de ped\u00f3filos | Arquivo","headline":"Monitoramento de site russo leva pol\u00edcia federal \u00e0 rede de ped\u00f3filos","author":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/author\/daredacao\/#author"},"publisher":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/#organization"},"image":{"@type":"ImageObject","url":52066},"datePublished":"2017-07-25T10:09:04-03:00","dateModified":"2017-07-25T10:09:04-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\/#webpage"},"isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\/#webpage"},"articleSection":"Geral"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornalja.com.br\/arquivo\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo#listItem","position":1,"name":"Home","item":"https:\/\/www.jornalja.com.br\/arquivo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo\/category\/geral\/#listItem","name":"Geral"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo\/category\/geral\/#listItem","position":2,"name":"Geral","item":"https:\/\/www.jornalja.com.br\/arquivo\/category\/geral\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\/#listItem","name":"Monitoramento de site russo leva pol\u00edcia federal \u00e0 rede de ped\u00f3filos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\/#listItem","position":3,"name":"Monitoramento de site russo leva pol\u00edcia federal \u00e0 rede de ped\u00f3filos","previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo\/category\/geral\/#listItem","name":"Geral"}}]},{"@type":"Organization","@id":"https:\/\/www.jornalja.com.br\/arquivo\/#organization","name":"Jornal J\u00c1","description":"Jornal J\u00c1 | Porto Alegre","url":"https:\/\/www.jornalja.com.br\/arquivo\/","telephone":"+555133307272","logo":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/cards\/JAslogan.png","@id":"https:\/\/www.jornalja.com.br\/arquivo\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\/#organizationLogo"},"image":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.jornalja.com.br\/arquivo\/author\/daredacao\/#author","url":"https:\/\/www.jornalja.com.br\/arquivo\/author\/daredacao\/","name":"da Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.jornalja.com.br\/arquivo\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g","width":96,"height":96,"caption":"da Reda\u00e7\u00e3o"}},{"@type":"WebPage","@id":"https:\/\/www.jornalja.com.br\/arquivo\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\/#webpage","url":"https:\/\/www.jornalja.com.br\/arquivo\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\/","name":"Monitoramento de site russo leva pol\u00edcia federal \u00e0 rede de ped\u00f3filos | Arquivo","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/#website"},"breadcrumb":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\/#breadcrumblist"},"author":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/author\/daredacao\/#author"},"creator":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/author\/daredacao\/#author"},"image":{"@type":"ImageObject","url":52066,"@id":"https:\/\/www.jornalja.com.br\/arquivo\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\/#mainImage"},"datePublished":"2017-07-25T10:09:04-03:00","dateModified":"2017-07-25T10:09:04-03:00"},{"@type":"WebSite","@id":"https:\/\/www.jornalja.com.br\/arquivo\/#website","url":"https:\/\/www.jornalja.com.br\/arquivo\/","name":"Arquivo","description":"Jornal J\u00c1 | Porto Alegre","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Arquivo | Jornal J\u00c1 | Porto Alegre","og:type":"article","og:title":"Monitoramento de site russo leva pol\u00edcia federal \u00e0 rede de ped\u00f3filos | Arquivo","og:url":"https:\/\/www.jornalja.com.br\/arquivo\/monitoramento-de-site-russo-leva-policia-federal-a-rede-de-pedofilos\/","og:image":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg","og:image:secure_url":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg","article:published_time":"2017-07-25T13:09:04+00:00","article:modified_time":"2017-07-25T13:09:04+00:00","twitter:card":"summary","twitter:title":"Monitoramento de site russo leva pol\u00edcia federal \u00e0 rede de ped\u00f3filos | Arquivo","twitter:image":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg"},"aioseo_meta_data":{"post_id":"52065","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-20 20:29:05","updated":"2025-07-19 23:34:08","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":5440,"url":"https:\/\/www.jornalja.com.br\/arquivo\/casarao-da-venancio-destino-permanece-incerto\/","url_meta":{"origin":52065,"position":0},"title":"Estado ainda n\u00e3o sabe o que fazer com casar\u00e3o abandonado h\u00e1 20 anos","author":"Elmar Bones","date":"6 de julho de 2009","format":false,"excerpt":"O casar\u00e3o amarelo, numa esquina nobre de Porto Alegre (Ven\u00e2ncio Aires com Jo\u00e3o Pessoa), j\u00e1 abrigou uma escola. H\u00e1 duas d\u00e9cadas, pelo menos, est\u00e1 abandonado, porque seu propriet\u00e1rio, o governo do Estado do Rio Grande do Sul, n\u00e3o consegue achar um destino para ele. Planos n\u00e3o faltaram. O governador Ol\u00edvio\u2026","rel":"","context":"Em &quot;X.Categorias velhas&quot;","block_context":{"text":"X.Categorias velhas","link":"https:\/\/www.jornalja.com.br\/arquivo\/category\/x-categorias-velhas\/"},"img":{"alt_text":"geraldo1","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/wp-content\/uploads\/2009\/07\/geraldo1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":14241,"url":"https:\/\/www.jornalja.com.br\/arquivo\/o-guaiba-nas-imagens-poeticas-de-achutti\/","url_meta":{"origin":52065,"position":1},"title":"O Gua\u00edba nas imagens po\u00e9ticas de Achutti","author":"da Reda\u00e7\u00e3o","date":"18 de junho de 2014","format":false,"excerpt":"Em \u201cO Gua\u00edba por Achutti\u201d \u2013 obra financiada via Minist\u00e9rio da Cultura, produ\u00e7\u00e3o executiva de Pedro Longhi, e Fl\u00e1vio Wild como designer \u2013, o fot\u00f3grafo revela a beleza e as mazelas de um espa\u00e7o aqu\u00e1tico de \u00e1guas sempre renovadas, cheio de hist\u00f3rias e lendas como as das cidades que foram\u2026","rel":"","context":"Em &quot;Cultura-Geral&quot;","block_context":{"text":"Cultura-Geral","link":"https:\/\/www.jornalja.com.br\/arquivo\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":13101,"url":"https:\/\/www.jornalja.com.br\/arquivo\/morre-um-guerreiro-do-texto\/","url_meta":{"origin":52065,"position":2},"title":"Morre um guerreiro do texto","author":"Patr\u00edcia Marini","date":"14 de maio de 2014","format":false,"excerpt":"Por Ricardo Kotscho Reproduzido do blog do autor, 11\/5\/2014; t\u00edtulo original \u201cE l\u00e1 se foi o nosso Myltainho, guerreiro do texto\u201d. Mi\u00fado e franzino, meu amigo Myltainho era um valente e inconformado guerreiro na luta contra as injusti\u00e7as sociais, a hipocrisia, as maracutaias, o autoritarismo, a intoler\u00e2ncia, a viol\u00eancia, o\u2026","rel":"","context":"Em &quot;Geral&quot;","block_context":{"text":"Geral","link":"https:\/\/www.jornalja.com.br\/arquivo\/category\/geral\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":13128,"url":"https:\/\/www.jornalja.com.br\/arquivo\/maconha-terra-diz-que-uso-medicinal-e-desculpa\/","url_meta":{"origin":52065,"position":3},"title":"Maconha: Terra diz que uso medicinal \u00e9 desculpa","author":"Patr\u00edcia Marini","date":"4 de junho de 2014","format":false,"excerpt":"A condi\u00e7\u00e3o de pol\u00edtico, em \u00e9poca de campanha de campanha eleitoral, tira for\u00e7a do discurso do m\u00e9dico Osmar Terra contra a legaliza\u00e7\u00e3o da maconha. A tese dele de que a libera\u00e7\u00e3o vai ampliar exponencialmente o consumo \u00e9 discutivel, o consumo \u00e9 corrente. Mas seus alertas quanto aos riscos tem que\u2026","rel":"","context":"Em &quot;X.Categorias velhas&quot;","block_context":{"text":"X.Categorias velhas","link":"https:\/\/www.jornalja.com.br\/arquivo\/category\/x-categorias-velhas\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":13109,"url":"https:\/\/www.jornalja.com.br\/arquivo\/judiciario-reconhece-poluicao-eletromagnetica\/","url_meta":{"origin":52065,"position":4},"title":"Judici\u00e1rio reconhece polui\u00e7\u00e3o eletromagn\u00e9tica","author":"Patr\u00edcia Marini","date":"16 de maio de 2014","format":false,"excerpt":"A\u00e7\u00e3o de duas associa\u00e7\u00f5es de moradores foi acolhida pelo Tribunal de Justi\u00e7a de S\u00e3o Paulo que. em decis\u00e3o in\u00e9dita, determinou a redu\u00e7\u00e3o do campo eletromagn\u00e9tico gerado pelas linhas de transmiss\u00e3o de energia que cortam os bairros City Boa\u00e7ava e Alto de Pinheiros. \u00c9 a primeira vez que um tribunal do\u2026","rel":"","context":"Em &quot;X.Categorias velhas&quot;","block_context":{"text":"X.Categorias velhas","link":"https:\/\/www.jornalja.com.br\/arquivo\/category\/x-categorias-velhas\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1280,"url":"https:\/\/www.jornalja.com.br\/arquivo\/o-menino-que-se-tornou-brizola\/","url_meta":{"origin":52065,"position":5},"title":"O Menino que se Tornou Brizola","author":"da Reda\u00e7\u00e3o","date":"28 de julho de 2008","format":false,"excerpt":"Autor: Cleber Dioni A vida de Leonel Brizola, com \u00eanfase para os primeiros anos em Porto Alegre, at\u00e9 o ex\u00edlio no Uruguai e a volta, quinze anos depois. \u00a0\"...\u00c9ramos todos jovens e nos identific\u00e1vamos com aquela massa an\u00f4nima a percorrer as ruas de Porto Alegre, gritando 'Get\u00falio', 'Get\u00falio' e empunhando\u2026","rel":"","context":"Em &quot;Livros&quot;","block_context":{"text":"Livros","link":"https:\/\/www.jornalja.com.br\/arquivo\/category\/livros\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/wp-content\/uploads\/2008\/07\/brizola.gif?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbQjBd-dxL","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/52065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=52065"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/52065\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=52065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=52065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=52065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}