{"id":52791,"date":"2017-08-04T12:44:44","date_gmt":"2017-08-04T15:44:44","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=52791"},"modified":"2017-08-04T12:44:44","modified_gmt":"2017-08-04T15:44:44","slug":"ipe-saude-alerta-para-boletos-emitidos-erroneamente","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/arquivo\/ipe-saude-alerta-para-boletos-emitidos-erroneamente\/","title":{"rendered":"IPE-Sa\u00fade alerta para boletos emitidos erroneamente"},"content":{"rendered":"<p>Uma falha no sistema de processamento da Procergs gerou diferentes erros na emiss\u00e3o de boletos de um grupo de alguns benefici\u00e1rios do IPE-Sa\u00fade.<br \/>\nNo in\u00edcio deste m\u00eas foram emitidos, erroneamente, boletos com vencimento para o dia 10 de setembro, para optantes do IPE-Sa\u00fade, com o envio duplo de documentos semelhantes,\u00a0que devem ser desconsiderados. A data de processamento foi em 01\/08\/2017 e 02\/08\/2017, conforme consta nos documentos.<br \/>\nA orienta\u00e7\u00e3o do IPE \u00e9 que os benefici\u00e1rios n\u00e3o paguem estes docs com vencimento do dia 10 de setembro. Para o pagamento correto, ser\u00e1 feito um novo envio com data de vencimento para 15 de setembro.Os docs ser\u00e3o considerados inv\u00e1lidos para quem, eventualmente, tentar efetuar o pagamento na rede Banrisul.<br \/>\nPara os casos j\u00e1 pagos, a solu\u00e7\u00e3o ser\u00e1 resolvida internamente, da melhor forma poss\u00edvel, sem \u00f4nus para o benefici\u00e1rio.<br \/>\nNo m\u00eas de julho tamb\u00e9m houve um erro na data de vencimento alterada. O correto seria 10 de agosto e os docs foram enviados com o vencimento dia 31 de agosto. O IPE refor\u00e7a que estes boletos com vencimento para 31 de agosto s\u00e3o v\u00e1lidos, portanto o pagamento pode ser efetuado sem problemas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma falha no sistema de processamento da Procergs gerou diferentes erros na emiss\u00e3o de boletos de um grupo de alguns benefici\u00e1rios do IPE-Sa\u00fade. No in\u00edcio deste m\u00eas foram emitidos, erroneamente, boletos com vencimento para o dia 10 de setembro, para optantes do IPE-Sa\u00fade, com o envio duplo de documentos semelhantes,\u00a0que devem ser desconsiderados. A data [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2022],"tags":[],"class_list":["post-52791","post","type-post","status-publish","format-standard","hentry","category-notas"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"da Reda\u00e7\u00e3o\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.jornalja.com.br\/arquivo\/ipe-saude-alerta-para-boletos-emitidos-erroneamente\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Arquivo | Jornal J\u00c1 | Porto Alegre\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"IPE-Sa\u00fade alerta para boletos emitidos erroneamente | Arquivo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.jornalja.com.br\/arquivo\/ipe-saude-alerta-para-boletos-emitidos-erroneamente\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-08-04T15:44:44+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-08-04T15:44:44+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"IPE-Sa\u00fade alerta para boletos emitidos erroneamente | Arquivo\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/ipe-saude-alerta-para-boletos-emitidos-erroneamente\\\/#blogposting\",\"name\":\"IPE-Sa\\u00fade alerta para boletos emitidos erroneamente | Arquivo\",\"headline\":\"IPE-Sa\\u00fade alerta para boletos emitidos erroneamente\",\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/author\\\/daredacao\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/wp-content\\\/uploads\\\/cards\\\/JAslogan.png\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/#articleImage\"},\"datePublished\":\"2017-08-04T12:44:44-03:00\",\"dateModified\":\"2017-08-04T12:44:44-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/ipe-saude-alerta-para-boletos-emitidos-erroneamente\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/ipe-saude-alerta-para-boletos-emitidos-erroneamente\\\/#webpage\"},\"articleSection\":\"NOTAS\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/ipe-saude-alerta-para-boletos-emitidos-erroneamente\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/category\\\/notas\\\/#listItem\",\"name\":\"NOTAS\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/category\\\/notas\\\/#listItem\",\"position\":2,\"name\":\"NOTAS\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/category\\\/notas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/ipe-saude-alerta-para-boletos-emitidos-erroneamente\\\/#listItem\",\"name\":\"IPE-Sa\\u00fade alerta para boletos emitidos erroneamente\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/ipe-saude-alerta-para-boletos-emitidos-erroneamente\\\/#listItem\",\"position\":3,\"name\":\"IPE-Sa\\u00fade alerta para boletos emitidos erroneamente\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/category\\\/notas\\\/#listItem\",\"name\":\"NOTAS\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/#organization\",\"name\":\"Jornal J\\u00c1\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/\",\"telephone\":\"+555133307272\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/wp-content\\\/uploads\\\/cards\\\/JAslogan.png\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/ipe-saude-alerta-para-boletos-emitidos-erroneamente\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/ipe-saude-alerta-para-boletos-emitidos-erroneamente\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/author\\\/daredacao\\\/#author\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/author\\\/daredacao\\\/\",\"name\":\"da Reda\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/ipe-saude-alerta-para-boletos-emitidos-erroneamente\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"da Reda\\u00e7\\u00e3o\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/ipe-saude-alerta-para-boletos-emitidos-erroneamente\\\/#webpage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/ipe-saude-alerta-para-boletos-emitidos-erroneamente\\\/\",\"name\":\"IPE-Sa\\u00fade alerta para boletos emitidos erroneamente | Arquivo\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/ipe-saude-alerta-para-boletos-emitidos-erroneamente\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/author\\\/daredacao\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/author\\\/daredacao\\\/#author\"},\"datePublished\":\"2017-08-04T12:44:44-03:00\",\"dateModified\":\"2017-08-04T12:44:44-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/#website\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/\",\"name\":\"Arquivo\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"IPE-Sa\u00fade alerta para boletos emitidos erroneamente | Arquivo","description":"","canonical_url":"https:\/\/www.jornalja.com.br\/arquivo\/ipe-saude-alerta-para-boletos-emitidos-erroneamente\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.jornalja.com.br\/arquivo\/ipe-saude-alerta-para-boletos-emitidos-erroneamente\/#blogposting","name":"IPE-Sa\u00fade alerta para boletos emitidos erroneamente | Arquivo","headline":"IPE-Sa\u00fade alerta para boletos emitidos erroneamente","author":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/author\/daredacao\/#author"},"publisher":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/cards\/JAslogan.png","@id":"https:\/\/www.jornalja.com.br\/arquivo\/#articleImage"},"datePublished":"2017-08-04T12:44:44-03:00","dateModified":"2017-08-04T12:44:44-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/ipe-saude-alerta-para-boletos-emitidos-erroneamente\/#webpage"},"isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/ipe-saude-alerta-para-boletos-emitidos-erroneamente\/#webpage"},"articleSection":"NOTAS"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornalja.com.br\/arquivo\/ipe-saude-alerta-para-boletos-emitidos-erroneamente\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo#listItem","position":1,"name":"Home","item":"https:\/\/www.jornalja.com.br\/arquivo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo\/category\/notas\/#listItem","name":"NOTAS"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo\/category\/notas\/#listItem","position":2,"name":"NOTAS","item":"https:\/\/www.jornalja.com.br\/arquivo\/category\/notas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo\/ipe-saude-alerta-para-boletos-emitidos-erroneamente\/#listItem","name":"IPE-Sa\u00fade alerta para boletos emitidos erroneamente"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo\/ipe-saude-alerta-para-boletos-emitidos-erroneamente\/#listItem","position":3,"name":"IPE-Sa\u00fade alerta para boletos emitidos erroneamente","previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo\/category\/notas\/#listItem","name":"NOTAS"}}]},{"@type":"Organization","@id":"https:\/\/www.jornalja.com.br\/arquivo\/#organization","name":"Jornal J\u00c1","description":"Jornal J\u00c1 | Porto Alegre","url":"https:\/\/www.jornalja.com.br\/arquivo\/","telephone":"+555133307272","logo":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/cards\/JAslogan.png","@id":"https:\/\/www.jornalja.com.br\/arquivo\/ipe-saude-alerta-para-boletos-emitidos-erroneamente\/#organizationLogo"},"image":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/ipe-saude-alerta-para-boletos-emitidos-erroneamente\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.jornalja.com.br\/arquivo\/author\/daredacao\/#author","url":"https:\/\/www.jornalja.com.br\/arquivo\/author\/daredacao\/","name":"da Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.jornalja.com.br\/arquivo\/ipe-saude-alerta-para-boletos-emitidos-erroneamente\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g","width":96,"height":96,"caption":"da Reda\u00e7\u00e3o"}},{"@type":"WebPage","@id":"https:\/\/www.jornalja.com.br\/arquivo\/ipe-saude-alerta-para-boletos-emitidos-erroneamente\/#webpage","url":"https:\/\/www.jornalja.com.br\/arquivo\/ipe-saude-alerta-para-boletos-emitidos-erroneamente\/","name":"IPE-Sa\u00fade alerta para boletos emitidos erroneamente | Arquivo","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/#website"},"breadcrumb":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/ipe-saude-alerta-para-boletos-emitidos-erroneamente\/#breadcrumblist"},"author":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/author\/daredacao\/#author"},"creator":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/author\/daredacao\/#author"},"datePublished":"2017-08-04T12:44:44-03:00","dateModified":"2017-08-04T12:44:44-03:00"},{"@type":"WebSite","@id":"https:\/\/www.jornalja.com.br\/arquivo\/#website","url":"https:\/\/www.jornalja.com.br\/arquivo\/","name":"Arquivo","description":"Jornal J\u00c1 | Porto Alegre","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Arquivo | Jornal J\u00c1 | Porto Alegre","og:type":"article","og:title":"IPE-Sa\u00fade alerta para boletos emitidos erroneamente | Arquivo","og:url":"https:\/\/www.jornalja.com.br\/arquivo\/ipe-saude-alerta-para-boletos-emitidos-erroneamente\/","og:image":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg","og:image:secure_url":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg","article:published_time":"2017-08-04T15:44:44+00:00","article:modified_time":"2017-08-04T15:44:44+00:00","twitter:card":"summary","twitter:title":"IPE-Sa\u00fade alerta para boletos emitidos erroneamente | Arquivo","twitter:image":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg"},"aioseo_meta_data":{"post_id":"52791","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-20 20:28:19","updated":"2025-07-20 00:03:47","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":13109,"url":"https:\/\/www.jornalja.com.br\/arquivo\/judiciario-reconhece-poluicao-eletromagnetica\/","url_meta":{"origin":52791,"position":0},"title":"Judici\u00e1rio reconhece polui\u00e7\u00e3o eletromagn\u00e9tica","author":"Patr\u00edcia Marini","date":"16 de maio de 2014","format":false,"excerpt":"A\u00e7\u00e3o de duas associa\u00e7\u00f5es de moradores foi acolhida pelo Tribunal de Justi\u00e7a de S\u00e3o Paulo que. em decis\u00e3o in\u00e9dita, determinou a redu\u00e7\u00e3o do campo eletromagn\u00e9tico gerado pelas linhas de transmiss\u00e3o de energia que cortam os bairros City Boa\u00e7ava e Alto de Pinheiros. \u00c9 a primeira vez que um tribunal do\u2026","rel":"","context":"Em &quot;X.Categorias velhas&quot;","block_context":{"text":"X.Categorias velhas","link":"https:\/\/www.jornalja.com.br\/arquivo\/category\/x-categorias-velhas\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":13240,"url":"https:\/\/www.jornalja.com.br\/arquivo\/plano-diretor-estamos-construindo-o-caos\/","url_meta":{"origin":52791,"position":1},"title":"Plano diretor: &quot;Estamos construindo o caos&quot;","author":"Patr\u00edcia Marini","date":"26 de maio de 2014","format":false,"excerpt":"Desabafo que arquiteta Eliana Castilhos, delegada da Regi\u00e3o de Planejamento 1, postou nas redes sociais \u00e9 um testemunho do ambiente que se criou no Conselho do Plano Diretor de Porto Alegre, onde a aprova\u00e7\u00e3o de grandes empreendimentos \u00e9 empurrada guela abaixo dos conselheiros. Ao CMDUA Como delegada da Regi\u00e3o de\u2026","rel":"","context":"Em &quot;Geral&quot;","block_context":{"text":"Geral","link":"https:\/\/www.jornalja.com.br\/arquivo\/category\/geral\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":13239,"url":"https:\/\/www.jornalja.com.br\/arquivo\/conselho-desdenha-do-plano-diretor\/","url_meta":{"origin":52791,"position":2},"title":"Porto Alegre: Conselho detona Plano Diretor","author":"Patr\u00edcia Marini","date":"25 de maio de 2014","format":false,"excerpt":"Den\u00fancia do arquiteto e \u00a0urbanista Ibir\u00e1 Santos Lucas. Ele diz que os conselheiros est\u00e3o votando com \"enorme irresponsabilidade\". \"Mudam regime com a maior naturalidade,,,regularizam absurdos de constru\u00e7\u00f5es irregulares... \"O CMDUA est\u00e1 flexibilizando a lei do plano diretor, de uma forma impactante na vida da cidade. Mudam regime com a maior\u2026","rel":"","context":"Em &quot;Geral&quot;","block_context":{"text":"Geral","link":"https:\/\/www.jornalja.com.br\/arquivo\/category\/geral\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":13128,"url":"https:\/\/www.jornalja.com.br\/arquivo\/maconha-terra-diz-que-uso-medicinal-e-desculpa\/","url_meta":{"origin":52791,"position":3},"title":"Maconha: Terra diz que uso medicinal \u00e9 desculpa","author":"Patr\u00edcia Marini","date":"4 de junho de 2014","format":false,"excerpt":"A condi\u00e7\u00e3o de pol\u00edtico, em \u00e9poca de campanha de campanha eleitoral, tira for\u00e7a do discurso do m\u00e9dico Osmar Terra contra a legaliza\u00e7\u00e3o da maconha. A tese dele de que a libera\u00e7\u00e3o vai ampliar exponencialmente o consumo \u00e9 discutivel, o consumo \u00e9 corrente. Mas seus alertas quanto aos riscos tem que\u2026","rel":"","context":"Em &quot;X.Categorias velhas&quot;","block_context":{"text":"X.Categorias velhas","link":"https:\/\/www.jornalja.com.br\/arquivo\/category\/x-categorias-velhas\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":13124,"url":"https:\/\/www.jornalja.com.br\/arquivo\/sangue-latino-no-iecine\/","url_meta":{"origin":52791,"position":4},"title":"Sangue latino no IECINE","author":"da Reda\u00e7\u00e3o","date":"18 de maio de 2014","format":false,"excerpt":"Francisco Ribeiro O Instituto Estadual de Cinema (IECINE) tem a frente, desde abril \u00faltimo, um novo diretor, o cineasta colombiano Juan Zapata, 36, que substitui Luiz Alberto Cassol. Radicado h\u00e1 dez anos em Porto Alegre, Zapata tem diante de si o desafio de conduzir at\u00e9 o final do ano um\u2026","rel":"","context":"Em &quot;Cultura-Geral&quot;","block_context":{"text":"Cultura-Geral","link":"https:\/\/www.jornalja.com.br\/arquivo\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":13101,"url":"https:\/\/www.jornalja.com.br\/arquivo\/morre-um-guerreiro-do-texto\/","url_meta":{"origin":52791,"position":5},"title":"Morre um guerreiro do texto","author":"Patr\u00edcia Marini","date":"14 de maio de 2014","format":false,"excerpt":"Por Ricardo Kotscho Reproduzido do blog do autor, 11\/5\/2014; t\u00edtulo original \u201cE l\u00e1 se foi o nosso Myltainho, guerreiro do texto\u201d. Mi\u00fado e franzino, meu amigo Myltainho era um valente e inconformado guerreiro na luta contra as injusti\u00e7as sociais, a hipocrisia, as maracutaias, o autoritarismo, a intoler\u00e2ncia, a viol\u00eancia, o\u2026","rel":"","context":"Em &quot;Geral&quot;","block_context":{"text":"Geral","link":"https:\/\/www.jornalja.com.br\/arquivo\/category\/geral\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbQjBd-dJt","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/52791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=52791"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/52791\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=52791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=52791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=52791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}