{"id":54654,"date":"2017-09-03T14:58:40","date_gmt":"2017-09-03T17:58:40","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=54654"},"modified":"2017-09-03T14:58:40","modified_gmt":"2017-09-03T17:58:40","slug":"empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/arquivo\/empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs\/","title":{"rendered":"Empoderamento de minorias \u00e9 tema de aula inaugural no Instituto de F\u00edsica da UFRGS"},"content":{"rendered":"<p>O Instituto de F\u00edsica promove no dia 5 de setembro, \u00e0s 16h, no anfiteatro do Instituto de Geoci\u00eancias, uma aula inaugural com o tema &#8220;Empoderamento de minorias e inclus\u00e3o na sociedade e no mercado de trabalho&#8221;.<br \/>\nA palestrante \u00e9 Tania Consentino, presidente da Schneider Electric para Am\u00e9rica Latina. Aberta \u00e0 comunidade em geral.<br \/>\nAnfiteatro do Instituto de Geoci\u00eancias fica no pr\u00e9dio 43128, na avenida Bento Gon\u00e7alves, 9.500 &#8211; Campus do Vale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Instituto de F\u00edsica promove no dia 5 de setembro, \u00e0s 16h, no anfiteatro do Instituto de Geoci\u00eancias, uma aula inaugural com o tema &#8220;Empoderamento de minorias e inclus\u00e3o na sociedade e no mercado de trabalho&#8221;. A palestrante \u00e9 Tania Consentino, presidente da Schneider Electric para Am\u00e9rica Latina. Aberta \u00e0 comunidade em geral. Anfiteatro do [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2022],"tags":[],"class_list":["post-54654","post","type-post","status-publish","format-standard","hentry","category-notas"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"da Reda\u00e7\u00e3o\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.jornalja.com.br\/arquivo\/empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Arquivo | Jornal J\u00c1 | Porto Alegre\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Empoderamento de minorias \u00e9 tema de aula inaugural no Instituto de F\u00edsica da UFRGS | Arquivo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.jornalja.com.br\/arquivo\/empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-09-03T17:58:40+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-09-03T17:58:40+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Empoderamento de minorias \u00e9 tema de aula inaugural no Instituto de F\u00edsica da UFRGS | Arquivo\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs\\\/#blogposting\",\"name\":\"Empoderamento de minorias \\u00e9 tema de aula inaugural no Instituto de F\\u00edsica da UFRGS | Arquivo\",\"headline\":\"Empoderamento de minorias \\u00e9 tema de aula inaugural no Instituto de F\\u00edsica da UFRGS\",\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/author\\\/daredacao\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/wp-content\\\/uploads\\\/cards\\\/JAslogan.png\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/#articleImage\"},\"datePublished\":\"2017-09-03T14:58:40-03:00\",\"dateModified\":\"2017-09-03T14:58:40-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs\\\/#webpage\"},\"articleSection\":\"NOTAS\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/category\\\/notas\\\/#listItem\",\"name\":\"NOTAS\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/category\\\/notas\\\/#listItem\",\"position\":2,\"name\":\"NOTAS\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/category\\\/notas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs\\\/#listItem\",\"name\":\"Empoderamento de minorias \\u00e9 tema de aula inaugural no Instituto de F\\u00edsica da UFRGS\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs\\\/#listItem\",\"position\":3,\"name\":\"Empoderamento de minorias \\u00e9 tema de aula inaugural no Instituto de F\\u00edsica da UFRGS\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/category\\\/notas\\\/#listItem\",\"name\":\"NOTAS\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/#organization\",\"name\":\"Jornal J\\u00c1\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/\",\"telephone\":\"+555133307272\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/wp-content\\\/uploads\\\/cards\\\/JAslogan.png\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/author\\\/daredacao\\\/#author\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/author\\\/daredacao\\\/\",\"name\":\"da Reda\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"da Reda\\u00e7\\u00e3o\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs\\\/#webpage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs\\\/\",\"name\":\"Empoderamento de minorias \\u00e9 tema de aula inaugural no Instituto de F\\u00edsica da UFRGS | Arquivo\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/author\\\/daredacao\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/author\\\/daredacao\\\/#author\"},\"datePublished\":\"2017-09-03T14:58:40-03:00\",\"dateModified\":\"2017-09-03T14:58:40-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/#website\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/\",\"name\":\"Arquivo\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/arquivo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Empoderamento de minorias \u00e9 tema de aula inaugural no Instituto de F\u00edsica da UFRGS | Arquivo","description":"","canonical_url":"https:\/\/www.jornalja.com.br\/arquivo\/empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.jornalja.com.br\/arquivo\/empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs\/#blogposting","name":"Empoderamento de minorias \u00e9 tema de aula inaugural no Instituto de F\u00edsica da UFRGS | Arquivo","headline":"Empoderamento de minorias \u00e9 tema de aula inaugural no Instituto de F\u00edsica da UFRGS","author":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/author\/daredacao\/#author"},"publisher":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/cards\/JAslogan.png","@id":"https:\/\/www.jornalja.com.br\/arquivo\/#articleImage"},"datePublished":"2017-09-03T14:58:40-03:00","dateModified":"2017-09-03T14:58:40-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs\/#webpage"},"isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs\/#webpage"},"articleSection":"NOTAS"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornalja.com.br\/arquivo\/empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo#listItem","position":1,"name":"Home","item":"https:\/\/www.jornalja.com.br\/arquivo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo\/category\/notas\/#listItem","name":"NOTAS"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo\/category\/notas\/#listItem","position":2,"name":"NOTAS","item":"https:\/\/www.jornalja.com.br\/arquivo\/category\/notas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo\/empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs\/#listItem","name":"Empoderamento de minorias \u00e9 tema de aula inaugural no Instituto de F\u00edsica da UFRGS"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo\/empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs\/#listItem","position":3,"name":"Empoderamento de minorias \u00e9 tema de aula inaugural no Instituto de F\u00edsica da UFRGS","previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/arquivo\/category\/notas\/#listItem","name":"NOTAS"}}]},{"@type":"Organization","@id":"https:\/\/www.jornalja.com.br\/arquivo\/#organization","name":"Jornal J\u00c1","description":"Jornal J\u00c1 | Porto Alegre","url":"https:\/\/www.jornalja.com.br\/arquivo\/","telephone":"+555133307272","logo":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/cards\/JAslogan.png","@id":"https:\/\/www.jornalja.com.br\/arquivo\/empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs\/#organizationLogo"},"image":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.jornalja.com.br\/arquivo\/author\/daredacao\/#author","url":"https:\/\/www.jornalja.com.br\/arquivo\/author\/daredacao\/","name":"da Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.jornalja.com.br\/arquivo\/empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g","width":96,"height":96,"caption":"da Reda\u00e7\u00e3o"}},{"@type":"WebPage","@id":"https:\/\/www.jornalja.com.br\/arquivo\/empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs\/#webpage","url":"https:\/\/www.jornalja.com.br\/arquivo\/empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs\/","name":"Empoderamento de minorias \u00e9 tema de aula inaugural no Instituto de F\u00edsica da UFRGS | Arquivo","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/#website"},"breadcrumb":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs\/#breadcrumblist"},"author":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/author\/daredacao\/#author"},"creator":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/author\/daredacao\/#author"},"datePublished":"2017-09-03T14:58:40-03:00","dateModified":"2017-09-03T14:58:40-03:00"},{"@type":"WebSite","@id":"https:\/\/www.jornalja.com.br\/arquivo\/#website","url":"https:\/\/www.jornalja.com.br\/arquivo\/","name":"Arquivo","description":"Jornal J\u00c1 | Porto Alegre","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.jornalja.com.br\/arquivo\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Arquivo | Jornal J\u00c1 | Porto Alegre","og:type":"article","og:title":"Empoderamento de minorias \u00e9 tema de aula inaugural no Instituto de F\u00edsica da UFRGS | Arquivo","og:url":"https:\/\/www.jornalja.com.br\/arquivo\/empoderamento-de-minorias-e-tema-de-aula-inaugural-no-instituto-de-fisica-da-ufrgs\/","og:image":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg","og:image:secure_url":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg","article:published_time":"2017-09-03T17:58:40+00:00","article:modified_time":"2017-09-03T17:58:40+00:00","twitter:card":"summary","twitter:title":"Empoderamento de minorias \u00e9 tema de aula inaugural no Instituto de F\u00edsica da UFRGS | Arquivo","twitter:image":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg"},"aioseo_meta_data":{"post_id":"54654","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-20 20:25:01","updated":"2025-07-20 00:52:24","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":12960,"url":"https:\/\/www.jornalja.com.br\/arquivo\/populacao-culpa-empresas-pela-greve-dos-rodoviarios\/","url_meta":{"origin":54654,"position":0},"title":"Popula\u00e7\u00e3o culpa empresas pela greve","author":"Patr\u00edcia Marini","date":"14 de fevereiro de 2014","format":false,"excerpt":"Pesquisa divulgada na edi\u00e7\u00e3o do jornal Metro desta sexta-feira,14, comprova o velho ditado: \u00e9 poss\u00edvel enganar muitos por algum tempo, mas n\u00e3o \u00e9 poss\u00edvel enganar a todos o tempo inteiro. A principal revela\u00e7\u00e3o foi que 59,8% dos entrevistados apontaram as empresas como as principais respons\u00e1veis pela grave e 46% culparam\u2026","rel":"","context":"Em &quot;X.Categorias velhas&quot;","block_context":{"text":"X.Categorias velhas","link":"https:\/\/www.jornalja.com.br\/arquivo\/category\/x-categorias-velhas\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":13124,"url":"https:\/\/www.jornalja.com.br\/arquivo\/sangue-latino-no-iecine\/","url_meta":{"origin":54654,"position":1},"title":"Sangue latino no IECINE","author":"da Reda\u00e7\u00e3o","date":"18 de maio de 2014","format":false,"excerpt":"Francisco Ribeiro O Instituto Estadual de Cinema (IECINE) tem a frente, desde abril \u00faltimo, um novo diretor, o cineasta colombiano Juan Zapata, 36, que substitui Luiz Alberto Cassol. Radicado h\u00e1 dez anos em Porto Alegre, Zapata tem diante de si o desafio de conduzir at\u00e9 o final do ano um\u2026","rel":"","context":"Em &quot;Cultura-Geral&quot;","block_context":{"text":"Cultura-Geral","link":"https:\/\/www.jornalja.com.br\/arquivo\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":13109,"url":"https:\/\/www.jornalja.com.br\/arquivo\/judiciario-reconhece-poluicao-eletromagnetica\/","url_meta":{"origin":54654,"position":2},"title":"Judici\u00e1rio reconhece polui\u00e7\u00e3o eletromagn\u00e9tica","author":"Patr\u00edcia Marini","date":"16 de maio de 2014","format":false,"excerpt":"A\u00e7\u00e3o de duas associa\u00e7\u00f5es de moradores foi acolhida pelo Tribunal de Justi\u00e7a de S\u00e3o Paulo que. em decis\u00e3o in\u00e9dita, determinou a redu\u00e7\u00e3o do campo eletromagn\u00e9tico gerado pelas linhas de transmiss\u00e3o de energia que cortam os bairros City Boa\u00e7ava e Alto de Pinheiros. \u00c9 a primeira vez que um tribunal do\u2026","rel":"","context":"Em &quot;X.Categorias velhas&quot;","block_context":{"text":"X.Categorias velhas","link":"https:\/\/www.jornalja.com.br\/arquivo\/category\/x-categorias-velhas\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":14241,"url":"https:\/\/www.jornalja.com.br\/arquivo\/o-guaiba-nas-imagens-poeticas-de-achutti\/","url_meta":{"origin":54654,"position":3},"title":"O Gua\u00edba nas imagens po\u00e9ticas de Achutti","author":"da Reda\u00e7\u00e3o","date":"18 de junho de 2014","format":false,"excerpt":"Em \u201cO Gua\u00edba por Achutti\u201d \u2013 obra financiada via Minist\u00e9rio da Cultura, produ\u00e7\u00e3o executiva de Pedro Longhi, e Fl\u00e1vio Wild como designer \u2013, o fot\u00f3grafo revela a beleza e as mazelas de um espa\u00e7o aqu\u00e1tico de \u00e1guas sempre renovadas, cheio de hist\u00f3rias e lendas como as das cidades que foram\u2026","rel":"","context":"Em &quot;Cultura-Geral&quot;","block_context":{"text":"Cultura-Geral","link":"https:\/\/www.jornalja.com.br\/arquivo\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbQjBd-edw","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/54654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=54654"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/54654\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=54654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=54654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=54654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}