{"id":1028,"date":"2005-11-09T16:42:21","date_gmt":"2005-11-09T19:42:21","guid":{"rendered":"http:\/\/75.126.185.46\/~jornalja\/?p=1028"},"modified":"2005-11-09T16:42:21","modified_gmt":"2005-11-09T19:42:21","slug":"o-sonho-de-francimar","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/colunas\/o-sonho-de-francimar\/","title":{"rendered":"O Sonho de Francimar"},"content":{"rendered":"<p>Francimar deixou seus pais em uma comunidade distante dois dias de barco da cidade de Manaus, na \u00e9poca, estava com 13 anos, hoje est\u00e1 com 17. Veio \u00e0 capital em busca de trabalho seguindo o exemplo de uma tia, com a qual divide a moradia. Conseguiu trabalho logo em seguida como auxiliar de servi\u00e7os gerais em uma produtora de v\u00eddeo especializada em acompanhar turistas em passeios por Manaus e arredores. H\u00e1 tr\u00eas anos ele foi promovido a cameraman, com isso, seu sal\u00e1rio melhorou, subiu para R$ 400,00. Como ele mesmo diz: \u201cGarraram confian\u00e7a em mim e me pagaram um curso de filmagem&#8230;\u201d.<br \/>\nO brilho nos olhos e a felicidade com que executa seu trabalho mostram que o jovem realmente gosta do que faz. Francimar \u00e9 um exemplo de persist\u00eancia e luta; trabalha durante o dia e estuda \u00e0 noite. Ano que vem termina o segundo grau. Em 2005 estava praticamente passado em todas as mat\u00e9rias antes mesmo do fim do ano letivo. Ele n\u00e3o tem tempo para lazer, j\u00e1 que nos finais de semana tamb\u00e9m precisa estudar. Fala que diverte-se na hora de trabalhar na edi\u00e7\u00e3o das imagens dos v\u00eddeos que s\u00e3o encomendados pelos turistas \u2013 \u00e9 muita v\u00eddeo-cassetada! O valor do transporte e a dist\u00e2ncia permitem que ele visite os familiares somente uma vez ao ano \u2013 geralmente no Natal.<br \/>\nNavegar pelos Igarap\u00e9s ouvindo seus relatos \u00e9 melhor do que estar acompanhado de um guia tur\u00edstico. Mesmo n\u00e3o gostando de hist\u00f3ria, geografia e ci\u00eancias \u2013 suas mat\u00e9rias preferidas s\u00e3o matem\u00e1tica, f\u00edsica e qu\u00edmica &#8211; Francimar demonstra ser um grande conhecedor da fauna e da flora locais. Al\u00e9m disso, discorre com facilidade sobre as ilhas, seus canais e a hist\u00f3ria da popula\u00e7\u00e3o ribeirinha.<br \/>\nDe uma coisa Francimar est\u00e1 certo, pelo menos por enquanto: jamais deixar\u00e1 Manaus. Vontade de conhecer outros lugares tamb\u00e9m n\u00e3o tem. A id\u00e9ia de distanciar-se do Rio Negro o assusta. Perder de vista as \u00e1guas que o levam at\u00e9 seus pais e antepassados est\u00e1 fora de cogita\u00e7\u00e3o. Por\u00e9m, como qualquer jovem, ele tem sonhos. Assim como sua vida, seus sonhos s\u00e3o modestos. Talvez o mais \u201caudacioso\u201d para ele mesmo, seja o de cursar uma faculdade, s\u00f3 n\u00e3o sabe ainda o que vai escolher. Da forma com que batalha, tenho certeza que conquistar\u00e1 seu espa\u00e7o em uma Universidade P\u00fablica; e isso, mais que um sonho, \u00e9 um direito seu adquirido por lei. Agora, s\u00f3 lhe falta decidir o curso.<br \/>\nEnt\u00e3o, Boa Sorte Francimar!<br \/>\n<em>Christian Lavich Goldschmidt<br \/>\n*escritor e ator<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Francimar deixou seus pais em uma comunidade distante dois dias de barco da cidade de Manaus, na \u00e9poca, estava com 13 anos, hoje est\u00e1 com 17. Veio \u00e0 capital em busca de trabalho seguindo o exemplo de uma tia, com a qual divide a moradia. Conseguiu trabalho logo em seguida como auxiliar de servi\u00e7os gerais [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-1028","post","type-post","status-publish","format-standard","hentry","category-analiseopiniao"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":84690,"url":"https:\/\/www.jornalja.com.br\/colunas\/17-de-abril-de-1996-30-anos-do-massacre-de-eldorado-do-carajas\/","url_meta":{"origin":1028,"position":0},"title":"17 de abril de 1996: 30 anos do Massacre de Eldorado do Caraj\u00e1s","author":"da Reda\u00e7\u00e3o","date":"17 de abril de 2026","format":false,"excerpt":"Cruz marca o local do massacre em Eldorado dos Caraj\u00e1s, Par\u00e1. Foto: Marcello Casal Jr.\/Arquivo ABr CRISTIANO GOLDSCHMIDT H\u00e1 datas que n\u00e3o passam. Ficam suspensas no tempo como poeira vermelha sobre a pele \u2014 insistem, infiltram-se, recusam o esquecimento. Abril, no sul do Par\u00e1, \u00e9 sempre um m\u00eas que arde.\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84761,"url":"https:\/\/www.jornalja.com.br\/colunas\/cmpc-nova-fabrica-velhos-impactos\/","url_meta":{"origin":1028,"position":1},"title":"CMPC: Nova f\u00e1brica, velhos impactos?","author":"Cleber Dioni Tentardini","date":"6 de maio de 2026","format":false,"excerpt":"EDUARDO RAGUSE* Por volta das 13h40, do dia 05 de maio de 2026, ocorreu a despressuriza\u00e7\u00e3o de emerg\u00eancia da caldeira da f\u00e1brica de celulose da empresa CMPC, no munic\u00edpio de Gua\u00edba. O evento causou grande susto e apreens\u00e3o entre os moradores do entorno da ind\u00fastria devido ao ru\u00eddo fort\u00edssimo, odor\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":84557,"url":"https:\/\/www.jornalja.com.br\/colunas\/entrevista-com-leonel-brizola-como-nascem-as-falsificacoes-historicas\/","url_meta":{"origin":1028,"position":2},"title":"Entrevista com Leonel Brizola: Como nascem as falsifica\u00e7\u00f5es hist\u00f3ricas","author":"An\u00e1lise &amp; Opini\u00e3o","date":"2 de mar\u00e7o de 2026","format":false,"excerpt":"SILVANA MOURA Mais do que direito \u00e0 Hist\u00f3ria, temos o direito \u00e0 verdade da Hist\u00f3ria, para evitar um passado falsificado, supostamente \u201climpo\u201d, eivado de manipula\u00e7\u00e3o e pretensa uniformidade. Em 1996 realizei, em Carazinho, uma Entrevista de Hist\u00f3ria Oral (sou Historiadora e trabalho com Hist\u00f3ria Oral h\u00e1 40 anos) com Leonel\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":84693,"url":"https:\/\/www.jornalja.com.br\/colunas\/fim-da-escala-6x1-cabe-ao-congresso-decidir-entre-o-progresso-e-o-atraso\/","url_meta":{"origin":1028,"position":3},"title":"Fim da escala 6&#215;1: cabe ao Congresso decidir entre o progresso e o atraso","author":"da Reda\u00e7\u00e3o","date":"20 de abril de 2026","format":false,"excerpt":"Plen\u00e1rio da C\u00e2mara dos Deputados durante sess\u00e3o solene do Congresso Nacional. Caber\u00e1 ao parlamento a decis\u00e3o final sobre a nova escala de trabalho. Foto: Leopoldo Silva\/Ag\u00eancia Senado CRISTIANO GOLDSCHMIDT A discuss\u00e3o sobre o fim da escala de trabalho 6x1 no Brasil tem ganhado centralidade no debate p\u00fablico contempor\u00e2neo por tocar\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84632,"url":"https:\/\/www.jornalja.com.br\/colunas\/medicos-alertam-para-os-riscos-a-saude-de-nova-fabrica-de-celulose-da-cmpc\/","url_meta":{"origin":1028,"position":4},"title":"M\u00e9dicos alertam para os riscos \u00e0 sa\u00fade de nova f\u00e1brica de celulose da CMPC","author":"Cleber Dioni Tentardini","date":"14 de abril de 2026","format":false,"excerpt":"ROSELAINE MURLIK * Represento um grupo de profissionais da medicina que, h\u00e1 alguns anos, estuda os diferentes impactos das mudan\u00e7as clim\u00e1ticas e da polui\u00e7\u00e3o ambiental nos ecossistemas na sa\u00fade humana e do planeta. Causa preocupa\u00e7\u00e3o o novo megaempreendimento de celulose da empresa chilena CMPC em Barra do Ribeiro (RS), pr\u00f3ximo\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/comite-contra-celulose.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":84748,"url":"https:\/\/www.jornalja.com.br\/colunas\/a-literatura-brasileira-no-dia-do-trabalhador\/","url_meta":{"origin":1028,"position":5},"title":"A Literatura Brasileira no Dia do Trabalho","author":"An\u00e1lise &amp; Opini\u00e3o","date":"1 de maio de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT O 1\u00ba de maio costuma ser lembrado pelo peso hist\u00f3rico das lutas trabalhistas, pelo som das manifesta\u00e7\u00f5es e pela mem\u00f3ria viva de direitos conquistados ao longo de d\u00e9cadas. No entanto, essa mesma data abriga uma outra forma de celebra\u00e7\u00e3o, menos ruidosa, mas igualmente significativa: o Dia da Literatura\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKo0s-gA","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/1028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/comments?post=1028"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/1028\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/media?parent=1028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/categories?post=1028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/tags?post=1028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}