{"id":1061,"date":"2006-07-26T13:34:16","date_gmt":"2006-07-26T16:34:16","guid":{"rendered":"http:\/\/75.126.185.46\/~jornalja\/?p=1061"},"modified":"2006-07-26T13:34:16","modified_gmt":"2006-07-26T16:34:16","slug":"a-inesperada-reabilitacao-de-getulio-vargas","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/colunas\/a-inesperada-reabilitacao-de-getulio-vargas\/","title":{"rendered":"A inesperada reabilita\u00e7\u00e3o de Get\u00falio Vargas"},"content":{"rendered":"<p align=\"justify\">\n<p align=\"justify\"><strong>M\u00e1rio Maestri *<\/strong><\/p>\n<p align=\"justify\">Get\u00falio Vargas tem sido desancado devido \u00e0s viol\u00eancias cometidas contra as comunidades alem\u00e3s e italianas do Rio Grande do Sul, sobretudo durante a II Guerra Mundial. Atribuiu-se tamb\u00e9m \u00e0 campanha getulista de \u201cnacionaliza\u00e7\u00e3o\u201d dos kystos raciais a crise dos falares \u00e9tnicos alem\u00e3es e italianos. Em geral, os fatos sucederam-se no passado em forma bastante diversa da que s\u00e3o percebidos pelo senso comum, mesmo historiogr\u00e1fico.<\/p>\n<p align=\"justify\">Ren\u00e9 Gertz, 57, professor da PUCRS e da UFRGS, tem dedicado boa parte de sua produ\u00e7\u00e3o historiogr\u00e1fica ao estudo dos sucessos ocorridos quando do Estado Novo [1937-45], no que se refere sobretudo \u00e0 comunidade colonial alem\u00e3 da qual descende. Seu ensaio O perigo alem\u00e3o, de 1991, constitui refer\u00eancia obrigat\u00f3ria na discuss\u00e3o do imagin\u00e1rio brasileiro sobre os alem\u00e3es no RS. Gertz tem dirigido tamb\u00e9m trabalhos de p\u00f3s-gradua\u00e7\u00e3o sobre esse e temas correlatos.<\/p>\n<p align=\"justify\">A publica\u00e7\u00e3o do livro O Estado Novo no Rio Grande do Sul, de Ren\u00e9 Gertz [Passo Fundo: EdiUPF, 2005], constituiu ato por si s\u00f3 merit\u00f3rio, considerando-se a car\u00eancia de estudos referentes ao Estado Novo no RS, pobreza em parte talvez devida aos inevit\u00e1veis constrangimentos biogr\u00e1ficos ensejados pelo per\u00edodo, no que se refere ao comportamento dos pr\u00f3ceres sulinos durante o per\u00edodo ditatorial.<\/p>\n<p align=\"justify\">O livro de Ren\u00e9 Gertz destaca-se pelo candente revisionismo, com destaque para a inesperada absolvi\u00e7\u00e3o de Vargas que, do inferno historiogr\u00e1fico, \u00e9 transferido para suave purgat\u00f3rio, j\u00e1 que o peso dos pecados da \u201ccampanha de nacionaliza\u00e7\u00e3o\u201d \u00e9 lan\u00e7ado \u00e0s costas do interventor Cordeiro de Farias e de seus dois principais s\u00facubos, o secret\u00e1rio da Educa\u00e7\u00e3o, Coelho de Souza, e o famigerado coronel Aur\u00e9lio Py, autor do best-seller A 5\u00aa coluna no Brasil: a conspira\u00e7\u00e3o nazi no RS, publicado pela Globo, em abril de 1942.<\/p>\n<p align=\"justify\">O Estado Novo no Rio Grande do Sul imp\u00f5e-se sobretudo por suas interpreta\u00e7\u00f5es. A apresenta\u00e7\u00e3o inicial dos sucessos hist\u00f3ricos que levaram ao Estado Novo \u00e9 sum\u00e1ria e a proposta do enfraquecimento da economia sulina durante o per\u00edodo fica em aberto, sobretudo devido \u00e0s limitadas fontes dispon\u00edveis, fato assinalado pelo autor. Tamb\u00e9m s\u00e3o sint\u00e9ticos os cap\u00edtulos \u201cAdministra\u00e7\u00e3o e sociedade\u201d e \u201cEduca\u00e7\u00e3o e sa\u00fade\u201d, ricos em sugest\u00f5es para novas investiga\u00e7\u00f5es.<\/p>\n<p align=\"justify\">O cap\u00edtulo a \u201cCultura no Rio Grande do Sul\u201d apresenta dura radiografia da a\u00e7\u00e3o da intelectualidade sulina durante o Estado Novo que, tanto na vers\u00e3o positivista como na cat\u00f3lica, segundo Gertz, colaborou, direta ou indiretamente, com a ditadura, ou adaptou-se a ela, sem maiores pruridos. Nas raras exce\u00e7\u00f5es que confirmam a triste regra encontram-se os intelectuais comunistas Dyon\u00e9lio Machado, Cyro Martins e Ivan Pedro Martins, que seguiram disparando sobretudo com as armas da fic\u00e7\u00e3o.<\/p>\n<p align=\"justify\">Ren\u00e9 Gertz apresenta provas incontest\u00e1veis da ades\u00e3o de intelectuais sulinos de destaque ao Estado Novo. Para outros, o material probat\u00f3rio \u00e9 mais fraco. Assinala que Erico Verissimo compareceu, com Moys\u00e9s Vellinho, Dante de Laytano, entre outros, ao lan\u00e7amento do Comit\u00ea Intelectual pr\u00f3-Estado Novo, pronunciando palestra radiof\u00f4nica, em abril de 1938, na R\u00e1dio Farroupilha, em defesa da ditadura. De M\u00e1rio Quintana, registra-se a participa\u00e7\u00e3o em \u201cComiss\u00e3o Julgadora de frases alusivas ao \u2018Dia da Bandeira\u2019\u201d.<\/p>\n<p align=\"justify\">Ainda que novos estudos retoquem o longo rol de intelectuais \u201ccuja vincula\u00e7\u00e3o ou a proximidade com o regime est\u00e1 claramente documentada\u201d, n\u00e3o modificar\u00e3o a constata\u00e7\u00e3o da harmonia entre a pena, do mundo das id\u00e9ias, e o coturno, da ordem ditatorial. Fen\u00f4meno que exige discuss\u00e3o mais profunda, j\u00e1 que envolve as ra\u00edzes pr\u00f3ximas da cultura erudita do Rio Grande do Sul.<\/p>\n<p align=\"justify\">Sobre essa quest\u00e3o, temos tamb\u00e9m a valiosa disserta\u00e7\u00e3o, ainda in\u00e9dita, de Gl\u00e1ucia Konrad, de 1994, \u201cA pol\u00edtica cultural do Estado novo no RS: imposi\u00e7\u00e3o e resist\u00eancia\u201d, na qual o autor ap\u00f3ia-se parcialmente. Com sensibilidade, Gertz lembra que a talvez \u201calegada falta de entusiasmo\u201d rio-grandense sobre o Estado Novo e, portanto, a colabora\u00e7\u00e3o despreocupada com ele, registre sentimento de que \u201cnada de muito novo estava ocorrendo\u201d, sobretudo em rela\u00e7\u00e3o \u00e0 Rep\u00fablica Velha.<\/p>\n<p align=\"justify\">No valioso cap\u00edtulo final, Gertz empreende sentida den\u00fancia das viol\u00eancias da \u201ccampanha da nacionaliza\u00e7\u00e3o\u201d que, para ele, teria vitimado sobretudo a popula\u00e7\u00e3o colonial alem\u00e3. Segundo o autor, a \u201ccampanha\u201d teria sido \u201cmenos agressiva\u201d na \u201cregi\u00e3o de coloniza\u00e7\u00e3o italiana ao norte de Porto Alegre, em Caxias do Sul e adjac\u00eancias\u201d do que \u201cnas regi\u00f5es de coloniza\u00e7\u00e3o alem\u00e3\u201d.<\/p>\n<p align=\"justify\">Entre as raz\u00f5es do comportamento diferencial estariam a maior simpatia brasileira para com os \u201citalianos\u201d; a exist\u00eancia de sentimento\u00a0 sobre o \u201cperigo alem\u00e3o\u201d desde a chegada dos imigrantes em 1824; a mobiliza\u00e7\u00e3o antialem\u00e3 durante a I Guerra Mundial; a ades\u00e3o e simpatia ao partido nazista no Estado, fen\u00f4meno para o qual n\u00e3o contamos ainda com an\u00e1lise de f\u00f4lego como a realizada para a Regi\u00e3o Colonial Italiana por Loraine Giron, em As sombras\u00a0 do littorio: o fascismo no Rio Grande do Sul, de 1994. Na abordagem da espinhosa quest\u00e3o, Gertz assinala que \u201cmais ou menos a metade dos pastores do S\u00ednodo Riograndense eram filiados ao partido nazista\u201d.<\/p>\n<p align=\"justify\">Sobretudo, Gertz defende que os excessos da \u201ccampanha da nacionaliza\u00e7\u00e3o\u201d seriam obra de Cordeiro de Farias, \u201cclaro adepto da tese do \u2018perigo alem\u00e3o\u2019, preocupad\u00edssimo com a situa\u00e7\u00e3o \u2018etnogr\u00e1fico-internacionalista\u2019\u201d sulina. Sugere que a partida do interventor para a It\u00e1lia, como membro da FEB, constituiu \u201cjustificativa p\u00fablica\u201d para supera\u00e7\u00e3o de situa\u00e7\u00e3o insustent\u00e1vel. Sua substitui\u00e7\u00e3o pelo cel. Ernesto Dorneles seria tamb\u00e9m tentativa de distens\u00e3o<\/p>\n<p align=\"justify\">Ren\u00e9 Gertz \u00e9 historiador ponderado e contido. A tens\u00e3o afetiva devido \u00e0 abordagem das viol\u00eancias antialem\u00e3s no Estado Novo fica registrada em algumas raras \u00eanfases ling\u00fc\u00edsticas. Professora brasileira agindo na zona colonial alem\u00e3 durante a \u201ccampanha de nacionaliza\u00e7\u00e3o\u201d em forma desembara\u00e7ada \u00e9 classificada de \u201cmenininha\u201d. As depreda\u00e7\u00f5es populares, em 18 e 19 de agosto, ap\u00f3s os dur\u00edssimos ataques a navios mercantes brasileiros desarmados por submarino alem\u00e3o que causaram mais de seiscentos mortos, s\u00e3o definidas como \u201canarquia\u201d, \u201canimalescas\u201d, produto da a\u00e7\u00e3o de \u201cfan\u00e1ticos\u201d.<\/p>\n<p align=\"justify\">Ren\u00e9 Gertz assinala que a interven\u00e7\u00e3o do Ex\u00e9rcito, pondo fim \u00e0s manifesta\u00e7\u00f5es populares anti-Eixo de agosto, ocorreu \u201c\u00e0 revelia do interventor\u201d, constituindo desautoriza\u00e7\u00e3o de sua exacerba\u00e7\u00e3o da \u201ccampanha de nacionaliza\u00e7\u00e3o\u201d. Assinala pedido de ren\u00fancia de Cordeiro de Farias, de 22 de agosto de 1942, ap\u00f3s a a\u00e7\u00e3o do Ex\u00e9rcito. Mais ainda. Em 1950, Get\u00falio justificava a nomea\u00e7\u00e3o do cel. Ernesto Dorneles como medida \u201ccontra aqueles\u201d que, em seu nome e contra a sua vontade, \u201cpraticavam atos de viol\u00eancia e de arb\u00edtrio, com base em preju\u00edzo \u00e9tnico\u201d.<\/p>\n<p align=\"justify\">Al\u00e9m das viol\u00eancias da \u201cnacionaliza\u00e7\u00e3o\u201d, Ren\u00e9 Gertz refere-se rapidamente \u00e0 repress\u00e3o do truculento Cordeiro de Farias ao movimento oper\u00e1rio, aos comunistas e aos integralistas. N\u00e3o chega a abordar o maior crime cometido pelo interventor nas primeiras semanas de seu consulado, contra pac\u00edfico movimento religioso popular de caboclos e colonos empobrecidos, em Sobradinho e Soledade, com a morte de talvez mais de cinq\u00fcenta beatos absolutamente desarmados. Sucessos que tardam ainda a ter a repara\u00e7\u00e3o que exigem na mem\u00f3ria e na historiografia rio-grandense.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1rio Maestri * Get\u00falio Vargas tem sido desancado devido \u00e0s viol\u00eancias cometidas contra as comunidades alem\u00e3s e italianas do Rio Grande do Sul, sobretudo durante a II Guerra Mundial. Atribuiu-se tamb\u00e9m \u00e0 campanha getulista de \u201cnacionaliza\u00e7\u00e3o\u201d dos kystos raciais a crise dos falares \u00e9tnicos alem\u00e3es e italianos. Em geral, os fatos sucederam-se no passado em [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-1061","post","type-post","status-publish","format-standard","hentry","category-analiseopiniao"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":84801,"url":"https:\/\/www.jornalja.com.br\/colunas\/a-lei-aurea-libertou-os-corpos-mas-preservou-as-correntes\/","url_meta":{"origin":1061,"position":0},"title":"A Lei \u00c1urea libertou os corpos, mas preservou as correntes","author":"An\u00e1lise &amp; Opini\u00e3o","date":"13 de maio de 2026","format":false,"excerpt":"Nossa heran\u00e7a africana ocupa um lugar amb\u00edguo demais: \u00e9simultaneamente origem de orgulho cultural e alvo hist\u00f3rico de exclus\u00e3o social. Por Cristiano GoldschmidtH\u00e1 datas que permanecem suspensas sobre um pa\u00eds como umapergunta sem resposta definitiva. O 13 de maio de 1888 \u00e9 umadessas anomalias hist\u00f3ricas: um acontecimento oficialmenteencerrado, mas moralmente inconcluso.\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-7.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-7.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-7.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":84714,"url":"https:\/\/www.jornalja.com.br\/colunas\/22-de-abril-o-instante-em-que-o-brasil-passa-a-existir-para-o-mundo-europeu\/","url_meta":{"origin":1061,"position":1},"title":"22 de abril: o instante em que o Brasil \u201cpassa a existir\u201d para o mundo europeu","author":"Patr\u00edcia Marini","date":"22 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Era 22 de abril de 1500 \u2014 ou, ao menos, \u00e9 assim que nos habituamos a dizer, com a serenidade quase ing\u00eanua de quem domestica o passado em datas redondas e memor\u00e1veis. Naquele dia, a esquadra comandada por Pedro \u00c1lvares Cabral avistou terra ap\u00f3s semanas de travessia pelo\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/desembarque-de-cabral-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/desembarque-de-cabral-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/desembarque-de-cabral-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/desembarque-de-cabral-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/desembarque-de-cabral-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/desembarque-de-cabral-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84632,"url":"https:\/\/www.jornalja.com.br\/colunas\/medicos-alertam-para-os-riscos-a-saude-de-nova-fabrica-de-celulose-da-cmpc\/","url_meta":{"origin":1061,"position":2},"title":"M\u00e9dicos alertam para os riscos \u00e0 sa\u00fade de nova f\u00e1brica de celulose da CMPC","author":"Cleber Dioni Tentardini","date":"14 de abril de 2026","format":false,"excerpt":"ROSELAINE MURLIK * Represento um grupo de profissionais da medicina que, h\u00e1 alguns anos, estuda os diferentes impactos das mudan\u00e7as clim\u00e1ticas e da polui\u00e7\u00e3o ambiental nos ecossistemas na sa\u00fade humana e do planeta. Causa preocupa\u00e7\u00e3o o novo megaempreendimento de celulose da empresa chilena CMPC em Barra do Ribeiro (RS), pr\u00f3ximo\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/comite-contra-celulose.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":84693,"url":"https:\/\/www.jornalja.com.br\/colunas\/fim-da-escala-6x1-cabe-ao-congresso-decidir-entre-o-progresso-e-o-atraso\/","url_meta":{"origin":1061,"position":3},"title":"Fim da escala 6&#215;1: cabe ao Congresso decidir entre o progresso e o atraso","author":"da Reda\u00e7\u00e3o","date":"20 de abril de 2026","format":false,"excerpt":"Plen\u00e1rio da C\u00e2mara dos Deputados durante sess\u00e3o solene do Congresso Nacional. Caber\u00e1 ao parlamento a decis\u00e3o final sobre a nova escala de trabalho. Foto: Leopoldo Silva\/Ag\u00eancia Senado CRISTIANO GOLDSCHMIDT A discuss\u00e3o sobre o fim da escala de trabalho 6x1 no Brasil tem ganhado centralidade no debate p\u00fablico contempor\u00e2neo por tocar\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84673,"url":"https:\/\/www.jornalja.com.br\/colunas\/40-anos-sem-simone-de-beauvoir-uma-interlocutora-ainda-incomoda-do-presente\/","url_meta":{"origin":1061,"position":4},"title":"40 anos sem Simone de Beauvoir, uma interlocutora ainda inc\u00f4moda do presente","author":"da Reda\u00e7\u00e3o","date":"14 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Quarenta anos ap\u00f3s a morte de Simone de Beauvoir (9 de janeiro de 1908 - 14 de abril de 1986), descubro que sua aus\u00eancia n\u00e3o \u00e9 propriamente um vazio \u2014 \u00e9 antes um rumor cont\u00ednuo, uma esp\u00e9cie de presen\u00e7a indireta que se infiltra nas conversas, nos livros, nas\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/simone-de-beauvoir-memorias-de-uma-menina-bemcomportada.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":84703,"url":"https:\/\/www.jornalja.com.br\/colunas\/tiradentes-o-martir-que-ainda-nos-observa-e-as-inquietacoes-de-um-brasil-inacabado\/","url_meta":{"origin":1061,"position":5},"title":"Tiradentes: o M\u00e1rtir que ainda nos observa e as inquieta\u00e7\u00f5es de um Brasil inacabado","author":"da Reda\u00e7\u00e3o","date":"21 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT H\u00e1 datas que n\u00e3o se imp\u00f5em pelo alarde, mas pela persist\u00eancia silenciosa com que atravessam os s\u00e9culos e se insinuam na consci\u00eancia coletiva. O 21 de abril pertence a essa estirpe discreta. N\u00e3o chega ornado de euforia, tampouco se anuncia com a grandiloqu\u00eancia de outras celebra\u00e7\u00f5es; antes, aproxima-se\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKo0s-h7","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/1061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/comments?post=1061"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/1061\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/media?parent=1061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/categories?post=1061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/tags?post=1061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}