{"id":1081,"date":"2007-05-18T13:59:16","date_gmt":"2007-05-18T16:59:16","guid":{"rendered":"http:\/\/75.126.185.46\/~jornalja\/?p=1081"},"modified":"2007-05-18T13:59:16","modified_gmt":"2007-05-18T16:59:16","slug":"pressoes-ambientais-sobre-o-bioma-pampa","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/colunas\/pressoes-ambientais-sobre-o-bioma-pampa\/","title":{"rendered":"Press\u00f5es ambientais sobre o bioma Pampa"},"content":{"rendered":"<p><strong>Ant\u00f4nio Eduardo Lanna, consultor em Recursos H\u00eddricos<\/strong><br \/>\nO bioma Pampa, que s\u00f3 existe no Rio Grande do Sul, ocupando cerca de 63% de sua \u00e1rea, est\u00e1 amea\u00e7ado. A amea\u00e7a mais evidente e que seguramente desperta maiores preocupa\u00e7\u00f5es \u00e9 com a monocultura de \u00e1rvores ex\u00f3ticas, em especial o eucalipto.<br \/>\nEntretanto elas n\u00e3o param a\u00ed. O governo federal e o estadual do Rio Grande do Sul v\u00eam anunciando a constru\u00e7\u00e3o de duas de cerca de uma d\u00fazia de barragens na bacia do rio Santa Maria, que se insere nesse bioma. Essas barragens, que inundar\u00e3o \u00e1reas importantes quanto \u00e0 biodiversidade e a presen\u00e7a de esp\u00e9cies end\u00eamicas, servir\u00e3o para disponibilizar\u00e3o de \u00e1gua para irriga\u00e7\u00e3o do arroz primordialmente. A cultura de arroz gera outro impacto, ao ocupar \u00e1reas de preserva\u00e7\u00e3o permanente, localizadas nas v\u00e1rzeas fluviais. Portanto, as barragens geram um duplo impacto: pela suas presen\u00e7as e por gerarem outro tipo de agress\u00e3o, representada pela expans\u00e3o da \u00e1rea de arroz irrigado.<br \/>\nFato surpreendente \u00e9 que o impacto ambiental da ocupa\u00e7\u00e3o de vastas \u00e1reas com eucalipto ainda tem como contrapartida a gera\u00e7\u00e3o de riqueza e renda, embora os custos ambientais possam ser considerados demasiados. Ao contr\u00e1rio, as barragens, com finalidade primordial de irriga\u00e7\u00e3o de arroz, n\u00e3o s\u00e3o sequer vi\u00e1veis economicamente. Qualquer estudo mais rigoroso que se fa\u00e7a a respeito da atividade oriz\u00edcola conclui que este cultivo \u00e9 excelente alternativa econ\u00f4mica quando existe disponibilidade natural de solos e \u00e1gua. Mas pode ser facilmente constatado que qualquer obra hidr\u00e1ulica de maior porte n\u00e3o pode ser paga pela renda gerada pelo arroz, seja ela resultante dos benef\u00edcios prim\u00e1rios, seja proveniente dos benef\u00edcios secund\u00e1rios, incluindo as chamadas externalidades econ\u00f4micas como os &#8220;efeitos multiplicadores&#8221; resultantes da dinamiza\u00e7\u00e3o da economia regional. Gerasse renda o arroz, os pr\u00f3prios arrozeiros se disporiam a empreender essas obras, e as regi\u00f5es onde se localiza a orizicultura no Rio Grande do Sul apresentariam grande desenvolvimento e n\u00e3o o quadro de estagna\u00e7\u00e3o econ\u00f4mica que vem de v\u00e1rios anos.<br \/>\nPor que essas barragens est\u00e3o sendo propostas pelo Estado? Quem ganha e quem perde com elas? Certamente os arrozeiros beneficiados ganhar\u00e3o j\u00e1 que a \u00e1gua lhes ser\u00e1 fornecida a custos subsidiados: \u00e9 informado que apenas pagar\u00e3o os custos de opera\u00e7\u00e3o e manuten\u00e7\u00e3o das barragens que s\u00e3o da ordem de menos de 1% dos custos de investimentos. Esse subs\u00eddio, como todo subs\u00eddio, seria justific\u00e1vel apenas se esse segmento apresentasse alguma car\u00eancia socioecon\u00f4mica, algo que n\u00e3o condiz com a realidade \u2013 os arrozeiros situam-se no estrato superior de qualquer escala que avalie a situa\u00e7\u00e3o socioecon\u00f4mica da popula\u00e7\u00e3o. Olhando por outra \u00f3tica, existem segmentos sociais que apresentam car\u00eancias bem maiores e que mereceriam maior prioridade de apoio governamental do que os arrozeiros da bacia do rio Santa Maria.. N\u00e3o \u00e9 aceit\u00e1vel, portanto, que o governo, seja federal ou estadual, subsidie esse segmento n\u00e3o priorit\u00e1rio.<br \/>\nA regi\u00e3o e os munic\u00edpios onde se encontram as barragens e as \u00e1reas irrigadas poderiam ser beneficiados. Isto decorreria dos benef\u00edcios gerados durante a constru\u00e7\u00e3o das barragens, devido aos gastos que seriam realizados na regi\u00e3o, movimentando sua economia. Por\u00e9m deve ser considerado que devido \u00e0 n\u00e3o especializa\u00e7\u00e3o regional, a maioria dos gastos seria com insumos adquiridos fora da regi\u00e3o. Nela poderiam ser obtidos m\u00e3o-de-obra n\u00e3o especializada e algum servi\u00e7o igualmente n\u00e3o-especializado \u2013 ou seja, a maior parte dos investimentos seria dirigido a insumos encontrados fora da regi\u00e3o, n\u00e3o trazendo maiores benef\u00edcios a ela. Com um agravante: esse tipo de constru\u00e7\u00e3o costuma atrair m\u00e3o-de-obra n\u00e3o especializada de outras regi\u00f5es, geralmente trabalhadores bra\u00e7ais, que se fixa no entorno da obra. Conclu\u00edda a obra resta ao munic\u00edpio um problema social derivado de ac\u00famulo de m\u00e3o-de-obra desempregada, n\u00e3o especializada, que requerer\u00e1 apoio que drenar\u00e1 parte dos poucos benef\u00edcios gerados durante a constru\u00e7\u00e3o.<br \/>\nOs munic\u00edpios captar\u00e3o, por\u00e9m, a produ\u00e7\u00e3o gerada nas \u00e1reas irrigadas. Contudo, o projeto das barragens comete um grande equ\u00edvoco: imagina que a \u00e1gua armazenada nos reservat\u00f3rios resultar\u00e1 proporcionalmente maior \u00e1rea irrigada. Isto seria correto se a \u00e1rea correntemente irrigada tivesse seu suprimento garantido em qualquer situa\u00e7\u00e3o hidrol\u00f3gica, mesmo durante as estiagens mais intensas. Isto n\u00e3o \u00e9 correto. As mesmas pessoas que apregoam os benef\u00edcios das barragens argumentam que elas evitar\u00e3o os problemas de car\u00eancia h\u00eddrica que t\u00eam sistematicamente afetado os rendimentos das lavouras arrozeiras. Ora, se maiores quantidades de \u00e1gua ser\u00e3o disponibilizados o racional seria que primeiro fossem destinados ao suprimento das \u00e1reas j\u00e1 desenvolvidas e somente depois \u00e0 amplia\u00e7\u00e3o das \u00e1reas irrigadas.<br \/>\nNo entanto, estudo da Universidade Federal de Santa Maria para o pr\u00f3prio governo do Estado do Rio Grande do Sul concluiu que em uma das barragens, a do arroio Jaguari, n\u00e3o permitiria qualquer expans\u00e3o da \u00e1rea irrigada. Ela apenas permitiria que as \u00e1reas j\u00e1 desenvolvidas tivessem maior garantia de suprimento durante as estiagens mais intensas. Portanto, os benef\u00edcios obtidos pelos munic\u00edpios contemplados com a irriga\u00e7\u00e3o do arroz foram exagerados e n\u00e3o podem ser usados para dimensionar as vantagens sob seus pontos de vista, sem melhores avalia\u00e7\u00f5es. O grave \u00e9 que esta expans\u00e3o de \u00e1rea irrigada, obtida por meio de equ\u00edvocos ou manipula\u00e7\u00f5es das an\u00e1lises, est\u00e1 sendo usada para justificativa do investimento! Isto mostra que os pr\u00f3prios projetos das barragens, do arroio Jaguari e do arroio Taquaremb\u00f3, j\u00e1 aprovados quanto \u00e0s viabilidades econ\u00f4micas no \u00e2mbito das inst\u00e2ncias t\u00e9cnicas do governo estadual e do governo federal, devem ser reavaliados e corrigidos dos erros que os invalidam como subs\u00eddios para decis\u00f5es.<br \/>\nO que deveria ser considerado pelos munic\u00edpios pretensamente beneficiados pelos projetos \u00e9 se n\u00e3o haveria outras alternativas de investimento que trouxessem maiores benef\u00edcios, j\u00e1 que os que s\u00e3o anunciados carecem de rigor nas suas estimativas e podem resultar, inclusive, em preju\u00edzos a m\u00e9dio e longo prazos. Esses poder\u00e3o ser provenientes do comprometimento de \u00e1reas de expressivo valor ambiental e tur\u00edstico, e especialmente pela considera\u00e7\u00e3o de que tais munic\u00edpios j\u00e1 foram beneficiados por investimentos estaduais e federais, reduzindo as suas prioridades concernentes a outras oportunidades de investimento.<br \/>\nUm estudo lan\u00e7ado no final de 2006, contratado pelo Governo do Rio Grande do Sul, o Rumos 2015 , prop\u00f4s estrat\u00e9gias de desenvolvimento para o Estado por regi\u00e3o funcional. Naquela que abrange a bacia do rio Santa Maria n\u00e3o houve previs\u00e3o de implanta\u00e7\u00e3o de barragens. No que se refere \u00e0 orizicultura foram propostos quatro programas; nenhum deles envolve a constru\u00e7\u00e3o de barragens e um programa prop\u00f5e a restaura\u00e7\u00e3o das matas ciliares, enquanto as barragens acarretar\u00e3o as suas elimina\u00e7\u00f5es. Eles s\u00e3o:<br \/>\n1) Desenvolvimento de pesquisas e divulga\u00e7\u00e3o, voltado a um melhor manejo agr\u00edcola, com projetos voltados \u00e0 pesquisa de novos cultivares, divulga\u00e7\u00e3o de informa\u00e7\u00f5es tecnol\u00f3gicas, capacita\u00e7\u00e3o em novas t\u00e9cnicas e gest\u00e3o da comercializa\u00e7\u00e3o;<br \/>\n2) Capitaliza\u00e7\u00e3o do potencial ambiental, voltado ao melhor controle e \u00e0 efici\u00eancia no uso da \u00e1gua nas \u00e1reas irrigadas;<br \/>\n3) Manuten\u00e7\u00e3o do potencial ambiental, que prop\u00f5e a prote\u00e7\u00e3o e recupera\u00e7\u00e3o do ambiente, em especial a restaura\u00e7\u00e3o das matas ciliares;<br \/>\n4) Suprimento de infra-estruturas, que se reporta a um &#8220;upgrade&#8221; em armazenamento.<br \/>\nEsse estudo, acatado pelo atual governo do estado, poder\u00e1 melhor direcionar os esfor\u00e7os de desenvolvimento da regi\u00e3o, usando os mesmos recursos disponibilizados pelos governos federal e estadual para essas barragens, com resultados certamente mais vantajosos sob os enfoques econ\u00f4mico, social e ambiental.<br \/>\nOutro equ\u00edvoco grave que \u00e9 apresentado nos projetos relaciona-se \u00e0 considera\u00e7\u00e3o de benef\u00edcios derivados de outros usos da \u00e1gua. Eles foram inseridos no projeto original, que previa unicamente a irriga\u00e7\u00e3o do arroz como benefici\u00e1ria, por causa da Resolu\u00e7\u00e3o Conama 369\/2006. Esta resolu\u00e7\u00e3o &#8220;disp\u00f5e sobre casos excepcionais, de utilidade p\u00fablica, interesse social ou baixo impacto ambiental, que possibilitam a interven\u00e7\u00e3o ou supress\u00e3o de vegeta\u00e7\u00e3o em \u00c1rea de Preserva\u00e7\u00e3o Permanente &#8211; APP&#8221;. Matas ciliares, que s\u00e3o inundadas por reservat\u00f3rios, e \u00e1rea de v\u00e1rzeas, aptas \u00e0 irriga\u00e7\u00e3o de arroz, s\u00e3o APPs. Casos excepcionais para suas supress\u00f5es n\u00e3o envolvem a irriga\u00e7\u00e3o do arroz, mas a constru\u00e7\u00e3o de &#8220;obras essenciais de infra-estrutura destinadas aos servi\u00e7os p\u00fablicos de transporte, saneamento e energia&#8221; entre outras possibilidades. Devido a isto foram incorporados outros benefici\u00e1rios aos projetos entre eles o abastecimento de n\u00facleos urbanos, recrea\u00e7\u00e3o e irriga\u00e7\u00e3o de outras culturas que n\u00e3o o arroz, e at\u00e9 o controle de inunda\u00e7\u00f5es. Isto serviu tanto para superar a restri\u00e7\u00e3o ambiental comentada, como para inflar os benef\u00edcios do projeto, j\u00e1 que como \u00e9 sabido e foi acima afirmado, o arroz n\u00e3o gera benef\u00edcios para justificar obras deste porte.<br \/>\nMuitos desses benef\u00edcios s\u00e3o fict\u00edcios ou exagerados, como foram os benef\u00edcios atribu\u00eddos \u00e0 irriga\u00e7\u00e3o do arroz. Para comentar apenas o de maior relev\u00e2ncia social e econ\u00f4mica, que \u00e9 o abastecimento de n\u00facleos urbanos, eventuais problemas de atendimento a essas demandas s\u00e3o causados pelo excesso de uso de \u00e1gua pelo arroz.. Bastaria, portanto, a redu\u00e7\u00e3o da \u00e1rea irrigada nas esta\u00e7\u00f5es de estiagem mais intensas para permitir o atendimento dessas demandas, sem necessidade de constru\u00e7\u00e3o de barragens. Sairia certamente mais barato e seria ambientalmente mais vantajoso compensar aos arrozeiros nesses per\u00edodos pela redu\u00e7\u00e3o de produ\u00e7\u00e3o do que construir uma barragem. O mesmo se pode dizer para alguns usos para recrea\u00e7\u00e3o.<br \/>\nN\u00e3o foi considerada nas an\u00e1lises dos projetos uma pr\u00e1tica comum e necess\u00e1ria chamada de an\u00e1lise incremental. Por ela, cada uso de \u00e1gua deve ser retirado do projeto global e reavaliada a nova dimens\u00e3o das estruturas que permitiria manter o suprimento aos demais usos \u2013 como esta dimens\u00e3o \u00e9 menor, os custos ser\u00e3o igualmente menores. O uso retirado somente \u00e9 vi\u00e1vel economicamente se os custos incrementais gerados por sua reinser\u00e7\u00e3o no projeto, ou seja, pelo aumento das dimens\u00f5es das estruturas at\u00e9 \u00e0 situa\u00e7\u00e3o original, forem superados pelos benef\u00edcios que gera. Certamente essa viabilidade n\u00e3o ocorreria com o arroz irrigado que, por ser grande consumidor de \u00e1gua, corresponde \u00e0 maior parte das dimens\u00f5es das estruturas e, portanto, dos investimentos. Os demais usos poderiam eventualmente ser considerados vi\u00e1veis economicamente, pois consomem menores quantidades de \u00e1gua e exigem menores dimens\u00f5es do projeto. Contudo, essas menores dimens\u00f5es corresponderiam certamente a projetos bem menores que aqueles atualmente considerados e que certamente teriam menores restri\u00e7\u00f5es ambientais.<br \/>\nEssa s\u00e9rie de equ\u00edvocos e incorre\u00e7\u00f5es nos projetos das barragens da bacia do rio Santa Maria culmina com uma proposta que mostra claramente a exist\u00eancia de decis\u00f5es que fogem ao interesse p\u00fablico e colidem com as normas legais.<br \/>\nNa barragem do arroio Jaguari h\u00e1 necessidade de constru\u00e7\u00e3o de um canal revestido de cerca de 40 quil\u00f4metros para aduzir \u00e1gua \u00e0s \u00e1reas destinadas \u00e0 irriga\u00e7\u00e3o do arroz. A necessidade de estrutura deste porte, por si s\u00f3, mostra que certamente n\u00e3o houve uma an\u00e1lise econ\u00f4mica criteriosa para sele\u00e7\u00e3o desta barragem. Canais deste porte s\u00e3o caros e normalmente inviabilizam um investimento dessa natureza. Como o canal serve para suprir alguns poucos orizicultores o correto seria que eles pagassem pelo menos o investimento nesse canal, mesmo sendo isentados de pagar os investimentos na barragem. N\u00e3o \u00e9 isto que o projeto prop\u00f5e, pois os custos desse canal ser\u00e3o tamb\u00e9m assumidos pelos governos federal e estadual. Ou seja, ambos os governos pretendem doar recursos p\u00fablicos de valor consider\u00e1vel, que poderiam ser aplicados em investimentos que gerariam benef\u00edcios mais expressivos, a um grupo de pessoas que j\u00e1 se encontra em uma posi\u00e7\u00e3o privilegiada na escala socioecon\u00f4mica da regi\u00e3o, do estado e do pa\u00eds.<br \/>\nResumindo, o bioma Pampa acha-se amea\u00e7ado por v\u00e1rios empreendimentos promovidos pelos governos federal e estadual, com destaque \u00e0 monocultura de \u00e1rvores ex\u00f3ticas e \u00e0 constru\u00e7\u00e3o de barragens para irriga\u00e7\u00e3o de arroz. Ambos os empreendimentos geram expressivos impactos ambientais que alterar\u00e3o fortemente um bioma que deveria ser protegido e preservado. Ao contr\u00e1rio da monocultura de \u00e1rvores ex\u00f3ticas, por\u00e9m, a implanta\u00e7\u00e3o das barragens para irriga\u00e7\u00e3o de arroz sequer apresenta signific\u00e2ncia nos benef\u00edcios econ\u00f4micos que ser\u00e3o gerados.<br \/>\nPortanto, a monocultura de \u00e1rvores ex\u00f3ticas estabelece um conflito entre os objetivos de desenvolvimento econ\u00f4mico, que s\u00e3o positivos, e de impacto ambiental, que s\u00e3o negativos e expressivos, e de eq\u00fcidade social, que s\u00e3o discut\u00edveis. J\u00e1 a constru\u00e7\u00e3o de barragens para irriga\u00e7\u00e3o de arroz n\u00e3o se justifica seja economicamente, seja socialmente e muito menos ambientalmente.<br \/>\nS\u00f3 fica uma d\u00favida: a proposta de implanta\u00e7\u00e3o dessas barragens decorre de um excesso de ignor\u00e2ncia ou da falta de esp\u00edrito republicano?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ant\u00f4nio Eduardo Lanna, consultor em Recursos H\u00eddricos O bioma Pampa, que s\u00f3 existe no Rio Grande do Sul, ocupando cerca de 63% de sua \u00e1rea, est\u00e1 amea\u00e7ado. A amea\u00e7a mais evidente e que seguramente desperta maiores preocupa\u00e7\u00f5es \u00e9 com a monocultura de \u00e1rvores ex\u00f3ticas, em especial o eucalipto. Entretanto elas n\u00e3o param a\u00ed. O governo [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-1081","post","type-post","status-publish","format-standard","hentry","category-analiseopiniao"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":84761,"url":"https:\/\/www.jornalja.com.br\/colunas\/cmpc-nova-fabrica-velhos-impactos\/","url_meta":{"origin":1081,"position":0},"title":"CMPC: Nova f\u00e1brica, velhos impactos?","author":"Cleber Dioni Tentardini","date":"6 de maio de 2026","format":false,"excerpt":"EDUARDO RAGUSE* Por volta das 13h40, do dia 05 de maio de 2026, ocorreu a despressuriza\u00e7\u00e3o de emerg\u00eancia da caldeira da f\u00e1brica de celulose da empresa CMPC, no munic\u00edpio de Gua\u00edba. O evento causou grande susto e apreens\u00e3o entre os moradores do entorno da ind\u00fastria devido ao ru\u00eddo fort\u00edssimo, odor\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":84564,"url":"https:\/\/www.jornalja.com.br\/colunas\/a-nova-celulose-a-beira-do-guaiba-e-o-risco-de-repetir-a-borregaard\/","url_meta":{"origin":1081,"position":1},"title":"A nova celulose \u00e0 beira do Gua\u00edba e o risco de repetir a Borregaard","author":"An\u00e1lise &amp; Opini\u00e3o","date":"6 de mar\u00e7o de 2026","format":false,"excerpt":"ELMAR BONES No dia 16 de mar\u00e7o de 1972 foi inaugurada a Ind\u00fastria de Celulose Borregaard, em Gua\u00edba, com a presen\u00e7a das mais altas autoridades e manchetes ufanistas em todos os jornais. Inaugura\u00e7\u00e3o da f\u00e1brica em Gua\u00edba, no ano de 1972. Foto Reprodu\u00e7\u00e3o Arquivo\/CeluloseRioGrandense Seria uma das maiores f\u00e1bricas em\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84590,"url":"https:\/\/www.jornalja.com.br\/colunas\/e-preciso-defender-o-jardim-botanico-de-porto-alegre\/","url_meta":{"origin":1081,"position":2},"title":"\u00c9 preciso defender o Jardim Bot\u00e2nico de Porto Alegre","author":"da Reda\u00e7\u00e3o","date":"8 de mar\u00e7o de 2026","format":false,"excerpt":"CLEBER DIONI TENTARDINI O Jardim Bot\u00e2nico de Porto Alegre (JBPA) tem 67 anos e \u00e9 considerado um dos cinco melhores e maiores do Brasil. Possui 28 cole\u00e7\u00f5es cient\u00edficas que somam mais de 4.200 plantas, incluindo esp\u00e9cies raras, amea\u00e7adas de extin\u00e7\u00e3o e end\u00eamicas, que s\u00e3o encontradas apenas no RS. No local\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84632,"url":"https:\/\/www.jornalja.com.br\/colunas\/medicos-alertam-para-os-riscos-a-saude-de-nova-fabrica-de-celulose-da-cmpc\/","url_meta":{"origin":1081,"position":3},"title":"M\u00e9dicos alertam para os riscos \u00e0 sa\u00fade de nova f\u00e1brica de celulose da CMPC","author":"Cleber Dioni Tentardini","date":"14 de abril de 2026","format":false,"excerpt":"ROSELAINE MURLIK * Represento um grupo de profissionais da medicina que, h\u00e1 alguns anos, estuda os diferentes impactos das mudan\u00e7as clim\u00e1ticas e da polui\u00e7\u00e3o ambiental nos ecossistemas na sa\u00fade humana e do planeta. Causa preocupa\u00e7\u00e3o o novo megaempreendimento de celulose da empresa chilena CMPC em Barra do Ribeiro (RS), pr\u00f3ximo\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/comite-contra-celulose.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":84725,"url":"https:\/\/www.jornalja.com.br\/colunas\/e-preciso-refletir-sobre-os-mais-de-84-mil-desaparecidos-no-brasil-em-2025\/","url_meta":{"origin":1081,"position":4},"title":"\u00c9 preciso refletir sobre os mais de 84 mil desaparecidos no Brasil em 2025","author":"An\u00e1lise &amp; Opini\u00e3o","date":"23 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Em 2025, o Brasil registrou 84.760 pessoas desaparecidas, segundo dados consolidados pelo Sistema Nacional de Informa\u00e7\u00f5es de Seguran\u00e7a P\u00fablica Sinesp), vinculado ao Minist\u00e9rio da Justi\u00e7a e Seguran\u00e7a P\u00fablica. Mais do que um n\u00famero expressivo, o dado revela um fen\u00f4meno cont\u00ednuo, distribu\u00eddo no tempo e no territ\u00f3rio \u2014 e,\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84690,"url":"https:\/\/www.jornalja.com.br\/colunas\/17-de-abril-de-1996-30-anos-do-massacre-de-eldorado-do-carajas\/","url_meta":{"origin":1081,"position":5},"title":"17 de abril de 1996: 30 anos do Massacre de Eldorado do Caraj\u00e1s","author":"da Reda\u00e7\u00e3o","date":"17 de abril de 2026","format":false,"excerpt":"Cruz marca o local do massacre em Eldorado dos Caraj\u00e1s, Par\u00e1. Foto: Marcello Casal Jr.\/Arquivo ABr CRISTIANO GOLDSCHMIDT H\u00e1 datas que n\u00e3o passam. Ficam suspensas no tempo como poeira vermelha sobre a pele \u2014 insistem, infiltram-se, recusam o esquecimento. Abril, no sul do Par\u00e1, \u00e9 sempre um m\u00eas que arde.\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKo0s-hr","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/1081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/comments?post=1081"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/1081\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/media?parent=1081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/categories?post=1081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/tags?post=1081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}