{"id":1087,"date":"2007-06-11T14:04:39","date_gmt":"2007-06-11T17:04:39","guid":{"rendered":"http:\/\/75.126.185.46\/~jornalja\/?p=1087"},"modified":"2007-06-11T14:04:39","modified_gmt":"2007-06-11T17:04:39","slug":"preconceito-racial","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/colunas\/preconceito-racial\/","title":{"rendered":"Preconceito Racial"},"content":{"rendered":"<p><strong>Christian Lavich Goldschmidt, escritor e ator<\/strong><br \/>\nO Brasil, sin\u00f4nimo de pluralidade racial e multiplicidade cultural, ainda n\u00e3o aprendeu a respeitar os negros de seu pa\u00eds. Embora cada vez mais possamos ver a negritude colorindo as diversas \u00e1reas da sociedade, ainda estamos longe de alcan\u00e7ar a situa\u00e7\u00e3o ideal: a de um Brasil livre do preconceito racial.<br \/>\nOs negros t\u00eam, lentamente, galgado degraus que os conduzem a uma carreira de sucesso. Geralmente \u00e9 comum vermos isso acontecer com aqueles que se dedicam \u00e0s artes ou ao esporte. Mais dif\u00edcil, por\u00e9m, \u00e9 encontrarmos negros m\u00e9dicos, advogados, engenheiros e at\u00e9 mesmo pol\u00edticos. A escassez de \u00e2ncoras negros nos telejornais brasileiros, rep\u00f3rteres e apresentadores, tamb\u00e9m \u00e9 vis\u00edvel. Salvo algumas raras exce\u00e7\u00f5es, a televis\u00e3o brasileira \u00e9 predominantemente branca. Essa disparidade fica ainda mais clara na Bahia, estado brasileiro que concentra a maior parte da popula\u00e7\u00e3o negra de nosso pa\u00eds.<br \/>\nA falta de pol\u00edticas p\u00fablicas que garantam \u00e0 popula\u00e7\u00e3o negra do Brasil o acesso \u00e0 educa\u00e7\u00e3o \u00e9 a maior respons\u00e1vel pela marginaliza\u00e7\u00e3o dos mesmos. Precisamos tirar o contingente negro das mazelas perif\u00e9ricas de nossas cidades. A solu\u00e7\u00e3o est\u00e1, em parte, em proporcionarmos condi\u00e7\u00f5es ideais de moradia, oferecer aos adultos trabalho dignificante, e \u00e0s crian\u00e7as e jovens o direito a uma educa\u00e7\u00e3o de qualidade em turno integral &#8211; porta de entrada para os cursos universit\u00e1rios. Enquanto tivermos uma sociedade dividida entre negros e brancos, onde uns nada t\u00eam e outros tudo podem, continuaremos a sofrer as graves conseq\u00fc\u00eancias da injusti\u00e7a social que prevalece em nosso pa\u00eds. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Christian Lavich Goldschmidt, escritor e ator O Brasil, sin\u00f4nimo de pluralidade racial e multiplicidade cultural, ainda n\u00e3o aprendeu a respeitar os negros de seu pa\u00eds. Embora cada vez mais possamos ver a negritude colorindo as diversas \u00e1reas da sociedade, ainda estamos longe de alcan\u00e7ar a situa\u00e7\u00e3o ideal: a de um Brasil livre do preconceito racial. [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-1087","post","type-post","status-publish","format-standard","hentry","category-analiseopiniao"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":84801,"url":"https:\/\/www.jornalja.com.br\/colunas\/a-lei-aurea-libertou-os-corpos-mas-preservou-as-correntes\/","url_meta":{"origin":1087,"position":0},"title":"A Lei \u00c1urea libertou os corpos, mas preservou as correntes","author":"An\u00e1lise &amp; Opini\u00e3o","date":"13 de maio de 2026","format":false,"excerpt":"Nossa heran\u00e7a africana ocupa um lugar amb\u00edguo demais: \u00e9simultaneamente origem de orgulho cultural e alvo hist\u00f3rico de exclus\u00e3o social. Por Cristiano GoldschmidtH\u00e1 datas que permanecem suspensas sobre um pa\u00eds como umapergunta sem resposta definitiva. O 13 de maio de 1888 \u00e9 umadessas anomalias hist\u00f3ricas: um acontecimento oficialmenteencerrado, mas moralmente inconcluso.\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-7.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-7.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-7.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":84748,"url":"https:\/\/www.jornalja.com.br\/colunas\/a-literatura-brasileira-no-dia-do-trabalhador\/","url_meta":{"origin":1087,"position":1},"title":"A Literatura Brasileira no Dia do Trabalho","author":"An\u00e1lise &amp; Opini\u00e3o","date":"1 de maio de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT O 1\u00ba de maio costuma ser lembrado pelo peso hist\u00f3rico das lutas trabalhistas, pelo som das manifesta\u00e7\u00f5es e pela mem\u00f3ria viva de direitos conquistados ao longo de d\u00e9cadas. No entanto, essa mesma data abriga uma outra forma de celebra\u00e7\u00e3o, menos ruidosa, mas igualmente significativa: o Dia da Literatura\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84737,"url":"https:\/\/www.jornalja.com.br\/colunas\/dia-internacional-da-educacao-o-brasil-que-se-revela-na-sala-de-aula\/","url_meta":{"origin":1087,"position":2},"title":"Dia Internacional da Educa\u00e7\u00e3o: o Brasil que se revela na sala de aula","author":"An\u00e1lise &amp; Opini\u00e3o","date":"28 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT A educa\u00e7\u00e3o n\u00e3o se deixa apreender como um simples conceito est\u00e1vel ou como um consenso j\u00e1 dado. Ela se apresenta, antes, como um campo de tens\u00f5es, no qual se entrecruzam disputas de sentido, sil\u00eancios hist\u00f3ricos e projetos de sociedade. Pensar a educa\u00e7\u00e3o, nesse horizonte, implica reconhecer que educar\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-1.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-1.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84622,"url":"https:\/\/www.jornalja.com.br\/colunas\/13-de-abril-queriam-transformar-o-hino-nacional-em-grito-de-guerra-mas-ele-insiste-em-ser-canto-de-paz\/","url_meta":{"origin":1087,"position":3},"title":"13 de abril: Queriam transformar o Hino Nacional em grito de guerra, mas ele insiste em ser canto de paz","author":"da Reda\u00e7\u00e3o","date":"13 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT No calend\u00e1rio das datas c\u00edvicas, o 13 de abril passa quase em sil\u00eancio, como um acorde sustentado que poucos escutam at\u00e9 o fim. N\u00e3o h\u00e1 fogos, n\u00e3o h\u00e1 desfiles grandiosos, n\u00e3o h\u00e1 a coreografia ensaiada das celebra\u00e7\u00f5es que se imp\u00f5em ao olhar. H\u00e1, antes, uma esp\u00e9cie de pausa\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/imagem-do-poeta-brasileiro-joaquim-osorio-duque-estrada-autor-da-letra-do-hino-nacional-escaneada-do-livro-flora-de-maio-edicao-de-1902.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/imagem-do-poeta-brasileiro-joaquim-osorio-duque-estrada-autor-da-letra-do-hino-nacional-escaneada-do-livro-flora-de-maio-edicao-de-1902.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/imagem-do-poeta-brasileiro-joaquim-osorio-duque-estrada-autor-da-letra-do-hino-nacional-escaneada-do-livro-flora-de-maio-edicao-de-1902.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":84714,"url":"https:\/\/www.jornalja.com.br\/colunas\/22-de-abril-o-instante-em-que-o-brasil-passa-a-existir-para-o-mundo-europeu\/","url_meta":{"origin":1087,"position":4},"title":"22 de abril: o instante em que o Brasil \u201cpassa a existir\u201d para o mundo europeu","author":"Patr\u00edcia Marini","date":"22 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Era 22 de abril de 1500 \u2014 ou, ao menos, \u00e9 assim que nos habituamos a dizer, com a serenidade quase ing\u00eanua de quem domestica o passado em datas redondas e memor\u00e1veis. Naquele dia, a esquadra comandada por Pedro \u00c1lvares Cabral avistou terra ap\u00f3s semanas de travessia pelo\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/desembarque-de-cabral-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/desembarque-de-cabral-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/desembarque-de-cabral-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/desembarque-de-cabral-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/desembarque-de-cabral-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/desembarque-de-cabral-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84725,"url":"https:\/\/www.jornalja.com.br\/colunas\/e-preciso-refletir-sobre-os-mais-de-84-mil-desaparecidos-no-brasil-em-2025\/","url_meta":{"origin":1087,"position":5},"title":"\u00c9 preciso refletir sobre os mais de 84 mil desaparecidos no Brasil em 2025","author":"An\u00e1lise &amp; Opini\u00e3o","date":"23 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Em 2025, o Brasil registrou 84.760 pessoas desaparecidas, segundo dados consolidados pelo Sistema Nacional de Informa\u00e7\u00f5es de Seguran\u00e7a P\u00fablica Sinesp), vinculado ao Minist\u00e9rio da Justi\u00e7a e Seguran\u00e7a P\u00fablica. Mais do que um n\u00famero expressivo, o dado revela um fen\u00f4meno cont\u00ednuo, distribu\u00eddo no tempo e no territ\u00f3rio \u2014 e,\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKo0s-hx","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/1087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/comments?post=1087"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/1087\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/media?parent=1087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/categories?post=1087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/tags?post=1087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}