{"id":1359,"date":"2008-08-08T15:01:55","date_gmt":"2008-08-08T18:01:55","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=1359"},"modified":"2008-08-08T15:01:55","modified_gmt":"2008-08-08T18:01:55","slug":"assaltos-nao-devem-causar-espanto","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/colunas\/assaltos-nao-devem-causar-espanto\/","title":{"rendered":"Assaltos n\u00e3o devem causar espanto."},"content":{"rendered":"<p><em>Policiamento n\u00e3o \u00e9 feito somente com efetivo completo, mas sem efetivo n\u00e3o h\u00e1 policiamento.<\/em><br \/>\nQuando os bandidos assaltaram, ontem, Lisete Feij\u00f3, eles n\u00e3o sabiam que se tratava da esposa do vice-governador do Estado, Paulo Feij\u00f3. No entanto, sabiam que poderiam assaltar, fosse quem fosse, num bairro nobre de Porto Alegre ou num beco de uma vila perif\u00e9rica. Como Lisete \u00e9 uma pessoa de destaque em nossa sociedade, h\u00e1 quem fique espantado. E n\u00e3o h\u00e1 raz\u00e3o para o espanto. Hoje h\u00e1 quadrilhas que atacam com grupos de at\u00e9 uma dezena de membros e o policiamento ostensivo, com gloriosas exce\u00e7\u00f5es, chega apenas depois do fato consumado. \u00c9 verdade que o policiamento n\u00e3o depende, exclusivamente, de efetivo completo nas ruas, mas \u00e9 tamb\u00e9m verdade quem sem efetivo n\u00e3o h\u00e1 policiamento.<br \/>\nE n\u00e3o se pode negar que a pol\u00edcia est\u00e1 trabalhando. Em todo o Estado, em sete meses, deste ano, a Brigada apreendeu 5.200 armas e prendeu 73 mil pessoas. At\u00e9 o fim do ano o n\u00famero de presos dever\u00e1 ser suficiente para lotar o Ol\u00edmpico e o Beira Rio e n\u00e3o tenho id\u00e9ia do local onde poder\u00e1 ser depositado o arsenal que vem por a\u00ed. Mas que armas s\u00e3o essas e com quem estavam? E os presos? Onde est\u00e1 esta multid\u00e3o? A sociedade n\u00e3o quer tantos presos, mas, sim, que sejam presas as pessoas certas.<br \/>\n<strong>Vandalismo<\/strong><br \/>\nA Pol\u00edcia Civil tem pistas que podem levar a localiza\u00e7\u00e3o do grupo que praticou atos de vandalismo em estabelecimentos comerciais na zona norte de Porto Alegre. Mais de dez lojas e pr\u00e9dios tiveram vitrinas e portas quebradas desde a noite desta quarta feira. As a\u00e7\u00f5es ocorreram nas avenidas Nilo Pe\u00e7anha, Carlos Gomes e D.Pedro II. De qualquer forma, estes fatos s\u00e3o reveladores da defici\u00eancia do policiamento ostensivo que \u00e9 realizado, principalmente, na capital e regi\u00e3o metropolitana.<br \/>\n<strong><br \/>\nBrigadianos<\/strong><br \/>\ntr\u00eas bandidos assaltaram, ontem, o posto banc\u00e1rio Sicredi na sede da AsofBM (Associa\u00e7\u00e3o dos Oficiais da Brigada Militar), na travessa Leonardo Truda, no Centro da capital. Os criminosos renderam uma mo\u00e7a na entrada do pr\u00e9dio e obrigaram os vigilantes a abrir a porta do posto que fica no 2\u00b0 andar. O presidente da AsofBM, coronel da reserva Cairo Bueno de Camargo, est\u00e1 inconformado com a sensa\u00e7\u00e3o de inseguran\u00e7a que atinge, inclusive, a fam\u00edlia brigadiana. Agosto tem m\u00e9dia de um ataque por dia contra agencias banc\u00e1rias somente na regi\u00e3o metropolitana.<br \/>\n<strong>Visita<\/strong><br \/>\nO titular da SSP-RS (Secretaria da Seguran\u00e7a P\u00fablica do RS) Edson de Oliveira Goularte, na manh\u00e3 de quinta-feira, visitou o Pal\u00e1cio da Pol\u00edcia. Recebido pelo chefe da Pol\u00edcia Civil, Goularte manteve um conversa informal com toda a c\u00fapula da institui\u00e7\u00e3o. Assim, Goularte come\u00e7a a conhecer, pessoalmente, quem ele vai confirmar e quem ir\u00e1 substituir.<br \/>\n<strong>Surpresa<\/strong><br \/>\nNo 1\u00ba Simp\u00f3sio de Seguran\u00e7a P\u00fablica promovido pelo CPC (Comando de Policiamento da Capital), desenvolvido quarta-feira, das 8h \u00e0s 17h, houve surpresas. Revelo uma: o audit\u00f3rio das torres g\u00eameas do Minist\u00e9rio P\u00fablico, onde ocorreu o evento, estava lotado. Pelo menos 500 PMs, fardados, n\u00e3o contando os membros da banda da corpora\u00e7\u00e3o, estavam presentes, fato comprovado pelos pr\u00f3prios fot\u00f3grafos da Brigada Militar. Inclino-me a crer que estou cometendo alguns equ\u00edvocos ao comentar a car\u00eancia de efetivo na Brigada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Policiamento n\u00e3o \u00e9 feito somente com efetivo completo, mas sem efetivo n\u00e3o h\u00e1 policiamento. Quando os bandidos assaltaram, ontem, Lisete Feij\u00f3, eles n\u00e3o sabiam que se tratava da esposa do vice-governador do Estado, Paulo Feij\u00f3. No entanto, sabiam que poderiam assaltar, fosse quem fosse, num bairro nobre de Porto Alegre ou num beco de uma [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-1359","post","type-post","status-publish","format-standard","hentry","category-analiseopiniao"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":84776,"url":"https:\/\/www.jornalja.com.br\/colunas\/do-conforto-a-frustracao-a-falencia-do-transporte-por-aplicativo\/","url_meta":{"origin":1359,"position":0},"title":"Do conforto \u00e0 frustra\u00e7\u00e3o: a fal\u00eancia do transporte por aplicativo","author":"An\u00e1lise &amp; Opini\u00e3o","date":"7 de maio de 2026","format":false,"excerpt":"O poder p\u00fablico, que deveria atuar como mediador e garantidor de padr\u00f5es m\u00ednimos, parece operar em ritmo lento ou, em alguns casos, simplesmente se omitir. CRISTIANO GOLDSCHMIDT A promessa, no come\u00e7o, parecia quase irrecus\u00e1vel. Quem viveu aquele momento lembra bem da sensa\u00e7\u00e3o de finalmente ter encontrado uma alternativa ao transporte\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84673,"url":"https:\/\/www.jornalja.com.br\/colunas\/40-anos-sem-simone-de-beauvoir-uma-interlocutora-ainda-incomoda-do-presente\/","url_meta":{"origin":1359,"position":1},"title":"40 anos sem Simone de Beauvoir, uma interlocutora ainda inc\u00f4moda do presente","author":"da Reda\u00e7\u00e3o","date":"14 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Quarenta anos ap\u00f3s a morte de Simone de Beauvoir (9 de janeiro de 1908 - 14 de abril de 1986), descubro que sua aus\u00eancia n\u00e3o \u00e9 propriamente um vazio \u2014 \u00e9 antes um rumor cont\u00ednuo, uma esp\u00e9cie de presen\u00e7a indireta que se infiltra nas conversas, nos livros, nas\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/simone-de-beauvoir-memorias-de-uma-menina-bemcomportada.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":84681,"url":"https:\/\/www.jornalja.com.br\/colunas\/recordar-zuzu-angel-50-anos-apos-sua-morte-e-um-ato-etico\/","url_meta":{"origin":1359,"position":2},"title":"Recordar Zuzu Angel 50 anos ap\u00f3s sua morte \u00e9 um ato \u00e9tico","author":"da Reda\u00e7\u00e3o","date":"16 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Cinco d\u00e9cadas transcorreram desde o silenciamento brutal de Zuzu Angel (05 de junho de 1921 - 14 de abril de 1976), e ainda assim sua voz persiste \u2014 n\u00e3o como eco esmaecido, mas como um timbre agudo que rasga o tecido do tempo e se inscreve na mem\u00f3ria\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84590,"url":"https:\/\/www.jornalja.com.br\/colunas\/e-preciso-defender-o-jardim-botanico-de-porto-alegre\/","url_meta":{"origin":1359,"position":3},"title":"\u00c9 preciso defender o Jardim Bot\u00e2nico de Porto Alegre","author":"da Reda\u00e7\u00e3o","date":"8 de mar\u00e7o de 2026","format":false,"excerpt":"CLEBER DIONI TENTARDINI O Jardim Bot\u00e2nico de Porto Alegre (JBPA) tem 67 anos e \u00e9 considerado um dos cinco melhores e maiores do Brasil. Possui 28 cole\u00e7\u00f5es cient\u00edficas que somam mais de 4.200 plantas, incluindo esp\u00e9cies raras, amea\u00e7adas de extin\u00e7\u00e3o e end\u00eamicas, que s\u00e3o encontradas apenas no RS. No local\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84622,"url":"https:\/\/www.jornalja.com.br\/colunas\/13-de-abril-queriam-transformar-o-hino-nacional-em-grito-de-guerra-mas-ele-insiste-em-ser-canto-de-paz\/","url_meta":{"origin":1359,"position":4},"title":"13 de abril: Queriam transformar o Hino Nacional em grito de guerra, mas ele insiste em ser canto de paz","author":"da Reda\u00e7\u00e3o","date":"13 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT No calend\u00e1rio das datas c\u00edvicas, o 13 de abril passa quase em sil\u00eancio, como um acorde sustentado que poucos escutam at\u00e9 o fim. N\u00e3o h\u00e1 fogos, n\u00e3o h\u00e1 desfiles grandiosos, n\u00e3o h\u00e1 a coreografia ensaiada das celebra\u00e7\u00f5es que se imp\u00f5em ao olhar. H\u00e1, antes, uma esp\u00e9cie de pausa\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/imagem-do-poeta-brasileiro-joaquim-osorio-duque-estrada-autor-da-letra-do-hino-nacional-escaneada-do-livro-flora-de-maio-edicao-de-1902.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/imagem-do-poeta-brasileiro-joaquim-osorio-duque-estrada-autor-da-letra-do-hino-nacional-escaneada-do-livro-flora-de-maio-edicao-de-1902.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/imagem-do-poeta-brasileiro-joaquim-osorio-duque-estrada-autor-da-letra-do-hino-nacional-escaneada-do-livro-flora-de-maio-edicao-de-1902.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":84690,"url":"https:\/\/www.jornalja.com.br\/colunas\/17-de-abril-de-1996-30-anos-do-massacre-de-eldorado-do-carajas\/","url_meta":{"origin":1359,"position":5},"title":"17 de abril de 1996: 30 anos do Massacre de Eldorado do Caraj\u00e1s","author":"da Reda\u00e7\u00e3o","date":"17 de abril de 2026","format":false,"excerpt":"Cruz marca o local do massacre em Eldorado dos Caraj\u00e1s, Par\u00e1. Foto: Marcello Casal Jr.\/Arquivo ABr CRISTIANO GOLDSCHMIDT H\u00e1 datas que n\u00e3o passam. Ficam suspensas no tempo como poeira vermelha sobre a pele \u2014 insistem, infiltram-se, recusam o esquecimento. Abril, no sul do Par\u00e1, \u00e9 sempre um m\u00eas que arde.\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKo0s-lV","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/1359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/comments?post=1359"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/1359\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/media?parent=1359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/categories?post=1359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/tags?post=1359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}