{"id":1405,"date":"2008-08-16T16:53:11","date_gmt":"2008-08-16T19:53:11","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=1405"},"modified":"2008-08-16T16:53:11","modified_gmt":"2008-08-16T19:53:11","slug":"as-algemas-e-ambiguidade-da-justica","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/colunas\/as-algemas-e-ambiguidade-da-justica\/","title":{"rendered":"As algemas e ambig\u00fcidade da Justi\u00e7a."},"content":{"rendered":"<p><em>A a\u00e7\u00e3o primeira ser\u00e1 das pol\u00edcias, mas os magistrados decidir\u00e3o sobre os pulsos que mereceram ou n\u00e3o a imobiliza\u00e7\u00e3o com ferros.<\/em><br \/>\nO governo dos EUA e de outros mandat\u00e1rios do planeta defendem os m\u00e9todos de tortura na medida em que a autoridade coatora entender que seja o caminho mais r\u00e1pido para apurar, por exemplo, se um barbudo preso \u00e9 ou n\u00e3o \u00e9 terrorista. Essa discuss\u00e3o \u00e9 levada com seriedade at\u00e9 pelos mais fervorosos crist\u00e3os. Durante o per\u00edodo da inquisi\u00e7\u00e3o, ensaiar qualquer tipo de desacato a um frade, estufado de comilan\u00e7a com vinhos, significava um atentado contra Deus e tratava-se, tamb\u00e9m, de assunto da maior seriedade que, invariavelmente, se consagrava na incinera\u00e7\u00e3o do autor do delito.  Hoje, contestar o Poder Judici\u00e1rio, especialmente os tribunais superiores, \u00e9 considerado por uma boa parte dos magistrados, como uma posi\u00e7\u00e3o her\u00e9tica, um atentado contra as cabe\u00e7as que atingiram a m\u00e1xima luz, com as b\u00ean\u00e7\u00e3os dos partidos pol\u00edticos que est\u00e3o no poder, no campo do Direito. Assim \u00e9 que o iluminado STF (Supremo Tribunal Federal) decidiu, com inusitada agilidade, regras limitadores para o uso de algemas com a certeza, \u00e9 claro, de que o pa\u00eds inteiro, segundo a concep\u00e7\u00e3o de suas excel\u00eancias, dever\u00e1 se persignar diante deste dogma.<br \/>\nA sociedade quer leis mais rigorosas e mais pres\u00eddios. Um maior n\u00famero de casas prisionais, com a estrutura m\u00ednima exig\u00edvel, poderia permitir, tamb\u00e9m, a humaniza\u00e7\u00e3o da pol\u00edtica penitenci\u00e1ria. E o Judici\u00e1rio responde a este clamor com uma hip\u00f3crita disciplina no uso de algemas, claramente dirigida para os bandidos de colarinho branco. Sigam-me.<br \/>\n<strong> O negr\u00e3o e o banqueiro<\/strong><br \/>\nA decis\u00e3o do STF \u00e9 de m\u00e1xima ambig\u00fcidade. As algemas poder\u00e3o ser utilizadas em situa\u00e7\u00f5es em que houver resist\u00eancia \u00e0 pris\u00e3o, risco de fuga e possibilidade de agress\u00e3o ao agente da lei, assim como para preservar a integridade f\u00edsica do preso. Ora, quem decide a gravidade da situa\u00e7\u00e3o \u00e9 o agente que est\u00e1 frente a frente com o autor do delito, mas quem dar\u00e1 a palavra final se a a\u00e7\u00e3o do agente foi ou n\u00e3o foi correta ser\u00e1 o magistrado sob a sua capa preta, em ambiente climatizado, enfrentando apenas as folhas do processo e com direito a cafezinhos e coisas outras. Resultado final: o negr\u00e3o detido em atitude suspeita, na Vila Umbu, nunca se livrar\u00e1 das algemas, mas o banqueiro ladr\u00e3o, bacharel em alguma coisa, gente fina, ter\u00e1 adrede cobertura de suas excel\u00eancias da corte m\u00e1xima do pa\u00eds para manter seus pulsinhos soltinhos.<br \/>\n<strong>Cidadania<\/strong><br \/>\nVez por outra tenho citado que h\u00e1 um movimento nacional, absolutamente democr\u00e1tico, no qual o Rio Grande se destaca atrav\u00e9s de um grupo de jovens magistrados, que peleia no sentido do direito de voto para todos os apenados. O objetivo maior \u00e9 o de que os presidi\u00e1rios tenham direito de eleger e de serem eleitos. O primeiro passo \u00e9 levar os cidad\u00e3os presos para o Legislativo e, com isso, estar\u00e1 aberto, naturalmente, o caminho para o Executivo. \u00c9 poss\u00edvel que esse movimento pelo resgate dos direitos plenos de cidadania para os criminosos venham a eliminar, definitivamente, o uso de algemas.<br \/>\n<strong>Assalto<\/strong><br \/>\nTr\u00eas homens assaltaram, ontem, uma joalheria em Tr\u00eas de Maio, na Regi\u00e3o Noroeste do Estado. Duas funcion\u00e1rias foram rendidas pelos bandidos e trancadas no banheiro.<br \/>\n<strong>Assassinato<\/strong><br \/>\nUm homem foi morto no bairro Vila Nova, em Porto Alegre, por volta das 21h desta sexta-feira. R\u00e9gis da Rosa Cambraia, 26 anos, foi encontrado ca\u00eddo ao lado de uma moto Honda Titan, na avenida Bel\u00e9m Velho, com um tiro no peito.<br \/>\n<strong>Execu\u00e7\u00e3o<\/strong><br \/>\nO corpo de um homem ainda n\u00e3o identificado foi encontrado, na manh\u00e3 de ontem, dentro de um saco de lixo em Viam\u00e3o. Segundo a Brigada Militar, o cad\u00e1ver estava com os p\u00e9s e m\u00e3os amarrados com fios de luz. Todas as circunst\u00e2ncias indicam uma execu\u00e7\u00e3o.<br \/>\n<strong> Felicidade<\/strong><br \/>\nAntes da greve dos agentes penitenci\u00e1rios, que se prolongou por 35 dias, o policiamento ostensivo no Estado, sempre com destaque para Porto Alegre e Regi\u00e3o Metropolitana, era sofr\u00edvel. Com a greve, aproximadamente 500 PMs, muitos deles lotados no interior, sa\u00edram das ruas para cuidar da seguran\u00e7a das casas prisionais. Por uma dedu\u00e7\u00e3o l\u00f3gica, durante 35 dias, de sofr\u00edvel, a\u00e7\u00e3o da Brigada Militar, nas ruas, ficou pior ainda. Agora, os 500 PMs retornaram para as ruas. Por uma dedu\u00e7\u00e3o l\u00f3gica, o policiamento, felizmente, retornou ao seu est\u00e1gio sofr\u00edvel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A a\u00e7\u00e3o primeira ser\u00e1 das pol\u00edcias, mas os magistrados decidir\u00e3o sobre os pulsos que mereceram ou n\u00e3o a imobiliza\u00e7\u00e3o com ferros. O governo dos EUA e de outros mandat\u00e1rios do planeta defendem os m\u00e9todos de tortura na medida em que a autoridade coatora entender que seja o caminho mais r\u00e1pido para apurar, por exemplo, se [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-1405","post","type-post","status-publish","format-standard","hentry","category-analiseopiniao"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":84673,"url":"https:\/\/www.jornalja.com.br\/colunas\/40-anos-sem-simone-de-beauvoir-uma-interlocutora-ainda-incomoda-do-presente\/","url_meta":{"origin":1405,"position":0},"title":"40 anos sem Simone de Beauvoir, uma interlocutora ainda inc\u00f4moda do presente","author":"da Reda\u00e7\u00e3o","date":"14 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Quarenta anos ap\u00f3s a morte de Simone de Beauvoir (9 de janeiro de 1908 - 14 de abril de 1986), descubro que sua aus\u00eancia n\u00e3o \u00e9 propriamente um vazio \u2014 \u00e9 antes um rumor cont\u00ednuo, uma esp\u00e9cie de presen\u00e7a indireta que se infiltra nas conversas, nos livros, nas\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/simone-de-beauvoir-memorias-de-uma-menina-bemcomportada.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":84742,"url":"https:\/\/www.jornalja.com.br\/colunas\/rejeicao-a-messias-quando-o-senado-tensiona-os-limites-da-democracia\/","url_meta":{"origin":1405,"position":1},"title":"Rejei\u00e7\u00e3o a Messias: quando o Senado tensiona os limites da democracia","author":"An\u00e1lise &amp; Opini\u00e3o","date":"30 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT A rejei\u00e7\u00e3o, pelo Senado, da indica\u00e7\u00e3o de Jorge Messias ao Supremo Tribunal Federal n\u00e3o \u00e9 um fato trivial \u2014 e trat\u00e1-la como um simples exerc\u00edcio de independ\u00eancia institucional seria, no m\u00ednimo, ing\u00eanuo. H\u00e1 algo mais profundo em jogo. O epis\u00f3dio exp\u00f5e, com certa nitidez, a forma como parcelas\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84622,"url":"https:\/\/www.jornalja.com.br\/colunas\/13-de-abril-queriam-transformar-o-hino-nacional-em-grito-de-guerra-mas-ele-insiste-em-ser-canto-de-paz\/","url_meta":{"origin":1405,"position":2},"title":"13 de abril: Queriam transformar o Hino Nacional em grito de guerra, mas ele insiste em ser canto de paz","author":"da Reda\u00e7\u00e3o","date":"13 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT No calend\u00e1rio das datas c\u00edvicas, o 13 de abril passa quase em sil\u00eancio, como um acorde sustentado que poucos escutam at\u00e9 o fim. N\u00e3o h\u00e1 fogos, n\u00e3o h\u00e1 desfiles grandiosos, n\u00e3o h\u00e1 a coreografia ensaiada das celebra\u00e7\u00f5es que se imp\u00f5em ao olhar. H\u00e1, antes, uma esp\u00e9cie de pausa\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/imagem-do-poeta-brasileiro-joaquim-osorio-duque-estrada-autor-da-letra-do-hino-nacional-escaneada-do-livro-flora-de-maio-edicao-de-1902.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/imagem-do-poeta-brasileiro-joaquim-osorio-duque-estrada-autor-da-letra-do-hino-nacional-escaneada-do-livro-flora-de-maio-edicao-de-1902.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/imagem-do-poeta-brasileiro-joaquim-osorio-duque-estrada-autor-da-letra-do-hino-nacional-escaneada-do-livro-flora-de-maio-edicao-de-1902.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":84748,"url":"https:\/\/www.jornalja.com.br\/colunas\/a-literatura-brasileira-no-dia-do-trabalhador\/","url_meta":{"origin":1405,"position":3},"title":"A Literatura Brasileira no Dia do Trabalho","author":"An\u00e1lise &amp; Opini\u00e3o","date":"1 de maio de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT O 1\u00ba de maio costuma ser lembrado pelo peso hist\u00f3rico das lutas trabalhistas, pelo som das manifesta\u00e7\u00f5es e pela mem\u00f3ria viva de direitos conquistados ao longo de d\u00e9cadas. No entanto, essa mesma data abriga uma outra forma de celebra\u00e7\u00e3o, menos ruidosa, mas igualmente significativa: o Dia da Literatura\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84681,"url":"https:\/\/www.jornalja.com.br\/colunas\/recordar-zuzu-angel-50-anos-apos-sua-morte-e-um-ato-etico\/","url_meta":{"origin":1405,"position":4},"title":"Recordar Zuzu Angel 50 anos ap\u00f3s sua morte \u00e9 um ato \u00e9tico","author":"da Reda\u00e7\u00e3o","date":"16 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Cinco d\u00e9cadas transcorreram desde o silenciamento brutal de Zuzu Angel (05 de junho de 1921 - 14 de abril de 1976), e ainda assim sua voz persiste \u2014 n\u00e3o como eco esmaecido, mas como um timbre agudo que rasga o tecido do tempo e se inscreve na mem\u00f3ria\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84703,"url":"https:\/\/www.jornalja.com.br\/colunas\/tiradentes-o-martir-que-ainda-nos-observa-e-as-inquietacoes-de-um-brasil-inacabado\/","url_meta":{"origin":1405,"position":5},"title":"Tiradentes: o M\u00e1rtir que ainda nos observa e as inquieta\u00e7\u00f5es de um Brasil inacabado","author":"da Reda\u00e7\u00e3o","date":"21 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT H\u00e1 datas que n\u00e3o se imp\u00f5em pelo alarde, mas pela persist\u00eancia silenciosa com que atravessam os s\u00e9culos e se insinuam na consci\u00eancia coletiva. O 21 de abril pertence a essa estirpe discreta. N\u00e3o chega ornado de euforia, tampouco se anuncia com a grandiloqu\u00eancia de outras celebra\u00e7\u00f5es; antes, aproxima-se\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKo0s-mF","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/1405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/comments?post=1405"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/1405\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/media?parent=1405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/categories?post=1405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/tags?post=1405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}