{"id":1410,"date":"2008-08-18T13:29:53","date_gmt":"2008-08-18T16:29:53","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=1410"},"modified":"2008-08-18T13:29:53","modified_gmt":"2008-08-18T16:29:53","slug":"legislativo-municipal-visitado-por-bandidos-2","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/colunas\/legislativo-municipal-visitado-por-bandidos-2\/","title":{"rendered":"Legislativo municipal visitado por bandidos."},"content":{"rendered":"<p>Assalto contra um pr\u00e9dio p\u00fablico \u00e9 indicativo da tranq\u00fcilidade com que avan\u00e7a a organiza\u00e7\u00e3o da bandidagem.<br \/>\nTr\u00eas casas banc\u00e1rias foram atacadas, ontem, na Capital. A unidade do Banrisul instalada na C\u00e2mara Municipal, invadida por quatro bandidos, d\u00e1 uma id\u00e9ia da tranq\u00fcilidade com que o crime organizado est\u00e1 crescendo em Porto Alegre e na Regi\u00e3o Metropolitana. Os quadrilheiros que estiveram no Legislativo municipal fugiram em um autom\u00f3vel Astra que foi abandonado, n\u00e3o muito longe dali, na rua Washington Lu\u00eds. Tudo est\u00e1 f\u00e1cil demais para os bandidos que realizam levantamentos, escolhem a hora de atacar um pr\u00e9dio p\u00fablico e escapam endinheirados e ilesos. E a partir de ontem, com m\u00e1xima certeza, passam a ser tomadas provid\u00eancias para que novas invas\u00f5es da bandidagem n\u00e3o ocorram no Legislativo municipal, o que, simplesmente, comprovar\u00e1, que os nossos ilustres vereadores ainda n\u00e3o sabem bem em que cidade est\u00e3o vivendo. Sigam-me.<br \/>\n<strong>Nobreza<\/strong><br \/>\nNa Benjamim Constant, tr\u00eas criminosos tentaram assaltar a ag\u00eancia do Sicred. Houve trocas de tiros quando o trio deixava o banco. Um dos bandidos foi preso. Durante um assalto, praticado por dois bandidos de moto, ocorrido contra uma ag\u00eancia do Bradesco, na avenida Carlos Gomes, o apresentador de televis\u00e3o Fernando Vieira resultou baleado na perna esquerda pelos motoqueiros. Fernando ingressou na inc\u00f4moda, para o poder p\u00fablico, estat\u00edstica das v\u00edtimas da bandidagem ao cometer a temeridade de circular numa zona nobre de Porto Alegre.<br \/>\n<strong> Jogatina<\/strong><br \/>\nEnquanto quadrilhas se formam e todo o Estado para assaltar cidad\u00e3os nas ruas, motoristas, transporte coletivo, resid\u00eancias, empresas, bancos, propriedades rurais, a pol\u00edcia continua mantendo em atividade for\u00e7as-tarefas para combater algumas \u00e1reas da jogatina, excetuando-se, evidentemente, os antros monitorados pela Caixa Federal.<br \/>\n<strong> Passeata<\/strong><br \/>\nAmanh\u00e3, a partir das 17 horas, familiares e amigos de Rodrigo de Almeida Carvalho, 28 anos, assassinado no dia 17 de agosto de 2006, promover\u00e3o uma passeata na travessa Miranda e Castro, bairro Santana e, \u00e0s 18h, ser\u00e1 celebrada uma missa na igreja Santa Terezinha. Rodrigo foi morto com um tiro no peito por seu vizinho, Wagner Lemos Medeiros quando comemorava a conquista da copa Libertadores pelo Inter. O processo, que tramita na 2\u00aa vara do J\u00fari, tem na assist\u00eancia da acusa\u00e7\u00e3o do criminalista Antonio Carlos C\u00f4rtes. O caso, de grande repercuss\u00e3o na \u00e9poca, teria conota\u00e7\u00e3o racista e n\u00e3o club\u00edstica, pois o autor do crime era tido tamb\u00e9m como torcedor do Inter.<br \/>\n<strong> Casal<\/strong><br \/>\nAgentes do Denarc prenderam um casal que vendia drogas a menos de 100 metros de uma escola na Vila dos Sargentos, bairro Serraria, Zona Sul de Porto Alegre. Roberto de Oliveira Mendes de 50 anos e Maria de Lurdes Mendes de 51 estavam numa casa em que foram apreendidas 40 pedras de Crack, 200 gramas de maconha, uma balan\u00e7a de precis\u00e3o al\u00e9m de telefones celulares e bolsas furtadas.<br \/>\n<strong> Palestra<\/strong><br \/>\nO Iargs (Instituto dos Advogados do RS) promover\u00e1 na pr\u00f3xima ter\u00e7a-feira,  dia 19, \u00e0s 12 horas, em sua sede, a palestra \u201cExecu\u00e7\u00e3o de alimentos e as Leis 11.232\/05 e 11.382\/06\u201d, que ser\u00e1 proferida por  Maria In\u00eas Linck. O evento  \u00e9 aberto ao p\u00fablico e tem entrada franca na travessa Acelino de Carvalho, 21. Maiores informa\u00e7\u00f5es pelo fone (051) 3224.5788, www.iargs.com.br e iargs@iargs.com.br.<br \/>\n<strong> Pres\u00eddios<\/strong><br \/>\nA greve dos agentes penitenci\u00e1rios chegou ao fim, ontem, e serviu para ressaltar dois pontos principais: a atrasada pol\u00edtica do governo no trato do sistema penitenci\u00e1rio e a for\u00e7a adquirida pelos profissionais dessa \u00e1rea gerada, exatamente, pela incompet\u00eancia dos governantes. A greve acabou, mas os problemas continuam latentes. Com o final da greve, o governo ressaltou que as 91 casas prisionais em funcionamento no Estado \u201cretornam a sua normalidade\u201d a partir de hoje. Resta saber o que o governo entende como \u201cnormalidade\u201d no sistema penitenci\u00e1rio.<br \/>\n<strong>Passo<\/strong><br \/>\nUma vez considerado como encerrado o epis\u00f3dio do sistema penitenci\u00e1rio, \u00e9 de se esperar que o titular da Seguran\u00e7a P\u00fablica, Edson de Oliveira Goularte, coloque em pr\u00e1tica as id\u00e9ias que o levaram a ser escolhido para o cargo. Ningu\u00e9m espera por um passo de m\u00e1gica, mas, no m\u00ednimo, a expectativa \u00e9 de um passo \u00e0 frente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Assalto contra um pr\u00e9dio p\u00fablico \u00e9 indicativo da tranq\u00fcilidade com que avan\u00e7a a organiza\u00e7\u00e3o da bandidagem. Tr\u00eas casas banc\u00e1rias foram atacadas, ontem, na Capital. A unidade do Banrisul instalada na C\u00e2mara Municipal, invadida por quatro bandidos, d\u00e1 uma id\u00e9ia da tranq\u00fcilidade com que o crime organizado est\u00e1 crescendo em Porto Alegre e na Regi\u00e3o Metropolitana. [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-1410","post","type-post","status-publish","format-standard","hentry","category-analiseopiniao"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":84761,"url":"https:\/\/www.jornalja.com.br\/colunas\/cmpc-nova-fabrica-velhos-impactos\/","url_meta":{"origin":1410,"position":0},"title":"CMPC: Nova f\u00e1brica, velhos impactos?","author":"Cleber Dioni Tentardini","date":"6 de maio de 2026","format":false,"excerpt":"EDUARDO RAGUSE* Por volta das 13h40, do dia 05 de maio de 2026, ocorreu a despressuriza\u00e7\u00e3o de emerg\u00eancia da caldeira da f\u00e1brica de celulose da empresa CMPC, no munic\u00edpio de Gua\u00edba. O evento causou grande susto e apreens\u00e3o entre os moradores do entorno da ind\u00fastria devido ao ru\u00eddo fort\u00edssimo, odor\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":84590,"url":"https:\/\/www.jornalja.com.br\/colunas\/e-preciso-defender-o-jardim-botanico-de-porto-alegre\/","url_meta":{"origin":1410,"position":1},"title":"\u00c9 preciso defender o Jardim Bot\u00e2nico de Porto Alegre","author":"da Reda\u00e7\u00e3o","date":"8 de mar\u00e7o de 2026","format":false,"excerpt":"CLEBER DIONI TENTARDINI O Jardim Bot\u00e2nico de Porto Alegre (JBPA) tem 67 anos e \u00e9 considerado um dos cinco melhores e maiores do Brasil. Possui 28 cole\u00e7\u00f5es cient\u00edficas que somam mais de 4.200 plantas, incluindo esp\u00e9cies raras, amea\u00e7adas de extin\u00e7\u00e3o e end\u00eamicas, que s\u00e3o encontradas apenas no RS. No local\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84693,"url":"https:\/\/www.jornalja.com.br\/colunas\/fim-da-escala-6x1-cabe-ao-congresso-decidir-entre-o-progresso-e-o-atraso\/","url_meta":{"origin":1410,"position":2},"title":"Fim da escala 6&#215;1: cabe ao Congresso decidir entre o progresso e o atraso","author":"da Reda\u00e7\u00e3o","date":"20 de abril de 2026","format":false,"excerpt":"Plen\u00e1rio da C\u00e2mara dos Deputados durante sess\u00e3o solene do Congresso Nacional. Caber\u00e1 ao parlamento a decis\u00e3o final sobre a nova escala de trabalho. Foto: Leopoldo Silva\/Ag\u00eancia Senado CRISTIANO GOLDSCHMIDT A discuss\u00e3o sobre o fim da escala de trabalho 6x1 no Brasil tem ganhado centralidade no debate p\u00fablico contempor\u00e2neo por tocar\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84609,"url":"https:\/\/www.jornalja.com.br\/colunas\/o-centro-historico-de-porto-alegre\/","url_meta":{"origin":1410,"position":3},"title":"O Centro (Hist\u00f3rico) de Porto Alegre","author":"Cleber Dioni Tentardini","date":"30 de mar\u00e7o de 2026","format":false,"excerpt":"CLEBER DIONI TENTARDINI Porto Alegre, nove horas da manh\u00e3 do dia\u00a030\u00a0de mar\u00e7o de 2026. No \"cora\u00e7\u00e3o\" do\u00a0Centro - que j\u00e1\u00a0foi hist\u00f3rico em tempos passados,\u00a0e limpo\u00a0-,\u00a0em um trecho de\u00a0cerca de\u00a0500 metros, entre as ruas General C\u00e2mara e Senhor dos Passos, existem mais de 50 im\u00f3veis comerciais de porta de rua fechados,\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":84742,"url":"https:\/\/www.jornalja.com.br\/colunas\/rejeicao-a-messias-quando-o-senado-tensiona-os-limites-da-democracia\/","url_meta":{"origin":1410,"position":4},"title":"Rejei\u00e7\u00e3o a Messias: quando o Senado tensiona os limites da democracia","author":"An\u00e1lise &amp; Opini\u00e3o","date":"30 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT A rejei\u00e7\u00e3o, pelo Senado, da indica\u00e7\u00e3o de Jorge Messias ao Supremo Tribunal Federal n\u00e3o \u00e9 um fato trivial \u2014 e trat\u00e1-la como um simples exerc\u00edcio de independ\u00eancia institucional seria, no m\u00ednimo, ing\u00eanuo. H\u00e1 algo mais profundo em jogo. O epis\u00f3dio exp\u00f5e, com certa nitidez, a forma como parcelas\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84632,"url":"https:\/\/www.jornalja.com.br\/colunas\/medicos-alertam-para-os-riscos-a-saude-de-nova-fabrica-de-celulose-da-cmpc\/","url_meta":{"origin":1410,"position":5},"title":"M\u00e9dicos alertam para os riscos \u00e0 sa\u00fade de nova f\u00e1brica de celulose da CMPC","author":"Cleber Dioni Tentardini","date":"14 de abril de 2026","format":false,"excerpt":"ROSELAINE MURLIK * Represento um grupo de profissionais da medicina que, h\u00e1 alguns anos, estuda os diferentes impactos das mudan\u00e7as clim\u00e1ticas e da polui\u00e7\u00e3o ambiental nos ecossistemas na sa\u00fade humana e do planeta. Causa preocupa\u00e7\u00e3o o novo megaempreendimento de celulose da empresa chilena CMPC em Barra do Ribeiro (RS), pr\u00f3ximo\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/comite-contra-celulose.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKo0s-mK","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/1410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/comments?post=1410"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/1410\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/media?parent=1410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/categories?post=1410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/tags?post=1410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}