{"id":1537,"date":"2008-09-03T02:09:10","date_gmt":"2008-09-03T05:09:10","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=1537"},"modified":"2008-09-03T02:09:10","modified_gmt":"2008-09-03T05:09:10","slug":"indecisoes-na-pasta-da-seguranca","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/colunas\/indecisoes-na-pasta-da-seguranca\/","title":{"rendered":"Indecis\u00f5es na pasta da Seguran\u00e7a"},"content":{"rendered":"<p><em>Mais do que os funcion\u00e1rios mais humildes, a modorra doa executivos da seguran\u00e7a p\u00fablica atinge a sociedade.<\/em><br \/>\nA situa\u00e7\u00e3o dos pra\u00e7as da Brigada Militar que prestam servi\u00e7o no Disp (De-partamento de Intelig\u00eancia da Secretaria da Seguran\u00e7a) n\u00e3o \u00e9 c\u00f4moda, co-mo de resto acontece com toda a \u00e1rea da pasta da Seguran\u00e7a. Eles n\u00e3o per-cebem FGs (remunera\u00e7\u00e3o por fun\u00e7\u00e3o gratificada), privil\u00e9gio de poucos, nem horas-extras, apesar da carga-hor\u00e1ria excessiva. H\u00e1 cinco meses que esses profissionais n\u00e3o recebem etapas de alimenta\u00e7\u00e3o e, nisso, vale um jogo de empurra entre o comando geral da Brigada Militar e a c\u00fapula da SSP-RS (Secretaria da Seguran\u00e7a P\u00fablica). Isso causa um grau de insatisfa-\u00e7\u00e3o do efetivo lotado naquele departamento que des\u00e1gua na sociedade, pois \u00e9 a partir dali que s\u00e3o prestados servi\u00e7os como o do disque-den\u00fancia, por exemplo. Cabe salientar que chegou a sair no Di\u00e1rio oficial do Estado de 30 de julho passado, a Portaria de n\u00ba 109\/2008, regulamentando as etapas de alimenta\u00e7\u00e3o, assinada por Jos\u00e9 Francisco Malmann. No entanto, a Bri-gada fez vistas grossas para a publica\u00e7\u00e3o ao alegar que Mallmann j\u00e1 era. Sigam-me.<br \/>\n<strong> O pato<\/strong><br \/>\nAl\u00e9m da car\u00eancia de efetivo e do arrastado apoio log\u00edstico, a seguran\u00e7a p\u00fablica \u00e9 permeada por procrastina\u00e7\u00e3o de decis\u00f5es que influenciam na me-sa de cada servidor, protecionismo em rela\u00e7\u00e3o a apadrinhados em desvio de fun\u00e7\u00e3o, o que tem a cobertura dos Tr\u00eas Poderes e at\u00e9 mesmo por fantasias futur\u00edsticas. Tudo isso leva a alimentar a boataria de que tudo est\u00e1 sendo feito, entre v\u00e1rios setores das organiza\u00e7\u00f5es policiais, no sentido de encami-nhar a extin\u00e7\u00e3o da pasta da Seguran\u00e7a. No entanto, no frigir dos ovos, quem paga o pato nesse processo s\u00e3o os servidores mais humildes e, muito mais ainda, a sociedade.<br \/>\n<strong> Ponto<\/strong><br \/>\nA Brigada Militar descobriu um ponto de tr\u00e1fico de drogas no  Jardim Aparecida, em Alvorada.  Sete homens, com idades entre 19 e 30 anos, fo-ram presos. Os policiais apreenderam uma pistola, um rev\u00f3lver, drogas e 14 telefones celulares.<br \/>\n<strong> Quadrilheiros<\/strong><br \/>\nSete pessoas foram presas em opera\u00e7\u00e3o desenvolvida pelo Deic, em Es-teio. O grupo \u00e9 apontado como respons\u00e1vel por clonar autom\u00f3veis rouba-dos, falsificar documentos e  vender os ve\u00edculos por meio de an\u00fancios em classificados. Seis pessoas foram detidas no bairro Primavera e outra em Alvorada. Foram apreendidos carros e dois rev\u00f3lveres. Segundo o delegado Heliomar Franco, os quadrilheiros se passavam por funcion\u00e1rios do f\u00f3rum central de Porto Alegre e da Receita Federal para vender os produtos com valor abaixo do mercado.<br \/>\n<strong> Mutir\u00e3o<\/strong><br \/>\nUm mutir\u00e3o cartor\u00e1rio da Pol\u00edcia Civil, em Porto Alegre, teve encerradas as atividades do m\u00eas de agosto. Dos 1.825 inqu\u00e9ritos distribu\u00eddos, 851 fo-ram conclu\u00eddos. Ao todo foram indiciadas 616 pessoas Segundo o delegado Miguel Mendes Ribeiro Neto, coordenador do mutir\u00e3o no m\u00eas de agosto, desde o in\u00edcio de junho foram remetidos \u00e0 Justi\u00e7a 2.719 inqu\u00e9ritos polici-ais.<br \/>\n<strong> Lei de Tr\u00e2nsito<\/strong><br \/>\nA Acadepol (Academia de Pol\u00edcia Civil) promover\u00e1, amanh\u00e3, a partir das 14horas, no Audit\u00f3rio da SSP-RS, uma palestra com o jurista Dam\u00e1sio E-vangelista de Jesus. O tema a ser abordado \u00e9 a repercuss\u00e3o penal da nova Lei de Tr\u00e2nsito. O evento resulta de uma parceria da Acadepol com a OAB\/RS.<br \/>\n<strong> Vales<\/strong><br \/>\nQuatro homens roubaram, ontem, 200 mil reais em vale transporte no hospital da Crian\u00e7a Concei\u00e7\u00e3o em Porto Alegre. \u00c9 espantoso que a maioria desses vales s\u00e3o vendidos abertamente nas proximidades dos terminais de transporte coletivo da Capital e Regi\u00e3o Metropolitana.<br \/>\n<strong> Banco<\/strong><br \/>\nQuatro homens assaltaram, ontem, a ag\u00eancia do Banrisul no centro de Tenente Portela, na Fronteira Oeste ga\u00facha. O seguran\u00e7a do banco ficou ferido, mas est\u00e1 fora de perigo. Os ladr\u00f5es fugiram em um Golf em dire\u00e7\u00e3o a Miragua\u00ed.<br \/>\n<strong> Idosos<\/strong><br \/>\nMaria In\u00eas de Castro Gon\u00e7alves e Vin\u00edcius Montag, escriv\u00e3es de pol\u00edcia lotados na DP para o Idoso, da capital, ministrar\u00e3o, hoje, uma palestra para o grupo da terceira idade \u201cOs Pioneiros\u201d. Tendo como tema a seguran\u00e7a, o evento acontecer\u00e1 a partir das 9h na sede do Clube Comercial Sarandi, lo-calizada na Avenida Salvador Le\u00e3o, n\u00ba 277, bairro Sarandi, em Porto Ale-gre.<br \/>\n<strong> Paralisa\u00e7\u00e3o<\/strong><br \/>\nOs agentes da Pol\u00edcia Civil do interior ga\u00facho paralisar\u00e3o suas atividades nos dias hoje e amanh\u00e3. Neste per\u00edodo s\u00f3 ser\u00e3o registradas ocorr\u00eancias (in-clusive flagrantes) de crimes com maior repercuss\u00e3o. O Sindicato dos Es-criv\u00e3es, Inspetores e Investigadores de Pol\u00edcia do Rio Grande do Sul apre-sentou as reivindica\u00e7\u00f5es ao secret\u00e1rio Edson de Oliveira Goularte, mas n\u00e3o houve, manifesta\u00e7\u00e3o sobre o atendimento das demandas. Nos dias 1\u00ba e 2 de outubro, a paralisa\u00e7\u00e3o ser\u00e1 feita na capital e regi\u00e3o metropolitana. Nos dias de protesto, ser\u00e3o registrados os crimes de latroc\u00ednio, homic\u00eddio, les\u00e3o cor-poral grave, estupro, atentado violento ao pudor e todas as ocorr\u00eancias que tiverem menores e\/ou idosos entre as v\u00edtimas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mais do que os funcion\u00e1rios mais humildes, a modorra doa executivos da seguran\u00e7a p\u00fablica atinge a sociedade. A situa\u00e7\u00e3o dos pra\u00e7as da Brigada Militar que prestam servi\u00e7o no Disp (De-partamento de Intelig\u00eancia da Secretaria da Seguran\u00e7a) n\u00e3o \u00e9 c\u00f4moda, co-mo de resto acontece com toda a \u00e1rea da pasta da Seguran\u00e7a. Eles n\u00e3o per-cebem FGs [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-1537","post","type-post","status-publish","format-standard","hentry","category-analiseopiniao"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":84776,"url":"https:\/\/www.jornalja.com.br\/colunas\/do-conforto-a-frustracao-a-falencia-do-transporte-por-aplicativo\/","url_meta":{"origin":1537,"position":0},"title":"Do conforto \u00e0 frustra\u00e7\u00e3o: a fal\u00eancia do transporte por aplicativo","author":"An\u00e1lise &amp; Opini\u00e3o","date":"7 de maio de 2026","format":false,"excerpt":"O poder p\u00fablico, que deveria atuar como mediador e garantidor de padr\u00f5es m\u00ednimos, parece operar em ritmo lento ou, em alguns casos, simplesmente se omitir. CRISTIANO GOLDSCHMIDT A promessa, no come\u00e7o, parecia quase irrecus\u00e1vel. Quem viveu aquele momento lembra bem da sensa\u00e7\u00e3o de finalmente ter encontrado uma alternativa ao transporte\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84761,"url":"https:\/\/www.jornalja.com.br\/colunas\/cmpc-nova-fabrica-velhos-impactos\/","url_meta":{"origin":1537,"position":1},"title":"CMPC: Nova f\u00e1brica, velhos impactos?","author":"Cleber Dioni Tentardini","date":"6 de maio de 2026","format":false,"excerpt":"EDUARDO RAGUSE* Por volta das 13h40, do dia 05 de maio de 2026, ocorreu a despressuriza\u00e7\u00e3o de emerg\u00eancia da caldeira da f\u00e1brica de celulose da empresa CMPC, no munic\u00edpio de Gua\u00edba. O evento causou grande susto e apreens\u00e3o entre os moradores do entorno da ind\u00fastria devido ao ru\u00eddo fort\u00edssimo, odor\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":84725,"url":"https:\/\/www.jornalja.com.br\/colunas\/e-preciso-refletir-sobre-os-mais-de-84-mil-desaparecidos-no-brasil-em-2025\/","url_meta":{"origin":1537,"position":2},"title":"\u00c9 preciso refletir sobre os mais de 84 mil desaparecidos no Brasil em 2025","author":"An\u00e1lise &amp; Opini\u00e3o","date":"23 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Em 2025, o Brasil registrou 84.760 pessoas desaparecidas, segundo dados consolidados pelo Sistema Nacional de Informa\u00e7\u00f5es de Seguran\u00e7a P\u00fablica Sinesp), vinculado ao Minist\u00e9rio da Justi\u00e7a e Seguran\u00e7a P\u00fablica. Mais do que um n\u00famero expressivo, o dado revela um fen\u00f4meno cont\u00ednuo, distribu\u00eddo no tempo e no territ\u00f3rio \u2014 e,\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84693,"url":"https:\/\/www.jornalja.com.br\/colunas\/fim-da-escala-6x1-cabe-ao-congresso-decidir-entre-o-progresso-e-o-atraso\/","url_meta":{"origin":1537,"position":3},"title":"Fim da escala 6&#215;1: cabe ao Congresso decidir entre o progresso e o atraso","author":"da Reda\u00e7\u00e3o","date":"20 de abril de 2026","format":false,"excerpt":"Plen\u00e1rio da C\u00e2mara dos Deputados durante sess\u00e3o solene do Congresso Nacional. Caber\u00e1 ao parlamento a decis\u00e3o final sobre a nova escala de trabalho. Foto: Leopoldo Silva\/Ag\u00eancia Senado CRISTIANO GOLDSCHMIDT A discuss\u00e3o sobre o fim da escala de trabalho 6x1 no Brasil tem ganhado centralidade no debate p\u00fablico contempor\u00e2neo por tocar\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84609,"url":"https:\/\/www.jornalja.com.br\/colunas\/o-centro-historico-de-porto-alegre\/","url_meta":{"origin":1537,"position":4},"title":"O Centro (Hist\u00f3rico) de Porto Alegre","author":"Cleber Dioni Tentardini","date":"30 de mar\u00e7o de 2026","format":false,"excerpt":"CLEBER DIONI TENTARDINI Porto Alegre, nove horas da manh\u00e3 do dia\u00a030\u00a0de mar\u00e7o de 2026. No \"cora\u00e7\u00e3o\" do\u00a0Centro - que j\u00e1\u00a0foi hist\u00f3rico em tempos passados,\u00a0e limpo\u00a0-,\u00a0em um trecho de\u00a0cerca de\u00a0500 metros, entre as ruas General C\u00e2mara e Senhor dos Passos, existem mais de 50 im\u00f3veis comerciais de porta de rua fechados,\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":84681,"url":"https:\/\/www.jornalja.com.br\/colunas\/recordar-zuzu-angel-50-anos-apos-sua-morte-e-um-ato-etico\/","url_meta":{"origin":1537,"position":5},"title":"Recordar Zuzu Angel 50 anos ap\u00f3s sua morte \u00e9 um ato \u00e9tico","author":"da Reda\u00e7\u00e3o","date":"16 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Cinco d\u00e9cadas transcorreram desde o silenciamento brutal de Zuzu Angel (05 de junho de 1921 - 14 de abril de 1976), e ainda assim sua voz persiste \u2014 n\u00e3o como eco esmaecido, mas como um timbre agudo que rasga o tecido do tempo e se inscreve na mem\u00f3ria\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKo0s-oN","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/1537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/comments?post=1537"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/1537\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/media?parent=1537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/categories?post=1537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/tags?post=1537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}