{"id":40659,"date":"2016-10-20T15:16:51","date_gmt":"2016-10-20T18:16:51","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=40659"},"modified":"2016-10-20T15:16:51","modified_gmt":"2016-10-20T18:16:51","slug":"a-prisao-de-cunha-nao-ameaca-lula","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/colunas\/a-prisao-de-cunha-nao-ameaca-lula\/","title":{"rendered":"A pris\u00e3o de Cunha n\u00e3o amea\u00e7a Lula"},"content":{"rendered":"<p><span class=\"assina\">Pinheiro do Vale\u00a0<\/span><br \/>\nA pris\u00e3o de Lula pela Opera\u00e7\u00e3o Lava Jato ainda \u00e9 improv\u00e1vel, pelo menos at\u00e9 este momento, desde que seja seguida a regra principal do juiz S\u00e9rgio Moro para encarcerar suspeitos.<br \/>\nO ex-presidente da C\u00e2mara, Eduardo Cunha, foi levado a Curitiba porque havia possibilidade concreta de fuga para o Exterior: contas em bancos estrangeiros e, mais ainda, um passaporte italiano que lhe daria imunidade no Velho Mundo.<br \/>\nAt\u00e9 ser definitivamente condenado, Cunha estaria protegido, tal como o ex-diretor de Marketing do Banco do Brasil, Henrique Pizolato, condenado no processo do Mensal\u00e3o e que se encontrava exilado na It\u00e1lia protegido por sua dupla nacionalidade. Confirmada a senten\u00e7a, o governo de Roma mandou-o de volta para a Penitenci\u00e1ria da Papuda. Em Bras\u00edlia.<br \/>\nIsto invalida o diz-que-diz-que de que Cunha est\u00e1 l\u00e1 para abrir a porta da cadeia ao ex-presidente.<br \/>\nLula n\u00e3o perfaz nenhuma dessas amea\u00e7as a um eventual processo (at\u00e9 o momento ele foi apenas indiciado). N\u00e3o tem contas no Exterior e s\u00f3 \u00e9 brasileiro puro.<br \/>\nO ex-presidente n\u00e3o se cansa de desmentir que vai pedir asilo neste ou naquele pa\u00eds. Isto \u00e9 importante pois quem espalha esses boatos s\u00e3o seus pr\u00f3prios correligion\u00e1rios, achando que, com isto, est\u00e3o protegendo Lula. Ledo engano: a acenarem com essa possibilidade est\u00e3o chamando os agentes da Pol\u00edcia Federal com mandado da Justi\u00e7a por amea\u00e7a de fuga do Pa\u00eds. Gol contra dos \u201ccompanheiros\u201d. Mui amigos.<br \/>\nLula tamb\u00e9m n\u00e3o se cansa de dizer que seus bens s\u00e3o os declarados e que o dinheiro de que disp\u00f5e vem de seus sal\u00e1rios como deputado federal e presidente da Rep\u00fablica, al\u00e9m de doa\u00e7\u00f5es e ajudas de custo do partido.<br \/>\nNada errado: o ex-presidente nunca escondeu que fora pol\u00edtico profissional, sustentado pelo PT, com doa\u00e7\u00f5es de seus militantes. N\u00e3o se esque\u00e7am que os petistas que ocupavam cargos p\u00fablicos tinham o compromisso de doar parte de seus subs\u00eddios ao partido.<br \/>\nNos \u00faltimos tempos, j\u00e1 como cidad\u00e3o comum, sustentava-se com seu sal\u00e1rio de ex-presidente e cach\u00eas por confer\u00eancias, apari\u00e7\u00f5es p\u00fablicas e outros tipos de remunera\u00e7\u00e3o de celebridades. Cobrava caro, pois ningu\u00e9m discorda que era uma das maiores personalidades mundiais, quase t\u00e3o famoso quanto Pel\u00e9. Portanto, tudo explicadinho.<br \/>\nA suspeita de que Lula tenha fundos no Exterior atira no ar a cal\u00fania de que seu dinheiro estaria em Angola e Cuba, pa\u00edses fora dos controles do sistema financeiro internacional, com regimes ditatoriais que n\u00e3o permitem intrusos nas suas contas p\u00fablicas ou privadas.<br \/>\nNeste caso, se n\u00e3o fosse uma cal\u00fania rasteira, tais fundos estariam nos grandes bancos, mas triangulados com Cuba ou Angola, em nome de laranjas desconhecidos. Isto n\u00e3o \u00e9 poss\u00edvel, tanto que nada apareceu. S\u00f3 cal\u00fanias.<br \/>\nDe ter fundos secretos em Cuba nem se deve dar ouvidos, pois se houvesse alguma coisa j\u00e1 teria surgido na imprensa internacional: o pa\u00eds de Fidel Castro at\u00e9 muito pouco tempo estava na lista de estados terroristas do FBI, portanto estreitamente vigiado. N\u00e3o faltaria um bom vazamento.<br \/>\nQuanto a Angola, dizem que Lula investiu seu dinheiro em opera\u00e7\u00f5es acobertadas pela filha do presidente Jos\u00e9 Eduardo Santos, a empres\u00e1ria Isabel Santos, atualmente apontada pela revista<em> Forbes<\/em> como a maior fortuna pessoal do continente africano.<br \/>\n\u00c9 uma grande maldade acolherar Lula com Isabel. Ela \u00e9 uma pessoa soterrada por suspeitas, considerada pela Transpar\u00eancia Internacional como a sexta pessoa mais corrupta do mundo. Sua fortuna n\u00e3o est\u00e1 apenas em Angola. Ela \u00e9 grande acionista de v\u00e1rios bancos europeus e tem investimentos em mais de uma dezena de megaempresas na Uni\u00e3o Europeia e, especialmente, em Portugal. Seria uma laranja invulner\u00e1vel.<br \/>\nNa verdade, as suspeitas lan\u00e7adas sobre Isabel Santos \u00e9 que ela seria n\u00e3o uma laranja, mas um pomar inteiro, e que Angola seria o estado reciclador dos caixas dois de uma dezena de potentados do antigo mundo sovi\u00e9tico, dentre eles Vladimir Putin. De fato, tamanha fortuna seria de muitos donos e seu pai, o presidente Santos, teria infiltrado Lula e alguns outros amigos brasileiros. Uma blindagem impenetr\u00e1vel.<br \/>\nIsabel n\u00e3o \u00e9 uma figura grosseira de uma ditadura africana. Pelo contr\u00e1rio. Nasceu em Baku, na ent\u00e3o Rep\u00fablica Socialista Sovi\u00e9tica do Azerbaij\u00e3o, onde seu pai estava exilado e atuava como um dos chefes da guerrilha angolana, o MPLA, no posto de general revolucion\u00e1rio.<br \/>\nSua m\u00e3e, Tatiana Kukanova, \u00e9 azerbaijana de etnia russa, alta funcion\u00e1ria do PCUS. Isabel nasceu em 1973. Teve uma educa\u00e7\u00e3o esmerada mesmo para os padr\u00f5es europeus: fez sua forma\u00e7\u00e3o b\u00e1sica na escola para mo\u00e7as da nobreza brit\u00e2nica, a Saint Paul Girls School, e graduou-se em Engenharia Eletr\u00f4nica pelo Kings College de Londres. Tamb\u00e9m se casou com um homem refinado, o conhecido colecionador de arte Sindika Dokolo, natural da Rep\u00fablica Democr\u00e1tica do Congo.<br \/>\nQuando voltou a seu pa\u00eds, nos anos 1990, chegou a trabalhar como engenheira, mas logo deslocou-se para o mundo dos neg\u00f3cios, onde triunfou a ponto de se converter numa das 100 mulheres mais poderosas do mundo. Seu pai trabalha sua candidatura a presidente de Angola.<br \/>\nEla seria a s\u00f3cia de Lula, segundo seus detratores. N\u00e3o h\u00e1 como provar essa liga\u00e7\u00e3o nem minimamente. Tampouco h\u00e1 qualquer ind\u00edcio de algum investimento do ex-presidente em neg\u00f3cios comandados pela angolana.<br \/>\nNem mesmo fazendo os mais sinuosos contorcionismos legais o arrojado juiz S\u00e9rgio Moro pode invocar seja o que for para sugerir que Lula n\u00e3o fala a verdade quando diz que n\u00e3o quer nem tem como fugir do Pa\u00eds.<br \/>\nO que se fala em Bras\u00edlia relativamente \u00e0s poss\u00edveis den\u00fancias de Eduardo Cunha \u00e9 que podem apontar corruptos em outras plagas, tanto no ninho tucano como na toca das raposas do PMDB. N\u00e3o seria por nada que o presidente ileg\u00edtimo Michel Temer pegou o avi\u00e3o e voltou voando para o Brasil t\u00e3o logo soube que seu correligion\u00e1rio cassado estava atr\u00e1s das grades.<br \/>\nNa verdade, n\u00e3o \u00e9 Lula, mas Temer que deve botar as barbas de molho.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pinheiro do Vale\u00a0 A pris\u00e3o de Lula pela Opera\u00e7\u00e3o Lava Jato ainda \u00e9 improv\u00e1vel, pelo menos at\u00e9 este momento, desde que seja seguida a regra principal do juiz S\u00e9rgio Moro para encarcerar suspeitos. O ex-presidente da C\u00e2mara, Eduardo Cunha, foi levado a Curitiba porque havia possibilidade concreta de fuga para o Exterior: contas em bancos [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-40659","post","type-post","status-publish","format-standard","hentry","category-analiseopiniao"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":84617,"url":"https:\/\/www.jornalja.com.br\/colunas\/o-candidato-de-si-mesmo\/","url_meta":{"origin":40659,"position":0},"title":"O candidato de si mesmo","author":"da Reda\u00e7\u00e3o","date":"10 de abril de 2026","format":false,"excerpt":"Sem emplacar nacionalmente, Leite pode ficar quatro anos sem mandato. Foto Jo\u00e3o Pedro Rodrigues\/SecomRS ELMAR BONES Ningu\u00e9m \u00e9 candidato de si mesmo. Essa \u00e9 a regra n\u00e3o escrita da pol\u00edtica partid\u00e1ria, que as velhas raposas n\u00e3o cansam de repetir aos novatos. Eduardo Leite parece n\u00e3o t\u00ea-la aprendido. Ele n\u00e3o tem\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84690,"url":"https:\/\/www.jornalja.com.br\/colunas\/17-de-abril-de-1996-30-anos-do-massacre-de-eldorado-do-carajas\/","url_meta":{"origin":40659,"position":1},"title":"17 de abril de 1996: 30 anos do Massacre de Eldorado do Caraj\u00e1s","author":"da Reda\u00e7\u00e3o","date":"17 de abril de 2026","format":false,"excerpt":"Cruz marca o local do massacre em Eldorado dos Caraj\u00e1s, Par\u00e1. Foto: Marcello Casal Jr.\/Arquivo ABr CRISTIANO GOLDSCHMIDT H\u00e1 datas que n\u00e3o passam. Ficam suspensas no tempo como poeira vermelha sobre a pele \u2014 insistem, infiltram-se, recusam o esquecimento. Abril, no sul do Par\u00e1, \u00e9 sempre um m\u00eas que arde.\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84766,"url":"https:\/\/www.jornalja.com.br\/colunas\/entre-o-compromisso-etico-da-amizade-e-a-omissao-silenciosa\/","url_meta":{"origin":40659,"position":2},"title":"Entre o compromisso \u00e9tico da amizade e a omiss\u00e3o silenciosa","author":"An\u00e1lise &amp; Opini\u00e3o","date":"6 de maio de 2026","format":false,"excerpt":"Uma amizade que se retrai diante da possibilidade concreta de promover o outro revela, em \u00faltima inst\u00e2ncia, que seu v\u00ednculo est\u00e1 condicionado a certas fronteiras invis\u00edveis. CRISTIANO GOLDSCHMIDT H\u00e1 uma forma silenciosa \u2014 e, por isso mesmo, profundamente reveladora \u2014 de medir o valor de uma amizade: n\u00e3o pelas palavras\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-2.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-2.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-2.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-2.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-2.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-2.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84622,"url":"https:\/\/www.jornalja.com.br\/colunas\/13-de-abril-queriam-transformar-o-hino-nacional-em-grito-de-guerra-mas-ele-insiste-em-ser-canto-de-paz\/","url_meta":{"origin":40659,"position":3},"title":"13 de abril: Queriam transformar o Hino Nacional em grito de guerra, mas ele insiste em ser canto de paz","author":"da Reda\u00e7\u00e3o","date":"13 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT No calend\u00e1rio das datas c\u00edvicas, o 13 de abril passa quase em sil\u00eancio, como um acorde sustentado que poucos escutam at\u00e9 o fim. N\u00e3o h\u00e1 fogos, n\u00e3o h\u00e1 desfiles grandiosos, n\u00e3o h\u00e1 a coreografia ensaiada das celebra\u00e7\u00f5es que se imp\u00f5em ao olhar. H\u00e1, antes, uma esp\u00e9cie de pausa\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/imagem-do-poeta-brasileiro-joaquim-osorio-duque-estrada-autor-da-letra-do-hino-nacional-escaneada-do-livro-flora-de-maio-edicao-de-1902.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/imagem-do-poeta-brasileiro-joaquim-osorio-duque-estrada-autor-da-letra-do-hino-nacional-escaneada-do-livro-flora-de-maio-edicao-de-1902.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/imagem-do-poeta-brasileiro-joaquim-osorio-duque-estrada-autor-da-letra-do-hino-nacional-escaneada-do-livro-flora-de-maio-edicao-de-1902.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":84725,"url":"https:\/\/www.jornalja.com.br\/colunas\/e-preciso-refletir-sobre-os-mais-de-84-mil-desaparecidos-no-brasil-em-2025\/","url_meta":{"origin":40659,"position":4},"title":"\u00c9 preciso refletir sobre os mais de 84 mil desaparecidos no Brasil em 2025","author":"An\u00e1lise &amp; Opini\u00e3o","date":"23 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Em 2025, o Brasil registrou 84.760 pessoas desaparecidas, segundo dados consolidados pelo Sistema Nacional de Informa\u00e7\u00f5es de Seguran\u00e7a P\u00fablica Sinesp), vinculado ao Minist\u00e9rio da Justi\u00e7a e Seguran\u00e7a P\u00fablica. Mais do que um n\u00famero expressivo, o dado revela um fen\u00f4meno cont\u00ednuo, distribu\u00eddo no tempo e no territ\u00f3rio \u2014 e,\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84714,"url":"https:\/\/www.jornalja.com.br\/colunas\/22-de-abril-o-instante-em-que-o-brasil-passa-a-existir-para-o-mundo-europeu\/","url_meta":{"origin":40659,"position":5},"title":"22 de abril: o instante em que o Brasil \u201cpassa a existir\u201d para o mundo europeu","author":"Patr\u00edcia Marini","date":"22 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Era 22 de abril de 1500 \u2014 ou, ao menos, \u00e9 assim que nos habituamos a dizer, com a serenidade quase ing\u00eanua de quem domestica o passado em datas redondas e memor\u00e1veis. Naquele dia, a esquadra comandada por Pedro \u00c1lvares Cabral avistou terra ap\u00f3s semanas de travessia pelo\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/desembarque-de-cabral-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/desembarque-de-cabral-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/desembarque-de-cabral-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/desembarque-de-cabral-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/desembarque-de-cabral-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/desembarque-de-cabral-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKo0s-azN","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/40659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/comments?post=40659"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/40659\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/media?parent=40659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/categories?post=40659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/tags?post=40659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}