{"id":44732,"date":"2017-02-16T19:16:32","date_gmt":"2017-02-16T22:16:32","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=44732"},"modified":"2017-02-16T19:16:32","modified_gmt":"2017-02-16T22:16:32","slug":"a-organizacao-ou-a-morte","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/colunas\/a-organizacao-ou-a-morte\/","title":{"rendered":"A organiza\u00e7\u00e3o ou a morte"},"content":{"rendered":"<p><strong><em>WALMARO PAZ<\/em><\/strong><br \/>\nNo ano de 2015 acompanhei o processo eleitoral do Haiti pessoalmente durante tr\u00eas meses. Tive a gra\u00e7a de conhecer a cultura riqu\u00edssima daquele povo e a erudi\u00e7\u00e3o de diversas de suas lideran\u00e7as.<br \/>\nQuem mais me impressionou foi o lider do Mouvement Paysan Papaye, Chavanes Jean Baptiste, que coordena as atividades de 60 mil fam\u00edlias de camponeses na regi\u00e3o do Plat\u00f4 Central.<br \/>\nSuas lutas v\u00e3o desde a briga pela terra que ocupam, passando pela pesquisa aplicada em agroecologia, at\u00e9 a educa\u00e7\u00e3o das crian\u00e7as assumida pelo movimento que constr\u00f3i e mant\u00eam escolas.<br \/>\nAo analisar a conjuntura em sua primeira entrevista Chavanes confessou n\u00e3o acreditar no processo eleitoral, para ele uma farsa ( une mascarade), mas que participaria da campanha para denunciar exatamente isso. \u201cEstamos passando por um processo de recoloniza\u00e7\u00e3o que dever\u00e1 se estender por toda a Am\u00e9rica Latina\u201d.<br \/>\nEle me fez entender a pol\u00edtica neoliberal em sua experi\u00eancia mais radical. No Haiti tudo foi privatizado, at\u00e9 a \u00e1gua pot\u00e1vel e suas praias. Um trabalhador haitiano recebe cerca de 4 d\u00f3lares por dia de trabalho e se for comprar \u00e1gua tratada gastara cerca de um d\u00f3lar por litro.<br \/>\nNo ensino publico se um pai n\u00e3o tiver 500 d\u00f3lares n\u00e3o consegue matricular seu filho. Nos postos de sa\u00fade para se ter uma consulta m\u00e9dica \u00e9 necess\u00e1rio dar ao m\u00e9dico plantonista cerca de 40 d\u00f3lares.<br \/>\nA previd\u00eancia social praticamente inexiste. Conheci uma pedagoga, diretora de escola aposentada que depois de 45 anos de trabalho vive da caridade de seus amigos e vizinhos e quase morreu de inani\u00e7\u00e3o depois do terremoto.<br \/>\nConversei com ela, amarga, mas ao mesmo tempo com esperan\u00e7a nas lutas da juventude, Bobol, este \u00e9 o seu apelido vive seus \u00faltimos dias num corti\u00e7o no meio de cabritos e porcos em Delmas, Porto Pr\u00edncipe.<br \/>\nA energia el\u00e9trica \u00e9 privada e a mesma empresa que gera e fornece energia durante cerca de dez horas na capital, vende geradores para quem tiver a necessidade de us\u00e1-la permanentemente.<br \/>\nS\u00e3o fatos que deixaram claro para mim, onde iremos com este processo. Mas porque estou falando nessa viv\u00eancia? \u00c9 simples, porque o processo de recoloniza\u00e7\u00e3o chegou ao Brasil e est\u00e1 sendo alavancado pelos golpistas de plant\u00e3o.<br \/>\nQuerem aprovar com rapidez medidas que terminar\u00e3o com a previd\u00eancia social trocando-a por uma privada sem a menor garantia; querem derrocar a CLT, colocando o contratado acima do legislado; j\u00e1 come\u00e7aram a privatizar a \u00e1gua no Estado do Rio de Janeiro; j\u00e1 privatizaram a energia el\u00e9trica e est\u00e3o entregando o que restou para as transnacionais abrindo o Pr\u00e9-sal.<\/p>\n<p align=\"left\">No Rio Grande do Sul entregar\u00e3o o carv\u00e3o mineral, o g\u00e1s resultante de seu aproveitamento e o que restou da Companhia Estadual de Energia El\u00e9trica (CEEE). O Banrisul est\u00e1 sendo negociado e n\u00e3o demora ser\u00e3o a CORSAN ( Companhia Riograndense de Saneamento) e o DMAE ( Departamento Municipal de \u00c1guas e esgotos).<\/p>\n<p align=\"left\">Isso me assusta, por isso , no in\u00edcio lembrei-me do Haiti e da previs\u00e3o de seu l\u00edder campon\u00eas para o restante da Am\u00e9rica Latina. Mas resta a esperan\u00e7a que tamb\u00e9m vem da P\u00e9rola das Antilhas: a resist\u00eancia de seu povo, sua organiza\u00e7\u00e3o em movimentos populares e camponeses. Por isso gostaria de lembrar o lema do MPP: \u201cLoganization ou lamort\u201d ( A Organiza\u00e7\u00e3o ou a morte).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>WALMARO PAZ No ano de 2015 acompanhei o processo eleitoral do Haiti pessoalmente durante tr\u00eas meses. Tive a gra\u00e7a de conhecer a cultura riqu\u00edssima daquele povo e a erudi\u00e7\u00e3o de diversas de suas lideran\u00e7as. Quem mais me impressionou foi o lider do Mouvement Paysan Papaye, Chavanes Jean Baptiste, que coordena as atividades de 60 mil [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-44732","post","type-post","status-publish","format-standard","hentry","category-analiseopiniao"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":84617,"url":"https:\/\/www.jornalja.com.br\/colunas\/o-candidato-de-si-mesmo\/","url_meta":{"origin":44732,"position":0},"title":"O candidato de si mesmo","author":"da Reda\u00e7\u00e3o","date":"10 de abril de 2026","format":false,"excerpt":"Sem emplacar nacionalmente, Leite pode ficar quatro anos sem mandato. Foto Jo\u00e3o Pedro Rodrigues\/SecomRS ELMAR BONES Ningu\u00e9m \u00e9 candidato de si mesmo. Essa \u00e9 a regra n\u00e3o escrita da pol\u00edtica partid\u00e1ria, que as velhas raposas n\u00e3o cansam de repetir aos novatos. Eduardo Leite parece n\u00e3o t\u00ea-la aprendido. Ele n\u00e3o tem\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84748,"url":"https:\/\/www.jornalja.com.br\/colunas\/a-literatura-brasileira-no-dia-do-trabalhador\/","url_meta":{"origin":44732,"position":1},"title":"A Literatura Brasileira no Dia do Trabalho","author":"An\u00e1lise &amp; Opini\u00e3o","date":"1 de maio de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT O 1\u00ba de maio costuma ser lembrado pelo peso hist\u00f3rico das lutas trabalhistas, pelo som das manifesta\u00e7\u00f5es e pela mem\u00f3ria viva de direitos conquistados ao longo de d\u00e9cadas. No entanto, essa mesma data abriga uma outra forma de celebra\u00e7\u00e3o, menos ruidosa, mas igualmente significativa: o Dia da Literatura\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84742,"url":"https:\/\/www.jornalja.com.br\/colunas\/rejeicao-a-messias-quando-o-senado-tensiona-os-limites-da-democracia\/","url_meta":{"origin":44732,"position":2},"title":"Rejei\u00e7\u00e3o a Messias: quando o Senado tensiona os limites da democracia","author":"An\u00e1lise &amp; Opini\u00e3o","date":"30 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT A rejei\u00e7\u00e3o, pelo Senado, da indica\u00e7\u00e3o de Jorge Messias ao Supremo Tribunal Federal n\u00e3o \u00e9 um fato trivial \u2014 e trat\u00e1-la como um simples exerc\u00edcio de independ\u00eancia institucional seria, no m\u00ednimo, ing\u00eanuo. H\u00e1 algo mais profundo em jogo. O epis\u00f3dio exp\u00f5e, com certa nitidez, a forma como parcelas\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84622,"url":"https:\/\/www.jornalja.com.br\/colunas\/13-de-abril-queriam-transformar-o-hino-nacional-em-grito-de-guerra-mas-ele-insiste-em-ser-canto-de-paz\/","url_meta":{"origin":44732,"position":3},"title":"13 de abril: Queriam transformar o Hino Nacional em grito de guerra, mas ele insiste em ser canto de paz","author":"da Reda\u00e7\u00e3o","date":"13 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT No calend\u00e1rio das datas c\u00edvicas, o 13 de abril passa quase em sil\u00eancio, como um acorde sustentado que poucos escutam at\u00e9 o fim. N\u00e3o h\u00e1 fogos, n\u00e3o h\u00e1 desfiles grandiosos, n\u00e3o h\u00e1 a coreografia ensaiada das celebra\u00e7\u00f5es que se imp\u00f5em ao olhar. H\u00e1, antes, uma esp\u00e9cie de pausa\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/imagem-do-poeta-brasileiro-joaquim-osorio-duque-estrada-autor-da-letra-do-hino-nacional-escaneada-do-livro-flora-de-maio-edicao-de-1902.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/imagem-do-poeta-brasileiro-joaquim-osorio-duque-estrada-autor-da-letra-do-hino-nacional-escaneada-do-livro-flora-de-maio-edicao-de-1902.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/imagem-do-poeta-brasileiro-joaquim-osorio-duque-estrada-autor-da-letra-do-hino-nacional-escaneada-do-livro-flora-de-maio-edicao-de-1902.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":84693,"url":"https:\/\/www.jornalja.com.br\/colunas\/fim-da-escala-6x1-cabe-ao-congresso-decidir-entre-o-progresso-e-o-atraso\/","url_meta":{"origin":44732,"position":4},"title":"Fim da escala 6&#215;1: cabe ao Congresso decidir entre o progresso e o atraso","author":"da Reda\u00e7\u00e3o","date":"20 de abril de 2026","format":false,"excerpt":"Plen\u00e1rio da C\u00e2mara dos Deputados durante sess\u00e3o solene do Congresso Nacional. Caber\u00e1 ao parlamento a decis\u00e3o final sobre a nova escala de trabalho. Foto: Leopoldo Silva\/Ag\u00eancia Senado CRISTIANO GOLDSCHMIDT A discuss\u00e3o sobre o fim da escala de trabalho 6x1 no Brasil tem ganhado centralidade no debate p\u00fablico contempor\u00e2neo por tocar\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84564,"url":"https:\/\/www.jornalja.com.br\/colunas\/a-nova-celulose-a-beira-do-guaiba-e-o-risco-de-repetir-a-borregaard\/","url_meta":{"origin":44732,"position":5},"title":"A nova celulose \u00e0 beira do Gua\u00edba e o risco de repetir a Borregaard","author":"An\u00e1lise &amp; Opini\u00e3o","date":"6 de mar\u00e7o de 2026","format":false,"excerpt":"ELMAR BONES No dia 16 de mar\u00e7o de 1972 foi inaugurada a Ind\u00fastria de Celulose Borregaard, em Gua\u00edba, com a presen\u00e7a das mais altas autoridades e manchetes ufanistas em todos os jornais. Inaugura\u00e7\u00e3o da f\u00e1brica em Gua\u00edba, no ano de 1972. Foto Reprodu\u00e7\u00e3o Arquivo\/CeluloseRioGrandense Seria uma das maiores f\u00e1bricas em\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKo0s-bDu","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/44732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/comments?post=44732"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/44732\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/media?parent=44732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/categories?post=44732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/tags?post=44732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}