{"id":45521,"date":"2017-03-09T14:49:44","date_gmt":"2017-03-09T17:49:44","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=45521"},"modified":"2017-03-09T14:49:44","modified_gmt":"2017-03-09T17:49:44","slug":"por-um-estado-democratico-e-transparente","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/colunas\/por-um-estado-democratico-e-transparente\/","title":{"rendered":"Por um Estado democr\u00e1tico e transparente"},"content":{"rendered":"<p><span class=\"assina\">Benedito Tadeu C\u00e9sar<\/span><br \/>\n<span class=\"descreve\">Intelectual e acad\u00eamico da UFRGS, aposentado<\/span><br \/>\nOs deputados do PMDB est\u00e3o repetindo a mesma cartilha. \u00c9 o que se deduz de manifesta\u00e7\u00f5es recentes do l\u00edder do governo na Assembleia e de um ex-presidente do partido na imprensa ga\u00facha.<br \/>\nEm artigos no Correio do Povo, no dia 18 de fevereiro, e na Zero Hora, no dia 28 do mesmo m\u00eas, os parlamentares classificaram de \u201c\u00b4pseudointelectuais ideol\u00f3gicos\u201d e de &#8220;academicistas ideol\u00f3gicos divorciados dos anseios sociais&#8221; todos os que ousam discordar das medidas de &#8220;moderniza\u00e7\u00e3o&#8221; propostas pelo governador Jos\u00e9 Ivo Sartori e acatadas inconteste pelos governistas.<br \/>\nO conceito de ideologia est\u00e1 ligado \u00e0 ideia de distorcer a realidade para favorecer os interesses de determinados grupos. Assim, talvez o ep\u00edteto de ideol\u00f3gico se adeque melhor a pol\u00edticos que defendem medidas sem serem capazes de comprovar sua real necessidade e efic\u00e1cia.<br \/>\nAfirmam, os deputados, que &#8220;as propostas resultam de an\u00e1lise profunda&#8221;, que &#8220;as a\u00e7\u00f5es para resgatar o Estado do naufr\u00e1gio foram debatidas Estado (sic) afora&#8221; e, ainda, que &#8220;uma pesquisa encomendada por entidades representativas do setor produtivo j\u00e1 revelou que 72,4% dos ga\u00fachos aprovam o plano de Sartori&#8221;.<br \/>\nOnde est\u00e1 a &#8220;an\u00e1lise profunda&#8221;, que n\u00e3o foi apresentada sequer ao Legislativo? Onde est\u00e3o os estudos dos impactos das extin\u00e7\u00f5es e das privatiza\u00e7\u00f5es pretendidas? Quem os realizou? Onde est\u00e3o as informa\u00e7\u00f5es sobre as datas, as localidades e o n\u00famero de presentes em cada debate realizado sobre as medidas?<br \/>\nSem questionar os interesses que moveram o gesto dadivoso das entidades que financiaram a pesquisa, o que se pergunta, seguindo a metodologia recomendada, \u00e9 se os entrevistados foram inquiridos, ao iniciar suas respostas, sobre o seu grau de conhecimento das compet\u00eancias e or\u00e7amentos das funda\u00e7\u00f5es e empresas amea\u00e7adas.<br \/>\nNenhuma dessas informa\u00e7\u00f5es veio \u00e0 luz, n\u00e3o obstante tenha sido encaminhado um pedido de di\u00e1logo ao governador, no dia 9 de janeiro, por meio de uma carta aberta encabe\u00e7ada por 66 artistas e acad\u00eamicos reconhecidos em suas \u00e1reas e que conta hoje com cerca de 1,5 mil subscritores.<br \/>\nReafirmando que encaminhar reformas n\u00e3o expostas claramente \u00e0 sociedade constitui postura ideol\u00f3gica, mantenho, como um dos signat\u00e1rios da carta aberta, nossa disposi\u00e7\u00e3o ao debate democr\u00e1tico e renovo o pedido de divulga\u00e7\u00e3o dos estudos e de instala\u00e7\u00e3o de um f\u00f3rum com representantes da sociedade civil para elaborar alternativas para o desenvolvimento do RS.<br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Benedito Tadeu C\u00e9sar Intelectual e acad\u00eamico da UFRGS, aposentado Os deputados do PMDB est\u00e3o repetindo a mesma cartilha. \u00c9 o que se deduz de manifesta\u00e7\u00f5es recentes do l\u00edder do governo na Assembleia e de um ex-presidente do partido na imprensa ga\u00facha. Em artigos no Correio do Povo, no dia 18 de fevereiro, e na Zero [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":45522,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-45521","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analiseopiniao"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":84693,"url":"https:\/\/www.jornalja.com.br\/colunas\/fim-da-escala-6x1-cabe-ao-congresso-decidir-entre-o-progresso-e-o-atraso\/","url_meta":{"origin":45521,"position":0},"title":"Fim da escala 6&#215;1: cabe ao Congresso decidir entre o progresso e o atraso","author":"da Reda\u00e7\u00e3o","date":"20 de abril de 2026","format":false,"excerpt":"Plen\u00e1rio da C\u00e2mara dos Deputados durante sess\u00e3o solene do Congresso Nacional. Caber\u00e1 ao parlamento a decis\u00e3o final sobre a nova escala de trabalho. Foto: Leopoldo Silva\/Ag\u00eancia Senado CRISTIANO GOLDSCHMIDT A discuss\u00e3o sobre o fim da escala de trabalho 6x1 no Brasil tem ganhado centralidade no debate p\u00fablico contempor\u00e2neo por tocar\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84622,"url":"https:\/\/www.jornalja.com.br\/colunas\/13-de-abril-queriam-transformar-o-hino-nacional-em-grito-de-guerra-mas-ele-insiste-em-ser-canto-de-paz\/","url_meta":{"origin":45521,"position":1},"title":"13 de abril: Queriam transformar o Hino Nacional em grito de guerra, mas ele insiste em ser canto de paz","author":"da Reda\u00e7\u00e3o","date":"13 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT No calend\u00e1rio das datas c\u00edvicas, o 13 de abril passa quase em sil\u00eancio, como um acorde sustentado que poucos escutam at\u00e9 o fim. N\u00e3o h\u00e1 fogos, n\u00e3o h\u00e1 desfiles grandiosos, n\u00e3o h\u00e1 a coreografia ensaiada das celebra\u00e7\u00f5es que se imp\u00f5em ao olhar. H\u00e1, antes, uma esp\u00e9cie de pausa\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/imagem-do-poeta-brasileiro-joaquim-osorio-duque-estrada-autor-da-letra-do-hino-nacional-escaneada-do-livro-flora-de-maio-edicao-de-1902.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/imagem-do-poeta-brasileiro-joaquim-osorio-duque-estrada-autor-da-letra-do-hino-nacional-escaneada-do-livro-flora-de-maio-edicao-de-1902.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/imagem-do-poeta-brasileiro-joaquim-osorio-duque-estrada-autor-da-letra-do-hino-nacional-escaneada-do-livro-flora-de-maio-edicao-de-1902.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":84617,"url":"https:\/\/www.jornalja.com.br\/colunas\/o-candidato-de-si-mesmo\/","url_meta":{"origin":45521,"position":2},"title":"O candidato de si mesmo","author":"da Reda\u00e7\u00e3o","date":"10 de abril de 2026","format":false,"excerpt":"Sem emplacar nacionalmente, Leite pode ficar quatro anos sem mandato. Foto Jo\u00e3o Pedro Rodrigues\/SecomRS ELMAR BONES Ningu\u00e9m \u00e9 candidato de si mesmo. Essa \u00e9 a regra n\u00e3o escrita da pol\u00edtica partid\u00e1ria, que as velhas raposas n\u00e3o cansam de repetir aos novatos. Eduardo Leite parece n\u00e3o t\u00ea-la aprendido. Ele n\u00e3o tem\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84590,"url":"https:\/\/www.jornalja.com.br\/colunas\/e-preciso-defender-o-jardim-botanico-de-porto-alegre\/","url_meta":{"origin":45521,"position":3},"title":"\u00c9 preciso defender o Jardim Bot\u00e2nico de Porto Alegre","author":"da Reda\u00e7\u00e3o","date":"8 de mar\u00e7o de 2026","format":false,"excerpt":"CLEBER DIONI TENTARDINI O Jardim Bot\u00e2nico de Porto Alegre (JBPA) tem 67 anos e \u00e9 considerado um dos cinco melhores e maiores do Brasil. Possui 28 cole\u00e7\u00f5es cient\u00edficas que somam mais de 4.200 plantas, incluindo esp\u00e9cies raras, amea\u00e7adas de extin\u00e7\u00e3o e end\u00eamicas, que s\u00e3o encontradas apenas no RS. No local\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84742,"url":"https:\/\/www.jornalja.com.br\/colunas\/rejeicao-a-messias-quando-o-senado-tensiona-os-limites-da-democracia\/","url_meta":{"origin":45521,"position":4},"title":"Rejei\u00e7\u00e3o a Messias: quando o Senado tensiona os limites da democracia","author":"An\u00e1lise &amp; Opini\u00e3o","date":"30 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT A rejei\u00e7\u00e3o, pelo Senado, da indica\u00e7\u00e3o de Jorge Messias ao Supremo Tribunal Federal n\u00e3o \u00e9 um fato trivial \u2014 e trat\u00e1-la como um simples exerc\u00edcio de independ\u00eancia institucional seria, no m\u00ednimo, ing\u00eanuo. H\u00e1 algo mais profundo em jogo. O epis\u00f3dio exp\u00f5e, com certa nitidez, a forma como parcelas\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84564,"url":"https:\/\/www.jornalja.com.br\/colunas\/a-nova-celulose-a-beira-do-guaiba-e-o-risco-de-repetir-a-borregaard\/","url_meta":{"origin":45521,"position":5},"title":"A nova celulose \u00e0 beira do Gua\u00edba e o risco de repetir a Borregaard","author":"An\u00e1lise &amp; Opini\u00e3o","date":"6 de mar\u00e7o de 2026","format":false,"excerpt":"ELMAR BONES No dia 16 de mar\u00e7o de 1972 foi inaugurada a Ind\u00fastria de Celulose Borregaard, em Gua\u00edba, com a presen\u00e7a das mais altas autoridades e manchetes ufanistas em todos os jornais. Inaugura\u00e7\u00e3o da f\u00e1brica em Gua\u00edba, no ano de 1972. Foto Reprodu\u00e7\u00e3o Arquivo\/CeluloseRioGrandense Seria uma das maiores f\u00e1bricas em\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKo0s-bQd","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/45521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/comments?post=45521"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/45521\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/media?parent=45521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/categories?post=45521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/tags?post=45521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}