{"id":46327,"date":"2017-03-25T16:04:40","date_gmt":"2017-03-25T19:04:40","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=46327"},"modified":"2017-03-25T16:04:40","modified_gmt":"2017-03-25T19:04:40","slug":"hora-do-pt-matar-a-mosca-azul","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/colunas\/hora-do-pt-matar-a-mosca-azul\/","title":{"rendered":"Hora do PT matar a mosca azul"},"content":{"rendered":"<p><span class=\"assina\">Geraldo Hasse<\/span><br \/>\nDepois do aluvi\u00e3o de den\u00fancias levantadas pela Opera\u00e7\u00e3o Lava Jato nos seus primeiros dois anos e meio, soubemos recentemente que n\u00e3o foram apenas petistas que prevaricaram, mas membros de praticamente todos os principais partidos brasileiros. Portanto, a come\u00e7ar pelo PT, imp\u00f5e-se um saneamento geral para higienizar a vida partid\u00e1ria no Brasil.<br \/>\nPara clarear o panorama, precisamos recordar que, logo em sua funda\u00e7\u00e3o em 1980, o PT criou uma f\u00f3rmula original da sobreviv\u00eancia partid\u00e1ria: estabeleceu uma mensalidade para os filiados e uma contribui\u00e7\u00e3o compuls\u00f3ria para os militantes eleitos para cargos p\u00fablicos. Cada mandat\u00e1rio tinha que dar ao partido 30% dos seus honor\u00e1rios.<br \/>\nPara coroar seu sucesso como partido de massa, s\u00f3 faltava ao PT filiar um n\u00famero pr\u00f3ximo de um milh\u00e3o de s\u00f3cios. Essa era sua meta expl\u00edcita. Sob o comando do deputado Jos\u00e9 Dirceu, o partido passou a fazer filia\u00e7\u00f5es pela internet. Consta que chegou a 700 mil s\u00f3cios.\u00a0 Uma esp\u00e9cie de Coring\u00e3o ou Flamengo entre os partidos.<br \/>\nAl\u00e9m dos pioneiros adeptos do socialismo democr\u00e1tico (\u201csem medo de ser feliz\u201d), o partido passou a contar com levas de adesistas de \u00faltima hora, alpinistas de ocasi\u00e3o, carreiristas sem vergonha e oportunistas loucos para ser governo.<br \/>\nNo final do s\u00e9culo XX, com apenas vinte anos de exist\u00eancia, o PT havia conquistado centenas de mandatos de vereador, prefeito, deputado, senador e governador. Cada um desses eleitos tinha direito de nomear um n\u00famero consider\u00e1vel de pessoas para cargos de confian\u00e7a, os chamados CCs, que tamb\u00e9m deviam dar o seu quinh\u00e3o para o sustento da estrutura partid\u00e1ria.<br \/>\nFoi nessa conviv\u00eancia for\u00e7ada entre os revolucion\u00e1rios de primeira hora e os rec\u00e9m-chegados famintos pelo poder que o PT perdeu a pureza original. Frei Betto escreveu um livro dizendo que seus amigos petistas se deixaram picar pela mosca azul do poder.<br \/>\nAlguns acreditam que o vacilo se deu durante a reda\u00e7\u00e3o da Carta ao Povo Brasileiro, assinada por Lula em 22 de junho de 2002, portanto, alguns meses antes da elei\u00e7\u00e3o que colocou o ex-oper\u00e1rio do ABC no Pal\u00e1cio do Planalto.<br \/>\nO pragmatismo petista no exerc\u00edcio do governo do Brasil rendeu a met\u00e1fora do presidente violinista: enquanto segurava o instrumento com a m\u00e3o esquerda, Lula acionava o arco do violino com a direita (a troca de m\u00e3os n\u00e3o alterava o resultado final, considerado bom para pobres e ricos).<br \/>\nSucesso de cr\u00edtica e de p\u00fablico, o concerto petista foi bem at\u00e9 que, por ambi\u00e7\u00e3o demasiada, erro de c\u00e1lculo, soberba ou falta de melhor alternativa, o PT achou por bem (ou por mal?) fazer como os outros partidos no exerc\u00edcio do poder.<br \/>\nAparentemente, n\u00e3o precisava ser assim, pois se todos os petistas seguissem a norma de contribui\u00e7\u00e3o ao partido, o PT poderia viver sem depender de doa\u00e7\u00f5es de empresas interessadas em favorecimentos.<br \/>\nTudo indica que o toma l\u00e1-d\u00e1 c\u00e1 come\u00e7ou na campanha eleitoral e se aprofundou perigosamente no jogo do(s) partido(s) no Congresso, sem o que n\u00e3o seria poss\u00edvel aprovar programas, projetos e pol\u00edticas de interesse da maioria da popula\u00e7\u00e3o \u2013 e tamb\u00e9m de setores empresariais.<br \/>\nDeu no que deu. Mesmo sem provas, a Justi\u00e7a condenou o chefe do partido Jos\u00e9 Dirceu a mofar na cadeia por conta do Mensal\u00e3o, nome moderno de uma pr\u00e1tica ancestral na administra\u00e7\u00e3o p\u00fablica do Brasil. Tamb\u00e9m foram condenados dois tesoureiros do partido. H\u00e1 quem diga que Jos\u00e9 Dirceu \u00e9 um preso pol\u00edtico condenado por sua \u201cextrema periculosidade\u201d.<br \/>\nEm consequ\u00eancia das evid\u00eancias dos delitos, o PT perdeu grande parte de sua credibilidade e a presidenta Dilma Rousseff foi tirada do Planalto por uma conspira\u00e7\u00e3o de pol\u00edticos, procuradores e jornalistas com aval do Supremo Tribunal Federal.<br \/>\nNas elei\u00e7\u00f5es de 2016 o PT perdeu um monte de votos e de cargos. Se fosse uma empresa, estaria no vermelho e sua diretoria seria substitu\u00edda.\u00a0 Por ser um partido, a democracia interna \u00e9 sufocada pelas camangas de c\u00fapula.<br \/>\nDe uma forma ou de outra, o PT contribuiu para a degrada\u00e7\u00e3o pol\u00edtica ao fazer acordos e alian\u00e7as com escroques, farsantes, traidores e pilantras protegidos por membros da baixa, m\u00e9dia e alta magistratura. \u00a0Por isso, ap\u00f3s a Opera\u00e7\u00e3o Lava Jato, \u00e9 indispens\u00e1vel passar um bombril nas panelas do partido e promover a volta ao caminho inicial, sem medo de ser feliz.<br \/>\nAt\u00e9 agora, quem andou mais pr\u00f3ximo dessa pr\u00e1tica foi o ex-governador ga\u00facho Ol\u00edvio Dutra. Adepto da limpeza, ele \u00e9 aplaudido onde quer que v\u00e1 em Porto Alegre, mas provoca desconforto na c\u00fapula nacional do partido.<br \/>\n<span class=\"intertit\">LEMBRETE DE OCASI\u00c3O<\/span><br \/>\n\u201cH\u00e1 outro caminho poss\u00edvel. \u00c9 o caminho do crescimento econ\u00f4mico com estabilidade e responsabilidade social. As mudan\u00e7as que forem necess\u00e1rias ser\u00e3o feitas democraticamente, dentro dos marcos institucionais. Vamos ordenar as contas p\u00fablicas e mant\u00ea-las sob controle. Mas, acima de tudo, vamos fazer um Compromisso pela Produ\u00e7\u00e3o, pelo emprego e por justi\u00e7a social. O que nos move \u00e9 a certeza de que o Brasil \u00e9 bem maior que todas as crises. O pa\u00eds n\u00e3o suporta mais conviver com a ideia de uma terceira d\u00e9cada perdida. O Brasil precisa navegar no mar aberto do desenvolvimento econ\u00f4mico e social. \u00c9 com essa convic\u00e7\u00e3o que chamo todos os que querem o bem do Brasil a se unirem em torno de um programa de mudan\u00e7as corajosas e respons\u00e1veis.\u201d<br \/>\n<em>\u00a0Luiz In\u00e1cio Lula da Silva no final da Carta ao Povo Brasileiro em 22 de junho de 2002<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Geraldo Hasse Depois do aluvi\u00e3o de den\u00fancias levantadas pela Opera\u00e7\u00e3o Lava Jato nos seus primeiros dois anos e meio, soubemos recentemente que n\u00e3o foram apenas petistas que prevaricaram, mas membros de praticamente todos os principais partidos brasileiros. Portanto, a come\u00e7ar pelo PT, imp\u00f5e-se um saneamento geral para higienizar a vida partid\u00e1ria no Brasil. Para clarear [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":46328,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-46327","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analiseopiniao"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":84617,"url":"https:\/\/www.jornalja.com.br\/colunas\/o-candidato-de-si-mesmo\/","url_meta":{"origin":46327,"position":0},"title":"O candidato de si mesmo","author":"da Reda\u00e7\u00e3o","date":"10 de abril de 2026","format":false,"excerpt":"Sem emplacar nacionalmente, Leite pode ficar quatro anos sem mandato. Foto Jo\u00e3o Pedro Rodrigues\/SecomRS ELMAR BONES Ningu\u00e9m \u00e9 candidato de si mesmo. Essa \u00e9 a regra n\u00e3o escrita da pol\u00edtica partid\u00e1ria, que as velhas raposas n\u00e3o cansam de repetir aos novatos. Eduardo Leite parece n\u00e3o t\u00ea-la aprendido. Ele n\u00e3o tem\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84590,"url":"https:\/\/www.jornalja.com.br\/colunas\/e-preciso-defender-o-jardim-botanico-de-porto-alegre\/","url_meta":{"origin":46327,"position":1},"title":"\u00c9 preciso defender o Jardim Bot\u00e2nico de Porto Alegre","author":"da Reda\u00e7\u00e3o","date":"8 de mar\u00e7o de 2026","format":false,"excerpt":"CLEBER DIONI TENTARDINI O Jardim Bot\u00e2nico de Porto Alegre (JBPA) tem 67 anos e \u00e9 considerado um dos cinco melhores e maiores do Brasil. Possui 28 cole\u00e7\u00f5es cient\u00edficas que somam mais de 4.200 plantas, incluindo esp\u00e9cies raras, amea\u00e7adas de extin\u00e7\u00e3o e end\u00eamicas, que s\u00e3o encontradas apenas no RS. No local\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84737,"url":"https:\/\/www.jornalja.com.br\/colunas\/dia-internacional-da-educacao-o-brasil-que-se-revela-na-sala-de-aula\/","url_meta":{"origin":46327,"position":2},"title":"Dia Internacional da Educa\u00e7\u00e3o: o Brasil que se revela na sala de aula","author":"An\u00e1lise &amp; Opini\u00e3o","date":"28 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT A educa\u00e7\u00e3o n\u00e3o se deixa apreender como um simples conceito est\u00e1vel ou como um consenso j\u00e1 dado. Ela se apresenta, antes, como um campo de tens\u00f5es, no qual se entrecruzam disputas de sentido, sil\u00eancios hist\u00f3ricos e projetos de sociedade. Pensar a educa\u00e7\u00e3o, nesse horizonte, implica reconhecer que educar\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-1.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-1.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84776,"url":"https:\/\/www.jornalja.com.br\/colunas\/do-conforto-a-frustracao-a-falencia-do-transporte-por-aplicativo\/","url_meta":{"origin":46327,"position":3},"title":"Do conforto \u00e0 frustra\u00e7\u00e3o: a fal\u00eancia do transporte por aplicativo","author":"An\u00e1lise &amp; Opini\u00e3o","date":"7 de maio de 2026","format":false,"excerpt":"O poder p\u00fablico, que deveria atuar como mediador e garantidor de padr\u00f5es m\u00ednimos, parece operar em ritmo lento ou, em alguns casos, simplesmente se omitir. CRISTIANO GOLDSCHMIDT A promessa, no come\u00e7o, parecia quase irrecus\u00e1vel. Quem viveu aquele momento lembra bem da sensa\u00e7\u00e3o de finalmente ter encontrado uma alternativa ao transporte\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84761,"url":"https:\/\/www.jornalja.com.br\/colunas\/cmpc-nova-fabrica-velhos-impactos\/","url_meta":{"origin":46327,"position":4},"title":"CMPC: Nova f\u00e1brica, velhos impactos?","author":"Cleber Dioni Tentardini","date":"6 de maio de 2026","format":false,"excerpt":"EDUARDO RAGUSE* Por volta das 13h40, do dia 05 de maio de 2026, ocorreu a despressuriza\u00e7\u00e3o de emerg\u00eancia da caldeira da f\u00e1brica de celulose da empresa CMPC, no munic\u00edpio de Gua\u00edba. O evento causou grande susto e apreens\u00e3o entre os moradores do entorno da ind\u00fastria devido ao ru\u00eddo fort\u00edssimo, odor\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":84557,"url":"https:\/\/www.jornalja.com.br\/colunas\/entrevista-com-leonel-brizola-como-nascem-as-falsificacoes-historicas\/","url_meta":{"origin":46327,"position":5},"title":"Entrevista com Leonel Brizola: Como nascem as falsifica\u00e7\u00f5es hist\u00f3ricas","author":"An\u00e1lise &amp; Opini\u00e3o","date":"2 de mar\u00e7o de 2026","format":false,"excerpt":"SILVANA MOURA Mais do que direito \u00e0 Hist\u00f3ria, temos o direito \u00e0 verdade da Hist\u00f3ria, para evitar um passado falsificado, supostamente \u201climpo\u201d, eivado de manipula\u00e7\u00e3o e pretensa uniformidade. Em 1996 realizei, em Carazinho, uma Entrevista de Hist\u00f3ria Oral (sou Historiadora e trabalho com Hist\u00f3ria Oral h\u00e1 40 anos) com Leonel\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKo0s-c3d","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/46327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/comments?post=46327"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/46327\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/media?parent=46327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/categories?post=46327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/tags?post=46327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}