{"id":47197,"date":"2017-04-12T15:17:07","date_gmt":"2017-04-12T18:17:07","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=47197"},"modified":"2017-04-12T15:17:07","modified_gmt":"2017-04-12T18:17:07","slug":"somos-todos-campeoes-na-modalidade-corrupcao","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/colunas\/somos-todos-campeoes-na-modalidade-corrupcao\/","title":{"rendered":"Somos todos campe\u00f5es na modalidade corrup\u00e7\u00e3o"},"content":{"rendered":"<p><span class=\"assina\">Geraldo Hasse<\/span><br \/>\nMesmo com suas distor\u00e7\u00f5es de fundo pol\u00edtico-ideol\u00f3gico, a Opera\u00e7\u00e3o Lava Jato tem sido bastante pedag\u00f3gica no sentido de revelar a extens\u00e3o e a profundidade dos arranjos feitos pelos malandros profissionais para fazer a m\u00e1quina dos neg\u00f3cios funcionar em harmonia com as engrenagens do poder em benef\u00edcio da chamada turma dos camarotes.<br \/>\nEles montaram o crime quase perfeito. Funcionou por d\u00e9cadas, do primeiro ao \u00faltimo Cabral. Se foram descobertos \u00e9 porque alguns protagonistas se refestelaram tanto na sacanagem que deixaram os rabinhos de fora, como nas par\u00e1bolas sobre os sete pecados capitais.<br \/>\nQuem ainda se lembra deles? Originalmente, segundo a igreja cat\u00f3lica, eram sete: avareza, gula, inveja, ira, lux\u00faria, pregui\u00e7a, soberba. Atire a primeira pedra quem nunca andou por uma das sete casas.<br \/>\nHoje em dia h\u00e1 outros pecados, como a cobi\u00e7a, exercida indiscriminadamente por empres\u00e1rios, executivos, atletas, pol\u00edticos e pastores religiosos, entre outros.<br \/>\nAdemais, mereceriam enquadrar-se como pecados capitais a desfa\u00e7atez dos ladr\u00f5es do dinheiro p\u00fablico e a hipocrisia de tantos mentirosos de of\u00edcio e de ocasi\u00e3o. Como diz o slogan da SporTV, da Rede Globo, \u201csomos todos campe\u00f5es\u201d.<br \/>\nEntre esses, poder\u00edamos apontar o maior dos corruptos: \u00e9 o achacador, que se prevalece de posi\u00e7\u00f5es de mando para angariar vantagens para si e para seus amigos. Na cadeia, impedido de achacar pessoalmente, amea\u00e7a alcaguetar ex-companheiros. Mau car\u00e1ter integral.<br \/>\nTodos os dias os jornais trazem indicadores not\u00f3rios de que n\u00e3o h\u00e1 lugar para a \u00e9tica no mundo moderno, pois quase todas as personagens citadas no notici\u00e1rio est\u00e3o invariavelmente mais preocupadas com os aspectos materiais da vida do que com os valores morais.<br \/>\nDe fato, nada pesa mais no jogo do poder do que a for\u00e7a do dinheiro.\u00a0 Pesa tanto que se tornou o <em>leit motif<\/em> (motivo condutor) da maioria dos crimes. Se n\u00e3o \u00e9 o motivador, est\u00e1 presente no cen\u00e1rio como pano de fundo. Por isso, para a maioria das pessoas, a palavra \u201cneg\u00f3cio\u201d traz impl\u00edcita a ideia de \u201csujeira\u201d. Dizendo de outro jeito: n\u00e3o h\u00e1 jogada limpa no mundo dos neg\u00f3cios. Por extens\u00e3o, a pol\u00edtica \u00e9 um jogo essencialmente sujo.<br \/>\nPropina, graxa, mutreta, bola, maracutaia, pixuleco: seja qual for seu apelido, a corrup\u00e7\u00e3o n\u00e3o se restringe aos empres\u00e1rios e executivos ou aos pol\u00edticos e funcion\u00e1rios de minist\u00e9rios e partidos pol\u00edticos.<br \/>\nEstamos mais do que cientes de que a corrup\u00e7\u00e3o \u00e9 generalizada: come\u00e7a na base da cidadania onde eleitores vendem seus votos, passa pelos pol\u00edticos que prometem mundos e manipulam fundos doados por picaretas empresariais, e chega aos togados que julgam contas de campanhas, absolvendo camaradas e condenando advers\u00e1rios.<br \/>\nPor artes de uma esp\u00e9cie intang\u00edvel de corrup\u00e7\u00e3o, salva-se quem tiver as costas quentes ou desfrutar de foro privilegiado, uma esp\u00e9cie de asilo procurado por bandidos que se protegem com o voto popular \u2013 uma modalidade de corrup\u00e7\u00e3o que parece estar com os dias contados.<br \/>\nA partir de 11 de abril, com o amplo acolhimento pelo ministro Facchin, do STF, das dela\u00e7\u00f5es de executivos da Odebrecht, pode ser que as coisas tomem um novo rumo no \u00e2mbito dos supremos poderes, onde o jogo se concentra em apenas 11 cabe\u00e7as cansadas da guerra pol\u00edtica.<br \/>\nPROV\u00c9RBIO DE OCASI\u00c3O<br \/>\n\u201cDe barriga de mulher, de urna eleitoral e de cabe\u00e7a de juiz, ningu\u00e9m sabe o que pode sair\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Geraldo Hasse Mesmo com suas distor\u00e7\u00f5es de fundo pol\u00edtico-ideol\u00f3gico, a Opera\u00e7\u00e3o Lava Jato tem sido bastante pedag\u00f3gica no sentido de revelar a extens\u00e3o e a profundidade dos arranjos feitos pelos malandros profissionais para fazer a m\u00e1quina dos neg\u00f3cios funcionar em harmonia com as engrenagens do poder em benef\u00edcio da chamada turma dos camarotes. Eles montaram [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-47197","post","type-post","status-publish","format-standard","hentry","category-analiseopiniao"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":84714,"url":"https:\/\/www.jornalja.com.br\/colunas\/22-de-abril-o-instante-em-que-o-brasil-passa-a-existir-para-o-mundo-europeu\/","url_meta":{"origin":47197,"position":0},"title":"22 de abril: o instante em que o Brasil \u201cpassa a existir\u201d para o mundo europeu","author":"Patr\u00edcia Marini","date":"22 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Era 22 de abril de 1500 \u2014 ou, ao menos, \u00e9 assim que nos habituamos a dizer, com a serenidade quase ing\u00eanua de quem domestica o passado em datas redondas e memor\u00e1veis. Naquele dia, a esquadra comandada por Pedro \u00c1lvares Cabral avistou terra ap\u00f3s semanas de travessia pelo\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/desembarque-de-cabral-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/desembarque-de-cabral-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/desembarque-de-cabral-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/desembarque-de-cabral-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/desembarque-de-cabral-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/desembarque-de-cabral-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84742,"url":"https:\/\/www.jornalja.com.br\/colunas\/rejeicao-a-messias-quando-o-senado-tensiona-os-limites-da-democracia\/","url_meta":{"origin":47197,"position":1},"title":"Rejei\u00e7\u00e3o a Messias: quando o Senado tensiona os limites da democracia","author":"An\u00e1lise &amp; Opini\u00e3o","date":"30 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT A rejei\u00e7\u00e3o, pelo Senado, da indica\u00e7\u00e3o de Jorge Messias ao Supremo Tribunal Federal n\u00e3o \u00e9 um fato trivial \u2014 e trat\u00e1-la como um simples exerc\u00edcio de independ\u00eancia institucional seria, no m\u00ednimo, ing\u00eanuo. H\u00e1 algo mais profundo em jogo. O epis\u00f3dio exp\u00f5e, com certa nitidez, a forma como parcelas\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84776,"url":"https:\/\/www.jornalja.com.br\/colunas\/do-conforto-a-frustracao-a-falencia-do-transporte-por-aplicativo\/","url_meta":{"origin":47197,"position":2},"title":"Do conforto \u00e0 frustra\u00e7\u00e3o: a fal\u00eancia do transporte por aplicativo","author":"An\u00e1lise &amp; Opini\u00e3o","date":"7 de maio de 2026","format":false,"excerpt":"O poder p\u00fablico, que deveria atuar como mediador e garantidor de padr\u00f5es m\u00ednimos, parece operar em ritmo lento ou, em alguns casos, simplesmente se omitir. CRISTIANO GOLDSCHMIDT A promessa, no come\u00e7o, parecia quase irrecus\u00e1vel. Quem viveu aquele momento lembra bem da sensa\u00e7\u00e3o de finalmente ter encontrado uma alternativa ao transporte\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84693,"url":"https:\/\/www.jornalja.com.br\/colunas\/fim-da-escala-6x1-cabe-ao-congresso-decidir-entre-o-progresso-e-o-atraso\/","url_meta":{"origin":47197,"position":3},"title":"Fim da escala 6&#215;1: cabe ao Congresso decidir entre o progresso e o atraso","author":"da Reda\u00e7\u00e3o","date":"20 de abril de 2026","format":false,"excerpt":"Plen\u00e1rio da C\u00e2mara dos Deputados durante sess\u00e3o solene do Congresso Nacional. Caber\u00e1 ao parlamento a decis\u00e3o final sobre a nova escala de trabalho. Foto: Leopoldo Silva\/Ag\u00eancia Senado CRISTIANO GOLDSCHMIDT A discuss\u00e3o sobre o fim da escala de trabalho 6x1 no Brasil tem ganhado centralidade no debate p\u00fablico contempor\u00e2neo por tocar\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84785,"url":"https:\/\/www.jornalja.com.br\/colunas\/maternidade-e-alteridade-reflexoes-sobre-origem-vinculo-e-responsabilidade\/","url_meta":{"origin":47197,"position":4},"title":"Maternidade e Alteridade:           reflex\u00f5es sobre origem, v\u00ednculo e responsabilidade","author":"An\u00e1lise &amp; Opini\u00e3o","date":"10 de maio de 2026","format":false,"excerpt":"A no\u00e7\u00e3o contempor\u00e2nea de maternidade tem se ampliado. Hoje, reconhece-se que o cuidado e a forma\u00e7\u00e3o n\u00e3o s\u00e3o prerrogativas exclusivas da m\u00e3e biol\u00f3gica CRISTIANO GOLDSCHMIDT O Dia das M\u00e3es, frequentemente envolto em sentimentalismo previs\u00edvel, merece uma abordagem que ultrapasse o gesto autom\u00e1tico da homenagem e se aproxime de uma reflex\u00e3o\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-4.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-4.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-4.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-4.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-4.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-4.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84617,"url":"https:\/\/www.jornalja.com.br\/colunas\/o-candidato-de-si-mesmo\/","url_meta":{"origin":47197,"position":5},"title":"O candidato de si mesmo","author":"da Reda\u00e7\u00e3o","date":"10 de abril de 2026","format":false,"excerpt":"Sem emplacar nacionalmente, Leite pode ficar quatro anos sem mandato. Foto Jo\u00e3o Pedro Rodrigues\/SecomRS ELMAR BONES Ningu\u00e9m \u00e9 candidato de si mesmo. Essa \u00e9 a regra n\u00e3o escrita da pol\u00edtica partid\u00e1ria, que as velhas raposas n\u00e3o cansam de repetir aos novatos. Eduardo Leite parece n\u00e3o t\u00ea-la aprendido. Ele n\u00e3o tem\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKo0s-chf","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/47197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/comments?post=47197"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/47197\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/media?parent=47197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/categories?post=47197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/tags?post=47197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}