{"id":48856,"date":"2017-05-24T12:03:36","date_gmt":"2017-05-24T15:03:36","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=48856"},"modified":"2017-05-24T12:03:36","modified_gmt":"2017-05-24T15:03:36","slug":"o-passado-recente-e-o-futuro-proximo","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/colunas\/o-passado-recente-e-o-futuro-proximo\/","title":{"rendered":"O passado recente e o futuro pr\u00f3ximo"},"content":{"rendered":"<p><span class=\"assina\">Walmaro Paz<\/span><br \/>\nPara entender a crise pol\u00edtica atual, isto \u00e9, a segunda parte do golpe iniciado com o impeachment da presidente Dilma Rousseff, precisamos fazer uma leitura da pol\u00edtica internacional. Com a queda do muro de Berlim e a suposta \u201cderrota do socialismo\u201d, o neoliberalismo perdeu seu grande opositor b\u00e9lico e econ\u00f4mico, a Uni\u00e3o Sovi\u00e9tica.<br \/>\nAs for\u00e7as reacion\u00e1rias do imperialismo, agora disfar\u00e7adas sob o manto do processo de globaliza\u00e7\u00e3o, resolveram retomar as col\u00f4nias perdidas durante a guerra-fria, todas nos antigos territ\u00f3rios dominados chamados por eles de terceiro mundo.<br \/>\nA \u00c1frica teria que ser recolonizada e ou seu povo exterminado atrav\u00e9s de guerras civis encomendadas pela ind\u00fastria armamentista e pelas mineradoras. A Am\u00e9rica Latina deveria se submeter a uma nova f\u00f3rmula da Doutrina Monroe: Am\u00e9rica para os americanos do Norte, transformando nossos pa\u00edses novamente em exportadores de commodities e importadores de produtos manufaturados.<br \/>\nNo caso brasileiro, ainda no final dos anos 80 tentaram implementar um chamado social liberalismo, com Collor, lideran\u00e7a populista constru\u00edda pela Globo (esta ali\u00e1s o instrumento ideol\u00f3gico mais usado no processo). O povo brasileiro resistiu.<br \/>\nEnt\u00e3o, ainda nos anos 90, criaram uma lideran\u00e7a com discurso de esquerda, mas totalmente submissa para fazer as privatiza\u00e7\u00f5es e reformas necess\u00e1rias. Elegeram Fernando Henrique Cardoso (FHC), um at\u00e9 ent\u00e3o respeit\u00e1vel pensador da esquerda brasileira e come\u00e7aram o processo. H\u00e1 muito tempo os militares estavam tendo um custo muito elevado politicamente.<br \/>\nConseguiram mant\u00ea-lo durante dois mandatos e iniciaram um processo de corrup\u00e7\u00e3o nunca visto no pa\u00eds, retratado fielmente na obra \u201cPrivataria Tucana\u201d, comprando deputados de todos os partidos.<br \/>\nMas o povo elegeu Lula (Lulinha paz e amor), que j\u00e1 havia renunciado ao projeto petista e popular antes da elei\u00e7\u00e3o na Carta aos Brasileiros. Assim que eleito, o presidente metal\u00fargico foi a Washington buscar o benepl\u00e1cito do presidente Bush e voltou com o Henrique Meirelles nomeado presidente do Banco Central. Ali come\u00e7ou a rendi\u00e7\u00e3o: Meirelles era o grande nome do consenso de Washington para o Brasil.<br \/>\nEsta figura\u00a0permaneceu no centro de poder durante este tempo todo, passando pela iniciativa privada, onde foi presidente do conselho de administra\u00e7\u00e3o do grupo Friboi. Com o golpe contra a presidente eleita Dilma Rousseff que, com sua pol\u00edtica nacional-desenvolvimentista, mostrara resist\u00eancia \u00e0s exig\u00eancias, Meirelles assume a chefia da pol\u00edtica econ\u00f4mica do t\u00edtere Temer.<br \/>\nTentaram aprofundar as chamadas reformas com a destrui\u00e7\u00e3o da CLT e da Seguridade Social. Mas o povo nas ruas fez com que Temer recuasse alguns passos e isto foi insuport\u00e1vel para seus mentores. Chega deste pulha: foraTemer e come\u00e7ou o processo de desestabiliza\u00e7\u00e3o que vai eleger Meirelles presidente por via indireta e, terminando a tarefa iniciada ainda nos anos 80, empurrando goela abaixo do povo brasileiro a sua pior derrota.<br \/>\nCheguei a esta leitura da conjuntura atual principalmente pelo interesse da Globo na deposi\u00e7\u00e3o de Temer e nas den\u00fancias contra seus asseclas e a todos os pol\u00edticos al\u00e9m da campanha pelas elei\u00e7\u00f5es indiretas e a coloca\u00e7\u00e3o de um \u201ct\u00e9cnico\u201d na presid\u00eancia. \u00a0Tor\u00e7o para estar errado, vamos esperar pelo futuro pr\u00f3ximo para confirmar ou n\u00e3o esta avalia\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Walmaro Paz Para entender a crise pol\u00edtica atual, isto \u00e9, a segunda parte do golpe iniciado com o impeachment da presidente Dilma Rousseff, precisamos fazer uma leitura da pol\u00edtica internacional. Com a queda do muro de Berlim e a suposta \u201cderrota do socialismo\u201d, o neoliberalismo perdeu seu grande opositor b\u00e9lico e econ\u00f4mico, a Uni\u00e3o Sovi\u00e9tica. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-48856","post","type-post","status-publish","format-standard","hentry","category-analiseopiniao"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":84622,"url":"https:\/\/www.jornalja.com.br\/colunas\/13-de-abril-queriam-transformar-o-hino-nacional-em-grito-de-guerra-mas-ele-insiste-em-ser-canto-de-paz\/","url_meta":{"origin":48856,"position":0},"title":"13 de abril: Queriam transformar o Hino Nacional em grito de guerra, mas ele insiste em ser canto de paz","author":"da Reda\u00e7\u00e3o","date":"13 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT No calend\u00e1rio das datas c\u00edvicas, o 13 de abril passa quase em sil\u00eancio, como um acorde sustentado que poucos escutam at\u00e9 o fim. N\u00e3o h\u00e1 fogos, n\u00e3o h\u00e1 desfiles grandiosos, n\u00e3o h\u00e1 a coreografia ensaiada das celebra\u00e7\u00f5es que se imp\u00f5em ao olhar. H\u00e1, antes, uma esp\u00e9cie de pausa\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/imagem-do-poeta-brasileiro-joaquim-osorio-duque-estrada-autor-da-letra-do-hino-nacional-escaneada-do-livro-flora-de-maio-edicao-de-1902.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/imagem-do-poeta-brasileiro-joaquim-osorio-duque-estrada-autor-da-letra-do-hino-nacional-escaneada-do-livro-flora-de-maio-edicao-de-1902.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/imagem-do-poeta-brasileiro-joaquim-osorio-duque-estrada-autor-da-letra-do-hino-nacional-escaneada-do-livro-flora-de-maio-edicao-de-1902.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":84557,"url":"https:\/\/www.jornalja.com.br\/colunas\/entrevista-com-leonel-brizola-como-nascem-as-falsificacoes-historicas\/","url_meta":{"origin":48856,"position":1},"title":"Entrevista com Leonel Brizola: Como nascem as falsifica\u00e7\u00f5es hist\u00f3ricas","author":"An\u00e1lise &amp; Opini\u00e3o","date":"2 de mar\u00e7o de 2026","format":false,"excerpt":"SILVANA MOURA Mais do que direito \u00e0 Hist\u00f3ria, temos o direito \u00e0 verdade da Hist\u00f3ria, para evitar um passado falsificado, supostamente \u201climpo\u201d, eivado de manipula\u00e7\u00e3o e pretensa uniformidade. Em 1996 realizei, em Carazinho, uma Entrevista de Hist\u00f3ria Oral (sou Historiadora e trabalho com Hist\u00f3ria Oral h\u00e1 40 anos) com Leonel\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":84703,"url":"https:\/\/www.jornalja.com.br\/colunas\/tiradentes-o-martir-que-ainda-nos-observa-e-as-inquietacoes-de-um-brasil-inacabado\/","url_meta":{"origin":48856,"position":2},"title":"Tiradentes: o M\u00e1rtir que ainda nos observa e as inquieta\u00e7\u00f5es de um Brasil inacabado","author":"da Reda\u00e7\u00e3o","date":"21 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT H\u00e1 datas que n\u00e3o se imp\u00f5em pelo alarde, mas pela persist\u00eancia silenciosa com que atravessam os s\u00e9culos e se insinuam na consci\u00eancia coletiva. O 21 de abril pertence a essa estirpe discreta. N\u00e3o chega ornado de euforia, tampouco se anuncia com a grandiloqu\u00eancia de outras celebra\u00e7\u00f5es; antes, aproxima-se\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84617,"url":"https:\/\/www.jornalja.com.br\/colunas\/o-candidato-de-si-mesmo\/","url_meta":{"origin":48856,"position":3},"title":"O candidato de si mesmo","author":"da Reda\u00e7\u00e3o","date":"10 de abril de 2026","format":false,"excerpt":"Sem emplacar nacionalmente, Leite pode ficar quatro anos sem mandato. Foto Jo\u00e3o Pedro Rodrigues\/SecomRS ELMAR BONES Ningu\u00e9m \u00e9 candidato de si mesmo. Essa \u00e9 a regra n\u00e3o escrita da pol\u00edtica partid\u00e1ria, que as velhas raposas n\u00e3o cansam de repetir aos novatos. Eduardo Leite parece n\u00e3o t\u00ea-la aprendido. Ele n\u00e3o tem\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84681,"url":"https:\/\/www.jornalja.com.br\/colunas\/recordar-zuzu-angel-50-anos-apos-sua-morte-e-um-ato-etico\/","url_meta":{"origin":48856,"position":4},"title":"Recordar Zuzu Angel 50 anos ap\u00f3s sua morte \u00e9 um ato \u00e9tico","author":"da Reda\u00e7\u00e3o","date":"16 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Cinco d\u00e9cadas transcorreram desde o silenciamento brutal de Zuzu Angel (05 de junho de 1921 - 14 de abril de 1976), e ainda assim sua voz persiste \u2014 n\u00e3o como eco esmaecido, mas como um timbre agudo que rasga o tecido do tempo e se inscreve na mem\u00f3ria\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84693,"url":"https:\/\/www.jornalja.com.br\/colunas\/fim-da-escala-6x1-cabe-ao-congresso-decidir-entre-o-progresso-e-o-atraso\/","url_meta":{"origin":48856,"position":5},"title":"Fim da escala 6&#215;1: cabe ao Congresso decidir entre o progresso e o atraso","author":"da Reda\u00e7\u00e3o","date":"20 de abril de 2026","format":false,"excerpt":"Plen\u00e1rio da C\u00e2mara dos Deputados durante sess\u00e3o solene do Congresso Nacional. Caber\u00e1 ao parlamento a decis\u00e3o final sobre a nova escala de trabalho. Foto: Leopoldo Silva\/Ag\u00eancia Senado CRISTIANO GOLDSCHMIDT A discuss\u00e3o sobre o fim da escala de trabalho 6x1 no Brasil tem ganhado centralidade no debate p\u00fablico contempor\u00e2neo por tocar\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKo0s-cI0","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/48856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/comments?post=48856"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/48856\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/media?parent=48856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/categories?post=48856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/tags?post=48856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}