{"id":50044,"date":"2017-06-17T00:43:54","date_gmt":"2017-06-17T03:43:54","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=50044"},"modified":"2017-06-17T00:43:54","modified_gmt":"2017-06-17T03:43:54","slug":"dilma-tentou-levantar-sigilo-dos-incentivos-fiscais","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/colunas\/dilma-tentou-levantar-sigilo-dos-incentivos-fiscais\/","title":{"rendered":"Dilma tentou levantar sigilo dos incentivos fiscais"},"content":{"rendered":"<p>O incentivo fiscal &#8211; o imposto de que o governo abre m\u00e3o para estimular o empreendedor privado &#8211; \u00e9 inevit\u00e1vel instrumento de gest\u00e3o p\u00fablica no Brasil h\u00e1 mais de 40 anos. \u00c9 cr\u00f4nica a guerra entre os Estados para ver quem d\u00e1 mais pelos grandes projetos.<br \/>\nAgora, por\u00e9m, com a situa\u00e7\u00e3o de calamidade financeira em Estados como o Rio Grande do Sul, Rio de Janeiro e Minas Gerais, os incentivos ou benef\u00edcios fiscais a grupos privados parecem indefens\u00e1veis.<br \/>\nComo podem Estados falidos continuar abrindo m\u00e3o de bilh\u00f5es em impostos para subsidiar projetos de grandes grupos privados? Em tempos de Lava Jato faz sentido perguntar: n\u00e3o tem propina ou Caixa 2 a\u00ed?<br \/>\nNo Rio Grande do Sul, por exemplo, onde o governo h\u00e1 mais de dois anos parcela o pagamento dos funcion\u00e1rios, foram concedidos algo como R$ 48 bilh\u00f5es em isen\u00e7\u00f5es fiscais a projetos privados, nos \u00faltimos seis anos (2010-2016, dados do Afocefe). Dez por cento disso cobriria o d\u00e9ficit previsto no pior cen\u00e1rio deste ano.<br \/>\nMais indefens\u00e1vel \u00e9 a falta de claridade quanto \u00e0 utiliza\u00e7\u00e3o desses recursos que afinal s\u00e3o p\u00fablicos, pois s\u00e3o impostos que deixam de ser arrecadados.<br \/>\nNo Mato Grosso uma CPI conseguiu obter R$ 2 bilh\u00f5es de volta aos cofres p\u00fablicos.<br \/>\nNo Rio Grande do Sul, onde uma CPI n\u00e3o alcan\u00e7a as assinaturas necess\u00e1rias na Assembleia, nem o procurador geral do Minist\u00e9rio P\u00fablico de Contas conseguiu informa\u00e7\u00f5es, a n\u00e3o ser dados gerais j\u00e1 conhecidos. \u00a0Em tempos de Laja Jato faz sentido perguntar: n\u00e3o tem propina a\u00ed?<br \/>\nM\u00e1rio Wunderlich, sub-secret\u00e1rio da Receita Estadual, rebateu a afirma\u00e7\u00e3o de que os programas de incentivos fiscais do governo do Estado \u201cs\u00e3o uma caixa preta&#8221;, como diz a campanha que mobiliza 36 entidades de servidores p\u00fablicos que colhe assinaturas para uma CPI sobre o assunto.<br \/>\n\u201cAs desonera\u00e7\u00f5es n\u00e3o s\u00e3o caixa preta. A Receita tem os dados centralizados dos benef\u00edcios. O sigilo \u00e9 por determina\u00e7\u00e3o de lei\u201d, disse Wunderlich no semin\u00e1rio promovido pelo sindicato dos fiscais de tributos do Estado na quarta-feira. A receita responde pela concess\u00e3o, revis\u00e3o, monitoramento, fiscaliza\u00e7\u00e3o dos contratos de desonera\u00e7\u00e3o fiscal.<br \/>\nEle reconheceu que os quadros de fiscaliza\u00e7\u00e3o do Estado est\u00e3o desfalcados. Entre os auditores fiscais \u00a0e t\u00e9cnicos, por exemplo, h\u00e1 apenas 48% dos cargos preenchidos.<br \/>\nFoi feito um concurso, mas as nomea\u00e7\u00f5es n\u00e3o saem: \u201cEstamos h\u00e1 dois anos para receber colegas novos\u201d. \u00a0E a situa\u00e7\u00e3o tende a piorar, pois 40% dos que est\u00e3o trabalhando t\u00eam mais de 50 anos, a caminho da aposentadoria.<br \/>\nWunderlich disse\u00a0 que a proibi\u00e7\u00e3o \u00a0de revelar informa\u00e7\u00f5es sobre isen\u00e7\u00f5es decorre de uma lei aprovada \u00a0no Senado, h\u00e1 15 anos: \u201cFoi \u00a0o PL 54 que estabeleceu a proibi\u00e7\u00e3o\u201d.<br \/>\nNo ano passado, antes de cair, a presidente Dilma Rousseff encaminhou ao congresso o \u00a0PL 280, \u00a0para colocar as desonera\u00e7\u00f5es de impostos nas exce\u00e7\u00f5es em que pode ser quebrado o sigilo fiscal. \u00a0Segundo ele, o projeto est\u00e1 parado no Senado.<br \/>\n\u201cAchamos que devia ser excetuado\u201d, disse o vice secret\u00e1rio. &#8220;Entendemos que devemos fornecer informa\u00e7\u00f5es individualizadas\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O incentivo fiscal &#8211; o imposto de que o governo abre m\u00e3o para estimular o empreendedor privado &#8211; \u00e9 inevit\u00e1vel instrumento de gest\u00e3o p\u00fablica no Brasil h\u00e1 mais de 40 anos. \u00c9 cr\u00f4nica a guerra entre os Estados para ver quem d\u00e1 mais pelos grandes projetos. Agora, por\u00e9m, com a situa\u00e7\u00e3o de calamidade financeira em [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-50044","post","type-post","status-publish","format-standard","hentry","category-analiseopiniao"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":84564,"url":"https:\/\/www.jornalja.com.br\/colunas\/a-nova-celulose-a-beira-do-guaiba-e-o-risco-de-repetir-a-borregaard\/","url_meta":{"origin":50044,"position":0},"title":"A nova celulose \u00e0 beira do Gua\u00edba e o risco de repetir a Borregaard","author":"An\u00e1lise &amp; Opini\u00e3o","date":"6 de mar\u00e7o de 2026","format":false,"excerpt":"ELMAR BONES No dia 16 de mar\u00e7o de 1972 foi inaugurada a Ind\u00fastria de Celulose Borregaard, em Gua\u00edba, com a presen\u00e7a das mais altas autoridades e manchetes ufanistas em todos os jornais. Inaugura\u00e7\u00e3o da f\u00e1brica em Gua\u00edba, no ano de 1972. Foto Reprodu\u00e7\u00e3o Arquivo\/CeluloseRioGrandense Seria uma das maiores f\u00e1bricas em\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84590,"url":"https:\/\/www.jornalja.com.br\/colunas\/e-preciso-defender-o-jardim-botanico-de-porto-alegre\/","url_meta":{"origin":50044,"position":1},"title":"\u00c9 preciso defender o Jardim Bot\u00e2nico de Porto Alegre","author":"da Reda\u00e7\u00e3o","date":"8 de mar\u00e7o de 2026","format":false,"excerpt":"CLEBER DIONI TENTARDINI O Jardim Bot\u00e2nico de Porto Alegre (JBPA) tem 67 anos e \u00e9 considerado um dos cinco melhores e maiores do Brasil. Possui 28 cole\u00e7\u00f5es cient\u00edficas que somam mais de 4.200 plantas, incluindo esp\u00e9cies raras, amea\u00e7adas de extin\u00e7\u00e3o e end\u00eamicas, que s\u00e3o encontradas apenas no RS. No local\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84617,"url":"https:\/\/www.jornalja.com.br\/colunas\/o-candidato-de-si-mesmo\/","url_meta":{"origin":50044,"position":2},"title":"O candidato de si mesmo","author":"da Reda\u00e7\u00e3o","date":"10 de abril de 2026","format":false,"excerpt":"Sem emplacar nacionalmente, Leite pode ficar quatro anos sem mandato. Foto Jo\u00e3o Pedro Rodrigues\/SecomRS ELMAR BONES Ningu\u00e9m \u00e9 candidato de si mesmo. Essa \u00e9 a regra n\u00e3o escrita da pol\u00edtica partid\u00e1ria, que as velhas raposas n\u00e3o cansam de repetir aos novatos. Eduardo Leite parece n\u00e3o t\u00ea-la aprendido. Ele n\u00e3o tem\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84761,"url":"https:\/\/www.jornalja.com.br\/colunas\/cmpc-nova-fabrica-velhos-impactos\/","url_meta":{"origin":50044,"position":3},"title":"CMPC: Nova f\u00e1brica, velhos impactos?","author":"Cleber Dioni Tentardini","date":"6 de maio de 2026","format":false,"excerpt":"EDUARDO RAGUSE* Por volta das 13h40, do dia 05 de maio de 2026, ocorreu a despressuriza\u00e7\u00e3o de emerg\u00eancia da caldeira da f\u00e1brica de celulose da empresa CMPC, no munic\u00edpio de Gua\u00edba. O evento causou grande susto e apreens\u00e3o entre os moradores do entorno da ind\u00fastria devido ao ru\u00eddo fort\u00edssimo, odor\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":84725,"url":"https:\/\/www.jornalja.com.br\/colunas\/e-preciso-refletir-sobre-os-mais-de-84-mil-desaparecidos-no-brasil-em-2025\/","url_meta":{"origin":50044,"position":4},"title":"\u00c9 preciso refletir sobre os mais de 84 mil desaparecidos no Brasil em 2025","author":"An\u00e1lise &amp; Opini\u00e3o","date":"23 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Em 2025, o Brasil registrou 84.760 pessoas desaparecidas, segundo dados consolidados pelo Sistema Nacional de Informa\u00e7\u00f5es de Seguran\u00e7a P\u00fablica Sinesp), vinculado ao Minist\u00e9rio da Justi\u00e7a e Seguran\u00e7a P\u00fablica. Mais do que um n\u00famero expressivo, o dado revela um fen\u00f4meno cont\u00ednuo, distribu\u00eddo no tempo e no territ\u00f3rio \u2014 e,\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84681,"url":"https:\/\/www.jornalja.com.br\/colunas\/recordar-zuzu-angel-50-anos-apos-sua-morte-e-um-ato-etico\/","url_meta":{"origin":50044,"position":5},"title":"Recordar Zuzu Angel 50 anos ap\u00f3s sua morte \u00e9 um ato \u00e9tico","author":"da Reda\u00e7\u00e3o","date":"16 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Cinco d\u00e9cadas transcorreram desde o silenciamento brutal de Zuzu Angel (05 de junho de 1921 - 14 de abril de 1976), e ainda assim sua voz persiste \u2014 n\u00e3o como eco esmaecido, mas como um timbre agudo que rasga o tecido do tempo e se inscreve na mem\u00f3ria\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKo0s-d1a","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/50044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/comments?post=50044"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/50044\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/media?parent=50044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/categories?post=50044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/tags?post=50044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}