{"id":50208,"date":"2017-06-19T08:53:42","date_gmt":"2017-06-19T11:53:42","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=50208"},"modified":"2017-06-19T08:53:42","modified_gmt":"2017-06-19T11:53:42","slug":"o-caso-andreas-von-richthofen-e-a-esquerda-brasileira","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/colunas\/o-caso-andreas-von-richthofen-e-a-esquerda-brasileira\/","title":{"rendered":"O caso Andreas von Richthofen e a esquerda brasileira"},"content":{"rendered":"<p><strong>Eduardo Maretti<\/strong><br \/>\nAo escrever estas curtas impress\u00f5es, esclare\u00e7o que minha preocupa\u00e7\u00e3o, aqui, n\u00e3o tem a ver com filtros do senso comum. A premissa \u00e9 que escrevo pensando em algo &#8220;m\u00e1s all\u00e1&#8221;, mas sempre dentro da esquerda brasileira.<br \/>\nDito isso, quero dizer que a esquerda brasileira tem que evoluir muito para ser transformadora. Penso no mestre Pier Paolo Pasolini.<br \/>\nUso para esta modesta an\u00e1lise impressionista o caso Andreas von Richthofen. Como era de se esperar, ap\u00f3s vir a p\u00fablico a informa\u00e7\u00e3o de que Andreas &#8212; o irm\u00e3o de Suzane, condenada por ser a autora intelectual do assassinato dos pais em 2002 &#8212; foi encontrado em condi\u00e7\u00f5es prec\u00e1rias e com &#8220;sinais de uso de drogas&#8221;, n\u00e3o tardaram as abordagens simplistas e, eu diria, espiritual e filosoficamente lim\u00edtrofes, sobre o caso, por parte da nossa nobre esquerda.<br \/>\nUma dessas abordagens, t\u00edpicas, diz o seguinte: &#8220;\u00e9 f\u00e1cil ter compaix\u00e3o e empatia pelo Andreas. Bem nascido, loirinho, frequentou os melhores col\u00e9gios e vivemos, todos, a sua dor. Vimos a destrui\u00e7\u00e3o da sua fam\u00edlia. Solidarizamos a dor dele, quando teve os pais assassinados. Dif\u00edcil mesmo \u00e9 enxergar humanidade e ter compaix\u00e3o e empatia com o viciado que parece vindo de outro mundo. Que \u00e9 analfabeto. Que sempre morou na rua e que j\u00e1 passou pela cadeia algumas vezes&#8221;.\u00a0\u00c9 o que diz <a href=\"http:\/\/justificando.cartacapital.com.br\/2017\/05\/31\/sabe-o-embrulho-no-estomago-ao-ver-que-andreas-estava-na-cracolandia\" data-saferedirecturl=\"http:\/\/www.google.com\/url?hl=pt-BR&amp;q=http:\/\/justificando.cartacapital.com.br\/2017\/05\/31\/sabe-o-embrulho-no-estomago-ao-ver-que-andreas-estava-na-cracolandia&amp;source=gmail&amp;ust=1497958309018000&amp;usg=AFQjCNFKqslxt1jD6yVMDR-_AovMQRebQg\">Marcelo Feller<\/a>, advogado criminal.<br \/>\n<em>Data venia<\/em>, \u00e9 o mesmo tipo de argumenta\u00e7\u00e3o que encara um atentado como o de Paris em 2015, ou o de Manchester, no m\u00eas passado, com afirma\u00e7\u00f5es do tipo: <em>\u00e9 f\u00e1cil lamentar as mortes de Paris, mas dif\u00edcil mesmo \u00e9 enxergar a humanidade dos assassinados nas periferias de S\u00e3o Paulo<\/em> etc etc etc.<br \/>\n\u00c9 como se a pessoa &#8220;bem nascida, loirinha&#8221;, <em>aben\u00e7oada <\/em>por ter frequentado &#8220;os melhores col\u00e9gios&#8221;, fosse destitu\u00edda de humanidade. \u00c9 um argumento filosoficamente indefens\u00e1vel. Um argumento que, no limite, justificaria os atentados de Paris de 2015.<br \/>\nAmbos, Andreas e o menino pobre da periferia, merecem a mesma compaix\u00e3o. A dor de ambos d\u00f3i igualmente, na alma. Mas na alma deles. A dor \u00e9 espiritual e f\u00edsica, e existencial.<br \/>\nSe ser humanista \u00e9 ser antiquado, eu sou antiquado. A quest\u00e3o de Andreas estar ou n\u00e3o na Cracol\u00e2ndia n\u00e3o importa.<br \/>\nA esquerda, da qual eu fa\u00e7o parte, precisa ir al\u00e9m do materialismo e do determinismo.<br \/>\n\u00c9 \u00f3bvio ululante, como diria Nelson Rodrigues, que o pa\u00eds, e particularmente S\u00e3o Paulo, est\u00e3o submetidos a pol\u00edticas higienistas e fascistas. Voltamos d\u00e9cadas no tempo. Sofremos um golpe (que, ali\u00e1s, foi conseguido de maneira t\u00e3o f\u00e1cil que chega a ser deprimente ser brasileiro na atual conjuntura &#8211; mas isso \u00e9 outro assunto).<br \/>\nE n\u00e3o \u00e9 isso que discuto aqui. Aqui, parto do pressuposto de que o fascismo \u00e9 incab\u00edvel no s\u00e9culo XXI. Mas, repito: a esquerda brasileira precisa ir al\u00e9m do materialismo e do determinismo.<br \/>\nA esquerda brasileira deveria ler Nietzsche, Dostoi\u00e9vski, Sartre e Baudelaire, para interpretar a hist\u00f3ria sob perspectivas menos materialistas e deterministas. Perspectivas que possam superar as abordagens f\u00e1ceis. Entender o sofrimento de Rask\u00f3lnikov (o protagonista de <em>Crime e Castigo<\/em>, de Dostoi\u00e9vski) da mesma maneira que entende o sofrimento dos perseguidos pelo higienismo fascista de Jo\u00e3o Doria. S\u00e3o dimens\u00f5es diferentes. Mas dimens\u00f5es que precisam ser compreendidas como paralelas.<br \/>\nA esquerda brasileira precisa se desvencilhar de seus moralismos e ir &#8220;m\u00e1s all\u00e1&#8221;, se quiser transformar este pobre Brasil em algo digno de ser chamado de uma na\u00e7\u00e3o.<br \/>\n\u00c9 s\u00f3 isso. <em>Data venia<\/em>.<br \/>\n<em>(Publicado originalmente no <a href=\"http:\/\/fatosetc.blogspot.com.br\/2017\/06\/o-caso-andreas-von-richthofen-e.html?utm_source=feedburner&amp;utm_medium=email&amp;utm_campaign=Feed:+FatosEtc+(Fatos+Etc.)\">blog <strong>Fatos Etc.<\/strong><\/a>)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eduardo Maretti Ao escrever estas curtas impress\u00f5es, esclare\u00e7o que minha preocupa\u00e7\u00e3o, aqui, n\u00e3o tem a ver com filtros do senso comum. A premissa \u00e9 que escrevo pensando em algo &#8220;m\u00e1s all\u00e1&#8221;, mas sempre dentro da esquerda brasileira. Dito isso, quero dizer que a esquerda brasileira tem que evoluir muito para ser transformadora. Penso no mestre [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-50208","post","type-post","status-publish","format-standard","hentry","category-analiseopiniao"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":84748,"url":"https:\/\/www.jornalja.com.br\/colunas\/a-literatura-brasileira-no-dia-do-trabalhador\/","url_meta":{"origin":50208,"position":0},"title":"A Literatura Brasileira no Dia do Trabalho","author":"An\u00e1lise &amp; Opini\u00e3o","date":"1 de maio de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT O 1\u00ba de maio costuma ser lembrado pelo peso hist\u00f3rico das lutas trabalhistas, pelo som das manifesta\u00e7\u00f5es e pela mem\u00f3ria viva de direitos conquistados ao longo de d\u00e9cadas. No entanto, essa mesma data abriga uma outra forma de celebra\u00e7\u00e3o, menos ruidosa, mas igualmente significativa: o Dia da Literatura\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84742,"url":"https:\/\/www.jornalja.com.br\/colunas\/rejeicao-a-messias-quando-o-senado-tensiona-os-limites-da-democracia\/","url_meta":{"origin":50208,"position":1},"title":"Rejei\u00e7\u00e3o a Messias: quando o Senado tensiona os limites da democracia","author":"An\u00e1lise &amp; Opini\u00e3o","date":"30 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT A rejei\u00e7\u00e3o, pelo Senado, da indica\u00e7\u00e3o de Jorge Messias ao Supremo Tribunal Federal n\u00e3o \u00e9 um fato trivial \u2014 e trat\u00e1-la como um simples exerc\u00edcio de independ\u00eancia institucional seria, no m\u00ednimo, ing\u00eanuo. H\u00e1 algo mais profundo em jogo. O epis\u00f3dio exp\u00f5e, com certa nitidez, a forma como parcelas\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84725,"url":"https:\/\/www.jornalja.com.br\/colunas\/e-preciso-refletir-sobre-os-mais-de-84-mil-desaparecidos-no-brasil-em-2025\/","url_meta":{"origin":50208,"position":2},"title":"\u00c9 preciso refletir sobre os mais de 84 mil desaparecidos no Brasil em 2025","author":"An\u00e1lise &amp; Opini\u00e3o","date":"23 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Em 2025, o Brasil registrou 84.760 pessoas desaparecidas, segundo dados consolidados pelo Sistema Nacional de Informa\u00e7\u00f5es de Seguran\u00e7a P\u00fablica Sinesp), vinculado ao Minist\u00e9rio da Justi\u00e7a e Seguran\u00e7a P\u00fablica. Mais do que um n\u00famero expressivo, o dado revela um fen\u00f4meno cont\u00ednuo, distribu\u00eddo no tempo e no territ\u00f3rio \u2014 e,\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84737,"url":"https:\/\/www.jornalja.com.br\/colunas\/dia-internacional-da-educacao-o-brasil-que-se-revela-na-sala-de-aula\/","url_meta":{"origin":50208,"position":3},"title":"Dia Internacional da Educa\u00e7\u00e3o: o Brasil que se revela na sala de aula","author":"An\u00e1lise &amp; Opini\u00e3o","date":"28 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT A educa\u00e7\u00e3o n\u00e3o se deixa apreender como um simples conceito est\u00e1vel ou como um consenso j\u00e1 dado. Ela se apresenta, antes, como um campo de tens\u00f5es, no qual se entrecruzam disputas de sentido, sil\u00eancios hist\u00f3ricos e projetos de sociedade. Pensar a educa\u00e7\u00e3o, nesse horizonte, implica reconhecer que educar\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-1.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-1.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84617,"url":"https:\/\/www.jornalja.com.br\/colunas\/o-candidato-de-si-mesmo\/","url_meta":{"origin":50208,"position":4},"title":"O candidato de si mesmo","author":"da Reda\u00e7\u00e3o","date":"10 de abril de 2026","format":false,"excerpt":"Sem emplacar nacionalmente, Leite pode ficar quatro anos sem mandato. Foto Jo\u00e3o Pedro Rodrigues\/SecomRS ELMAR BONES Ningu\u00e9m \u00e9 candidato de si mesmo. Essa \u00e9 a regra n\u00e3o escrita da pol\u00edtica partid\u00e1ria, que as velhas raposas n\u00e3o cansam de repetir aos novatos. Eduardo Leite parece n\u00e3o t\u00ea-la aprendido. Ele n\u00e3o tem\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84673,"url":"https:\/\/www.jornalja.com.br\/colunas\/40-anos-sem-simone-de-beauvoir-uma-interlocutora-ainda-incomoda-do-presente\/","url_meta":{"origin":50208,"position":5},"title":"40 anos sem Simone de Beauvoir, uma interlocutora ainda inc\u00f4moda do presente","author":"da Reda\u00e7\u00e3o","date":"14 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Quarenta anos ap\u00f3s a morte de Simone de Beauvoir (9 de janeiro de 1908 - 14 de abril de 1986), descubro que sua aus\u00eancia n\u00e3o \u00e9 propriamente um vazio \u2014 \u00e9 antes um rumor cont\u00ednuo, uma esp\u00e9cie de presen\u00e7a indireta que se infiltra nas conversas, nos livros, nas\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/simone-de-beauvoir-memorias-de-uma-menina-bemcomportada.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKo0s-d3O","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/50208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/comments?post=50208"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/50208\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/media?parent=50208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/categories?post=50208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/tags?post=50208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}