{"id":51520,"date":"2017-07-16T20:32:54","date_gmt":"2017-07-16T23:32:54","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=51520"},"modified":"2017-07-16T20:32:54","modified_gmt":"2017-07-16T23:32:54","slug":"eles-nao-querem-diminuir-o-desemprego","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/colunas\/eles-nao-querem-diminuir-o-desemprego\/","title":{"rendered":"Eles n\u00e3o querem diminuir o desemprego"},"content":{"rendered":"<p><span class=\"assina\">ANDRES VINCE<\/span><br \/>\nNo in\u00edcio de 2014, quando o Brasil beliscou o pleno emprego, do alto da mesa mais cara, do restaurante mais caro, da cidade mais cara, foi decretado: \u201cisso tem que acabar!\u201d.<br \/>\nA gota d\u2019\u00e1gua, que transbordou a ta\u00e7a da elite econ\u00f4mica brasileira, havia pingado de algum lugar entre a cozinha e os corredores das mesas, por onde circulam os servi\u00e7ais.<br \/>\nEstava decidido: nenhum membro daquela elite iria tolerar mais ser submetido aos desmandos dessa ditadura de trabalhadores que se instalou no pa\u00eds. Nenhum deles iria aceitar mais negociar em igualdade de condi\u00e7\u00f5es. \u201cAumento real de sal\u00e1rio?\u201d. Abusados. \u201cTem quem pague?\u201d. Mentira! Que absurdo! \u201cParticipa\u00e7\u00e3o maior nos lucros crescentes?\u201d. Um acinte! \u201cAmpliar direitos trabalhistas?\u201d V\u00e2ndalos! Est\u00e3o acabando com a livre iniciativa! Como vamos investir num pa\u00eds onde somos ref\u00e9ns \u201cdessa gente\u201d?<br \/>\nMenos de tr\u00eas anos depois, tudo j\u00e1 est\u00e1 resolvido. N\u00e3o s\u00f3 resolvido, como definitivamente remediado. A cobra est\u00e1 morta, e agora, orgulhosa, a elite mostra o pau.<br \/>\nN\u00e3o adiantou nem tomar a mesa do Senado \u00e0 unha, para evitar que o trabalhador fosse servido de sobremesa. E a cena das senadoras comendo quentinhas na mesa do Senado, pat\u00e9tica para os elitistas, era apenas o ensaio do que o trabalhador ser\u00e1 submetido daqui pra frente.<br \/>\nPorque \u00e9 assim que funciona: hoje, te tiram meia hora de almo\u00e7o; amanh\u00e3 ser\u00e1: \u201cpra que almo\u00e7o?\u201d. Tudo em nome da modernidade e da competitividade<br \/>\nMas, a verdade \u00e9 que essa elite nacional n\u00e3o quer competir com ningu\u00e9m. N\u00e2o conseguem dar conta nem do mercado interno! Eles n\u00e3o precisam de (mais) dinheiro, j\u00e1 tem o suficiente para incont\u00e1veis gera\u00e7\u00f5es. O problema n\u00e3o \u00e9 o dinheiro. O objetivo que eles buscavam, e atingiram com m\u00e9ritos, era retomar o poder e, consequentemente, as pol\u00edticas p\u00fablicas: &#8220;chega de cr\u00e9dito pra pedreiro e a\u00e7ougueiro, n\u00f3s queremos \u00e9 o gar\u00e7om!&#8221;.<br \/>\nCerta senadora destes pagos, orgulhosa representante do agroneg\u00f3cio nacional, disse da tribuna, no dia seguinte ao da revoga\u00e7\u00e3o da lei \u00e1urea, que a atitude das senadoras de\u00a0tomar a mesa foi bolivariana, e que \u201co Brasil n\u00e3o \u00e9 uma Venezuela.\u201d.<br \/>\n\u00c9 uma pena que n\u00e3o seja senadora, pois l\u00e1, seja de direita ou de esquerda, as pessoas est\u00e3o nas ruas, lutando por seus interesses, e, as mortes que esses conflitos geram, s\u00e3o muito mais valorosas que as mortes causadas pela neglig\u00eancia administrativa a qual essa mesma senadora d\u00e1 suporte. Pelo menos, por l\u00e1, as pessoas morrem lutando pelos seus ideais, n\u00e3o por inani\u00e7\u00e3o.<br \/>\nPor aqui, ao contr\u00e1rio da Venezuela, onde a resist\u00eancia \u00e9 admir\u00e1vel, a elite conseguiu seu objetivo: enfraquecer a classe trabalhadora e as minorias, para que esteja sempre abaixo da sola do sapato do sistema.<br \/>\nTudo sem causar traumas. Para eles, \u00e9 claro.<br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ANDRES VINCE No in\u00edcio de 2014, quando o Brasil beliscou o pleno emprego, do alto da mesa mais cara, do restaurante mais caro, da cidade mais cara, foi decretado: \u201cisso tem que acabar!\u201d. A gota d\u2019\u00e1gua, que transbordou a ta\u00e7a da elite econ\u00f4mica brasileira, havia pingado de algum lugar entre a cozinha e os corredores [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":51522,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-51520","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analiseopiniao"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":84748,"url":"https:\/\/www.jornalja.com.br\/colunas\/a-literatura-brasileira-no-dia-do-trabalhador\/","url_meta":{"origin":51520,"position":0},"title":"A Literatura Brasileira no Dia do Trabalho","author":"An\u00e1lise &amp; Opini\u00e3o","date":"1 de maio de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT O 1\u00ba de maio costuma ser lembrado pelo peso hist\u00f3rico das lutas trabalhistas, pelo som das manifesta\u00e7\u00f5es e pela mem\u00f3ria viva de direitos conquistados ao longo de d\u00e9cadas. No entanto, essa mesma data abriga uma outra forma de celebra\u00e7\u00e3o, menos ruidosa, mas igualmente significativa: o Dia da Literatura\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84776,"url":"https:\/\/www.jornalja.com.br\/colunas\/do-conforto-a-frustracao-a-falencia-do-transporte-por-aplicativo\/","url_meta":{"origin":51520,"position":1},"title":"Do conforto \u00e0 frustra\u00e7\u00e3o: a fal\u00eancia do transporte por aplicativo","author":"An\u00e1lise &amp; Opini\u00e3o","date":"7 de maio de 2026","format":false,"excerpt":"O poder p\u00fablico, que deveria atuar como mediador e garantidor de padr\u00f5es m\u00ednimos, parece operar em ritmo lento ou, em alguns casos, simplesmente se omitir. CRISTIANO GOLDSCHMIDT A promessa, no come\u00e7o, parecia quase irrecus\u00e1vel. Quem viveu aquele momento lembra bem da sensa\u00e7\u00e3o de finalmente ter encontrado uma alternativa ao transporte\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84761,"url":"https:\/\/www.jornalja.com.br\/colunas\/cmpc-nova-fabrica-velhos-impactos\/","url_meta":{"origin":51520,"position":2},"title":"CMPC: Nova f\u00e1brica, velhos impactos?","author":"Cleber Dioni Tentardini","date":"6 de maio de 2026","format":false,"excerpt":"EDUARDO RAGUSE* Por volta das 13h40, do dia 05 de maio de 2026, ocorreu a despressuriza\u00e7\u00e3o de emerg\u00eancia da caldeira da f\u00e1brica de celulose da empresa CMPC, no munic\u00edpio de Gua\u00edba. O evento causou grande susto e apreens\u00e3o entre os moradores do entorno da ind\u00fastria devido ao ru\u00eddo fort\u00edssimo, odor\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":84737,"url":"https:\/\/www.jornalja.com.br\/colunas\/dia-internacional-da-educacao-o-brasil-que-se-revela-na-sala-de-aula\/","url_meta":{"origin":51520,"position":3},"title":"Dia Internacional da Educa\u00e7\u00e3o: o Brasil que se revela na sala de aula","author":"An\u00e1lise &amp; Opini\u00e3o","date":"28 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT A educa\u00e7\u00e3o n\u00e3o se deixa apreender como um simples conceito est\u00e1vel ou como um consenso j\u00e1 dado. Ela se apresenta, antes, como um campo de tens\u00f5es, no qual se entrecruzam disputas de sentido, sil\u00eancios hist\u00f3ricos e projetos de sociedade. Pensar a educa\u00e7\u00e3o, nesse horizonte, implica reconhecer que educar\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-1.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-1.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84690,"url":"https:\/\/www.jornalja.com.br\/colunas\/17-de-abril-de-1996-30-anos-do-massacre-de-eldorado-do-carajas\/","url_meta":{"origin":51520,"position":4},"title":"17 de abril de 1996: 30 anos do Massacre de Eldorado do Caraj\u00e1s","author":"da Reda\u00e7\u00e3o","date":"17 de abril de 2026","format":false,"excerpt":"Cruz marca o local do massacre em Eldorado dos Caraj\u00e1s, Par\u00e1. Foto: Marcello Casal Jr.\/Arquivo ABr CRISTIANO GOLDSCHMIDT H\u00e1 datas que n\u00e3o passam. Ficam suspensas no tempo como poeira vermelha sobre a pele \u2014 insistem, infiltram-se, recusam o esquecimento. Abril, no sul do Par\u00e1, \u00e9 sempre um m\u00eas que arde.\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84622,"url":"https:\/\/www.jornalja.com.br\/colunas\/13-de-abril-queriam-transformar-o-hino-nacional-em-grito-de-guerra-mas-ele-insiste-em-ser-canto-de-paz\/","url_meta":{"origin":51520,"position":5},"title":"13 de abril: Queriam transformar o Hino Nacional em grito de guerra, mas ele insiste em ser canto de paz","author":"da Reda\u00e7\u00e3o","date":"13 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT No calend\u00e1rio das datas c\u00edvicas, o 13 de abril passa quase em sil\u00eancio, como um acorde sustentado que poucos escutam at\u00e9 o fim. N\u00e3o h\u00e1 fogos, n\u00e3o h\u00e1 desfiles grandiosos, n\u00e3o h\u00e1 a coreografia ensaiada das celebra\u00e7\u00f5es que se imp\u00f5em ao olhar. H\u00e1, antes, uma esp\u00e9cie de pausa\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/imagem-do-poeta-brasileiro-joaquim-osorio-duque-estrada-autor-da-letra-do-hino-nacional-escaneada-do-livro-flora-de-maio-edicao-de-1902.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/imagem-do-poeta-brasileiro-joaquim-osorio-duque-estrada-autor-da-letra-do-hino-nacional-escaneada-do-livro-flora-de-maio-edicao-de-1902.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/imagem-do-poeta-brasileiro-joaquim-osorio-duque-estrada-autor-da-letra-do-hino-nacional-escaneada-do-livro-flora-de-maio-edicao-de-1902.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKo0s-doY","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/51520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/comments?post=51520"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/51520\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/media?parent=51520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/categories?post=51520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/tags?post=51520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}