{"id":52406,"date":"2017-08-01T10:12:47","date_gmt":"2017-08-01T13:12:47","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=52406"},"modified":"2017-08-01T10:12:47","modified_gmt":"2017-08-01T13:12:47","slug":"a-intervencao-no-rio-e-as-eleicoes-de-2018","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/colunas\/a-intervencao-no-rio-e-as-eleicoes-de-2018\/","title":{"rendered":"A Interven\u00e7\u00e3o no Rio e as elei\u00e7\u00f5es de 2018"},"content":{"rendered":"<p><span class=\"assina\">Jorge Rubem Folena de Oliveira*<\/span><br \/>\nO estado do Rio de Janeiro est\u00e1 sob uma interven\u00e7\u00e3o federal branca e a Garantia da Lei e da Ordem (GLO), decretada por Temer em 28 de julho de 2017, est\u00e1 em desacordo com a Constitui\u00e7\u00e3o e a lei de emprego das For\u00e7as Armadas (FFAA).<br \/>\nO governador do Estado do Rio de Janeiro deve ser imediatamente afastado de suas fun\u00e7\u00f5es, uma vez que permitiu uma interven\u00e7\u00e3o federal no Rio de Janeiro.<br \/>\nPara ser autorizada a decreta\u00e7\u00e3o da GLO, como fez Temer, era necess\u00e1rio que o governador Pez\u00e3o declarasse formalmente, por decreto, que as for\u00e7as de seguran\u00e7a do Rio de Janeiro s\u00e3o incapazes de combater o aumento da viol\u00eancia no Estado; restando, desta forma, esgotado os requisitos do artigo 144 da Constitui\u00e7\u00e3o (quanto ao uso das for\u00e7as de seguran\u00e7a p\u00fablica) para autorizar o emprego da GLO, prevista no artigo 142 da Constitui\u00e7\u00e3o.<br \/>\nCaso tal declara\u00e7\u00e3o tivesse sido feita, os militares poderiam ser empregados, por <strong><em>tempo determinado e com atua\u00e7\u00e3o em \u00e1reas delimitadas<\/em><\/strong>, \u00a0como apoio para a garantia da lei e da ordem.<br \/>\nMas o que de fato ocorreu foi que Pez\u00e3o, pressionado por Temer e Meirelles, e com a finalidade de entregar\/vender a CEDAE, permitiu que Temer (de forma disfar\u00e7ada e jogando para a plateia) utilizasse as FFAA como pol\u00edcia para atuar nas ruas do Rio de Janeiro at\u00e9 o final do ano de 2017.<br \/>\nA Constitui\u00e7\u00e3o Federal diz que pode ser decretada a interven\u00e7\u00e3o federal em caso de \u201ccomprometimento da ordem p\u00fablica\u201d (artigo 35, III). Neste caso, dever\u00e1 ser nomeado, por decreto, um interventor federal a ser submetido ao Congresso Nacional, no prazo de 24 horas (artigo 36, \u00a7 1.\u00ba).<br \/>\nNo caso, Temer, usando de subterf\u00fagio para fugir das r\u00edgidas regras da interven\u00e7\u00e3o federal, nomeou o Ministro da Defesa, com o auxilio dos ministros do Gabinete de Seguran\u00e7a Institucional e da Justi\u00e7a, como interventor no Rio do Janeiro.<br \/>\nA Garantia da Lei e da Ordem est\u00e1 sendo utilizada de forma indevida pelo governo federal, como tem denunciado o Comandante do Ex\u00e9rcito em v\u00e1rias oportunidades. N\u00e3o \u00e9 papel constitucional das FFAA servir de guarda pretoriana de governos impopulares nem de pol\u00edcia, pois isto pode expor demasiadamente os militares, para o caso de haver mortes ou repress\u00f5es al\u00e9m da medida.<br \/>\nNo caso do Rio de Janeiro, como nos demais Estados brasileiros, o aumento da viol\u00eancia urbana est\u00e1 ligada ao aumento da pobreza e ao corte de verbas p\u00fablicas, patrocinadas pelo desgoverno Temer neste \u00faltimo ano.<br \/>\nAl\u00e9m disso, n\u00e3o existe uma efetiva pol\u00edtica de combate aos neg\u00f3cios relacionados com o tr\u00e1fico internacional de armas e entorpecentes, que exigem grande movimenta\u00e7\u00e3o de capitais e lavagem de dinheiro, que n\u00e3o s\u00e3o fiscalizadas adequadamente pelas autoridades monet\u00e1rias e fiscais do governo federal. Diga-se de passagem que, quem controla a movimenta\u00e7\u00e3o financeira s\u00e3o os bancos (mercado financeiro), cuja fiscaliza\u00e7\u00e3o \u00e9 atribui\u00e7\u00e3o do Banco Central.<br \/>\nO Brasil retornou para o mapa da mis\u00e9ria, de onde tinha sa\u00eddo. Logo, a viol\u00eancia tende a aumentar cada vez mais, tendo em vista a situa\u00e7\u00e3o econ\u00f4mica atual, com um quadro superior a quinze milh\u00f5es de desempregados. As causas do aumento da viol\u00eancia s\u00e3o pol\u00edticas, econ\u00f4micas e sociais, e os militares n\u00e3o ter\u00e3o como elimin\u00e1-las.<br \/>\nO decreto da GLO, de 28 de julho de 2017, cont\u00e9m erro crassos, como a aus\u00eancia da indica\u00e7\u00e3o de \u00e1rea espec\u00edfica para a atua\u00e7\u00e3o dos militares, o que contraria o artigo 15, \u00a7 4.<sup>\u00ba<\/sup>, da Lei Complementar 97\/99. Ou seja, foi conferida ao Ministro da Defesa a delega\u00e7\u00e3o de empregar as FFAA por todo o Estado do Rio de Janeiro, quando deveriam ser especificados os locais em que os militares poderiam atuar, como ocorreu anteriormente nos complexos do Alem\u00e3o e Mar\u00e9.<br \/>\nAdemais, o planejamento das a\u00e7\u00f5es dos militares foi delegado para autoridades como os ministros do Gabinete de Seguran\u00e7a Institucional, da Justi\u00e7a e da Secretaria de Seguran\u00e7a P\u00fablica do Rio de Janeiro. Por\u00e9m, a Lei Complementar 97\/99, no seu artigo 15, estabelece que esta atribui\u00e7\u00e3o caber\u00e1 exclusivamente ao Ministro da Defesa, a quem os militares est\u00e3o subordinados, nos termos da referida lei.<br \/>\nOu seja, um Ministro da Defesa \u2013 que tem sua compet\u00eancia questionada por Temer \u2013 \u00e9 o interventor do desgoverno no Rio, uma vez que a GLO foi a forma jur\u00eddica (inconstitucional e ilegal) utilizada para realizar uma interven\u00e7\u00e3o no Estado do Rio de Janeiro, sem promover diretamente o afastamento do fraco governador do Estado do exerc\u00edcio de suas fun\u00e7\u00f5es.<br \/>\nEnquanto isso, em Bras\u00edlia, Meirelles acelera o processo de destrui\u00e7\u00e3o do segundo Estado mais importante da Federa\u00e7\u00e3o, ao reter as verbas pr\u00f3prias do Estado do Rio de Janeiro, que n\u00e3o t\u00eam sido repassadas e que s\u00e3o necess\u00e1rias para o pagamento dos servidores, aposentados e pensionistas, e tamb\u00e9m para a realiza\u00e7\u00e3o de investimentos nas atividades p\u00fablicas essenciais do Estado, como seguran\u00e7a, sa\u00fade e educa\u00e7\u00e3o.<br \/>\nA Assembleia Legislativa do Rio de Janeiro necessita se pronunciar com urg\u00eancia sobre esta indevida interven\u00e7\u00e3o, por suposto \u201ccomprometimento da ordem p\u00fablica\u201d, e tamb\u00e9m sobre o afastamento de Pez\u00e3o de suas fun\u00e7\u00f5es, para, assim, desautorizar qualquer ato de venda da CEDAE, que s\u00f3 interessa ao mercado financeiro.<br \/>\nA interven\u00e7\u00e3o no Estado do Rio de Janeiro \u00e9 apenas um ensaio e, sem d\u00favida, eles partir\u00e3o para os outros Estados, pois os militares, mais uma vez \u2013 como em 1964 \u2013 poder\u00e3o estar sendo manipulados para instaurar um estado de exce\u00e7\u00e3o contra o povo brasileiro.<br \/>\nEst\u00e1 mais do que estabelecido que Temer e seus s\u00f3cios n\u00e3o entregar\u00e3o facilmente o poder, pois, se isto ocorrer, eles dever\u00e3o ser processados e \u00a0poder\u00e3o\u00a0 ser condenados e presos.<br \/>\nO golpe de 2016 foi muito caro para a nossa incipiente democracia e est\u00e1 matando o Brasil. Al\u00e9m disso, tendo em vista a manipula\u00e7\u00e3o pol\u00edtica com vistas ao recrudescimento do estado de exce\u00e7\u00e3o, mediante a utiliza\u00e7\u00e3o das for\u00e7as militares, pode-se cogitar que a realiza\u00e7\u00e3o de elei\u00e7\u00f5es em 2018 \u00e9 uma inc\u00f3gnita.<br \/>\n*<strong>Advogado e cientista pol\u00edtico<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jorge Rubem Folena de Oliveira* O estado do Rio de Janeiro est\u00e1 sob uma interven\u00e7\u00e3o federal branca e a Garantia da Lei e da Ordem (GLO), decretada por Temer em 28 de julho de 2017, est\u00e1 em desacordo com a Constitui\u00e7\u00e3o e a lei de emprego das For\u00e7as Armadas (FFAA). O governador do Estado do [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-52406","post","type-post","status-publish","format-standard","hentry","category-analiseopiniao"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":84564,"url":"https:\/\/www.jornalja.com.br\/colunas\/a-nova-celulose-a-beira-do-guaiba-e-o-risco-de-repetir-a-borregaard\/","url_meta":{"origin":52406,"position":0},"title":"A nova celulose \u00e0 beira do Gua\u00edba e o risco de repetir a Borregaard","author":"An\u00e1lise &amp; Opini\u00e3o","date":"6 de mar\u00e7o de 2026","format":false,"excerpt":"ELMAR BONES No dia 16 de mar\u00e7o de 1972 foi inaugurada a Ind\u00fastria de Celulose Borregaard, em Gua\u00edba, com a presen\u00e7a das mais altas autoridades e manchetes ufanistas em todos os jornais. Inaugura\u00e7\u00e3o da f\u00e1brica em Gua\u00edba, no ano de 1972. Foto Reprodu\u00e7\u00e3o Arquivo\/CeluloseRioGrandense Seria uma das maiores f\u00e1bricas em\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84725,"url":"https:\/\/www.jornalja.com.br\/colunas\/e-preciso-refletir-sobre-os-mais-de-84-mil-desaparecidos-no-brasil-em-2025\/","url_meta":{"origin":52406,"position":1},"title":"\u00c9 preciso refletir sobre os mais de 84 mil desaparecidos no Brasil em 2025","author":"An\u00e1lise &amp; Opini\u00e3o","date":"23 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Em 2025, o Brasil registrou 84.760 pessoas desaparecidas, segundo dados consolidados pelo Sistema Nacional de Informa\u00e7\u00f5es de Seguran\u00e7a P\u00fablica Sinesp), vinculado ao Minist\u00e9rio da Justi\u00e7a e Seguran\u00e7a P\u00fablica. Mais do que um n\u00famero expressivo, o dado revela um fen\u00f4meno cont\u00ednuo, distribu\u00eddo no tempo e no territ\u00f3rio \u2014 e,\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84590,"url":"https:\/\/www.jornalja.com.br\/colunas\/e-preciso-defender-o-jardim-botanico-de-porto-alegre\/","url_meta":{"origin":52406,"position":2},"title":"\u00c9 preciso defender o Jardim Bot\u00e2nico de Porto Alegre","author":"da Reda\u00e7\u00e3o","date":"8 de mar\u00e7o de 2026","format":false,"excerpt":"CLEBER DIONI TENTARDINI O Jardim Bot\u00e2nico de Porto Alegre (JBPA) tem 67 anos e \u00e9 considerado um dos cinco melhores e maiores do Brasil. Possui 28 cole\u00e7\u00f5es cient\u00edficas que somam mais de 4.200 plantas, incluindo esp\u00e9cies raras, amea\u00e7adas de extin\u00e7\u00e3o e end\u00eamicas, que s\u00e3o encontradas apenas no RS. No local\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84557,"url":"https:\/\/www.jornalja.com.br\/colunas\/entrevista-com-leonel-brizola-como-nascem-as-falsificacoes-historicas\/","url_meta":{"origin":52406,"position":3},"title":"Entrevista com Leonel Brizola: Como nascem as falsifica\u00e7\u00f5es hist\u00f3ricas","author":"An\u00e1lise &amp; Opini\u00e3o","date":"2 de mar\u00e7o de 2026","format":false,"excerpt":"SILVANA MOURA Mais do que direito \u00e0 Hist\u00f3ria, temos o direito \u00e0 verdade da Hist\u00f3ria, para evitar um passado falsificado, supostamente \u201climpo\u201d, eivado de manipula\u00e7\u00e3o e pretensa uniformidade. Em 1996 realizei, em Carazinho, uma Entrevista de Hist\u00f3ria Oral (sou Historiadora e trabalho com Hist\u00f3ria Oral h\u00e1 40 anos) com Leonel\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":84617,"url":"https:\/\/www.jornalja.com.br\/colunas\/o-candidato-de-si-mesmo\/","url_meta":{"origin":52406,"position":4},"title":"O candidato de si mesmo","author":"da Reda\u00e7\u00e3o","date":"10 de abril de 2026","format":false,"excerpt":"Sem emplacar nacionalmente, Leite pode ficar quatro anos sem mandato. Foto Jo\u00e3o Pedro Rodrigues\/SecomRS ELMAR BONES Ningu\u00e9m \u00e9 candidato de si mesmo. Essa \u00e9 a regra n\u00e3o escrita da pol\u00edtica partid\u00e1ria, que as velhas raposas n\u00e3o cansam de repetir aos novatos. Eduardo Leite parece n\u00e3o t\u00ea-la aprendido. Ele n\u00e3o tem\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84742,"url":"https:\/\/www.jornalja.com.br\/colunas\/rejeicao-a-messias-quando-o-senado-tensiona-os-limites-da-democracia\/","url_meta":{"origin":52406,"position":5},"title":"Rejei\u00e7\u00e3o a Messias: quando o Senado tensiona os limites da democracia","author":"An\u00e1lise &amp; Opini\u00e3o","date":"30 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT A rejei\u00e7\u00e3o, pelo Senado, da indica\u00e7\u00e3o de Jorge Messias ao Supremo Tribunal Federal n\u00e3o \u00e9 um fato trivial \u2014 e trat\u00e1-la como um simples exerc\u00edcio de independ\u00eancia institucional seria, no m\u00ednimo, ing\u00eanuo. H\u00e1 algo mais profundo em jogo. O epis\u00f3dio exp\u00f5e, com certa nitidez, a forma como parcelas\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKo0s-dDg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/52406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/comments?post=52406"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/52406\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/media?parent=52406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/categories?post=52406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/tags?post=52406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}