{"id":53885,"date":"2017-08-21T12:23:56","date_gmt":"2017-08-21T15:23:56","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=53885"},"modified":"2017-08-21T12:23:56","modified_gmt":"2017-08-21T15:23:56","slug":"uma-nova-escravidao","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/colunas\/uma-nova-escravidao\/","title":{"rendered":"Uma nova escravid\u00e3o"},"content":{"rendered":"<p><span class=\"assina\">J. A. PINHEIRO MACHADO<\/span><br \/>\nExatamente 129 anos depois da aboli\u00e7\u00e3o ocorrida no Brasil em 1888, a escravatura est\u00e1 de volta.<br \/>\nVoltou mais democr\u00e1tica: atinge a todos ou a quase todos, indistintamente.\u00a0Afora uns poucos libert\u00e1rios, a maioria de n\u00f3s hoje mais do que usar o celular, est\u00e1 algemado ao celular.<br \/>\nUma colega trabalhando a um metro da minha mesa dia desses me avisou: &#8220;acabo de te mandar um wats&#8221;. Texto do wats: \u201cVais ao jogo do Gr\u00eamio?\u201d Explodi: \u201cOra, por que n\u00e3o me perguntaste falando?\u201d<br \/>\nE a resposta: \u201cSei l\u00e1! \u00c9 t\u00e3o mais pr\u00e1tico o wats&#8230;\u201d A comunica\u00e7\u00e3o virtual chegou a um n\u00edvel t\u00e3o extraordin\u00e1rio que pouco a pouco destr\u00f3i a comunica\u00e7\u00e3o pessoal, o olho no olho&#8230;<br \/>\nEm vez de uma boa gargalhada, digitamos um insosso Kkkkkk&#8230; N\u00e3o sei onde vamos parar. Mas com certeza jamais surgir\u00e1 um dispositivo eletr\u00f4nico que substitua um bom aperto de m\u00e3o, um abra\u00e7o&#8230; um beijo na pessoa amada&#8230;<br \/>\nOu mesmo os aromas e sabores de uma receita do Anonymus Gourmet&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>J. A. PINHEIRO MACHADO Exatamente 129 anos depois da aboli\u00e7\u00e3o ocorrida no Brasil em 1888, a escravatura est\u00e1 de volta. Voltou mais democr\u00e1tica: atinge a todos ou a quase todos, indistintamente.\u00a0Afora uns poucos libert\u00e1rios, a maioria de n\u00f3s hoje mais do que usar o celular, est\u00e1 algemado ao celular. Uma colega trabalhando a um metro [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-53885","post","type-post","status-publish","format-standard","hentry","category-analiseopiniao"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":84725,"url":"https:\/\/www.jornalja.com.br\/colunas\/e-preciso-refletir-sobre-os-mais-de-84-mil-desaparecidos-no-brasil-em-2025\/","url_meta":{"origin":53885,"position":0},"title":"\u00c9 preciso refletir sobre os mais de 84 mil desaparecidos no Brasil em 2025","author":"An\u00e1lise &amp; Opini\u00e3o","date":"23 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Em 2025, o Brasil registrou 84.760 pessoas desaparecidas, segundo dados consolidados pelo Sistema Nacional de Informa\u00e7\u00f5es de Seguran\u00e7a P\u00fablica Sinesp), vinculado ao Minist\u00e9rio da Justi\u00e7a e Seguran\u00e7a P\u00fablica. Mais do que um n\u00famero expressivo, o dado revela um fen\u00f4meno cont\u00ednuo, distribu\u00eddo no tempo e no territ\u00f3rio \u2014 e,\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84761,"url":"https:\/\/www.jornalja.com.br\/colunas\/cmpc-nova-fabrica-velhos-impactos\/","url_meta":{"origin":53885,"position":1},"title":"CMPC: Nova f\u00e1brica, velhos impactos?","author":"Cleber Dioni Tentardini","date":"6 de maio de 2026","format":false,"excerpt":"EDUARDO RAGUSE* Por volta das 13h40, do dia 05 de maio de 2026, ocorreu a despressuriza\u00e7\u00e3o de emerg\u00eancia da caldeira da f\u00e1brica de celulose da empresa CMPC, no munic\u00edpio de Gua\u00edba. O evento causou grande susto e apreens\u00e3o entre os moradores do entorno da ind\u00fastria devido ao ru\u00eddo fort\u00edssimo, odor\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":84673,"url":"https:\/\/www.jornalja.com.br\/colunas\/40-anos-sem-simone-de-beauvoir-uma-interlocutora-ainda-incomoda-do-presente\/","url_meta":{"origin":53885,"position":2},"title":"40 anos sem Simone de Beauvoir, uma interlocutora ainda inc\u00f4moda do presente","author":"da Reda\u00e7\u00e3o","date":"14 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Quarenta anos ap\u00f3s a morte de Simone de Beauvoir (9 de janeiro de 1908 - 14 de abril de 1986), descubro que sua aus\u00eancia n\u00e3o \u00e9 propriamente um vazio \u2014 \u00e9 antes um rumor cont\u00ednuo, uma esp\u00e9cie de presen\u00e7a indireta que se infiltra nas conversas, nos livros, nas\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/simone-de-beauvoir-memorias-de-uma-menina-bemcomportada.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":84690,"url":"https:\/\/www.jornalja.com.br\/colunas\/17-de-abril-de-1996-30-anos-do-massacre-de-eldorado-do-carajas\/","url_meta":{"origin":53885,"position":3},"title":"17 de abril de 1996: 30 anos do Massacre de Eldorado do Caraj\u00e1s","author":"da Reda\u00e7\u00e3o","date":"17 de abril de 2026","format":false,"excerpt":"Cruz marca o local do massacre em Eldorado dos Caraj\u00e1s, Par\u00e1. Foto: Marcello Casal Jr.\/Arquivo ABr CRISTIANO GOLDSCHMIDT H\u00e1 datas que n\u00e3o passam. Ficam suspensas no tempo como poeira vermelha sobre a pele \u2014 insistem, infiltram-se, recusam o esquecimento. Abril, no sul do Par\u00e1, \u00e9 sempre um m\u00eas que arde.\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84766,"url":"https:\/\/www.jornalja.com.br\/colunas\/entre-o-compromisso-etico-da-amizade-e-a-omissao-silenciosa\/","url_meta":{"origin":53885,"position":4},"title":"Entre o compromisso \u00e9tico da amizade e a omiss\u00e3o silenciosa","author":"An\u00e1lise &amp; Opini\u00e3o","date":"6 de maio de 2026","format":false,"excerpt":"Uma amizade que se retrai diante da possibilidade concreta de promover o outro revela, em \u00faltima inst\u00e2ncia, que seu v\u00ednculo est\u00e1 condicionado a certas fronteiras invis\u00edveis. CRISTIANO GOLDSCHMIDT H\u00e1 uma forma silenciosa \u2014 e, por isso mesmo, profundamente reveladora \u2014 de medir o valor de uma amizade: n\u00e3o pelas palavras\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-2.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-2.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-2.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-2.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-2.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-2.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84703,"url":"https:\/\/www.jornalja.com.br\/colunas\/tiradentes-o-martir-que-ainda-nos-observa-e-as-inquietacoes-de-um-brasil-inacabado\/","url_meta":{"origin":53885,"position":5},"title":"Tiradentes: o M\u00e1rtir que ainda nos observa e as inquieta\u00e7\u00f5es de um Brasil inacabado","author":"da Reda\u00e7\u00e3o","date":"21 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT H\u00e1 datas que n\u00e3o se imp\u00f5em pelo alarde, mas pela persist\u00eancia silenciosa com que atravessam os s\u00e9culos e se insinuam na consci\u00eancia coletiva. O 21 de abril pertence a essa estirpe discreta. N\u00e3o chega ornado de euforia, tampouco se anuncia com a grandiloqu\u00eancia de outras celebra\u00e7\u00f5es; antes, aproxima-se\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKo0s-e17","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/53885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/comments?post=53885"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/53885\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/media?parent=53885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/categories?post=53885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/tags?post=53885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}