{"id":54661,"date":"2017-09-04T11:00:23","date_gmt":"2017-09-04T14:00:23","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=54661"},"modified":"2017-09-04T11:00:23","modified_gmt":"2017-09-04T14:00:23","slug":"a-fala-de-dilma-na-abi","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/colunas\/a-fala-de-dilma-na-abi\/","title":{"rendered":"A fala de Dilma na ABI"},"content":{"rendered":"<p>Para quem \u00e9 normalmente considerada uma figura pouco afeita \u00e0 pol\u00edtica, Dilma Rousseff mostrou na \u00faltima quinta-feira, 31 de agosto, que n\u00e3o \u00e9 bem\u00a0assim. Em um\u00a0<a href=\"http:\/\/www.redebrasilatual.com.br\/politica\/2017\/09\/dilma-golpe-explica-por-que-temos-a-mais-egoista-atrasada-e-irresponsavel-elite\" data-saferedirecturl=\"http:\/\/www.google.com\/url?hl=pt-BR&amp;q=http:\/\/www.redebrasilatual.com.br\/politica\/2017\/09\/dilma-golpe-explica-por-que-temos-a-mais-egoista-atrasada-e-irresponsavel-elite&amp;source=gmail&amp;ust=1504619432097000&amp;usg=AFQjCNHG3Mg7n7HEEvS_tI9gQkMcZX1VuQ\">discurso pausado e calmo<\/a>, de quase uma hora e meia, na Associa\u00e7\u00e3o Brasileira de Imprensa, a ex-presidente da Rep\u00fablica deixou claro que est\u00e1 longe de ignorar algumas algumas rela\u00e7\u00f5es bastante sutis da pol\u00edtica.<br \/>\n\u00c9 interessante destacar, por exemplo, sua avalia\u00e7\u00e3o sobre a (aparente?) divis\u00e3o no seio do grupo golpista que tomou o poder de assalto, no golpe consumado em 31 de agosto de 2016, mas que havia sido desfechado com sucesso, e desde ent\u00e3o definitivamente, em 17 de abril na C\u00e2mara dos Deputados: \u201cTem uma cis\u00e3o (<em>entre os golpistas<\/em>), mas tem tamb\u00e9m uma unidade entre eles: unidade pela reforma da Previd\u00eancia, pela reforma trabalhista, pela entrega das terra f\u00e9rteis, pela entrega da Petrobras\u201d, disse, no evento &#8220;descomemorativo&#8221; de um ano do golpe.<br \/>\nDilma parece ter politicamente amadurecido anos no \u00faltimo ano. Deve ter aprendido muito com seus erros pol\u00edticos e as justas cr\u00edticas que recebeu sobre sua condu\u00e7\u00e3o da pol\u00edtica econ\u00f4mica a partir de 2014, cujo cl\u00edmax foi a nomea\u00e7\u00e3o de Joaquim Levy para comandar a Fazenda no segundo mandato. Cr\u00edticas como a de Luiz Gonzaga Belluzzo, que me disse em dezembro de 2014: &#8220;O pa\u00eds est\u00e1 entregue \u00e0 ignor\u00e2ncia dos macroeconomistas (&#8230;) Eles v\u00e3o cortar renda e emprego. S\u00f3 que isso vai ser feito com uma recess\u00e3o.&#8221;<br \/>\nOu como\u00a0<a href=\"http:\/\/www.redebrasilatual.com.br\/politica\/2017\/08\/debate-nausp-investiga-causas-e-saida-para-a-crise-brasileira\" data-saferedirecturl=\"http:\/\/www.google.com\/url?hl=pt-BR&amp;q=http:\/\/www.redebrasilatual.com.br\/politica\/2017\/08\/debate-nausp-investiga-causas-e-saida-para-a-crise-brasileira&amp;source=gmail&amp;ust=1504619432097000&amp;usg=AFQjCNFuzF49VqUzUrE3FGQljXYpJ3SanQ\">disse Andr\u00e9 Singer esta semana<\/a>: &#8220;Sou cr\u00edtico a Dilma, principalmente pela nomea\u00e7\u00e3o de Joaquim Levy (ao minist\u00e9rio da Fazenda), um grande equ\u00edvoco, mas fa\u00e7o quest\u00e3o de fazer justi\u00e7a a ela, porque ela foi corajosa no sentido de implementar um programa que decidi chamar de ensaio desenvolvimentista&#8221;<br \/>\n\u00c9 certo que Dilma errou e n\u00e3o errou pouco. S\u00f3 que errar ou conduzir equivocadamente as pol\u00edticas de Estado est\u00e3o longe de justificar a estupidez golpista que assola este pa\u00eds desde que se tornou uma Rep\u00fablica. No evento da ABI, a ex-presidente afirmou que o golpe que a derrubou mostra &#8220;por que temos a mais ego\u00edsta, atrasada e irrespons\u00e1vel elite\u201d. As elites de outros pa\u00edses, acrescentou, \u201cpensaram em sua na\u00e7\u00e3o, perceberam que seu destino seria maior se elas incorporassem o destino de seu povo. No nosso caso, tivemos sempre uma imensa dificuldade de fazer os processos mais simples de inclus\u00e3o\u201d, disse ela. Para mim, o pa\u00eds-paradigma dessa observa\u00e7\u00e3o de Dilma chama-se Estados Unidos da Am\u00e9rica.<br \/>\nEssas avalia\u00e7\u00f5es podem parecer \u00f3bvias, mas n\u00e3o s\u00e3o. Vi analistas pol\u00edticos destacarem a divis\u00e3o que haveria entre os l\u00edderes do golpe, ou pelo menos a falta de coes\u00e3o que poderia comprometer o pr\u00f3prio sucesso de seus planos a m\u00e9dio prazo. O &#8220;racha&#8221; que dentro do PSDB seria um dos mais importantes. Tudo ledo engano.<br \/>\nA avalia\u00e7\u00e3o de Dilma (&#8220;tem uma cis\u00e3o, mas tem tamb\u00e9m uma unidade entre eles&#8221;) \u00e9 muito mais l\u00facida. Me faz lembrar o que\u00a0<a href=\"http:\/\/www.redebrasilatual.com.br\/politica\/2017\/08\/divisao-do-psdb-em-relacao-a-temer-e-teatro-politico\" data-saferedirecturl=\"http:\/\/www.google.com\/url?hl=pt-BR&amp;q=http:\/\/www.redebrasilatual.com.br\/politica\/2017\/08\/divisao-do-psdb-em-relacao-a-temer-e-teatro-politico&amp;source=gmail&amp;ust=1504619432097000&amp;usg=AFQjCNFFIjgAWkN2DQQsEndOnMpnjfT6LA\">disse o cientista pol\u00edtico Vitor Marchetti<\/a>, da UFABC, h\u00e1 um m\u00eas, quando o assunto do momento era a divis\u00e3o dos tucanos entre os que queriam ficar e os que defendiam abandonar o barco de Temer: &#8220;Acredito que essa divis\u00e3o do PSDB tenta dialogar com as duas pontas da sociedade: a daqueles que n\u00e3o toleram a corrup\u00e7\u00e3o e mant\u00eam esse discurso de \u2018fora todos, n\u00e3o aceito corrup\u00e7\u00e3o\u2019 etc., mas tamb\u00e9m dialoga com a parcela para a qual o que importa \u00e9 que as reformas avancem. At\u00e9 a divis\u00e3o do PSDB pode ter sido orquestrada\u201d, disse Marchetti. \u201cO partido n\u00e3o fechou com Temer, mas apoia a agenda de desenvolvimento segundo a agenda liberal. Eu acho, inclusive, que eles fizeram as contas, sobre quem vota a favor e quem vota contra.\u201d Embora circunscrita ao PSDB, a an\u00e1lise \u00e9 a mesma que Dilma faz em rela\u00e7\u00e3o ao conjunto mais amplo dos golpistas para al\u00e9m do PSDB.<br \/>\nA fala de Dilma na ABI me parece, em certos aspectos, mais precisa do que os discursos do pr\u00f3prio Lula, que, apesar de seu carisma, sua lideran\u00e7a, sabedoria e genialidade pol\u00edtica, \u00e0s vezes soa como um populismo ultrapassado e cansativo.<br \/>\nOutro aspecto que tem me impressionado \u00e9 a maneira como Dilma tem sido recebida pela milit\u00e2ncia e mesmo por setores mais amplos do que o pr\u00f3prio PT. Ela \u00e9 recebida com enorme receptividade. Torturada por covardes na ditadura, primeira mulher presidente do Brasil e deposta pela &#8220;mais ego\u00edsta, atrasada e irrespons\u00e1vel elite&#8221;, Dilma \u00e9 um s\u00edmbolo. Um s\u00edmbolo guerreiro em um pa\u00eds colonizado e pusil\u00e2nime.<br \/>\nComo j\u00e1 escrevi em\u00a0<a href=\"http:\/\/fatosetc.blogspot.com.br\/2016\/06\/o-fenomeno-dilma.html\" data-saferedirecturl=\"http:\/\/www.google.com\/url?hl=pt-BR&amp;q=http:\/\/fatosetc.blogspot.com.br\/2016\/06\/o-fenomeno-dilma.html&amp;source=gmail&amp;ust=1504619432097000&amp;usg=AFQjCNHCCSh3Mq4zxTQ6Q1YVyUX8zuvTkw\">post no ano passado<\/a>:\u00a0&#8220;Minha imagina\u00e7\u00e3o me leva, conduzido por Plat\u00e3o, a uma situa\u00e7\u00e3o. Imaginemos que o Brasil fosse hoje um pa\u00eds que, com todas as suas caracter\u00edsticas (a diversidade principalmente), estivesse no patamar de uma na\u00e7\u00e3o desenvolvida e politicamente respeitada, na qual as oligarquias esp\u00farias tivessem sido reduzidas a sombras da hist\u00f3ria e n\u00e3o mais influenciassem a vida do pa\u00eds.<br \/>\n&#8220;Nessa hip\u00f3tese plat\u00f4nica, governando um pa\u00eds que tivesse superado sua triste voca\u00e7\u00e3o a col\u00f4nia, Dilma Rousseff seria uma presidente e l\u00edder sofisticada&#8221;.<br \/>\nNo caso brasileiro, temos ainda o cong\u00eanito problema da apatia de um povo que n\u00e3o reage e que \u00e9 tratado pela esquerda como pobre v\u00edtima. &#8220;Por que o\u00a0povo\u00a0est\u00e1 tendo seus direitos e interesses massacrados e ainda n\u00e3o entrou em cena aqui no Brasil, eu ainda n\u00e3o sei\u201d, me disse o deputado federal Wadih Damous (PT-RJ) recentemente.<br \/>\nMas falar o povo brasileiro \u00e9 outro assunto. Fica para outra oportunidade.<br \/>\n(Publicado originalmente com o t\u00edtulo &#8220;Dilma Rousseff, s\u00edmbolo de resist\u00eancia num pa\u00eds colonizado e pusil\u00e2mine&#8221;, no blog do autor <a href=\"http:\/\/fatosetc.blogspot.com.br\/2017\/09\/dilma-rousseff-simbolo-de-resistencia.html?utm_source=feedburner&amp;utm_medium=email&amp;utm_campaign=Feed:+FatosEtc+(Fatos+Etc.)\">FatosEtc<\/a>).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para quem \u00e9 normalmente considerada uma figura pouco afeita \u00e0 pol\u00edtica, Dilma Rousseff mostrou na \u00faltima quinta-feira, 31 de agosto, que n\u00e3o \u00e9 bem\u00a0assim. Em um\u00a0discurso pausado e calmo, de quase uma hora e meia, na Associa\u00e7\u00e3o Brasileira de Imprensa, a ex-presidente da Rep\u00fablica deixou claro que est\u00e1 longe de ignorar algumas algumas rela\u00e7\u00f5es bastante [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-54661","post","type-post","status-publish","format-standard","hentry","category-analiseopiniao"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":84590,"url":"https:\/\/www.jornalja.com.br\/colunas\/e-preciso-defender-o-jardim-botanico-de-porto-alegre\/","url_meta":{"origin":54661,"position":0},"title":"\u00c9 preciso defender o Jardim Bot\u00e2nico de Porto Alegre","author":"da Reda\u00e7\u00e3o","date":"8 de mar\u00e7o de 2026","format":false,"excerpt":"CLEBER DIONI TENTARDINI O Jardim Bot\u00e2nico de Porto Alegre (JBPA) tem 67 anos e \u00e9 considerado um dos cinco melhores e maiores do Brasil. Possui 28 cole\u00e7\u00f5es cient\u00edficas que somam mais de 4.200 plantas, incluindo esp\u00e9cies raras, amea\u00e7adas de extin\u00e7\u00e3o e end\u00eamicas, que s\u00e3o encontradas apenas no RS. No local\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84742,"url":"https:\/\/www.jornalja.com.br\/colunas\/rejeicao-a-messias-quando-o-senado-tensiona-os-limites-da-democracia\/","url_meta":{"origin":54661,"position":1},"title":"Rejei\u00e7\u00e3o a Messias: quando o Senado tensiona os limites da democracia","author":"An\u00e1lise &amp; Opini\u00e3o","date":"30 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT A rejei\u00e7\u00e3o, pelo Senado, da indica\u00e7\u00e3o de Jorge Messias ao Supremo Tribunal Federal n\u00e3o \u00e9 um fato trivial \u2014 e trat\u00e1-la como um simples exerc\u00edcio de independ\u00eancia institucional seria, no m\u00ednimo, ing\u00eanuo. H\u00e1 algo mais profundo em jogo. O epis\u00f3dio exp\u00f5e, com certa nitidez, a forma como parcelas\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84725,"url":"https:\/\/www.jornalja.com.br\/colunas\/e-preciso-refletir-sobre-os-mais-de-84-mil-desaparecidos-no-brasil-em-2025\/","url_meta":{"origin":54661,"position":2},"title":"\u00c9 preciso refletir sobre os mais de 84 mil desaparecidos no Brasil em 2025","author":"An\u00e1lise &amp; Opini\u00e3o","date":"23 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Em 2025, o Brasil registrou 84.760 pessoas desaparecidas, segundo dados consolidados pelo Sistema Nacional de Informa\u00e7\u00f5es de Seguran\u00e7a P\u00fablica Sinesp), vinculado ao Minist\u00e9rio da Justi\u00e7a e Seguran\u00e7a P\u00fablica. Mais do que um n\u00famero expressivo, o dado revela um fen\u00f4meno cont\u00ednuo, distribu\u00eddo no tempo e no territ\u00f3rio \u2014 e,\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84617,"url":"https:\/\/www.jornalja.com.br\/colunas\/o-candidato-de-si-mesmo\/","url_meta":{"origin":54661,"position":3},"title":"O candidato de si mesmo","author":"da Reda\u00e7\u00e3o","date":"10 de abril de 2026","format":false,"excerpt":"Sem emplacar nacionalmente, Leite pode ficar quatro anos sem mandato. Foto Jo\u00e3o Pedro Rodrigues\/SecomRS ELMAR BONES Ningu\u00e9m \u00e9 candidato de si mesmo. Essa \u00e9 a regra n\u00e3o escrita da pol\u00edtica partid\u00e1ria, que as velhas raposas n\u00e3o cansam de repetir aos novatos. Eduardo Leite parece n\u00e3o t\u00ea-la aprendido. Ele n\u00e3o tem\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84681,"url":"https:\/\/www.jornalja.com.br\/colunas\/recordar-zuzu-angel-50-anos-apos-sua-morte-e-um-ato-etico\/","url_meta":{"origin":54661,"position":4},"title":"Recordar Zuzu Angel 50 anos ap\u00f3s sua morte \u00e9 um ato \u00e9tico","author":"da Reda\u00e7\u00e3o","date":"16 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Cinco d\u00e9cadas transcorreram desde o silenciamento brutal de Zuzu Angel (05 de junho de 1921 - 14 de abril de 1976), e ainda assim sua voz persiste \u2014 n\u00e3o como eco esmaecido, mas como um timbre agudo que rasga o tecido do tempo e se inscreve na mem\u00f3ria\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84693,"url":"https:\/\/www.jornalja.com.br\/colunas\/fim-da-escala-6x1-cabe-ao-congresso-decidir-entre-o-progresso-e-o-atraso\/","url_meta":{"origin":54661,"position":5},"title":"Fim da escala 6&#215;1: cabe ao Congresso decidir entre o progresso e o atraso","author":"da Reda\u00e7\u00e3o","date":"20 de abril de 2026","format":false,"excerpt":"Plen\u00e1rio da C\u00e2mara dos Deputados durante sess\u00e3o solene do Congresso Nacional. Caber\u00e1 ao parlamento a decis\u00e3o final sobre a nova escala de trabalho. Foto: Leopoldo Silva\/Ag\u00eancia Senado CRISTIANO GOLDSCHMIDT A discuss\u00e3o sobre o fim da escala de trabalho 6x1 no Brasil tem ganhado centralidade no debate p\u00fablico contempor\u00e2neo por tocar\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKo0s-edD","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/54661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/comments?post=54661"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/54661\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/media?parent=54661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/categories?post=54661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/tags?post=54661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}