{"id":56798,"date":"2017-10-28T19:14:42","date_gmt":"2017-10-28T22:14:42","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=56798"},"modified":"2017-10-28T19:14:42","modified_gmt":"2017-10-28T22:14:42","slug":"o-fator-lula","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/colunas\/o-fator-lula\/","title":{"rendered":"O fator Lula"},"content":{"rendered":"<p><span class=\"assina\">Elmar Bones<\/span><br \/>\nO \u00fanico ponto fora da curva do golpe neste momento \u00e9 a candidatura Lula \u00e0 presid\u00eancia em 2018.<br \/>\nN\u00e3o por acaso a m\u00eddia corporativa e seus comentaristas amestrados fazem o que podem para desqualificar ou mesmo ignorar as caravanas do ex-presidente pelo pa\u00eds.<br \/>\nUm dos truques nestes dias \u00e9 comparar a condi\u00e7\u00e3o de Lula, &#8220;na emin\u00eancia de ser condenado pelo juiz S\u00e9rgio Moro&#8221;, com a de\u00a0 Michel Temer, acossado pelas den\u00fancias do Procurador Janot.<br \/>\nPara sustentar esse racioc\u00ednio abstruso, omite-se o essencial.<br \/>\nTemer, sorrateiro, sustenta-se com manobras palacianas, gastando bilh\u00f5es do er\u00e1rio p\u00fablico para comprar o apoio de deputados venais.<br \/>\nLula, de peito aberto, foi para as ruas buscar guarida no pov\u00e3o. Mesmo que o condenem ou prendam, n\u00e3o conseguir\u00e3o impedir que seja o fator que pode barrar a consolida\u00e7\u00e3o do golpe nas urnas.<br \/>\nS\u00e3o personagens e circunst\u00e2ncias incompar\u00e1veis, mas n\u00e3o \u00e9 descabido lembrar Get\u00falio Vargas, em 1950, no primeiro ciclo do trabalhismo. .<br \/>\nDerrubado por um golpe, Vargas saiu do ex\u00edlio volunt\u00e1rio em S\u00e3o Borja para percorrer o pa\u00eds e retornar ao poder pelo voto popular.<br \/>\nSeu programa nacionalista, tinha tamb\u00e9m no centro da meta a causa do petr\u00f3leo e a Petrobras.<br \/>\nComo se sabe, os inimigos, mesmo derrotados, n\u00e3o deram tr\u00e9gua, at\u00e9 lev\u00e1-lo \u00e0 trag\u00e9dia de 24 de agosto de 1954. O lema era: Vargas n\u00e3o pode ser candidato, se for candidato n\u00e3o pode ser eleito, se for eleito, n\u00e3o pode governar&#8230;<br \/>\nO que quero dizer: as for\u00e7as que promoveram o golpe parlamentar que derrubou Dilma (e que se sustenta a golpes de aud\u00e1cia) aspiram legitim\u00e1-lo pela via eleitoral. Lula, com seu cesarismo, \u00e9 no momento o \u00fanico obst\u00e1culo real.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elmar Bones O \u00fanico ponto fora da curva do golpe neste momento \u00e9 a candidatura Lula \u00e0 presid\u00eancia em 2018. N\u00e3o por acaso a m\u00eddia corporativa e seus comentaristas amestrados fazem o que podem para desqualificar ou mesmo ignorar as caravanas do ex-presidente pelo pa\u00eds. Um dos truques nestes dias \u00e9 comparar a condi\u00e7\u00e3o de [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-56798","post","type-post","status-publish","format-standard","hentry","category-analiseopiniao"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":84617,"url":"https:\/\/www.jornalja.com.br\/colunas\/o-candidato-de-si-mesmo\/","url_meta":{"origin":56798,"position":0},"title":"O candidato de si mesmo","author":"da Reda\u00e7\u00e3o","date":"10 de abril de 2026","format":false,"excerpt":"Sem emplacar nacionalmente, Leite pode ficar quatro anos sem mandato. Foto Jo\u00e3o Pedro Rodrigues\/SecomRS ELMAR BONES Ningu\u00e9m \u00e9 candidato de si mesmo. Essa \u00e9 a regra n\u00e3o escrita da pol\u00edtica partid\u00e1ria, que as velhas raposas n\u00e3o cansam de repetir aos novatos. Eduardo Leite parece n\u00e3o t\u00ea-la aprendido. Ele n\u00e3o tem\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84690,"url":"https:\/\/www.jornalja.com.br\/colunas\/17-de-abril-de-1996-30-anos-do-massacre-de-eldorado-do-carajas\/","url_meta":{"origin":56798,"position":1},"title":"17 de abril de 1996: 30 anos do Massacre de Eldorado do Caraj\u00e1s","author":"da Reda\u00e7\u00e3o","date":"17 de abril de 2026","format":false,"excerpt":"Cruz marca o local do massacre em Eldorado dos Caraj\u00e1s, Par\u00e1. Foto: Marcello Casal Jr.\/Arquivo ABr CRISTIANO GOLDSCHMIDT H\u00e1 datas que n\u00e3o passam. Ficam suspensas no tempo como poeira vermelha sobre a pele \u2014 insistem, infiltram-se, recusam o esquecimento. Abril, no sul do Par\u00e1, \u00e9 sempre um m\u00eas que arde.\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84766,"url":"https:\/\/www.jornalja.com.br\/colunas\/entre-o-compromisso-etico-da-amizade-e-a-omissao-silenciosa\/","url_meta":{"origin":56798,"position":2},"title":"Entre o compromisso \u00e9tico da amizade e a omiss\u00e3o silenciosa","author":"An\u00e1lise &amp; Opini\u00e3o","date":"6 de maio de 2026","format":false,"excerpt":"Uma amizade que se retrai diante da possibilidade concreta de promover o outro revela, em \u00faltima inst\u00e2ncia, que seu v\u00ednculo est\u00e1 condicionado a certas fronteiras invis\u00edveis. CRISTIANO GOLDSCHMIDT H\u00e1 uma forma silenciosa \u2014 e, por isso mesmo, profundamente reveladora \u2014 de medir o valor de uma amizade: n\u00e3o pelas palavras\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-2.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-2.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-2.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-2.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-2.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-2.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84693,"url":"https:\/\/www.jornalja.com.br\/colunas\/fim-da-escala-6x1-cabe-ao-congresso-decidir-entre-o-progresso-e-o-atraso\/","url_meta":{"origin":56798,"position":3},"title":"Fim da escala 6&#215;1: cabe ao Congresso decidir entre o progresso e o atraso","author":"da Reda\u00e7\u00e3o","date":"20 de abril de 2026","format":false,"excerpt":"Plen\u00e1rio da C\u00e2mara dos Deputados durante sess\u00e3o solene do Congresso Nacional. Caber\u00e1 ao parlamento a decis\u00e3o final sobre a nova escala de trabalho. Foto: Leopoldo Silva\/Ag\u00eancia Senado CRISTIANO GOLDSCHMIDT A discuss\u00e3o sobre o fim da escala de trabalho 6x1 no Brasil tem ganhado centralidade no debate p\u00fablico contempor\u00e2neo por tocar\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84776,"url":"https:\/\/www.jornalja.com.br\/colunas\/do-conforto-a-frustracao-a-falencia-do-transporte-por-aplicativo\/","url_meta":{"origin":56798,"position":4},"title":"Do conforto \u00e0 frustra\u00e7\u00e3o: a fal\u00eancia do transporte por aplicativo","author":"An\u00e1lise &amp; Opini\u00e3o","date":"7 de maio de 2026","format":false,"excerpt":"O poder p\u00fablico, que deveria atuar como mediador e garantidor de padr\u00f5es m\u00ednimos, parece operar em ritmo lento ou, em alguns casos, simplesmente se omitir. CRISTIANO GOLDSCHMIDT A promessa, no come\u00e7o, parecia quase irrecus\u00e1vel. Quem viveu aquele momento lembra bem da sensa\u00e7\u00e3o de finalmente ter encontrado uma alternativa ao transporte\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84785,"url":"https:\/\/www.jornalja.com.br\/colunas\/maternidade-e-alteridade-reflexoes-sobre-origem-vinculo-e-responsabilidade\/","url_meta":{"origin":56798,"position":5},"title":"Maternidade e Alteridade:           reflex\u00f5es sobre origem, v\u00ednculo e responsabilidade","author":"An\u00e1lise &amp; Opini\u00e3o","date":"10 de maio de 2026","format":false,"excerpt":"A no\u00e7\u00e3o contempor\u00e2nea de maternidade tem se ampliado. Hoje, reconhece-se que o cuidado e a forma\u00e7\u00e3o n\u00e3o s\u00e3o prerrogativas exclusivas da m\u00e3e biol\u00f3gica CRISTIANO GOLDSCHMIDT O Dia das M\u00e3es, frequentemente envolto em sentimentalismo previs\u00edvel, merece uma abordagem que ultrapasse o gesto autom\u00e1tico da homenagem e se aproxime de uma reflex\u00e3o\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-4.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-4.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-4.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-4.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-4.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-4.png?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKo0s-eM6","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/56798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/comments?post=56798"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/56798\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/media?parent=56798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/categories?post=56798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/tags?post=56798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}