{"id":61733,"date":"2018-04-25T10:24:24","date_gmt":"2018-04-25T13:24:24","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=61733"},"modified":"2018-04-25T10:24:24","modified_gmt":"2018-04-25T13:24:24","slug":"ha-54-anos-a-mais-longeva-ditadura-de-nossa-historia","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/colunas\/ha-54-anos-a-mais-longeva-ditadura-de-nossa-historia\/","title":{"rendered":"H\u00e1 54 anos\u2026 A mais longeva ditadura de nossa hist\u00f3ria"},"content":{"rendered":"<h1 class=\"m_-4136392732003160440title\"><\/h1>\n<p>O clima de hoje lembra o vivido nas v\u00e9speras do golpe de 1964, que dividiu o pa\u00eds e abriu espa\u00e7o para a viol\u00eancia. Antes da ruptura, a conflagra\u00e7\u00e3o<br \/>\nCompletaram-se, no \u00faltimo 1\u00ba de abril,\u00a054 anos da implanta\u00e7\u00e3o da mais longeva ditadura de nossa hist\u00f3ria, com todo o seu acervo de trag\u00e9dias sociais e individuais, e profundo atraso pol\u00edtico. Suas consequ\u00eancias ainda se fazem sentir, pois est\u00e3o na raiz dos dramas de nossos dias, cujo desfecho\u00a0 n\u00e3o podemos divisar: em alguns momentos a \u2018luz no fim do t\u00fanel\u2019 nos enche de esperan\u00e7as; noutros sugere um trem na contram\u00e3o.<br \/>\nLamentavelmente, os\u00a0regimes autorit\u00e1rios\u00a0e as ditaduras n\u00e3o s\u00e3o fen\u00f4menos estranhos \u00e0 Rep\u00fablica, marcada por insurrei\u00e7\u00f5es militares e golpes de Estado, manifesta\u00e7\u00f5es exacerbadas de um\u00a0 autoritarismo larvar cujas fontes remontam \u00e0 Col\u00f4nia e ao escravismo de s\u00e9culos, construtor da ideologia da casa-grande, profundamente presente em nossa vida pol\u00edtica e em nossa vida social, e mesmo nas rela\u00e7\u00f5es interpessoais.<br \/>\nA pr\u00f3pria Rep\u00fablica \u00e9 obra de um golpe de Estado constru\u00eddo na caserna, e sua consolida\u00e7\u00e3o fez-se dependente de outro golpe, sustentado pela espada\u00a0 de Floriano Peixoto. Assim se firmou a\u00a0Rep\u00fablica olig\u00e1rquico-agr\u00e1ria,\u00a0sem povo e sem eleitores, que sobreviveria at\u00e9 a \u2018revolu\u00e7\u00e3o de 1930\u2019. Antes, por\u00e9m, viveria o pa\u00eds a insurrei\u00e7\u00e3o de 1922 (Levante do Forte de Copacabana), e os dois 5 de julho que desembocariam na Coluna Prestes (1924).<br \/>\nE, na sequ\u00eancia de 1930, o levante paulista de 1932, o levante comunista de 1935, a implanta\u00e7\u00e3o da ditadura do \u2018Estado Novo\u2019, o\u00a0<i>putsch\u00a0<\/i>integralista de 1938 e, fechando o ciclo, o golpe que detonou a ditadura e levou Vargas para seu ex\u00edlio na est\u00e2ncia Santos Reis em 1945.<br \/>\n\u00c9 a hist\u00f3ria do \u2018tenentismo\u2019 que se estende at\u00e9 o regime de 1964, quando seus l\u00edderes j\u00e1 eram generais, almirantes e brigadeiros.\u00a0 No seu curr\u00edculo constam ainda a deposi\u00e7\u00e3o e suic\u00eddio de Vargas em 1954, o golpe e contragolpe de 1955, a crise de 1961 e a implanta\u00e7\u00e3o casu\u00edstica do Parlamentarismo, de vida breve. A hist\u00f3ria da Rep\u00fablica tem sido a hist\u00f3ria da preemin\u00eancia dos militares sobre a pol\u00edtica e a vida institucional.<br \/>\nO clima de hoje muito lembra aqueles vividos nas v\u00e9speras do golpe de 1964, dividindo o pa\u00eds e abrindo espa\u00e7o para a viol\u00eancia. \u00c9 sempre assim. Antes da ruptura propriamente dita, a conflagra\u00e7\u00e3o. Os\u00a0 conflitos exacerbados em 1963 foram a prepara\u00e7\u00e3o ideol\u00f3gica da ditadura militar.<br \/>\nOs anos dif\u00edceis que se instalam com as jornadas de 2013, de que se apropriou a direita com seu aparato midi\u00e1tico, abrem as rotas que levariam ao golpe de 2016 e \u00e0 instaura\u00e7\u00e3o do regime de exce\u00e7\u00e3o jur\u00eddica que n\u00e3o sabemos se ser\u00e1 declarado perempto com as elei\u00e7\u00f5es de 2018. O precedente hist\u00f3rico n\u00e3o \u00e9 animador.<br \/>\nEsse vi\u00e9s autorit\u00e1rio, cultivado pela casa-grande desde a Col\u00f4nia, \u00e9 servido \u00e0 popula\u00e7\u00e3o pelos aparelhos ideol\u00f3gicos do Estado a servi\u00e7o dos interesses de nossas elites perversas. Nesta\u00a0 faina destaca-se o papel dos meios de comunica\u00e7\u00e3o de massa, a quem se pode tributar, hoje, a maior responsabilidade pelo clima de viol\u00eancia que pervade a pol\u00edtica.<br \/>\nEm 1964 os militares e seus associados \u2013 na pol\u00edtica e no \u2018mercado\u2019\u2013 encerraram o ciclo da Constitui\u00e7\u00e3o democr\u00e1tica de 1946, enquanto a consolida\u00e7\u00e3o do impeachment de 2016 declarou perempto o ciclo iniciado com a \u2018Constitui\u00e7\u00e3o cidad\u00e3\u2019 de Ulisses Guimar\u00e3es, que culminara com a ascens\u00e3o e queda do lulismo.<br \/>\nTalvez sejam os dias correntes a boa oportunidade para tentarmos antecipar o que podem ser os tempos vindouros. As li\u00e7\u00f5es colhidas dos fatos que n\u00e3o se repetem podem orientar estrat\u00e9gias e corrigir t\u00e1ticas, principalmente quando o distanciamento hist\u00f3rico favorece a an\u00e1lise fria.<br \/>\nNaqueles anos hoje distantes, os anos do pr\u00e9-golpe e do golpe de 1\u00ba de abril,\u00a0 poucos viram para al\u00e9m da superf\u00edcie, e assim muitos ignoraram a conspira\u00e7\u00e3o que se desenvolvia nos subterr\u00e2neos da caserna em\u00a0 interlocu\u00e7\u00e3o com a ordem econ\u00f4mica, o Congresso e os meios de comunica\u00e7\u00e3o,\u00a0 para logo estampar-se \u00e0 luz do dia.<br \/>\nDe outra parte, uma vez mais, a continuidade e seguran\u00e7a do governo popular se havia deslocado das ruas para os acordos pol\u00edticos de c\u00fapula. O povo continuava percebido como\u00a0 elemento t\u00e1tico numa estrat\u00e9gia que se resolveria fora das ruas.<br \/>\nN\u00e3o obstante os elementos fornecidos pela realidade palp\u00e1vel, n\u00e3o eram poucos, ent\u00e3o, os que transferiam da mobiliza\u00e7\u00e3o popular\u00a0 para o \u2018dispositivo militar do general Assis Brasil\u2019,\u00a0 chefe da Casa Militar de Jango, a defesa do governo, das \u2018reformas de base\u2019 e da ascens\u00e3o das massas.<br \/>\nNesta linha pontificava o antigo capit\u00e3o\u00a0Luiz Carlos Prestes, secret\u00e1rio-geral do Partido Comunista Brasileiro.<br \/>\nNo dia 17 de mar\u00e7o de 1964, para uma plateia que lotava o audit\u00f3rio da Associa\u00e7\u00e3o Brasileira de Imprensa (ABI), o antigo Cavaleiro da Esperan\u00e7a, ap\u00f3s dissertar sobre \u2018a forma\u00e7\u00e3o popular do Ex\u00e9rcito brasileiro\u2019, anunciou, com o respaldo de sua biografia, a impossibilidade de um golpe militar no Brasil. E quando este se efetivou, muitos o viram como \u2018apenas mais uma quartelada\u2019, como as outras\u00a0 que haviam pontuado a Rep\u00fablica de 46. Passaria logo.<br \/>\nA hist\u00f3ria que se segue \u00e9 conhecida.<br \/>\nDo golpe de 1964 muito se pode afirmar, menos a surpresa, defendido que foi abertamente\u00a0 pela grande imprensa, preparando sua recep\u00e7\u00e3o e animando as manifesta\u00e7\u00f5es dos advers\u00e1rios do governo e de suas teses.<br \/>\nO pretenso combate \u00e0 corrup\u00e7\u00e3o de 2013-2016 era, em 1963-1964, a den\u00fancia de suposta\u00a0 corrup\u00e7\u00e3o e \u00a0de infiltra\u00e7\u00e3o comunista no governo\u00a0Jo\u00e3o Goulart, dando conta das conspira\u00e7\u00f5es de toda ordem, militares e civis igualmente conjurados, e, hoje documentalmente comprovada, a arquitetura do Departamento de Estado dos EUA, para quem Goulart, se n\u00e3o era comunista, estava a servi\u00e7o do comunismo, o que dava no mesmo, segundo Washington. Viv\u00edamos o auge da\u00a0Guerra Fria\u00a0e poucos meses nos separavam da crise dos m\u00edsseis estocados em Cuba pela Uni\u00e3o Sovi\u00e9tica, incidente que por muito pouco n\u00e3o nos levou ao suic\u00eddio nuclear.<br \/>\nA conspira\u00e7\u00e3o, ali\u00e1s, j\u00e1 se iniciara e era vis\u00edvel\u00a0 desde a posse de Goulart,\u00a0 como em suas mem\u00f3rias registra sem peias o Marechal Denis, l\u00edder da trinca militar que em agosto de 1961 tentara impedir a posse do vice-presidente constitucional, chamado ao posto pela ren\u00fancia do presidente J\u00e2nio Quadros.<br \/>\nHoje tamb\u00e9m j\u00e1 se sabe que a articula\u00e7\u00e3o que culminou com a deposi\u00e7\u00e3o de Dilma Rousseff j\u00e1 era maquinada nos idos de 2013, a onda preparadora do levante de 2015, com sua in\u00e9dita carga de viol\u00eancia, deixando\u00a0 para tr\u00e1s os piores momentos de 1963.<br \/>\nNas duas oportunidades os golpes foram precedidos de grandes mobiliza\u00e7\u00f5es populares e, ainda em ambos, o\u00a0<i>leitmotiv\u00a0<\/i>unificador da conspira\u00e7\u00e3o era, fundamentalmente,\u00a0 a resist\u00eancia da casa-grande \u00e0 ascens\u00e3o pol\u00edtico-econ\u00f4mica das grandes massas, naquela altura representada pelo varguismo, em nossos dias pelo lulismo.<br \/>\nOs \u00a0golpes de 1964 e de 2016 guardam parentesco que precisa ser posto de manifesto. Ambos foram precedidos de mobiliza\u00e7\u00f5es populares \u00a0carregadas de atos de viol\u00eancia que expunham a genealogia fascista. Em 1964 importava\u00a0 aos seus verdadeiros formuladores algo muito al\u00e9m da mera deposi\u00e7\u00e3o de Jango e esse seu car\u00e1ter profundo s\u00f3 ficou claro aos analistas em 1965, com o Ato Institucional n. 2, baixado pelo presidente que havia jurado a Constitui\u00e7\u00e3o e prometido defender a democracia.<br \/>\nO significado de 2013 n\u00e3o foi compreendido em seu primeiro momento, e os sism\u00f3grafos dos especialistas\u00a0 n\u00e3o perceberam o real significado do impeachment, aquele que se revelaria pelo governo que a ele se segue..<br \/>\nO dif\u00edcil n\u00e3o est\u00e1 na identifica\u00e7\u00e3o dos fatos expostos e vividos, mas na arte ou ci\u00eancia da prospec\u00e7\u00e3o social, aquela que revela a realidade ainda em gesta\u00e7\u00e3o, ou seja, a serpente ainda no ovo.<br \/>\nEm 1964 muitos n\u00e3o lograram antever o significado e os objetivos da ditadura, nem seu largo e profundo mando de 21 anos.\u00a0Carlos Lacerda, sua principal voz civil, e\u00a0Juscelino Kubitschek, que votaria no\u00a0marechal Castello Branco, primeiro ditador, apostaram, olhando para tr\u00e1s,\u00a0 na transitoriedade do novo regime, e logo engrossariam\u00a0 a lista de suas v\u00edtimas.<br \/>\nSe n\u00e3o nos foi poss\u00edvel antever a gesta\u00e7\u00e3o da irrup\u00e7\u00e3o popular de 2013, tamb\u00e9m faltou clareza \u00e0 esquerda quanto a deposi\u00e7\u00e3o da presidente Dilma Rousseff, apenas o passo necess\u00e1rio para\u00a0 defenestrar o lulismo, a grande opera\u00e7\u00e3o de nossos dias.<br \/>\n<i>O ovo da serpente,\u00a0<\/i>este \u00e9 o t\u00edtulo da obra-prima de\u00a0Ingmar Bergman. Quem j\u00e1 assistiu, assista de novo. Quem ainda n\u00e3o o viu, corra para ver. Est\u00e1 no YouTube.<br \/>\n<strong>Roberto Amaral<\/strong><br \/>\n&nbsp;<\/p>\n<div>______________<\/div>\n<p>Roberto Amaral \u00e9 escritor e ex-ministro de Ci\u00eancia e Tecnologia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O clima de hoje lembra o vivido nas v\u00e9speras do golpe de 1964, que dividiu o pa\u00eds e abriu espa\u00e7o para a viol\u00eancia. Antes da ruptura, a conflagra\u00e7\u00e3o Completaram-se, no \u00faltimo 1\u00ba de abril,\u00a054 anos da implanta\u00e7\u00e3o da mais longeva ditadura de nossa hist\u00f3ria, com todo o seu acervo de trag\u00e9dias sociais e individuais, e [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-61733","post","type-post","status-publish","format-standard","hentry","category-analiseopiniao"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":84681,"url":"https:\/\/www.jornalja.com.br\/colunas\/recordar-zuzu-angel-50-anos-apos-sua-morte-e-um-ato-etico\/","url_meta":{"origin":61733,"position":0},"title":"Recordar Zuzu Angel 50 anos ap\u00f3s sua morte \u00e9 um ato \u00e9tico","author":"da Reda\u00e7\u00e3o","date":"16 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Cinco d\u00e9cadas transcorreram desde o silenciamento brutal de Zuzu Angel (05 de junho de 1921 - 14 de abril de 1976), e ainda assim sua voz persiste \u2014 n\u00e3o como eco esmaecido, mas como um timbre agudo que rasga o tecido do tempo e se inscreve na mem\u00f3ria\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84564,"url":"https:\/\/www.jornalja.com.br\/colunas\/a-nova-celulose-a-beira-do-guaiba-e-o-risco-de-repetir-a-borregaard\/","url_meta":{"origin":61733,"position":1},"title":"A nova celulose \u00e0 beira do Gua\u00edba e o risco de repetir a Borregaard","author":"An\u00e1lise &amp; Opini\u00e3o","date":"6 de mar\u00e7o de 2026","format":false,"excerpt":"ELMAR BONES No dia 16 de mar\u00e7o de 1972 foi inaugurada a Ind\u00fastria de Celulose Borregaard, em Gua\u00edba, com a presen\u00e7a das mais altas autoridades e manchetes ufanistas em todos os jornais. Inaugura\u00e7\u00e3o da f\u00e1brica em Gua\u00edba, no ano de 1972. Foto Reprodu\u00e7\u00e3o Arquivo\/CeluloseRioGrandense Seria uma das maiores f\u00e1bricas em\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84673,"url":"https:\/\/www.jornalja.com.br\/colunas\/40-anos-sem-simone-de-beauvoir-uma-interlocutora-ainda-incomoda-do-presente\/","url_meta":{"origin":61733,"position":2},"title":"40 anos sem Simone de Beauvoir, uma interlocutora ainda inc\u00f4moda do presente","author":"da Reda\u00e7\u00e3o","date":"14 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Quarenta anos ap\u00f3s a morte de Simone de Beauvoir (9 de janeiro de 1908 - 14 de abril de 1986), descubro que sua aus\u00eancia n\u00e3o \u00e9 propriamente um vazio \u2014 \u00e9 antes um rumor cont\u00ednuo, uma esp\u00e9cie de presen\u00e7a indireta que se infiltra nas conversas, nos livros, nas\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/simone-de-beauvoir-memorias-de-uma-menina-bemcomportada.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":84557,"url":"https:\/\/www.jornalja.com.br\/colunas\/entrevista-com-leonel-brizola-como-nascem-as-falsificacoes-historicas\/","url_meta":{"origin":61733,"position":3},"title":"Entrevista com Leonel Brizola: Como nascem as falsifica\u00e7\u00f5es hist\u00f3ricas","author":"An\u00e1lise &amp; Opini\u00e3o","date":"2 de mar\u00e7o de 2026","format":false,"excerpt":"SILVANA MOURA Mais do que direito \u00e0 Hist\u00f3ria, temos o direito \u00e0 verdade da Hist\u00f3ria, para evitar um passado falsificado, supostamente \u201climpo\u201d, eivado de manipula\u00e7\u00e3o e pretensa uniformidade. Em 1996 realizei, em Carazinho, uma Entrevista de Hist\u00f3ria Oral (sou Historiadora e trabalho com Hist\u00f3ria Oral h\u00e1 40 anos) com Leonel\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":84617,"url":"https:\/\/www.jornalja.com.br\/colunas\/o-candidato-de-si-mesmo\/","url_meta":{"origin":61733,"position":4},"title":"O candidato de si mesmo","author":"da Reda\u00e7\u00e3o","date":"10 de abril de 2026","format":false,"excerpt":"Sem emplacar nacionalmente, Leite pode ficar quatro anos sem mandato. Foto Jo\u00e3o Pedro Rodrigues\/SecomRS ELMAR BONES Ningu\u00e9m \u00e9 candidato de si mesmo. Essa \u00e9 a regra n\u00e3o escrita da pol\u00edtica partid\u00e1ria, que as velhas raposas n\u00e3o cansam de repetir aos novatos. Eduardo Leite parece n\u00e3o t\u00ea-la aprendido. Ele n\u00e3o tem\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84690,"url":"https:\/\/www.jornalja.com.br\/colunas\/17-de-abril-de-1996-30-anos-do-massacre-de-eldorado-do-carajas\/","url_meta":{"origin":61733,"position":5},"title":"17 de abril de 1996: 30 anos do Massacre de Eldorado do Caraj\u00e1s","author":"da Reda\u00e7\u00e3o","date":"17 de abril de 2026","format":false,"excerpt":"Cruz marca o local do massacre em Eldorado dos Caraj\u00e1s, Par\u00e1. Foto: Marcello Casal Jr.\/Arquivo ABr CRISTIANO GOLDSCHMIDT H\u00e1 datas que n\u00e3o passam. Ficam suspensas no tempo como poeira vermelha sobre a pele \u2014 insistem, infiltram-se, recusam o esquecimento. Abril, no sul do Par\u00e1, \u00e9 sempre um m\u00eas que arde.\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKo0s-g3H","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/61733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/comments?post=61733"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/61733\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/media?parent=61733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/categories?post=61733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/tags?post=61733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}