{"id":65857,"date":"2018-09-28T20:08:49","date_gmt":"2018-09-28T23:08:49","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=65857"},"modified":"2018-09-28T20:08:49","modified_gmt":"2018-09-28T23:08:49","slug":"cobertura","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/colunas\/cobertura\/","title":{"rendered":"Cobertura"},"content":{"rendered":"<p>A elei\u00e7\u00e3o mais eletrizante desde a redemocratiza\u00e7\u00e3o merece p\u00edfia e burocr\u00e1tica cobertura jornal\u00edstica.<br \/>\nO notici\u00e1rio limita-se a um registro insosso do que dizem os candidatos e de suas andan\u00e7as, o que \u00e9 uma repeti\u00e7\u00e3o do que est\u00e1 no hor\u00e1rio eleitoral no r\u00e1dio e na tv.<br \/>\nAs entrevistas, mesmo aquelas pomposas com dez perguntadores, ficam ao n\u00edvel do notici\u00e1rio superficial, de onde os rep\u00f3rteres tiram suas perguntas. A falta de informa\u00e7\u00e3o \u00e9 encoberta pela agressividade, quando se trata de certos candidatos.<br \/>\nOs debates, com sorteio de quest\u00f5es e de quem pergunta para quem, lembram os prim\u00f3rdios dos programas do Silvio Santos, sem a anima\u00e7\u00e3o do audit\u00f3rio.<br \/>\nAs restri\u00e7\u00f5es impostas pela Justi\u00e7a Eleitoral, que a imprensa aceitou passivamente, contribuem, certamente. Mas longe de justificar a falta de jornalismo num momento em que a democracia mais precisa de informa\u00e7\u00f5es confi\u00e1veis.<br \/>\nFica evidente a falta independ\u00eancia para abordar certas quest\u00f5es. N\u00e3o falta intelig\u00eancia, falta liberdade. Exce\u00e7\u00f5es confirmam a regra.<br \/>\n\u00c9 por isso que a melhor cobertura da elei\u00e7\u00e3o est\u00e1 sendo feita pelo espanhol El Pais, em sua edi\u00e7\u00e3o para o Brasil.<br \/>\n&nbsp;<br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A elei\u00e7\u00e3o mais eletrizante desde a redemocratiza\u00e7\u00e3o merece p\u00edfia e burocr\u00e1tica cobertura jornal\u00edstica. O notici\u00e1rio limita-se a um registro insosso do que dizem os candidatos e de suas andan\u00e7as, o que \u00e9 uma repeti\u00e7\u00e3o do que est\u00e1 no hor\u00e1rio eleitoral no r\u00e1dio e na tv. As entrevistas, mesmo aquelas pomposas com dez perguntadores, ficam ao [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-65857","post","type-post","status-publish","format-standard","hentry","category-analiseopiniao"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":84617,"url":"https:\/\/www.jornalja.com.br\/colunas\/o-candidato-de-si-mesmo\/","url_meta":{"origin":65857,"position":0},"title":"O candidato de si mesmo","author":"da Reda\u00e7\u00e3o","date":"10 de abril de 2026","format":false,"excerpt":"Sem emplacar nacionalmente, Leite pode ficar quatro anos sem mandato. Foto Jo\u00e3o Pedro Rodrigues\/SecomRS ELMAR BONES Ningu\u00e9m \u00e9 candidato de si mesmo. Essa \u00e9 a regra n\u00e3o escrita da pol\u00edtica partid\u00e1ria, que as velhas raposas n\u00e3o cansam de repetir aos novatos. Eduardo Leite parece n\u00e3o t\u00ea-la aprendido. Ele n\u00e3o tem\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84725,"url":"https:\/\/www.jornalja.com.br\/colunas\/e-preciso-refletir-sobre-os-mais-de-84-mil-desaparecidos-no-brasil-em-2025\/","url_meta":{"origin":65857,"position":1},"title":"\u00c9 preciso refletir sobre os mais de 84 mil desaparecidos no Brasil em 2025","author":"An\u00e1lise &amp; Opini\u00e3o","date":"23 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Em 2025, o Brasil registrou 84.760 pessoas desaparecidas, segundo dados consolidados pelo Sistema Nacional de Informa\u00e7\u00f5es de Seguran\u00e7a P\u00fablica Sinesp), vinculado ao Minist\u00e9rio da Justi\u00e7a e Seguran\u00e7a P\u00fablica. Mais do que um n\u00famero expressivo, o dado revela um fen\u00f4meno cont\u00ednuo, distribu\u00eddo no tempo e no territ\u00f3rio \u2014 e,\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84766,"url":"https:\/\/www.jornalja.com.br\/colunas\/entre-o-compromisso-etico-da-amizade-e-a-omissao-silenciosa\/","url_meta":{"origin":65857,"position":2},"title":"Entre o compromisso \u00e9tico da amizade e a omiss\u00e3o silenciosa","author":"An\u00e1lise &amp; Opini\u00e3o","date":"6 de maio de 2026","format":false,"excerpt":"Uma amizade que se retrai diante da possibilidade concreta de promover o outro revela, em \u00faltima inst\u00e2ncia, que seu v\u00ednculo est\u00e1 condicionado a certas fronteiras invis\u00edveis. CRISTIANO GOLDSCHMIDT H\u00e1 uma forma silenciosa \u2014 e, por isso mesmo, profundamente reveladora \u2014 de medir o valor de uma amizade: n\u00e3o pelas palavras\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-2.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-2.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-2.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-2.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-2.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-2.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84703,"url":"https:\/\/www.jornalja.com.br\/colunas\/tiradentes-o-martir-que-ainda-nos-observa-e-as-inquietacoes-de-um-brasil-inacabado\/","url_meta":{"origin":65857,"position":3},"title":"Tiradentes: o M\u00e1rtir que ainda nos observa e as inquieta\u00e7\u00f5es de um Brasil inacabado","author":"da Reda\u00e7\u00e3o","date":"21 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT H\u00e1 datas que n\u00e3o se imp\u00f5em pelo alarde, mas pela persist\u00eancia silenciosa com que atravessam os s\u00e9culos e se insinuam na consci\u00eancia coletiva. O 21 de abril pertence a essa estirpe discreta. N\u00e3o chega ornado de euforia, tampouco se anuncia com a grandiloqu\u00eancia de outras celebra\u00e7\u00f5es; antes, aproxima-se\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84776,"url":"https:\/\/www.jornalja.com.br\/colunas\/do-conforto-a-frustracao-a-falencia-do-transporte-por-aplicativo\/","url_meta":{"origin":65857,"position":4},"title":"Do conforto \u00e0 frustra\u00e7\u00e3o: a fal\u00eancia do transporte por aplicativo","author":"An\u00e1lise &amp; Opini\u00e3o","date":"7 de maio de 2026","format":false,"excerpt":"O poder p\u00fablico, que deveria atuar como mediador e garantidor de padr\u00f5es m\u00ednimos, parece operar em ritmo lento ou, em alguns casos, simplesmente se omitir. CRISTIANO GOLDSCHMIDT A promessa, no come\u00e7o, parecia quase irrecus\u00e1vel. Quem viveu aquele momento lembra bem da sensa\u00e7\u00e3o de finalmente ter encontrado uma alternativa ao transporte\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/screenshot-20260507-114507-99-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84673,"url":"https:\/\/www.jornalja.com.br\/colunas\/40-anos-sem-simone-de-beauvoir-uma-interlocutora-ainda-incomoda-do-presente\/","url_meta":{"origin":65857,"position":5},"title":"40 anos sem Simone de Beauvoir, uma interlocutora ainda inc\u00f4moda do presente","author":"da Reda\u00e7\u00e3o","date":"14 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Quarenta anos ap\u00f3s a morte de Simone de Beauvoir (9 de janeiro de 1908 - 14 de abril de 1986), descubro que sua aus\u00eancia n\u00e3o \u00e9 propriamente um vazio \u2014 \u00e9 antes um rumor cont\u00ednuo, uma esp\u00e9cie de presen\u00e7a indireta que se infiltra nas conversas, nos livros, nas\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/simone-de-beauvoir-memorias-de-uma-menina-bemcomportada.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKo0s-h8d","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/65857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/comments?post=65857"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/65857\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/media?parent=65857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/categories?post=65857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/tags?post=65857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}