{"id":71319,"date":"2018-11-27T22:37:55","date_gmt":"2018-11-28T00:37:55","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=71319"},"modified":"2018-11-27T22:37:55","modified_gmt":"2018-11-28T00:37:55","slug":"71319-2","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/colunas\/71319-2\/","title":{"rendered":"Pacto Alegre"},"content":{"rendered":"<p><span class=\"assina\">CARLOS ALBERTO CASTRO<\/span><br \/>\nH\u00e1 d\u00e9cadas Porto Alegre se desmilingue enquanto o Rio Grande do Sul<br \/>\nretroage \u00e0 condi\u00e7\u00e3o de &#8220;latif\u00fandio agropastoril&#8221; de um s\u00e9culo atr\u00e1s.<br \/>\nE a capital que j\u00e1 foi um centro de desenvolvimento [&#8220;inova\u00e7\u00e3o&#8221;]<br \/>\nt\u00e9cnico e gerencial importante \u00e9 hoje periferia dos outros dois polos<br \/>\necon\u00f4micos da Regi\u00e3o Sul &#8211; Paran\u00e1 e Santa Catarina.<br \/>\nSem d\u00favida \u00e9 preciso fazer alguma coisa!<br \/>\nE o que n\u00e3o estou entendendo?<br \/>\nN\u00e3o estou entendendo as &#8220;circunst\u00e2ncias&#8221; que conformam este Pacto<br \/>\nAlegre da Alian\u00e7a pela Inova\u00e7\u00e3o. E cito algumas destas<br \/>\n&#8220;circunst\u00e2ncias&#8221; [&#8220;intrigantes&#8221;]:<\/p>\n<ul>\n<li>As universidades em Porto Alegre dispensaram recentemente professores<br \/>\ne fizeram radicais mudan\u00e7as nos seus curr\u00edculos e na suas ofertas de<br \/>\ntitula\u00e7\u00e3o;<\/li>\n<li>Centros de pesquisa do Governo do Estado &#8211; funda\u00e7\u00f5es fortemente<br \/>\nintegradas com as universidades &#8211; foram EXTINTOS, apesar dos<br \/>\ninsistentes alertas da pr\u00f3pria comunidade universit\u00e1ria;<\/li>\n<li>A sede de grupos empresariais importantes de origem ga\u00facha deixaram<br \/>\nPorto Alegre em fun\u00e7\u00e3o do decl\u00ednio econ\u00f4mico;<\/li>\n<li>Diversos setores, como o da sa\u00fade, constitu\u00edam polos locais com<br \/>\ndensidade tecnol\u00f3gica &#8220;enraizada&#8221; nas nossas universidades mas foram<br \/>\n&#8220;colonizados&#8221; por corpora\u00e7\u00f5es geralmente estrangeiras;<\/li>\n<li>A RBS, uma das &#8220;\u00e2ncoras&#8221; assumidas do Pacto Alegre, est\u00e1 numa<br \/>\n&#8220;trajet\u00f3ria&#8221; no m\u00ednimo estranha, pois desde 2014 faz movimentos em<br \/>\nsentido contr\u00e1rio daqueles que se sup\u00f5em ser\u00e3o &#8220;sustentados&#8221; pelo<br \/>\npacto;<\/li>\n<li>E o mais intrigante: a CRISE FISCAL que infelicita e mina<br \/>\nabsolutamente as possibilidades de revers\u00e3o da anomia e estagna\u00e7\u00e3o no<br \/>\nBrasil, no Rio Grande do Sul e em Porto Alegre n\u00e3o \u00e9 ao menos motivo de preocupa\u00e7\u00e3o, portanto, n\u00e3o ter\u00e1 nenhum tratamento dispensado pelo\u00a0 Pacto Alegre.<\/li>\n<\/ul>\n<p>Ent\u00e3o n\u00e3o sei se foi feliz este nome de Pacto Alegre, pois para mim<br \/>\nn\u00e3o passa otimismo. Antes, me soa como ironia triste&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CARLOS ALBERTO CASTRO H\u00e1 d\u00e9cadas Porto Alegre se desmilingue enquanto o Rio Grande do Sul retroage \u00e0 condi\u00e7\u00e3o de &#8220;latif\u00fandio agropastoril&#8221; de um s\u00e9culo atr\u00e1s. E a capital que j\u00e1 foi um centro de desenvolvimento [&#8220;inova\u00e7\u00e3o&#8221;] t\u00e9cnico e gerencial importante \u00e9 hoje periferia dos outros dois polos econ\u00f4micos da Regi\u00e3o Sul &#8211; Paran\u00e1 e Santa [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-71319","post","type-post","status-publish","format-standard","hentry","category-analiseopiniao"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":84590,"url":"https:\/\/www.jornalja.com.br\/colunas\/e-preciso-defender-o-jardim-botanico-de-porto-alegre\/","url_meta":{"origin":71319,"position":0},"title":"\u00c9 preciso defender o Jardim Bot\u00e2nico de Porto Alegre","author":"da Reda\u00e7\u00e3o","date":"8 de mar\u00e7o de 2026","format":false,"excerpt":"CLEBER DIONI TENTARDINI O Jardim Bot\u00e2nico de Porto Alegre (JBPA) tem 67 anos e \u00e9 considerado um dos cinco melhores e maiores do Brasil. Possui 28 cole\u00e7\u00f5es cient\u00edficas que somam mais de 4.200 plantas, incluindo esp\u00e9cies raras, amea\u00e7adas de extin\u00e7\u00e3o e end\u00eamicas, que s\u00e3o encontradas apenas no RS. No local\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84609,"url":"https:\/\/www.jornalja.com.br\/colunas\/o-centro-historico-de-porto-alegre\/","url_meta":{"origin":71319,"position":1},"title":"O Centro (Hist\u00f3rico) de Porto Alegre","author":"Cleber Dioni Tentardini","date":"30 de mar\u00e7o de 2026","format":false,"excerpt":"CLEBER DIONI TENTARDINI Porto Alegre, nove horas da manh\u00e3 do dia\u00a030\u00a0de mar\u00e7o de 2026. No \"cora\u00e7\u00e3o\" do\u00a0Centro - que j\u00e1\u00a0foi hist\u00f3rico em tempos passados,\u00a0e limpo\u00a0-,\u00a0em um trecho de\u00a0cerca de\u00a0500 metros, entre as ruas General C\u00e2mara e Senhor dos Passos, existem mais de 50 im\u00f3veis comerciais de porta de rua fechados,\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":84564,"url":"https:\/\/www.jornalja.com.br\/colunas\/a-nova-celulose-a-beira-do-guaiba-e-o-risco-de-repetir-a-borregaard\/","url_meta":{"origin":71319,"position":2},"title":"A nova celulose \u00e0 beira do Gua\u00edba e o risco de repetir a Borregaard","author":"An\u00e1lise &amp; Opini\u00e3o","date":"6 de mar\u00e7o de 2026","format":false,"excerpt":"ELMAR BONES No dia 16 de mar\u00e7o de 1972 foi inaugurada a Ind\u00fastria de Celulose Borregaard, em Gua\u00edba, com a presen\u00e7a das mais altas autoridades e manchetes ufanistas em todos os jornais. Inaugura\u00e7\u00e3o da f\u00e1brica em Gua\u00edba, no ano de 1972. Foto Reprodu\u00e7\u00e3o Arquivo\/CeluloseRioGrandense Seria uma das maiores f\u00e1bricas em\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84557,"url":"https:\/\/www.jornalja.com.br\/colunas\/entrevista-com-leonel-brizola-como-nascem-as-falsificacoes-historicas\/","url_meta":{"origin":71319,"position":3},"title":"Entrevista com Leonel Brizola: Como nascem as falsifica\u00e7\u00f5es hist\u00f3ricas","author":"An\u00e1lise &amp; Opini\u00e3o","date":"2 de mar\u00e7o de 2026","format":false,"excerpt":"SILVANA MOURA Mais do que direito \u00e0 Hist\u00f3ria, temos o direito \u00e0 verdade da Hist\u00f3ria, para evitar um passado falsificado, supostamente \u201climpo\u201d, eivado de manipula\u00e7\u00e3o e pretensa uniformidade. Em 1996 realizei, em Carazinho, uma Entrevista de Hist\u00f3ria Oral (sou Historiadora e trabalho com Hist\u00f3ria Oral h\u00e1 40 anos) com Leonel\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":84761,"url":"https:\/\/www.jornalja.com.br\/colunas\/cmpc-nova-fabrica-velhos-impactos\/","url_meta":{"origin":71319,"position":4},"title":"CMPC: Nova f\u00e1brica, velhos impactos?","author":"Cleber Dioni Tentardini","date":"6 de maio de 2026","format":false,"excerpt":"EDUARDO RAGUSE* Por volta das 13h40, do dia 05 de maio de 2026, ocorreu a despressuriza\u00e7\u00e3o de emerg\u00eancia da caldeira da f\u00e1brica de celulose da empresa CMPC, no munic\u00edpio de Gua\u00edba. O evento causou grande susto e apreens\u00e3o entre os moradores do entorno da ind\u00fastria devido ao ru\u00eddo fort\u00edssimo, odor\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":84693,"url":"https:\/\/www.jornalja.com.br\/colunas\/fim-da-escala-6x1-cabe-ao-congresso-decidir-entre-o-progresso-e-o-atraso\/","url_meta":{"origin":71319,"position":5},"title":"Fim da escala 6&#215;1: cabe ao Congresso decidir entre o progresso e o atraso","author":"da Reda\u00e7\u00e3o","date":"20 de abril de 2026","format":false,"excerpt":"Plen\u00e1rio da C\u00e2mara dos Deputados durante sess\u00e3o solene do Congresso Nacional. Caber\u00e1 ao parlamento a decis\u00e3o final sobre a nova escala de trabalho. Foto: Leopoldo Silva\/Ag\u00eancia Senado CRISTIANO GOLDSCHMIDT A discuss\u00e3o sobre o fim da escala de trabalho 6x1 no Brasil tem ganhado centralidade no debate p\u00fablico contempor\u00e2neo por tocar\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/plenario-do-congresso-nacional-posse-presidencial-2023-foto-de-leopoldo-silva-agencia-senado-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKo0s-iyj","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/71319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/comments?post=71319"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/71319\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/media?parent=71319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/categories?post=71319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/tags?post=71319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}