{"id":78187,"date":"2019-10-09T15:57:28","date_gmt":"2019-10-09T18:57:28","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=78187"},"modified":"2019-10-09T15:57:28","modified_gmt":"2019-10-09T18:57:28","slug":"manifesto-pelo-futuro-do-rs","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/colunas\/manifesto-pelo-futuro-do-rs\/","title":{"rendered":"Manifesto Pelo Futuro do RS"},"content":{"rendered":"<p><strong>Francisco Milanez*<\/strong><br \/>\nO Rio Grande do Sul sempre foi expoente da luta ambientalista moderna, na qual, al\u00e9m da preserva\u00e7\u00e3o, se discute a forma de desenvolvimento da sociedade. A Agapan lan\u00e7a este manifesto e convoca os ga\u00fachos para garantir o futuro do Rio Grande.<br \/>\nA Agapan &#8211; Associa\u00e7\u00e3o Ga\u00facha de Prote\u00e7\u00e3o ao Ambiente Natural \u2013 foi criada em 1971, antes mesmo do pr\u00f3prio Greenpeace. A entidade \u00e9 pioneira no Brasil e uma das primeiras do mundo na luta ambiental. A Agapan foi o ber\u00e7o da agroecologia, especialmente por seu primeiro presidente, Jos\u00e9 Lutzenberger, ter sa\u00eddo de uma multinacional de agrot\u00f3xicos para se alinhar na luta contra os venenos junto com os demais fundadores da Agapan.<br \/>\nPor influ\u00eancia dos ambientalistas, o RS acumula v\u00e1rios pioneirismo no Brasil, como a cria\u00e7\u00e3o da primeira secretaria municipal de Meio Ambiente, primeiro \u00f3rg\u00e3o estadual de Meio Ambiente, um dos primeiros mestrados em Ecologia do pa\u00eds (na UFRGS), cria\u00e7\u00e3o da lei de podas, lei dos agrot\u00f3xicos e a lei dos recursos h\u00eddricos, entre outras que serviram de refer\u00eancia para todo o pa\u00eds.<br \/>\nEsses movimentos hist\u00f3ricos e de vanguarda demonstram uma sensibilidade cultural e de valores de nosso povo. Conseguimos chegar ao s\u00e9culo 21 sem termos destru\u00eddo nosso Estado de forma irrevers\u00edvel e, hoje, somos e podemos ser ainda mais atrativos para o desenvolvimento do futuro, com novos valores e nova qualidade de vida.<br \/>\nSomos o ambiente perfeito para empresas sustent\u00e1veis que querem qualidade ambiental e pagam bons sal\u00e1rios. Est\u00e1 tudo pronto gra\u00e7as a 48 anos de lutas das entidades ambientalistas e simpatizantes. Temos o melhor futuro pela frente, devido ao nosso passado.<br \/>\nPROTEGER AS \u00c1GUAS<br \/>\nOs planejadores urbanos pelo mundo t\u00eam se dado conta de que uma das mais importantes necessidades de um munic\u00edpio \u00e9 \u00e1gua de boa qualidade. Boa parte das cidades \u00e9 cercada por atividades industriais e agr\u00edcolas poluentes, cujos rejeitos contaminam a \u00e1gua de abastecimento.<br \/>\nIsto tem feito com que estes munic\u00edpios invistam grandes somas em \u00e1reas de prote\u00e7\u00e3o e de produ\u00e7\u00e3o agroecol\u00f3gica, que constituem formas de n\u00e3o poluir e de preservar\/filtrar a \u00e1gua. Junto com isso, v\u00e1rias outras vantagens: ar puro, estabilidade t\u00e9rmica, beleza est\u00e9tica, e outros.<br \/>\nPorto Alegre tem de gra\u00e7a um cintur\u00e3o verde agroecol\u00f3gico, que muitas cidades modernas da Europa e EUA est\u00e3o investindo milh\u00f5es para ter. Os assentamentos agroecol\u00f3gicos de trabalhadores rurais implantados na regi\u00e3o da Grande Porto Alegre contribuem para que a cidade receba desta regi\u00e3o o que de melhor um munic\u00edpio pode ter: ar limpo, \u00e1gua filtrada, prote\u00e7\u00e3o clim\u00e1tica\/de flora\/fauna\/de ru\u00eddos e ainda excelentes alimentos org\u00e2nicos para sua popula\u00e7\u00e3o.<br \/>\n\u00c9 justamente nesta regi\u00e3o que uma empresa, por ambi\u00e7\u00e3o desmesurada, tem um projeto para implantar a maior mina de carv\u00e3o da Am\u00e9rica Latina, dentro da regi\u00e3o metropolitana a 16 km do centro da capital do Estado. Como se n\u00e3o bastasse, a empresa quer retirar um assentamento de produtores agroecol\u00f3gicos campe\u00f5es na produ\u00e7\u00e3o de arroz e de hortifruticultura org\u00e2nicos.<br \/>\nATIVIDADE POLUENTE<br \/>\nUma iniciativa il\u00f3gica para tempos em que pa\u00edses da Europa e a China buscam fugir do uso de combust\u00edveis f\u00f3sseis, em especial do carv\u00e3o, por ser esta a energia mais poluente. Atualmente, Inglaterra e Alemanha fecham suas minas de carv\u00e3o e a China cria suas novas cidades verdes e com energia limpa.<br \/>\nNo mundo inteiro milh\u00f5es de jovens e adultos saem \u00e0s ruas pedindo o fim dos combust\u00edveis f\u00f3sseis, como petr\u00f3leo, g\u00e1s e carv\u00e3o mineral porque contribuem para as mudan\u00e7as clim\u00e1ticas e comprometem o futuro do Planeta.<br \/>\nA produ\u00e7\u00e3o de energia tem sido revolucionada no mundo. As formas limpas de produ\u00e7\u00e3o como a solar e e\u00f3lica se tornaram tamb\u00e9m as mais baratas. Al\u00e9m disto, a produ\u00e7\u00e3o descentralizada de energia \u00e9 uma conquista importante para a sociedade, j\u00e1 que barateia a transmiss\u00e3o e diminui perdas.<br \/>\nNo mundo inteiro as regi\u00f5es do carv\u00e3o t\u00eam popula\u00e7\u00f5es pobres e doentes. O carv\u00e3o nunca melhorou a qualidade de vida de ningu\u00e9m, exceto, talvez, dos donos das minas que v\u00e3o morar e gastar seu dinheiro bem longe da polui\u00e7\u00e3o que produzem.<br \/>\nVejamos algumas consequ\u00eancias que esta mina poderia trazer: destrui\u00e7\u00e3o do maior manancial de \u00e1gua l\u00edmpida para abastecer a zona metropolitana futuramente; destrui\u00e7\u00e3o do cintur\u00e3o agroecol\u00f3gico da capital, destrui\u00e7\u00e3o da sa\u00fade metropolitana atrav\u00e9s de gases e particulados cancer\u00edgenos no ar; ru\u00eddos; destrui\u00e7\u00e3o do Parque Delta do Jacu\u00ed, o maior parque pr\u00f3ximo a uma capital; rebaixamento e contamina\u00e7\u00e3o do len\u00e7ol subterr\u00e2neo e do Jacu\u00ed, destrui\u00e7\u00e3o da atividade agr\u00edcola regional.<br \/>\nO argumento de que o empreendimento vai gerar empregos cai por terra quando se analisa o balan\u00e7o total, que subtrai as vagas perdidas na agricultura j\u00e1 existente e em outras atividades que v\u00e3o sucumbir.<br \/>\nA arrecada\u00e7\u00e3o de impostos com a minera\u00e7\u00e3o \u00e9 m\u00edsera comparada aos danos causados \u00e0 sociedade e n\u00e3o computa as despesas com os consequentes tratamentos de sa\u00fade da popula\u00e7\u00e3o..<br \/>\nA Mina Gua\u00edba significa a destrui\u00e7\u00e3o simb\u00f3lica e pr\u00e1tica do futuro do Estado do Rio Grande do Sul que, ao minerar a sua pr\u00f3pria capital, passar\u00e1 a repelir qualquer tipo de investimento limpo e de futuro.<br \/>\nCONSULTA P\u00daBLICA<br \/>\nA popula\u00e7\u00e3o ga\u00facha tem o direito de exigir uma consulta p\u00fablica para as 170 minera\u00e7\u00f5es aprovadas no Estado e que podem transformar o Rio Grande numa nova vers\u00e3o de Minas Gerais com Brumadinho.<br \/>\nO Rio Grande do Sul tem o direito de colher neste novo mil\u00eanio os frutos de 48 anos de luta pela qualidade vida de todos. Temos hoje a maior rede de agroecologistas do pa\u00eds, temos o \u00fanico bioma natural para produ\u00e7\u00e3o de carne org\u00e2nica em pasto natural do Brasil, temos uma popula\u00e7\u00e3o que ama a natureza e uma excelente qualidade de vida.<br \/>\nN\u00e3o queremos ser mineradores.<br \/>\n<em>*Francisco Milanez \u00e9 presidente da Agapan\u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Francisco Milanez* O Rio Grande do Sul sempre foi expoente da luta ambientalista moderna, na qual, al\u00e9m da preserva\u00e7\u00e3o, se discute a forma de desenvolvimento da sociedade. A Agapan lan\u00e7a este manifesto e convoca os ga\u00fachos para garantir o futuro do Rio Grande. A Agapan &#8211; Associa\u00e7\u00e3o Ga\u00facha de Prote\u00e7\u00e3o ao Ambiente Natural \u2013 foi [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-78187","post","type-post","status-publish","format-standard","hentry","category-analiseopiniao"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":84564,"url":"https:\/\/www.jornalja.com.br\/colunas\/a-nova-celulose-a-beira-do-guaiba-e-o-risco-de-repetir-a-borregaard\/","url_meta":{"origin":78187,"position":0},"title":"A nova celulose \u00e0 beira do Gua\u00edba e o risco de repetir a Borregaard","author":"An\u00e1lise &amp; Opini\u00e3o","date":"6 de mar\u00e7o de 2026","format":false,"excerpt":"ELMAR BONES No dia 16 de mar\u00e7o de 1972 foi inaugurada a Ind\u00fastria de Celulose Borregaard, em Gua\u00edba, com a presen\u00e7a das mais altas autoridades e manchetes ufanistas em todos os jornais. Inaugura\u00e7\u00e3o da f\u00e1brica em Gua\u00edba, no ano de 1972. Foto Reprodu\u00e7\u00e3o Arquivo\/CeluloseRioGrandense Seria uma das maiores f\u00e1bricas em\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/20260306-112140-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84761,"url":"https:\/\/www.jornalja.com.br\/colunas\/cmpc-nova-fabrica-velhos-impactos\/","url_meta":{"origin":78187,"position":1},"title":"CMPC: Nova f\u00e1brica, velhos impactos?","author":"Cleber Dioni Tentardini","date":"6 de maio de 2026","format":false,"excerpt":"EDUARDO RAGUSE* Por volta das 13h40, do dia 05 de maio de 2026, ocorreu a despressuriza\u00e7\u00e3o de emerg\u00eancia da caldeira da f\u00e1brica de celulose da empresa CMPC, no munic\u00edpio de Gua\u00edba. O evento causou grande susto e apreens\u00e3o entre os moradores do entorno da ind\u00fastria devido ao ru\u00eddo fort\u00edssimo, odor\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":84590,"url":"https:\/\/www.jornalja.com.br\/colunas\/e-preciso-defender-o-jardim-botanico-de-porto-alegre\/","url_meta":{"origin":78187,"position":2},"title":"\u00c9 preciso defender o Jardim Bot\u00e2nico de Porto Alegre","author":"da Reda\u00e7\u00e3o","date":"8 de mar\u00e7o de 2026","format":false,"excerpt":"CLEBER DIONI TENTARDINI O Jardim Bot\u00e2nico de Porto Alegre (JBPA) tem 67 anos e \u00e9 considerado um dos cinco melhores e maiores do Brasil. Possui 28 cole\u00e7\u00f5es cient\u00edficas que somam mais de 4.200 plantas, incluindo esp\u00e9cies raras, amea\u00e7adas de extin\u00e7\u00e3o e end\u00eamicas, que s\u00e3o encontradas apenas no RS. No local\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/03\/jb-3.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84632,"url":"https:\/\/www.jornalja.com.br\/colunas\/medicos-alertam-para-os-riscos-a-saude-de-nova-fabrica-de-celulose-da-cmpc\/","url_meta":{"origin":78187,"position":3},"title":"M\u00e9dicos alertam para os riscos \u00e0 sa\u00fade de nova f\u00e1brica de celulose da CMPC","author":"Cleber Dioni Tentardini","date":"14 de abril de 2026","format":false,"excerpt":"ROSELAINE MURLIK * Represento um grupo de profissionais da medicina que, h\u00e1 alguns anos, estuda os diferentes impactos das mudan\u00e7as clim\u00e1ticas e da polui\u00e7\u00e3o ambiental nos ecossistemas na sa\u00fade humana e do planeta. Causa preocupa\u00e7\u00e3o o novo megaempreendimento de celulose da empresa chilena CMPC em Barra do Ribeiro (RS), pr\u00f3ximo\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/comite-contra-celulose.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":84617,"url":"https:\/\/www.jornalja.com.br\/colunas\/o-candidato-de-si-mesmo\/","url_meta":{"origin":78187,"position":4},"title":"O candidato de si mesmo","author":"da Reda\u00e7\u00e3o","date":"10 de abril de 2026","format":false,"excerpt":"Sem emplacar nacionalmente, Leite pode ficar quatro anos sem mandato. Foto Jo\u00e3o Pedro Rodrigues\/SecomRS ELMAR BONES Ningu\u00e9m \u00e9 candidato de si mesmo. Essa \u00e9 a regra n\u00e3o escrita da pol\u00edtica partid\u00e1ria, que as velhas raposas n\u00e3o cansam de repetir aos novatos. Eduardo Leite parece n\u00e3o t\u00ea-la aprendido. Ele n\u00e3o tem\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84557,"url":"https:\/\/www.jornalja.com.br\/colunas\/entrevista-com-leonel-brizola-como-nascem-as-falsificacoes-historicas\/","url_meta":{"origin":78187,"position":5},"title":"Entrevista com Leonel Brizola: Como nascem as falsifica\u00e7\u00f5es hist\u00f3ricas","author":"An\u00e1lise &amp; Opini\u00e3o","date":"2 de mar\u00e7o de 2026","format":false,"excerpt":"SILVANA MOURA Mais do que direito \u00e0 Hist\u00f3ria, temos o direito \u00e0 verdade da Hist\u00f3ria, para evitar um passado falsificado, supostamente \u201climpo\u201d, eivado de manipula\u00e7\u00e3o e pretensa uniformidade. Em 1996 realizei, em Carazinho, uma Entrevista de Hist\u00f3ria Oral (sou Historiadora e trabalho com Hist\u00f3ria Oral h\u00e1 40 anos) com Leonel\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKo0s-kl5","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/78187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/comments?post=78187"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/78187\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/media?parent=78187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/categories?post=78187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/tags?post=78187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}