{"id":79225,"date":"2019-11-15T01:24:09","date_gmt":"2019-11-15T04:24:09","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=79225"},"modified":"2019-11-15T01:24:09","modified_gmt":"2019-11-15T04:24:09","slug":"a-republica-e-o-mito-de-floriano-peixoto","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/colunas\/a-republica-e-o-mito-de-floriano-peixoto\/","title":{"rendered":"A Rep\u00fablica e o mito de Floriano Peixoto"},"content":{"rendered":"<p style=\"text-align: right\"><em>Trecho do livro <strong>A Espada de Floriano<\/strong>, <\/em><\/p>\n<p style=\"text-align: right\"><em>\u00e0 venda na banca da ARI na Feira do Livro de Porto Alegre:<\/em><\/p>\n<p>Na manh\u00e3 de 15 de novembro de 1889 as tropas cercaram o Quartel-General onde o Conselho de Ministros\u00a0 passara a noite reunido.<br \/>\nAssestaram metralhadoras e canh\u00f5es leves contra o pr\u00e9dio e gritaram Vivas \u00e0 Rep\u00fablica. O l\u00edder dos amotinados entrou a cavalo no p\u00e1tio.<br \/>\nDesmontou, subiu as escadas e intimou todos a se retirarem para suas casas. O governo estava destitu\u00eddo.<br \/>\nHoras depois, o Imperador, ainda sem acreditar no que lhe dizem, recebe tr\u00eas emiss\u00e1rios dos sediciosos. Ele e sua fam\u00edlia deviam deixar o pa\u00eds naquele mesmo dia.<br \/>\nHerdeiro de um trono vital\u00edcio, desde os 15 anos,\u00a0 Pedro II n\u00e3o representava mais nada.<br \/>\nO Imp\u00e9rio fundado por seu pai, ao declarar o Brasil independente de Portugal, h\u00e1\u00a0 66 anos, estava acabado. Daria lugar a uma Rep\u00fablica Federativa em que o poder seria conferido a um presidente atrav\u00e9s do voto popular e renovado periodicamente.<br \/>\nN\u00e3o chegou a ser a revolu\u00e7\u00e3o que poderia ter sido.\u00a0 Depois do surto de radicalismo\u00a0 jacobino dos primeiros anos, os grupos dominantes do regime imperial &#8211; os bar\u00f5es do caf\u00e9 de S\u00e3o Paulo, os coron\u00e9is dos engenhos do Nordeste, os grandes charqueadores do Sul &#8211; se reorganizam e retomam o poder. N\u00e3o foi contudo uma simples manobra, que muda na superf\u00edcie para no final deixar tudo como sempre esteve.<br \/>\nOs ativistas republicanos expressavam as classes m\u00e9dias e prolet\u00e1rias que surgiam nas cidades com as mudan\u00e7as na economia. Alguma coisa dessas novas for\u00e7as e de seus interesses a nova situa\u00e7\u00e3o teve que incorporar, at\u00e9 para assegurar a pr\u00f3pria sobreviv\u00eancia.<br \/>\nAt\u00e9 hoje se discute o que efetivamente mudou.\u00a0 Ficou a pergunta que n\u00e3o esconde a frustra\u00e7\u00e3o e o desencanto: os &#8220;ideais republicanos&#8221;, da igualdade, da fraternidade, da liberdade, a Rep\u00fablica do cidad\u00e3o, dos direitos civis, do interesse p\u00fablico, a Rep\u00fablica dos sonhos de Silva Jardim, em que desv\u00e3o da hist\u00f3ria se extraviou?.<br \/>\nAs tentativas de resposta desdobram-se em in\u00fameras variantes e o resultado \u00e9 que nenhuma delas explica, talvez, pelo simples fato de que as teorias nunca conseguem apreender a realidade inteira.<br \/>\nDeodoro, o chefe militar que proclamou a Rep\u00fablica, \u00e9 um homem acossado pelas circunst\u00e2ncias. Quase todos os participantes das reuni\u00f5es na casa dele, nos dias anteriores ao golpe, registram sua relut\u00e2ncia.<br \/>\nAt\u00e9 o \u00faltimo momento, ele queria apenas a deposi\u00e7\u00e3o do Minist\u00e9rio e afastava a ideia de Rep\u00fablica. Relutou, depois, em aceitar a chefia do governo. Comanda o golpe, toma o poder mas n\u00e3o consegue sustenta\u00e7\u00e3o e cai um ano depois de derrubar o imperador.<br \/>\nFloriano Peixoto, o vice que assumiu,\u00a0 era um &#8220;soldado por instinto&#8221;, um dos her\u00f3is da Guerra do Paraguai que ainda estava na mem\u00f3ria de todos. Vice de Deodoro, toma seu lugar e diz que seus inimigos s\u00e3o os inimigos da Rep\u00fablica. Consegue unir o Ex\u00e9rcito, ao mesmo tempo em que divide a Marinha, onde \u00e9 maior a resist\u00eancia.<br \/>\nApoia-se nos Jacobinos e usa seu grande prestigio no meio militar para esmagar os movimentos armados que o desafiam.<br \/>\nOs jacobinos v\u00e3o contribuir com o discurso que sustentar\u00e1 seu governo.<br \/>\nO Ex\u00e9rcito, que n\u00e3o apoiou o golpe de Deodoro, coloca-se inteiro ao lado de Floriano, quando ele diz que a Rep\u00fablica est\u00e1 em perigo. Muitos de seus oficiais mais valorosos deram a vida para cumprir a ordem de defender o novo regime a qualquer pre\u00e7o, como fez o coronel\u00a0 Gomes Carneiro, que morreu defendendo a Lapa. Outros mataram friamente, como fez o coronel Moreira Cesar, que fuzilou 185 pessoas em Florian\u00f3polis.<br \/>\nEuclides da Cunha, que o chamou de &#8220;esfinge&#8221;, diz que Floriano foi um ditador que cresceu \u00e0s avessas, &#8220;avultando no cen\u00e1rio pol\u00edtico da p\u00e1tria pela depress\u00e3o que se escavara em seu entorno&#8221;.<br \/>\nPara Rui Barbosa, Floriano foi o sin\u00f4nimo de militarismo. &#8220;O militarismo est\u00e1 para o Ex\u00e9rcito assim como o fanatismo para a religi\u00e3o, o charlatanismo para a ci\u00eancia&#8221;, dizia.<br \/>\nNelson Werneck Sodr\u00e9, militar e historiador, diz que as for\u00e7as\u00a0 militares encarnadas por Floriano foram naquele momento &#8220;criadoras da vontade do povo&#8221;, &#8220;porta-vozes dos anseios populares&#8221;. O &#8220;Marechal de Ferro&#8221; pagaria at\u00e9 hoje, segundo Sodr\u00e9, o crime de ter defendido as causas populares. &#8220;Quem deseja estudar-lhe a figura singular n\u00e3o encontra fontes id\u00f4neas, todas transmitem a imagem deformada, carregada de v\u00edcios morais e descomedimento&#8230;&#8221;<br \/>\nA interpreta\u00e7\u00e3o de Sodr\u00e9, intelectual de forma\u00e7\u00e3o marxista, revela que a ditadura n\u00e3o \u00e9 s\u00f3 um recurso da direita para impedir as mudan\u00e7as, mas tamb\u00e9m um mito da esquerda que n\u00e3o descarta um regime de for\u00e7a, com apoio popular para acelerar as mudan\u00e7as&#8221;.<br \/>\nUma vez no poder, os militares republicanos relutaram em devolver aos civis. Achavam que o regime novo ainda n\u00e3o estava consolidado, precisava da prote\u00e7\u00e3o &#8211; das armas, subentendia-se. Mas n\u00e3o tiveram unidade para manter Floriano nem para encontrar um substituto para ele.<br \/>\nQuando todos pensam que Floriano vai resistir, ele vai para casa.<br \/>\nFicou esse sentimento de que a ditadura republicana, inaugurada por Deodoro, continuada por Floriano, teve fim prematuro, &#8220;antes de completar sua obra&#8221;, que ainda hoje aparece no fundo de uma frustra\u00e7\u00e3o geral com o projeto republicano.<br \/>\nParece ter ficado como uma nostalgia na mem\u00f3ria nacional, essa ideia de que nossas institui\u00e7\u00f5es republicanas, por terem uma incompletude original, s\u00e3o sempre fr\u00e1geis enjambra\u00e7\u00f5es, que de tempos em tempos precisa da prote\u00e7\u00e3o das armas para n\u00e3o sucumbir.\u00a0 \u00a0.<br \/>\nO Floriano que conhecemos hoje ainda \u00e9 &#8220;um homem cercado de sombras&#8221;. O certo \u00e9 que depois dele, o imagin\u00e1rio popular n\u00e3o se livrou mais de ideia de que s\u00f3 uma ditadura militar pode salvar o Brasil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trecho do livro A Espada de Floriano, \u00e0 venda na banca da ARI na Feira do Livro de Porto Alegre: Na manh\u00e3 de 15 de novembro de 1889 as tropas cercaram o Quartel-General onde o Conselho de Ministros\u00a0 passara a noite reunido. Assestaram metralhadoras e canh\u00f5es leves contra o pr\u00e9dio e gritaram Vivas \u00e0 Rep\u00fablica. [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-79225","post","type-post","status-publish","format-standard","hentry","category-analiseopiniao"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":84617,"url":"https:\/\/www.jornalja.com.br\/colunas\/o-candidato-de-si-mesmo\/","url_meta":{"origin":79225,"position":0},"title":"O candidato de si mesmo","author":"da Reda\u00e7\u00e3o","date":"10 de abril de 2026","format":false,"excerpt":"Sem emplacar nacionalmente, Leite pode ficar quatro anos sem mandato. Foto Jo\u00e3o Pedro Rodrigues\/SecomRS ELMAR BONES Ningu\u00e9m \u00e9 candidato de si mesmo. Essa \u00e9 a regra n\u00e3o escrita da pol\u00edtica partid\u00e1ria, que as velhas raposas n\u00e3o cansam de repetir aos novatos. Eduardo Leite parece n\u00e3o t\u00ea-la aprendido. Ele n\u00e3o tem\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/infraestrutura-escolar.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84761,"url":"https:\/\/www.jornalja.com.br\/colunas\/cmpc-nova-fabrica-velhos-impactos\/","url_meta":{"origin":79225,"position":1},"title":"CMPC: Nova f\u00e1brica, velhos impactos?","author":"Cleber Dioni Tentardini","date":"6 de maio de 2026","format":false,"excerpt":"EDUARDO RAGUSE* Por volta das 13h40, do dia 05 de maio de 2026, ocorreu a despressuriza\u00e7\u00e3o de emerg\u00eancia da caldeira da f\u00e1brica de celulose da empresa CMPC, no munic\u00edpio de Gua\u00edba. O evento causou grande susto e apreens\u00e3o entre os moradores do entorno da ind\u00fastria devido ao ru\u00eddo fort\u00edssimo, odor\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":84673,"url":"https:\/\/www.jornalja.com.br\/colunas\/40-anos-sem-simone-de-beauvoir-uma-interlocutora-ainda-incomoda-do-presente\/","url_meta":{"origin":79225,"position":2},"title":"40 anos sem Simone de Beauvoir, uma interlocutora ainda inc\u00f4moda do presente","author":"da Reda\u00e7\u00e3o","date":"14 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Quarenta anos ap\u00f3s a morte de Simone de Beauvoir (9 de janeiro de 1908 - 14 de abril de 1986), descubro que sua aus\u00eancia n\u00e3o \u00e9 propriamente um vazio \u2014 \u00e9 antes um rumor cont\u00ednuo, uma esp\u00e9cie de presen\u00e7a indireta que se infiltra nas conversas, nos livros, nas\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/simone-de-beauvoir-memorias-de-uma-menina-bemcomportada.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":84703,"url":"https:\/\/www.jornalja.com.br\/colunas\/tiradentes-o-martir-que-ainda-nos-observa-e-as-inquietacoes-de-um-brasil-inacabado\/","url_meta":{"origin":79225,"position":3},"title":"Tiradentes: o M\u00e1rtir que ainda nos observa e as inquieta\u00e7\u00f5es de um Brasil inacabado","author":"da Reda\u00e7\u00e3o","date":"21 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT H\u00e1 datas que n\u00e3o se imp\u00f5em pelo alarde, mas pela persist\u00eancia silenciosa com que atravessam os s\u00e9culos e se insinuam na consci\u00eancia coletiva. O 21 de abril pertence a essa estirpe discreta. N\u00e3o chega ornado de euforia, tampouco se anuncia com a grandiloqu\u00eancia de outras celebra\u00e7\u00f5es; antes, aproxima-se\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/tiradentes-esquartejado-1893-do-artista-pedro-americo.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84690,"url":"https:\/\/www.jornalja.com.br\/colunas\/17-de-abril-de-1996-30-anos-do-massacre-de-eldorado-do-carajas\/","url_meta":{"origin":79225,"position":4},"title":"17 de abril de 1996: 30 anos do Massacre de Eldorado do Caraj\u00e1s","author":"da Reda\u00e7\u00e3o","date":"17 de abril de 2026","format":false,"excerpt":"Cruz marca o local do massacre em Eldorado dos Caraj\u00e1s, Par\u00e1. Foto: Marcello Casal Jr.\/Arquivo ABr CRISTIANO GOLDSCHMIDT H\u00e1 datas que n\u00e3o passam. Ficam suspensas no tempo como poeira vermelha sobre a pele \u2014 insistem, infiltram-se, recusam o esquecimento. Abril, no sul do Par\u00e1, \u00e9 sempre um m\u00eas que arde.\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84681,"url":"https:\/\/www.jornalja.com.br\/colunas\/recordar-zuzu-angel-50-anos-apos-sua-morte-e-um-ato-etico\/","url_meta":{"origin":79225,"position":5},"title":"Recordar Zuzu Angel 50 anos ap\u00f3s sua morte \u00e9 um ato \u00e9tico","author":"da Reda\u00e7\u00e3o","date":"16 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Cinco d\u00e9cadas transcorreram desde o silenciamento brutal de Zuzu Angel (05 de junho de 1921 - 14 de abril de 1976), e ainda assim sua voz persiste \u2014 n\u00e3o como eco esmaecido, mas como um timbre agudo que rasga o tecido do tempo e se inscreve na mem\u00f3ria\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKo0s-kBP","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/79225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/comments?post=79225"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/79225\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/media?parent=79225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/categories?post=79225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/tags?post=79225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}