{"id":79247,"date":"2019-11-17T00:57:40","date_gmt":"2019-11-17T03:57:40","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=79247"},"modified":"2019-11-17T00:57:40","modified_gmt":"2019-11-17T03:57:40","slug":"verde-amarelismo-juridico-movimento-por-um-trabalho-sem-direitos","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/colunas\/verde-amarelismo-juridico-movimento-por-um-trabalho-sem-direitos\/","title":{"rendered":"Verde-amarelismo jur\u00eddico: movimento por um trabalho sem direitos"},"content":{"rendered":"<p><strong>Almiro Eduardo de Almeida*<\/strong><br \/>\n<strong>Oscar Krost**<\/strong><br \/>\nEm 1926 surgia no Brasil, como uma das decorr\u00eancias da Semana de Arte Moderna de 1922, o movimento liter\u00e1rio Verde Amarelo. Tamb\u00e9m conhecido como \u201cEscola da Anta\u201d, o movimento sustentava em seu Manifesto oficial, como regra fundamental, \u201ca liberdade plena de cada um ser brasileiro como quiser e puder\u201d. O grupo defendia \u201ctodas as institui\u00e7\u00f5es conservadoras\u201d acreditando que somente por meio delas \u00e9 que conseguiriam alcan\u00e7ar a \u201cinevit\u00e1vel renova\u00e7\u00e3o do Brasil\u201d O movimento propunha um &#8220;retorno ao passado&#8221; e via \u201cno popular, com sua \u00edndole pac\u00edfica, a alma da nacionalidade, a ser guiada pelas elites do pa\u00eds\u201d.<br \/>\nQuase cem anos mais tarde, como um dos desdobramentos da \u201cmoderniza\u00e7\u00e3o\u201d das leis trabalhistas realizada pela Reforma Trabalhista, em vigor h\u00e1 dois anos, o Presidente da Rep\u00fablica lan\u00e7a um novo programa para \u201cbeneficiar\u201d jovens trabalhadores. Sob a denomina\u00e7\u00e3o de contrato de trabalho verde e amarelo, o programa \u00e9 institu\u00eddo pela Medida Provis\u00f3ria N\u00ba 905, de 11 de novembro de 2019 e visa \u00e0 cria\u00e7\u00e3o de novos postos de trabalho para que jovens entre dezoito e vinte e nove anos de idade tenham acesso ao primeiro emprego.<br \/>\nDe acordo com o texto da Medida Provis\u00f3ria, o programa deveria se destinar exclusivamente a novos postos de trabalho, conforme preceitua o Artigo 2\u00ba. Curiosamente, entretanto, o par\u00e1grafo primeiro do Artigo 5\u00ba autoriza a nova forma de contrata\u00e7\u00e3o \u201cpara qualquer tipo de atividade, transit\u00f3ria ou permanente, e para substitui\u00e7\u00e3o transit\u00f3ria de pessoal permanente\u201d (destacamos).<br \/>\nSob o fundamento de n\u00e3o se destinar a trabalhadores qualificados, o programa coloca um limitador salarial de um sal\u00e1rio m\u00ednimo e meio para o sal\u00e1rio b\u00e1sico mensal dos empregados contratados na nova modalidade. Garante, entretanto, a manuten\u00e7\u00e3o da modalidade contratual mesmo quando o sal\u00e1rio ultrapassar esse valor em decorr\u00eancia de aumento ap\u00f3s doze meses de trabalho.<br \/>\nO Artigo 4\u00ba da Medida Provis\u00f3ria \u201cgarante\u201d os direitos previstos na Constitui\u00e7\u00e3o Federal \u2013 como se uma Medida Provis\u00f3ria pudesse dispor de modo diverso. N\u00e3o s\u00e3o garantidos, entretanto, os direitos previstos na CLT e nas normas coletivas da categoria a que pertencer o trabalhador. Como ficam os Princ\u00edpios do N\u00e3o-Retrocesso Social, da N\u00e3o-Discrimina\u00e7\u00e3o e da Prote\u00e7\u00e3o, raz\u00f5es de ser do Direito do Trabalho? A proje\u00e7\u00e3o da aplica\u00e7\u00e3o da regra mais favor\u00e1vel, por exemplo, ganha uma ressalva, mais ou menos assim, \u201csalvo se disposto em contr\u00e1rio, especialmente em MP\u201d. E a\u00ed come\u00e7a uma s\u00e9rie de retirada de direitos trabalhistas, quer pela supress\u00e3o direta, quer pela eros\u00e3o, afetando, inclusive, o custeio do Estado Social.<br \/>\nO discurso de gera\u00e7\u00e3o de empregos \u2013 apesar de n\u00e3o ser in\u00e9dito, pois serviu de lastro para o movimento da reforma deflagrado pela Lei n. 13.467\/17, sabidamente inexitoso \u2013 mostra-se falacioso. N\u00e3o s\u00f3 porque a nova modalidade contratual retira direitos dos trabalhadores, diminuindo o poder de compra daqueles que mais consomem, mas tamb\u00e9m por se tratar de uma nova modalidade de contrato por prazo determinado, por at\u00e9 vinte e quatro meses, \u201ca crit\u00e9rio do empregador\u201d (sic.). Assim, ainda que a nova modalidade contratual, fosse capaz de gerar mais empregos, esses teriam a ef\u00eamera dura\u00e7\u00e3o de, no m\u00e1ximo, dois anos. Regras de exce\u00e7\u00e3o e tempor\u00e1rias em mat\u00e9ria trabalhista, ali\u00e1s, tamb\u00e9m n\u00e3o se mostram novidade, servindo, apenas, como uma cortina de fuma\u00e7a, passageira e fr\u00e1gil, com finalidade populista e eleitoreira, como em situa\u00e7\u00f5es recentes envolvendo a realiza\u00e7\u00e3o da Copa do Mundo de Futebol. Al\u00e9m disso, como j\u00e1 referido, a norma autoriza a contrata\u00e7\u00e3o de trabalhadores sob a nova modalidade para a substitui\u00e7\u00e3o transit\u00f3ria de pessoal permanente, o que em nada faz aumentar o n\u00famero de postos de trabalho.<br \/>\nA nova modalidade de contrata\u00e7\u00e3o deixa o jovem trabalhador totalmente \u00e0 merc\u00ea do empregador. Isso porque, al\u00e9m de o prazo contratual ser o que melhor sirva aos interesses desse \u00faltimo, fica afastada a convers\u00e3o contratual para prazo indeterminado quando o contrato for prorrogado mais de uma vez, em evidente ofensa ao princ\u00edpio da continuidade da rela\u00e7\u00e3o de emprego. Acentua a hipossufici\u00eancia do polo fraco da rela\u00e7\u00e3o, tirando o foco da luta de classes. Deixa, em seu lugar, aparentemente, um conflito de gera\u00e7\u00f5es, entre trabalhadores novos e nem tanto, corroendo ideais de classe e de pertencimento.<br \/>\nUma leitura do artigo 6\u00ba da Medida Provis\u00f3ria permite compreender porque o \u201clegislador\u201d fez quest\u00e3o de referir no Artigo 4\u00ba que os direitos previstos na Constitui\u00e7\u00e3o restam mantidos. Trata-se, na verdade, de mais um ardil para, de forma indireta, suprimir os direitos dos trabalhadores. E, dessa vez, inclusive, os direitos constitucionalmente assegurados.<br \/>\nO artigo 6\u00ba da Medida Provis\u00f3ria prev\u00ea o fracionamento do pagamento do 13\u00ba sal\u00e1rio e das f\u00e9rias em per\u00edodos mensais ou inferiores, conforme ajustado entre empregado e empregador. Dessa forma, o trabalhador que receber o sal\u00e1rio mensal de R$ 1.497,00 (teto salarial da nova modalidade contratual) receber\u00e1 todo m\u00eas um acr\u00e9scimo salarial de R$ 124,75 a t\u00edtulo de 13\u00ba sal\u00e1rio e outro de R$ 165,92 a t\u00edtulo de f\u00e9rias com o acr\u00e9scimo de 1\/3. Ou seja, o seu sal\u00e1rio mensal ser\u00e1 de, no m\u00e1ximo, R$ 1.787,67, valor inferior a dois sal\u00e1rios m\u00ednimos e, no final do ano, o trabalhador n\u00e3o ter\u00e1 direito \u00e0 renda extra representada pelo 13\u00ba sal\u00e1rio, tampouco receber\u00e1 a remunera\u00e7\u00e3o com o acr\u00e9scimo de 1\/3 quando (e se) puder gozar suas f\u00e9rias. Para trabalhadores que percebem menos de R$ 1.500,00 por m\u00eas, o acr\u00e9scimo de R$ 290,67 ser\u00e1 certamente dilu\u00eddo nas despesas di\u00e1rias com moradia, alimenta\u00e7\u00e3o, educa\u00e7\u00e3o, sa\u00fade, lazer, vestu\u00e1rio, higiene, transporte e previd\u00eancia social, necessidades vitais b\u00e1sicas do trabalhador e de sua fam\u00edlia, que o sal\u00e1rio m\u00ednimo deveria ser capaz de atender, conforme disp\u00f5e expressamente o texto constitucional.<br \/>\nPara que efetivamente fosse garantido o sal\u00e1rio m\u00ednimo assegurado na Constitui\u00e7\u00e3o \u2013 e nem falamos aqui dos demais direitos, como faz refer\u00eancia o artigo 4\u00ba da Medida Provis\u00f3ria \u2013 o seu valor deveria ser de R$ 4.214,62, conforme aponta o DIEESE. Ou seja, mesmo com a perda do direito \u00e0 d\u00e9cima terceira remunera\u00e7\u00e3o no final do ano e a perda da remunera\u00e7\u00e3o das f\u00e9rias com o acr\u00e9scimo constitucional de 1\/3 quando o trabalhador efetivamente as gozar, o sal\u00e1rio m\u00e1ximo do novo programa governamental de \u201ccria\u00e7\u00e3o de empregos\u201d n\u00e3o garante nem mesmo a metade do m\u00ednimo que um trabalhador deveria receber no Brasil para suprir as suas necessidades vitais b\u00e1sicas e \u00e0s de sua fam\u00edlia.<br \/>\nAssim como o 13\u00ba sal\u00e1rio e as f\u00e9rias com 1\/3, o FGTS tamb\u00e9m dever\u00e1 ser dilu\u00eddo no sal\u00e1rio mensal do trabalhador, sofrendo, ainda, uma redu\u00e7\u00e3o de 75% de seu valor. O trabalhador que, at\u00e9 ent\u00e3o tinha direito a dep\u00f3sitos mensais R$ 119,76 a t\u00edtulo de FGTS, de modo a corresponder ao valor aproximado de uma remunera\u00e7\u00e3o por ano de trabalho, a partir de agora receber\u00e1 apenas R$ 29,94 por m\u00eas, valor que tendencialmente desaparecer\u00e1 no conjunto das parcelas salariais. E ainda se tem a desfa\u00e7atez de falar na garantia dos direitos constitucionalmente previstos.<br \/>\nO programa simplesmente acaba com a prote\u00e7\u00e3o contra a despedida arbitr\u00e1ria ou sem justa causa prevista no Artigo 10, inciso I, do ADCT. Isso porque, o seu pagamento tamb\u00e9m passa a se dar m\u00eas a m\u00eas, dilu\u00eddo nas demais parcelas que comp\u00f5em o sal\u00e1rio, \u201cindependentemente do motivo de demiss\u00e3o do empregado, mesmo que por justa causa\u201d (sic.). Al\u00e9m disso, o valor passa a ser reduzido pela metade. Dito de forma clara, com o contrato de trabalho verde e amarelo, a prote\u00e7\u00e3o contra a despedida arbitr\u00e1ria ou sem justa causa assegurada na Constitui\u00e7\u00e3o Federal de 1988 n\u00e3o mais se destina a proteger qualquer forma de despedida e se reduz a R$ 5,98 (cinco reais e noventa e oito centavos), no m\u00e1ximo!<br \/>\nPassados mais de trinta anos da promulga\u00e7\u00e3o da Constitui\u00e7\u00e3o Federal, a promessa da prote\u00e7\u00e3o contra a despedida arbitr\u00e1ria ou sem justa causa, estabelecida no inciso I do seu Artigo 7\u00ba, n\u00e3o apenas n\u00e3o foi efetivada, pela aus\u00eancia da edi\u00e7\u00e3o da Lei Complementar a que o texto faz refer\u00eancia, mas acaba sendo esvaziada de qualquer efetividade pela Medida Provis\u00f3ria em an\u00e1lise.<br \/>\nNesse ponto, salta aos olhos a inconstitucionalidade da medida. Ainda que se entenda que a prote\u00e7\u00e3o estabelecida no inciso I do artigo 7\u00ba, da Constitui\u00e7\u00e3o Federal configure de norma de efic\u00e1cia limitada, n\u00e3o se pode olvidar que, conforme a li\u00e7\u00e3o de Jos\u00e9 Afonso da Silva, mesmo essas normas t\u00eam certo grau de efic\u00e1cia. Com efeito, al\u00e9m de revogar a legisla\u00e7\u00e3o infraconstitucional em contr\u00e1rio, estabelecem um dever ao legislador e aos entes p\u00fablicos de legislarem no sentido de regulament\u00e1-las e, especialmente, impedem a edi\u00e7\u00e3o de leis infraconstitucionais em sentido contr\u00e1rio. Sendo assim, a Medida Provis\u00f3ria apresenta-se duplamente inconstitucional, no particular: n\u00e3o apenas esvazia uma garantia constitucional, legislando no sentido contr\u00e1rio ao determinado pela norma fundamental, mas ainda faz por Medida Provis\u00f3ria o que nem mesmo uma Lei Ordin\u00e1ria poderia fazer, haja vista a necessidade de Lei Complementar para regular a mat\u00e9ria.<br \/>\nSabe-se que lei n\u00e3o cria emprego, salvo postos de trabalho junto ao Poder P\u00fablico. O que gera emprego \u00e9 produ\u00e7\u00e3o e o que gera produ\u00e7\u00e3o \u00e9 consumo. Este, por sua vez, decorre da \u201crenda\u201d, cuja maior parte provem dos sal\u00e1rios. Assim, retirando direitos e reduzindo sal\u00e1rios, justamente da parcela da popula\u00e7\u00e3o que mais consome, como j\u00e1 referido, se est\u00e1 retirando dinheiro do mercado, agravando ainda mais a crise econ\u00f4mica que assola o pa\u00eds.<br \/>\nEm seus discursos de campanha eleitoral, o atual Presidente da Rep\u00fablica bradava que os brasileiros deveriam escolher entre direitos sem emprego ou emprego sem direitos, deixando clara a linha diretriz de sua pol\u00edtica econ\u00f4mica. Uma vez eleito, passou imediatamente a cumprir as suas \u201cpromessas\u201d de campanha. Como primeiro ato, editou, em 1\u00ba de Janeiro de 2019, a Medida Provis\u00f3ria n\u00ba 870, convertida na Lei n\u00ba 13.844\/2019, n\u00e3o apenas extinguindo o Minist\u00e9rio do Trabalho, mas tamb\u00e9m o esquartejando e o distribuindo entre o Minist\u00e9rio da Economia, para onde foi a maior parte de suas atribui\u00e7\u00f5es, e o Minist\u00e9rio da Justi\u00e7a e Seguran\u00e7a P\u00fablica, fazendo com que, o movimento sindical voltasse a ser tratado como uma quest\u00e3o de pol\u00edcia.<br \/>\nE assim, como se entr\u00e1ssemos em uma engenhosa m\u00e1quina do tempo, somos novamente lan\u00e7ados ao ano de 1926, quando o \u00faltimo presidente da Rep\u00fablica Velha, Washington Lu\u00eds, assumia o comando do pa\u00eds defendendo que a quest\u00e3o social era uma quest\u00e3o de pol\u00edcia!<br \/>\nO retorno ao passado nos remete ao in\u00edcio do presente texto. A anta fez escola. Os ideais do verde-amarelismo de 1926 parecem encontrar terreno f\u00e9rtil no verde-amarelismo de 2019. Assim como movimento liter\u00e1rio de outrora, o programa do atual governo parece acreditar que apenas pelo conservadorismo se conseguir\u00e1 a renova\u00e7\u00e3o. Assim como l\u00e1, prop\u00f5e-se aqui um retorno ao passado. Um passado em que os trabalhadores praticamente n\u00e3o tinham direitos e que a maior parte da popula\u00e7\u00e3o, \u201ccom sua \u00edndole pac\u00edfica\u201d era considerada os bra\u00e7os oper\u00e1rios do pa\u00eds, \u201ca serem guiados pelas elites\u201d.<br \/>\nE \u00e9 assim, retirando-lhes os direitos mais b\u00e1sicos, que o governo pretende \u201cbeneficiar\u201d os jovens, abrindo-lhes as portas para o mercado de trabalho. Como j\u00e1 havia feito o Manifesto do verde-amarelismo h\u00e1 quase cem anos, o governo convida a nova gera\u00e7\u00e3o a produzir sem discutir. Bem ou mal (com o sem direitos), mas produzir. E, como uma reinven\u00e7\u00e3o malfeita do passado, a regra fundamental da \u201cnova economia\u201d brasileira volta a ser \u201ca liberdade plena de cada um ser brasileiro como quiser&#8230; mas acima de tudo, como puder\u201d.<br \/>\n<em>Santa Cruz do Sul\/RS e Blumenau\/SC, 12 de novembro de 2019<\/em><br \/>\n_______________<br \/>\n<em>*<strong>Almiro Eduardo de Almeida \u00e9 j<\/strong>uiz do Trabalho vinculado ao Tribunal Regional do Trabalho da 4a Regi\u00e3o, professor de Gradua\u00e7\u00e3o no Centro Universit\u00e1rio Metodista \u2013 IPA, especialista em Direito do Trabalho pela Universidad de la Rep\u00fablica Oriental del Uruguay, mestre em Direitos Sociais e Pol\u00edticas P\u00fablicas pela Universidade de Santa Cruz do Sul \u2013 UNISC, doutor em Direito do Trabalho pela Universidade de S\u00e3o Paulo \u2013 USP.<\/em><br \/>\n**<strong>Oscar Kros <\/strong>\u00e9 juiz do Trabalho vinculado ao Tribunal Regional do Trabalho da 12a Regi\u00e3o, professor em n\u00edvel de P\u00f3s-Gradua\u00e7\u00e3o em Direito e Processo do Trabalho (Amatra\/Furb, Cesusc, Unifebe, Femargs, Univille e Unidavi), mestre em Desenvolvimento Regional (PPGDR\/Furb), membro do Instituto de Pesquisas e Estudos Avan\u00e7ados da Magistratura e do Minist\u00e9rio P\u00fablico do Trabalho (Ipeatra), coordenador e conciliador do Cejusc\/Blumenau e coordenador de curso de especializa\u00e7\u00e3o em Direito e Processo do Trabalho (Amatra\/Furb).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Almiro Eduardo de Almeida* Oscar Krost** Em 1926 surgia no Brasil, como uma das decorr\u00eancias da Semana de Arte Moderna de 1922, o movimento liter\u00e1rio Verde Amarelo. Tamb\u00e9m conhecido como \u201cEscola da Anta\u201d, o movimento sustentava em seu Manifesto oficial, como regra fundamental, \u201ca liberdade plena de cada um ser brasileiro como quiser e puder\u201d. [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-79247","post","type-post","status-publish","format-standard","hentry","category-analiseopiniao"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":84690,"url":"https:\/\/www.jornalja.com.br\/colunas\/17-de-abril-de-1996-30-anos-do-massacre-de-eldorado-do-carajas\/","url_meta":{"origin":79247,"position":0},"title":"17 de abril de 1996: 30 anos do Massacre de Eldorado do Caraj\u00e1s","author":"da Reda\u00e7\u00e3o","date":"17 de abril de 2026","format":false,"excerpt":"Cruz marca o local do massacre em Eldorado dos Caraj\u00e1s, Par\u00e1. Foto: Marcello Casal Jr.\/Arquivo ABr CRISTIANO GOLDSCHMIDT H\u00e1 datas que n\u00e3o passam. Ficam suspensas no tempo como poeira vermelha sobre a pele \u2014 insistem, infiltram-se, recusam o esquecimento. Abril, no sul do Par\u00e1, \u00e9 sempre um m\u00eas que arde.\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/mc006.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":84761,"url":"https:\/\/www.jornalja.com.br\/colunas\/cmpc-nova-fabrica-velhos-impactos\/","url_meta":{"origin":79247,"position":1},"title":"CMPC: Nova f\u00e1brica, velhos impactos?","author":"Cleber Dioni Tentardini","date":"6 de maio de 2026","format":false,"excerpt":"EDUARDO RAGUSE* Por volta das 13h40, do dia 05 de maio de 2026, ocorreu a despressuriza\u00e7\u00e3o de emerg\u00eancia da caldeira da f\u00e1brica de celulose da empresa CMPC, no munic\u00edpio de Gua\u00edba. O evento causou grande susto e apreens\u00e3o entre os moradores do entorno da ind\u00fastria devido ao ru\u00eddo fort\u00edssimo, odor\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":84748,"url":"https:\/\/www.jornalja.com.br\/colunas\/a-literatura-brasileira-no-dia-do-trabalhador\/","url_meta":{"origin":79247,"position":2},"title":"A Literatura Brasileira no Dia do Trabalho","author":"An\u00e1lise &amp; Opini\u00e3o","date":"1 de maio de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT O 1\u00ba de maio costuma ser lembrado pelo peso hist\u00f3rico das lutas trabalhistas, pelo som das manifesta\u00e7\u00f5es e pela mem\u00f3ria viva de direitos conquistados ao longo de d\u00e9cadas. No entanto, essa mesma data abriga uma outra forma de celebra\u00e7\u00e3o, menos ruidosa, mas igualmente significativa: o Dia da Literatura\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/05\/image-1.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84681,"url":"https:\/\/www.jornalja.com.br\/colunas\/recordar-zuzu-angel-50-anos-apos-sua-morte-e-um-ato-etico\/","url_meta":{"origin":79247,"position":3},"title":"Recordar Zuzu Angel 50 anos ap\u00f3s sua morte \u00e9 um ato \u00e9tico","author":"da Reda\u00e7\u00e3o","date":"16 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT Cinco d\u00e9cadas transcorreram desde o silenciamento brutal de Zuzu Angel (05 de junho de 1921 - 14 de abril de 1976), e ainda assim sua voz persiste \u2014 n\u00e3o como eco esmaecido, mas como um timbre agudo que rasga o tecido do tempo e se inscreve na mem\u00f3ria\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/zuzu-angel-1972-fotografo-desconhecido-colecao-arquivo-nacional.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84557,"url":"https:\/\/www.jornalja.com.br\/colunas\/entrevista-com-leonel-brizola-como-nascem-as-falsificacoes-historicas\/","url_meta":{"origin":79247,"position":4},"title":"Entrevista com Leonel Brizola: Como nascem as falsifica\u00e7\u00f5es hist\u00f3ricas","author":"An\u00e1lise &amp; Opini\u00e3o","date":"2 de mar\u00e7o de 2026","format":false,"excerpt":"SILVANA MOURA Mais do que direito \u00e0 Hist\u00f3ria, temos o direito \u00e0 verdade da Hist\u00f3ria, para evitar um passado falsificado, supostamente \u201climpo\u201d, eivado de manipula\u00e7\u00e3o e pretensa uniformidade. Em 1996 realizei, em Carazinho, uma Entrevista de Hist\u00f3ria Oral (sou Historiadora e trabalho com Hist\u00f3ria Oral h\u00e1 40 anos) com Leonel\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":84742,"url":"https:\/\/www.jornalja.com.br\/colunas\/rejeicao-a-messias-quando-o-senado-tensiona-os-limites-da-democracia\/","url_meta":{"origin":79247,"position":5},"title":"Rejei\u00e7\u00e3o a Messias: quando o Senado tensiona os limites da democracia","author":"An\u00e1lise &amp; Opini\u00e3o","date":"30 de abril de 2026","format":false,"excerpt":"CRISTIANO GOLDSCHMIDT A rejei\u00e7\u00e3o, pelo Senado, da indica\u00e7\u00e3o de Jorge Messias ao Supremo Tribunal Federal n\u00e3o \u00e9 um fato trivial \u2014 e trat\u00e1-la como um simples exerc\u00edcio de independ\u00eancia institucional seria, no m\u00ednimo, ing\u00eanuo. H\u00e1 algo mais profundo em jogo. O epis\u00f3dio exp\u00f5e, com certa nitidez, a forma como parcelas\u2026","rel":"","context":"Em &quot;An\u00e1lise&amp;Opini\u00e3o&quot;","block_context":{"text":"An\u00e1lise&amp;Opini\u00e3o","link":"https:\/\/www.jornalja.com.br\/colunas\/category\/analiseopiniao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/colunas\/wp-content\/uploads\/sites\/5\/2026\/04\/image-2.png?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKo0s-kCb","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/79247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/comments?post=79247"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/posts\/79247\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/media?parent=79247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/categories?post=79247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/colunas\/wp-json\/wp\/v2\/tags?post=79247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}