{"id":88090,"date":"2023-07-10T19:56:46","date_gmt":"2023-07-10T22:56:46","guid":{"rendered":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/07\/wander-wildner-foto-de-eva-sibela.jpg"},"modified":"2023-07-10T19:59:41","modified_gmt":"2023-07-10T22:59:41","slug":"wander-wildner-foto-de-eva-sibela","status":"inherit","type":"attachment","link":"https:\/\/www.jornalja.com.br\/cultura\/wander-wildner-e-banda-celebrando-o-dia-mundial-do-rock-no-theatro-fuga\/wander-wildner-foto-de-eva-sibela\/","title":{"rendered":"Wander Wildner &#8211; Foto de Eva Sibela"},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-88090","attachment","type-attachment","status-inherit","hentry"],"aioseo_notices":[],"jetpack_shortlink":"https:\/\/wp.me\/abKnZc-mUO","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/07\/wander-wildner-foto-de-eva-sibela.jpg'><img decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/07\/wander-wildner-foto-de-eva-sibela-212x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/07\/wander-wildner-foto-de-eva-sibela-212x300.jpg 212w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/07\/wander-wildner-foto-de-eva-sibela-724x1024.jpg 724w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/07\/wander-wildner-foto-de-eva-sibela-768x1086.jpg 768w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/07\/wander-wildner-foto-de-eva-sibela-1086x1536.jpg 1086w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/07\/wander-wildner-foto-de-eva-sibela-1200x1697.jpg 1200w, https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/07\/wander-wildner-foto-de-eva-sibela.jpg 1414w\" sizes=\"(max-width: 212px) 100vw, 212px\" data-attachment-id=\"88090\" data-permalink=\"https:\/\/www.jornalja.com.br\/cultura\/wander-wildner-e-banda-celebrando-o-dia-mundial-do-rock-no-theatro-fuga\/wander-wildner-foto-de-eva-sibela\/\" data-orig-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/07\/wander-wildner-foto-de-eva-sibela.jpg\" data-orig-size=\"1414,2000\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Wander Wildner &amp;#8211; Foto de Eva Sibela\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Wander Wildner se apresenta pr\u00f3ximo dia 13 &amp;#8211; Foto de Eva Sibela\/ Divulga\u00e7\u00e3o&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/07\/wander-wildner-foto-de-eva-sibela-724x1024.jpg\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Wander Wildner se apresenta pr\u00f3ximo dia 13 &#8211; Foto de Eva Sibela\/ Divulga\u00e7\u00e3o<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1414,"height":2000,"file":"2023\/07\/wander-wildner-foto-de-eva-sibela.jpg","filesize":1779029,"sizes":{"medium":{"file":"wander-wildner-foto-de-eva-sibela-212x300.jpg","width":212,"height":300,"filesize":19078,"mime_type":"image\/jpeg","source_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/07\/wander-wildner-foto-de-eva-sibela-212x300.jpg"},"large":{"file":"wander-wildner-foto-de-eva-sibela-724x1024.jpg","width":724,"height":1024,"filesize":119462,"mime_type":"image\/jpeg","source_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/07\/wander-wildner-foto-de-eva-sibela-724x1024.jpg"},"thumbnail":{"file":"wander-wildner-foto-de-eva-sibela-150x150.jpg","width":150,"height":150,"filesize":8719,"mime_type":"image\/jpeg","source_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/07\/wander-wildner-foto-de-eva-sibela-150x150.jpg"},"medium_large":{"file":"wander-wildner-foto-de-eva-sibela-768x1086.jpg","width":768,"height":1086,"filesize":130017,"mime_type":"image\/jpeg","source_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/07\/wander-wildner-foto-de-eva-sibela-768x1086.jpg"},"1536x1536":{"file":"wander-wildner-foto-de-eva-sibela-1086x1536.jpg","width":1086,"height":1536,"filesize":219235,"mime_type":"image\/jpeg","source_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/07\/wander-wildner-foto-de-eva-sibela-1086x1536.jpg"},"post-thumbnail":{"file":"wander-wildner-foto-de-eva-sibela-1200x1697.jpg","width":1200,"height":1697,"filesize":254631,"mime_type":"image\/jpeg","source_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/07\/wander-wildner-foto-de-eva-sibela-1200x1697.jpg"},"full":{"file":"wander-wildner-foto-de-eva-sibela.jpg","width":1414,"height":2000,"mime_type":"image\/jpeg","source_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/07\/wander-wildner-foto-de-eva-sibela.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":88089,"source_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/07\/wander-wildner-foto-de-eva-sibela.jpg","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media\/88090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/comments?post=88090"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":88089,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/88089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}