{"id":74438,"date":"2019-05-06T18:18:09","date_gmt":"2019-05-06T21:18:09","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=74438"},"modified":"2019-05-06T18:18:09","modified_gmt":"2019-05-06T21:18:09","slug":"28-vezes-frida-kahlo-na-pintura-de-graca-graidy","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/cultura\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\/","title":{"rendered":"28 vezes Frida Kahlo na pintura de Gra\u00e7a Craidy"},"content":{"rendered":"<p style=\"font-weight: 400\">\n<p style=\"font-weight: 400\">A figura m\u00edtica e apaixonante de Frida Kahlo estar\u00e1 em destaque na exposi\u00e7\u00e3o Fridas, da artista Gra\u00e7a Craidy, na Pinacoteca da Ajuris (Associa\u00e7\u00e3o dos Ju\u00edzes do Rio Grande do Sul), localizada na Rua Celeste Gobatto, 229, em Porto Alegre, com vernissage no dia 9 de maio, a partir das 18h30. A exposi\u00e7\u00e3o vai at\u00e9 o dia 31 de maio, com entrada franca.<\/p>\n<p style=\"font-weight: 400\">As 28 obras da artista pl\u00e1stica ga\u00facha Gra\u00e7a Craidy retratam a expressividade da mexicana, com sua for\u00e7a e suas flores, que tamb\u00e9m se espalham pela exposi\u00e7\u00e3o em imagens que emolduram a artista. Diego Rivera, grande amor de Frida, tamb\u00e9m ocupa o espa\u00e7o, com um retrato feito especialmente para a mostra.<\/p>\n<p style=\"font-weight: 400\">Para Gra\u00e7a, o mito empoderador que move a paix\u00e3o por Frida Kahlo \u00e9 o seu exemplo de vida. \u201c\u00c9 a sua supera\u00e7\u00e3o como mulher, como ativista, como pintora. \u00c9 a sua autonomia para ser o que quis, dentro dos seus limites, que n\u00e3o foram poucos. Frida \u00e9 tipo uma Santa B\u00e1rbara contempor\u00e2nea. Guerreira. Atrevida. Apaixonada. Valente. Frida \u00e9 tipo uma Yans\u00e3 urbana. Uma S\u00e3o Jorge de saias. Uma Joana D\u2019Arc latina. Ter uma Frida por perto \u00e9 como se nutrir da sua ousadia\u201d, compara a artista.<\/p>\n<figure id=\"attachment_74440\" aria-describedby=\"caption-attachment-74440\" style=\"width: 304px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-74440 size-medium\" src=\"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/2019\/05\/arte-Frida-Medieval-Baixa-Resolu\u00e7\u00e3o-304x450.jpg\" alt=\"\" width=\"304\" height=\"450\" \/><figcaption id=\"caption-attachment-74440\" class=\"wp-caption-text\">Mostra est\u00e1 na Pinacoteca da Ajuris<\/figcaption><\/figure>\n<p style=\"font-weight: 400\">Gra\u00e7a Craidy \u00e9 artista visual e publicit\u00e1ria. Em sua obra, a realidade est\u00e1 presente em den\u00fancias da viol\u00eancia contra mulher, a guerra e o abandono dos idosos. Tamb\u00e9m retrata animais, flores e artistas. Sua mais recente exposi\u00e7\u00e3o, Feminicidas, que segue em exposi\u00e7\u00e3o at\u00e9 11 de maio, no Centro Cultural CEEE Erico Verissimo, mostra um grande\u00a0pol\u00edptico (3,60 m X 1,80 m), com 12 telas (90 cm X 60 cm), com 12 homens de v\u00e1rias classes sociais e faixas et\u00e1rias, portando armas no lugar do p\u00eanis, em uma imagem que traduz o horror desse tipo de crime e seu avan\u00e7o no Pa\u00eds.<\/p>\n<p style=\"font-weight: 400\"><strong>Servi\u00e7o:<\/strong><\/p>\n<p style=\"font-weight: 400\"><strong>Exposi\u00e7\u00e3o Fridas<\/strong><\/p>\n<p style=\"font-weight: 400\">Artista: Gra\u00e7a Craidy<\/p>\n<p style=\"font-weight: 400\">Local: Pinacoteca da Ajuris<br \/>\nEndere\u00e7o: Rua Celeste Gobatto, 229 \u2013 Porto Alegre<\/p>\n<p style=\"font-weight: 400\">Abertura: 9 de maio, \u00e0s 18h30<\/p>\n<p style=\"font-weight: 400\">Visita\u00e7\u00e3o: At\u00e9 31 de maio<\/p>\n<p style=\"font-weight: 400\">Entrada franca.<\/p>\n<p style=\"font-weight: 400\">\n<p style=\"font-weight: 400\">\n","protected":false},"excerpt":{"rendered":"<p>A figura m\u00edtica e apaixonante de Frida Kahlo estar\u00e1 em destaque na exposi\u00e7\u00e3o Fridas, da artista Gra\u00e7a Craidy, na Pinacoteca da Ajuris (Associa\u00e7\u00e3o dos Ju\u00edzes do Rio Grande do Sul), localizada na Rua Celeste Gobatto, 229, em Porto Alegre, com vernissage no dia 9 de maio, a partir das 18h30. A exposi\u00e7\u00e3o vai at\u00e9 o [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":74439,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-74438","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-materiasecundaria"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"A figura m\u00edtica e apaixonante de Frida Kahlo estar\u00e1 em destaque na exposi\u00e7\u00e3o Fridas, da artista Gra\u00e7a Craidy, na Pinacoteca da Ajuris (Associa\u00e7\u00e3o dos Ju\u00edzes do Rio Grande do Sul), localizada na Rua Celeste Gobatto, 229, em Porto Alegre, com vernissage no dia 9 de maio, a partir das 18h30. A exposi\u00e7\u00e3o vai at\u00e9 o\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"da Reda\u00e7\u00e3o\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.jornalja.com.br\/cultura\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cultura\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"28 vezes Frida Kahlo na pintura de Gra\u00e7a Craidy | Cultura\" \/>\n\t\t<meta property=\"og:description\" content=\"A figura m\u00edtica e apaixonante de Frida Kahlo estar\u00e1 em destaque na exposi\u00e7\u00e3o Fridas, da artista Gra\u00e7a Craidy, na Pinacoteca da Ajuris (Associa\u00e7\u00e3o dos Ju\u00edzes do Rio Grande do Sul), localizada na Rua Celeste Gobatto, 229, em Porto Alegre, com vernissage no dia 9 de maio, a partir das 18h30. A exposi\u00e7\u00e3o vai at\u00e9 o\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/2019\/05\/arte-Frida-Medieval-Baixa-Resolu\u00e7\u00e3o-304x450.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/2019\/05\/arte-Frida-Medieval-Baixa-Resolu\u00e7\u00e3o-304x450.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-05-06T21:18:09+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-05-06T21:18:09+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaljanaweb\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@jornal_ja\" \/>\n\t\t<meta name=\"twitter:title\" content=\"28 vezes Frida Kahlo na pintura de Gra\u00e7a Craidy | Cultura\" \/>\n\t\t<meta name=\"twitter:description\" content=\"A figura m\u00edtica e apaixonante de Frida Kahlo estar\u00e1 em destaque na exposi\u00e7\u00e3o Fridas, da artista Gra\u00e7a Craidy, na Pinacoteca da Ajuris (Associa\u00e7\u00e3o dos Ju\u00edzes do Rio Grande do Sul), localizada na Rua Celeste Gobatto, 229, em Porto Alegre, com vernissage no dia 9 de maio, a partir das 18h30. A exposi\u00e7\u00e3o vai at\u00e9 o\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/2019\/05\/arte-Frida-Medieval-Baixa-Resolu\u00e7\u00e3o-304x450.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\\\/#article\",\"name\":\"28 vezes Frida Kahlo na pintura de Gra\\u00e7a Craidy | Cultura\",\"headline\":\"28 vezes Frida Kahlo na pintura de Gra\\u00e7a Craidy\",\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":74439},\"datePublished\":\"2019-05-06T18:18:09-03:00\",\"dateModified\":\"2019-05-06T18:18:09-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\\\/#webpage\"},\"articleSection\":\"Cultura-MAT\\u00c9RIA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"position\":2,\"name\":\"Cultura-MAT\\u00c9RIA\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\\\/#listItem\",\"name\":\"28 vezes Frida Kahlo na pintura de Gra\\u00e7a Craidy\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\\\/#listItem\",\"position\":3,\"name\":\"28 vezes Frida Kahlo na pintura de Gra\\u00e7a Craidy\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\",\"name\":\"Jornal J\\u00c1 Editora\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"telephone\":\"+555133307272\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/2020-logotipia-ja-35anos.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\\\/#organizationLogo\",\"width\":1067,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/jornaljapoa\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JornalJ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/\",\"name\":\"da Reda\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"da Reda\\u00e7\\u00e3o\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\\\/#webpage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\\\/\",\"name\":\"28 vezes Frida Kahlo na pintura de Gra\\u00e7a Craidy | Cultura\",\"description\":\"A figura m\\u00edtica e apaixonante de Frida Kahlo estar\\u00e1 em destaque na exposi\\u00e7\\u00e3o Fridas, da artista Gra\\u00e7a Craidy, na Pinacoteca da Ajuris (Associa\\u00e7\\u00e3o dos Ju\\u00edzes do Rio Grande do Sul), localizada na Rua Celeste Gobatto, 229, em Porto Alegre, com vernissage no dia 9 de maio, a partir das 18h30. A exposi\\u00e7\\u00e3o vai at\\u00e9 o\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":74439,\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\\\/#mainImage\"},\"datePublished\":\"2019-05-06T18:18:09-03:00\",\"dateModified\":\"2019-05-06T18:18:09-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"name\":\"Cultura\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"28 vezes Frida Kahlo na pintura de Gra\u00e7a Craidy | Cultura","description":"A figura m\u00edtica e apaixonante de Frida Kahlo estar\u00e1 em destaque na exposi\u00e7\u00e3o Fridas, da artista Gra\u00e7a Craidy, na Pinacoteca da Ajuris (Associa\u00e7\u00e3o dos Ju\u00edzes do Rio Grande do Sul), localizada na Rua Celeste Gobatto, 229, em Porto Alegre, com vernissage no dia 9 de maio, a partir das 18h30. A exposi\u00e7\u00e3o vai at\u00e9 o","canonical_url":"https:\/\/www.jornalja.com.br\/cultura\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornalja.com.br\/cultura\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\/#article","name":"28 vezes Frida Kahlo na pintura de Gra\u00e7a Craidy | Cultura","headline":"28 vezes Frida Kahlo na pintura de Gra\u00e7a Craidy","author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"},"image":{"@type":"ImageObject","url":74439},"datePublished":"2019-05-06T18:18:09-03:00","dateModified":"2019-05-06T18:18:09-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\/#webpage"},"isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\/#webpage"},"articleSection":"Cultura-MAT\u00c9RIA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornalja.com.br\/cultura\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","position":1,"name":"Home","item":"https:\/\/www.jornalja.com.br\/cultura","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","position":2,"name":"Cultura-MAT\u00c9RIA","item":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\/#listItem","name":"28 vezes Frida Kahlo na pintura de Gra\u00e7a Craidy"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\/#listItem","position":3,"name":"28 vezes Frida Kahlo na pintura de Gra\u00e7a Craidy","previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}}]},{"@type":"Organization","@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization","name":"Jornal J\u00c1 Editora","description":"Jornal J\u00c1 | Porto Alegre","url":"https:\/\/www.jornalja.com.br\/cultura\/","telephone":"+555133307272","logo":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/2020-logotipia-ja-35anos.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\/#organizationLogo","width":1067,"height":800},"image":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/jornaljapoa","https:\/\/www.youtube.com\/c\/JornalJ"]},{"@type":"Person","@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author","url":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/","name":"da Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.jornalja.com.br\/cultura\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g","width":96,"height":96,"caption":"da Reda\u00e7\u00e3o"}},{"@type":"WebPage","@id":"https:\/\/www.jornalja.com.br\/cultura\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\/#webpage","url":"https:\/\/www.jornalja.com.br\/cultura\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\/","name":"28 vezes Frida Kahlo na pintura de Gra\u00e7a Craidy | Cultura","description":"A figura m\u00edtica e apaixonante de Frida Kahlo estar\u00e1 em destaque na exposi\u00e7\u00e3o Fridas, da artista Gra\u00e7a Craidy, na Pinacoteca da Ajuris (Associa\u00e7\u00e3o dos Ju\u00edzes do Rio Grande do Sul), localizada na Rua Celeste Gobatto, 229, em Porto Alegre, com vernissage no dia 9 de maio, a partir das 18h30. A exposi\u00e7\u00e3o vai at\u00e9 o","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#website"},"breadcrumb":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\/#breadcrumblist"},"author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"creator":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"image":{"@type":"ImageObject","url":74439,"@id":"https:\/\/www.jornalja.com.br\/cultura\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\/#mainImage"},"datePublished":"2019-05-06T18:18:09-03:00","dateModified":"2019-05-06T18:18:09-03:00"},{"@type":"WebSite","@id":"https:\/\/www.jornalja.com.br\/cultura\/#website","url":"https:\/\/www.jornalja.com.br\/cultura\/","name":"Cultura","description":"Jornal J\u00c1 | Porto Alegre","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Cultura","og:type":"article","og:title":"28 vezes Frida Kahlo na pintura de Gra\u00e7a Craidy | Cultura","og:description":"A figura m\u00edtica e apaixonante de Frida Kahlo estar\u00e1 em destaque na exposi\u00e7\u00e3o Fridas, da artista Gra\u00e7a Craidy, na Pinacoteca da Ajuris (Associa\u00e7\u00e3o dos Ju\u00edzes do Rio Grande do Sul), localizada na Rua Celeste Gobatto, 229, em Porto Alegre, com vernissage no dia 9 de maio, a partir das 18h30. A exposi\u00e7\u00e3o vai at\u00e9 o","og:url":"https:\/\/www.jornalja.com.br\/cultura\/28-vezes-frida-kahlo-na-pintura-de-graca-graidy\/","og:image":"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/2019\/05\/arte-Frida-Medieval-Baixa-Resolu\u00e7\u00e3o-304x450.jpg","og:image:secure_url":"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/2019\/05\/arte-Frida-Medieval-Baixa-Resolu\u00e7\u00e3o-304x450.jpg","article:published_time":"2019-05-06T21:18:09+00:00","article:modified_time":"2019-05-06T21:18:09+00:00","article:publisher":"https:\/\/www.facebook.com\/jornaljanaweb","twitter:card":"summary","twitter:site":"@jornal_ja","twitter:title":"28 vezes Frida Kahlo na pintura de Gra\u00e7a Craidy | Cultura","twitter:description":"A figura m\u00edtica e apaixonante de Frida Kahlo estar\u00e1 em destaque na exposi\u00e7\u00e3o Fridas, da artista Gra\u00e7a Craidy, na Pinacoteca da Ajuris (Associa\u00e7\u00e3o dos Ju\u00edzes do Rio Grande do Sul), localizada na Rua Celeste Gobatto, 229, em Porto Alegre, com vernissage no dia 9 de maio, a partir das 18h30. A exposi\u00e7\u00e3o vai at\u00e9 o","twitter:image":"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/2019\/05\/arte-Frida-Medieval-Baixa-Resolu\u00e7\u00e3o-304x450.jpg"},"aioseo_meta_data":{"post_id":"74438","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-20 20:16:03","updated":"2025-06-04 11:28:22","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":86773,"url":"https:\/\/www.jornalja.com.br\/cultura\/100-vezes-graca-craidy-na-exposicao-de-retratos-em-caxias-do-sul\/","url_meta":{"origin":74438,"position":0},"title":"100 vezes Gra\u00e7a Craidy, na exposi\u00e7\u00e3o de retratos, em Caxias do Sul","author":"da Reda\u00e7\u00e3o","date":"29 de setembro de 2022","format":false,"excerpt":"Exatos 100 retratos de personalidades nacionais e internacionais da literatura, da m\u00fasica, das artes e de outras importantes atividades humanas comp\u00f5em a exposi\u00e7\u00e3o individual\u00a0\u201c100 Ritratti\u201d,\u00a0da artista visual ga\u00facha Gra\u00e7a Craidy, na Galeria Municipal de Arte Gerd Bornheim, em Caxias do Sul. A mostra ser\u00e1 aberta no s\u00e1bado (1\u00ba\/10), \u00e0s 11h,\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/09\/graca-11-oartista-gracacraidy-foto-de-wanderlei-oliveira.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/09\/graca-11-oartista-gracacraidy-foto-de-wanderlei-oliveira.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/09\/graca-11-oartista-gracacraidy-foto-de-wanderlei-oliveira.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/09\/graca-11-oartista-gracacraidy-foto-de-wanderlei-oliveira.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/09\/graca-11-oartista-gracacraidy-foto-de-wanderlei-oliveira.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":80768,"url":"https:\/\/www.jornalja.com.br\/cultura\/clara-pechansky-agrega-suas-33-amigas-na-galeria-frida-kahlo-no-mexico\/","url_meta":{"origin":74438,"position":1},"title":"Clara Pechansky agrega suas 33 amigas na galeria Frida Kahlo, no M\u00e9xico","author":"da Reda\u00e7\u00e3o","date":"28 de janeiro de 2020","format":false,"excerpt":"Clara Pechansky, que este ano celebra 64 anos como profissional das Artes Visuais,\u00a0 inova na sua pr\u00f3xima exposi\u00e7\u00e3o internacional. Convidada pelo professor Jorge Luis Hurtado Reyes, Coordenador de Artes Pl\u00e1sticas da Universidade Aut\u00f3noma de Sinaloa (UAS), para expor pela segunda vez na Galeria Frida Kahlo, decidiu agregar outras artistas \u00e0\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/01\/arte-ClaraPechansky_LisaRoos_0013_08052019.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/01\/arte-ClaraPechansky_LisaRoos_0013_08052019.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/01\/arte-ClaraPechansky_LisaRoos_0013_08052019.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/01\/arte-ClaraPechansky_LisaRoos_0013_08052019.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/01\/arte-ClaraPechansky_LisaRoos_0013_08052019.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":81941,"url":"https:\/\/www.jornalja.com.br\/cultura\/no-festival-internacional-de-cultura-em-formato-digital-exposicao-clara-pechansky-y-sus-amigas\/","url_meta":{"origin":74438,"position":2},"title":"No\u00a0Festival Internacional de Cultura, em formato digital,  Exposi\u00e7\u00e3o Clara Pechansky y Sus Amigas","author":"da Reda\u00e7\u00e3o","date":"7 de maio de 2020","format":false,"excerpt":"A exposi\u00e7\u00e3o Clara Pechansky y Sus Amigas, que inaugurou no M\u00e9xico, em fevereiro, agora poder\u00e1 ser conferida no mundo todo. A mostra foi escolhida para participar do XXV Festival Internacional Universitario de La Cultura, representando as artes visuais, at\u00e9 o dia 11 de maio de 2020.\u00a0 O festival \u00e9 promovido\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/05\/arte-ClaraPechansky_LisaRoos_0013_08052019-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/05\/arte-ClaraPechansky_LisaRoos_0013_08052019-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/05\/arte-ClaraPechansky_LisaRoos_0013_08052019-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/05\/arte-ClaraPechansky_LisaRoos_0013_08052019-scaled.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":83660,"url":"https:\/\/www.jornalja.com.br\/cultura\/exposicao-clara-pechansky-y-sus-33-amigas-comeca-a-percorrer-o-mexico\/","url_meta":{"origin":74438,"position":3},"title":"Exposi\u00e7\u00e3o \u201cClara Pechansky y sus 33 amigas\u201d come\u00e7a a percorrer o M\u00e9xico","author":"da Reda\u00e7\u00e3o","date":"26 de mar\u00e7o de 2021","format":false,"excerpt":"\u00a0 Depois de um ano em exibi\u00e7\u00e3o na Galeria Frida Kahlo da Universidade Aut\u00f4noma de Sinaloa (UAS), em Culiac\u00e1n, a exposi\u00e7\u00e3o \u201cClara Pechansky y sus 33 amigas\u201d come\u00e7a a ser mostrada por outras cidades do M\u00e9xico. As amigas de Clara, no caso, s\u00e3o artistas ga\u00fachas, ou que possuem fortes la\u00e7os\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/03\/exposicao-clara-a-oitava-em-pe-da-esq-para-dir-e-suas-convidadas-para-a-exposicao-no-mexico-foto-lisa-roos-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/03\/exposicao-clara-a-oitava-em-pe-da-esq-para-dir-e-suas-convidadas-para-a-exposicao-no-mexico-foto-lisa-roos-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/03\/exposicao-clara-a-oitava-em-pe-da-esq-para-dir-e-suas-convidadas-para-a-exposicao-no-mexico-foto-lisa-roos-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/03\/exposicao-clara-a-oitava-em-pe-da-esq-para-dir-e-suas-convidadas-para-a-exposicao-no-mexico-foto-lisa-roos-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/03\/exposicao-clara-a-oitava-em-pe-da-esq-para-dir-e-suas-convidadas-para-a-exposicao-no-mexico-foto-lisa-roos-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/03\/exposicao-clara-a-oitava-em-pe-da-esq-para-dir-e-suas-convidadas-para-a-exposicao-no-mexico-foto-lisa-roos-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":82493,"url":"https:\/\/www.jornalja.com.br\/cultura\/clara-pechansky-e-homenageada-no-mexico-em-exposicao-internacional\/","url_meta":{"origin":74438,"position":4},"title":"Clara Pechansky \u00e9 homenageada, no M\u00e9xico, em exposi\u00e7\u00e3o internacional","author":"da Reda\u00e7\u00e3o","date":"12 de agosto de 2020","format":false,"excerpt":"Clara Pechansky \u00e9 a artista homenageada da exposi\u00e7\u00e3o \u201cUm Minuto de Reflex\u00e3o na Arte Internacional\u201d, promovida pela Universidade Aut\u00f3noma de Sinaloa, no M\u00e9xico. Participam da mostra artistas do Brasil, Col\u00f4mbia, Cuba, M\u00e9xico e Venezuela.\u00a0A exposi\u00e7\u00e3o \u201cUm minuto de Reflex\u00e3o na Arte Internacional\u201d estar\u00e1 inclu\u00edda na programa\u00e7\u00e3o oficial da 39\u00aa edi\u00e7\u00e3o\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/08\/exposicao-clara-pechansky-foto-lisa-roos-0020-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/08\/exposicao-clara-pechansky-foto-lisa-roos-0020-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/08\/exposicao-clara-pechansky-foto-lisa-roos-0020-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/08\/exposicao-clara-pechansky-foto-lisa-roos-0020-scaled.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":82112,"url":"https:\/\/www.jornalja.com.br\/cultura\/exposicao-clara-pechansky-y-sus-amigas-em-grande-estilo-na-gravura-galeria-de-arte\/","url_meta":{"origin":74438,"position":5},"title":"Exposi\u00e7\u00e3o &#8220;Clara Pechansky y Sus Amigas&#8221;, em grande estilo na Gravura Galeria de Arte","author":"Higino Barros","date":"10 de junho de 2020","format":false,"excerpt":"Higino Barros Acontece em grande estilo, na pr\u00f3xima semana, a \"Exposi\u00e7\u00e3o Clara Pechansky y Sus Amigas\", que estreou em fevereiro no M\u00e9xico. A inaugura\u00e7\u00e3o ser\u00e1 no dia 17 de junho, quarta-feira, com lan\u00e7amento virtual tamb\u00e9m nas redes sociais da Gravura Galeria de Arte.\u00a0 A visita\u00e7\u00e3o, com acesso limitado, vai at\u00e9\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/06\/arte-clara-1-LisaRoos_0140_27112019-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/06\/arte-clara-1-LisaRoos_0140_27112019-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/06\/arte-clara-1-LisaRoos_0140_27112019-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/06\/arte-clara-1-LisaRoos_0140_27112019-scaled.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKnZc-jmC","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/74438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/comments?post=74438"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/74438\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media?parent=74438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/categories?post=74438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/tags?post=74438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}