{"id":76203,"date":"2019-08-11T19:07:38","date_gmt":"2019-08-11T22:07:38","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=76203"},"modified":"2019-08-11T19:07:38","modified_gmt":"2019-08-11T22:07:38","slug":"a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/cultura\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\/","title":{"rendered":"A m\u00fasica e a poesia de Vinicius de Moraes, no Chap\u00e9u Ac\u00fastico da BPE"},"content":{"rendered":"<p>&nbsp;<br \/>\n<figure id=\"attachment_76204\" aria-describedby=\"caption-attachment-76204\" style=\"width: 450px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-76204\" src=\"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/2019\/08\/arte-Ben\u00e7\u00e3o-Poetinha-foto-Giovanna-Hagemann-291018GP016-450x300.jpg\" alt=\"\" width=\"450\" height=\"300\" \/><figcaption id=\"caption-attachment-76204\" class=\"wp-caption-text\">Ben\u00e7\u00e3o Poetinha . Fotos Giovanna Hagemann -\/ Divulga\u00e7\u00e3o<\/figcaption><\/figure><\/p>\n<p style=\"font-weight: 400\">A partir da obra de Vinicius de Moraes, a cantora Anaadi, a atriz Deborah Finocchiaro e o pianista Pablo Trindade falam do amor, exaltam a vida e traduzem quest\u00f5es cruciais dos nossos tempos, em \u201cBen\u00e7\u00e3o Poetinha\u201d. O show litero-musical ser\u00e1 atra\u00e7\u00e3o do projeto Chap\u00e9u Ac\u00fastico no dia 13 de agosto (ter\u00e7a-feira), a partir das 19h, na Biblioteca P\u00fablica do estado (Riachuelo, 1190). A entrada \u00e9 gratuita ou mediante contribui\u00e7\u00e3o espont\u00e2nea.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-76205\" src=\"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/2019\/08\/arte-Ben\u00e7\u00e3o-Poetinha-foto-Giovanna-Hagemann-1-450x300.jpg\" alt=\"\" width=\"450\" height=\"300\" \/><\/p>\n<p style=\"font-weight: 400\">O espet\u00e1culo utiliza uma linguagem h\u00edbrida, com can\u00e7\u00f5es, textos e poemas \u00a0tocados, falados e cantados de forma delicada, profunda e contundente. Os sentidos s\u00e3o agu\u00e7ados, o prazer art\u00edstico compartilhado, o exerc\u00edcio do pensamento cr\u00edtico estimulado e as energias revigoradas. \u201cBen\u00e7\u00e3o Poetinha\u201d humaniza as rela\u00e7\u00f5es e promove encontros saud\u00e1veis. Une m\u00fasica e poesia como espelhos da alma e cria um ambiente de arte sanadora, com al\u00edvio, leveza e acolhimento, onde \u00e9 poss\u00edvel retirar as m\u00e1scaras, desatar n\u00f3s e se sentir em casa, entre amigos, como viveu Vinicius de Moraes. O p\u00fablico \u00e9 transportado pra outro lugar&#8230;lugar este que cada um encontra, ao final de tudo, dentro de si mesmo\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-76206\" src=\"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/2019\/08\/arte-Ben\u00e7\u00e3o-Poetinha-foto-Giovanna-Hagemann-291018GP004-4-300x450.jpg\" alt=\"\" width=\"300\" height=\"450\" \/><\/p>\n<p style=\"font-weight: 400\"><em>\u00a0<\/em>Vinicius de Moraes(1913-1980), poeta, dramaturgo, jornalista, diplomata, cantor e compositor\u00a0passou a vida rompendo conven\u00e7\u00f5es sociais. Passou da poesia culta para a popular, misturando ritmos brancos com negros, samba com candombl\u00e9 e o comportamento aristocr\u00e1tico com o bo\u00eamio.\u00a0Al\u00e9m de ter um dos fundadores da bossa nova, foi tamb\u00e9m importante poeta da segunda fase do modernismo e um dos mais famosos compositores da MPB.\u00a0Qualquer que seja a an\u00e1lise feita da obra de Vinicius de Moraes, n\u00e3o se pode escapar das palavras &#8220;mudan\u00e7a&#8221;, &#8220;evolu\u00e7\u00e3o&#8221;, &#8220;transi\u00e7\u00e3o&#8221;. Sua poesia, al\u00e9m de ser a encarna\u00e7\u00e3o do movimento e do transit\u00f3rio, elege a busca como motor primordial: do divino, da coisa ordin\u00e1ria, do homem concreto, do homem social, do homem banal, do amante e, sobretudo, da mulher. N\u00e3o importa que Vinicius parta do et\u00e9reo para chegar ao real, o que mais vale em sua obra \u00e9 a busca da fus\u00e3o com a vida.<\/p>\n<p style=\"font-weight: 400\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-76207\" src=\"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/2019\/08\/arte-Ben\u00e7\u00e3o-Poetinha-foto-Giovanna-Hagemann-291018GP002-2-450x300.jpg\" alt=\"\" width=\"450\" height=\"300\" \/><\/p>\n<p style=\"font-weight: 400\"><em>\u201c&#8230; haver\u00e1 nos olhos, na boca, nas m\u00e3os, nos p\u00e9s de todos uma \u00e2nsia t\u00e3o intensa de repouso e de poesia, que a paix\u00e3o os conduzir\u00e1 para os mesmos caminhos, os \u00fanicos que fazem a vida digna: os da ternura e do despojamento&#8230; A esse mundo, s\u00f3 a poesia poder\u00e1 salvar, e a humildade diante da sua voz&#8230;\u201d<\/em><\/p>\n<p style=\"font-weight: 400\"><em>Vinicius de Moraes<\/em><\/p>\n<p style=\"font-weight: 400\"><strong>FICHA T\u00c9CNICA:<\/strong><\/p>\n<p style=\"font-weight: 400\"><strong>Textos, poemas e m\u00fasicas:\u00a0<\/strong>Vinicius de Moraes<\/p>\n<p style=\"font-weight: 400\"><strong>Repert\u00f3rio<\/strong>: Deborah Finocchiaro e Pablo Trindade<\/p>\n<p style=\"font-weight: 400\"><strong>Piano<\/strong>: Pablo Trindade<\/p>\n<p style=\"font-weight: 400\"><strong>Int\u00e9rpretes:\u00a0<\/strong>Anaadi, Deborah Finocchiaro e Pablo Trindade<\/p>\n<p style=\"font-weight: 400\"><strong>PARTICIPANTES:<\/strong><\/p>\n<p style=\"font-weight: 400\"><strong>\u00a0<\/strong><strong>ANAADI<\/strong><\/p>\n<p style=\"font-weight: 400\">Cantora e Compositora, j\u00e1 trabalhou com grandes nomes, como Rick Wakeman, Roberto Menescal e Guinga.\u00a0 Em 2017 lan\u00e7ou o disco &#8220;Noturno&#8221;, primeiro de sua carreira, vencedor do Grammy Latino 2018 na categoria Melhor Album Pop Contempor\u00e2neo em L\u00edngua Portuguesa e indicado em outras tr\u00eas categorias: Artista Revela\u00e7\u00e3o, Grava\u00e7\u00e3o do Ano e Melhor \u00c1lbum de Engenharia de Grava\u00e7\u00e3o. A turn\u00ea \u201cAnaadi Noturno\u201d j\u00e1 passou por cidades como Porto Alegre, S\u00e3o Paulo e Curitiba no Brasil, Los Angeles e San Diego nos EUA, entre outras. No cinema, Anaadi \u00e9 autora do document\u00e1rio &#8220;Arte das Musas?&#8221;, sobre mulheres\u00a0na m\u00fasica;\u00a0cantriz no filme musical &#8220;Nervos de A\u00e7o&#8221; e autora da trilha sonora do\u00a0curta &#8220;Madrep\u00e9rola&#8221;, sobre mulheres gordas, beleza e auto-estima. A dimens\u00e3o social de seu trabalho, que lan\u00e7a luz \u00e0s quest\u00f5es de popula\u00e7\u00f5es mais vulner\u00e1veis, principalmente as mulheres, ganhou for\u00e7a em 2018 com o lan\u00e7amento do clipe \u201c\u00c9 Fake (Homem Barato)\u201d, dedicado ao protagonismo feminino.<\/p>\n<p style=\"font-weight: 400\">\n<p style=\"font-weight: 400\"><strong>DEBORAH FINOCCHIARO<\/strong><\/p>\n<p style=\"font-weight: 400\">Estreou no teatro em 1985. Bacharel em Interpreta\u00e7\u00e3o Teatral na Faculdade de Artes C\u00eanicas da UFRGS, j\u00e1 participou de centenas de trabalhos como atriz no teatro, cinema e televis\u00e3o, como diretora, produtora e ministrante em grande parte do territ\u00f3rio brasileiro, Uruguai e Argentina. Ao longo de sua carreira, recebeu 32 pr\u00eamios, entre eles 9 de Melhor Espet\u00e1culo, 17 de Melhor Atriz, 1 de Melhor Dire\u00e7\u00e3o, 1 de Melhor Texto Adaptado, 1 de Melhor Roteiro e 3 como Melhor Artista de Teatro. Em 1993 criou a\u00a0<em>Companhia de Solos &amp; Bem Acompanhados<\/em>, que atualmente tem em seu repert\u00f3rio as pe\u00e7as \u201cPois \u00e9 Vizinha&#8230;\u201d (1993), \u201cSobre Anjos &amp; Grilos &#8211; O Universo de Mario Quintana\u201d (2006), \u201cGPS GAZA\u201d (2014), \u201cCaio do C\u00e9u\u201d (2017), \u201cDi\u00e1rio Secreto de Uma Secret\u00e1ria Bilingue\u201d (2019), as pe\u00e7as curtas \u201cErico de Bolso\u201d (2013) e \u201cHist\u00f3rias de Um Canto do Mundo Chamado Sul\u201d (2008), os projetos<strong>\u201cPalavra de Bolso &#8211; Onde a Literatura ganha Voz\u201d (2016),\u00a0<\/strong>\u201cSarau Voador &#8211; Literatura e Improvisos Transcriados\u201d (2018) e as obras litero-musicais: \u201cLeitura \u00e0s Cegas\u201d (2018); \u201cBen\u00e7\u00e3o Poetinha\u201d, a partir da obra de Vinicius de Morais (2018) e \u201cPalavra Balada\u201d (2018). Em 2014 foi a artista homenageada do 21\u00ba Festival Internacional de Teatro Porto Alegre em Cena, ganhando a biografia \u201c<em>A Arte Transformadora\u201d<\/em>, escrita por Luiz Gonzaga Lopes, que\u00a0integra o 5\u00ba volume da cole\u00e7\u00e3o Ga\u00fachos Em Cena. Desde 2009 assina a coluna de teatro na R\u00e1dio Band News FM Porto Alegre &#8211; 99,3.<\/p>\n<p style=\"font-weight: 400\"><strong>\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400\"><strong>PABLO TRINDADE-ROBALLO<\/strong><\/p>\n<p style=\"font-weight: 400\">Formado em Piano, Reg\u00eancia orquestral e coral, estudou tamb\u00e9m Composi\u00e7\u00e3o e Contrabaixo no Conservat\u00f3rio F\u00e1lleri-Balzo,de Montevideo. Foi bolsista da OEA e do Conselho Interamericano de M\u00fasica (CIDEM) na Venezuela, onde se especializou em Reg\u00eancia Orquestral e \u00e9 Licenciado em M\u00fasica pelo Centro Metodista Universit\u00e1rio, IPA de Porto Alegre, Brasil. Suas composi\u00e7\u00f5es e arranjos integram o repert\u00f3rio de grupos vocais e coros da Am\u00e9rica, \u00c1sia e da Europa. Tem regido e ministrado cursos e oficinas na Alemanha, Argentina, Brasil, EEUU, Equador, Espanha, Fran\u00e7a, M\u00e9xico, Paraguai, Portugal, Uruguai e Venezuela.<\/p>\n<p style=\"font-weight: 400\">\u00c9 Regente e Diretor Art\u00edstico do grupo Expresso 25 de Porto Alegre, \u00a0do Grupo Sem Contraindica\u00e7\u00e3o de Porto Alegre, o Coro Tramontina em Farroupilha\/RS, e o Grupo Aret\u00e9 em Itaja\u00ed\/SC. \u00c9 ganhador do \u201cPr\u00eamio A\u00e7orianos de M\u00fasica 2004\u201d como Melhor Int\u00e9rprete de MPB, pelo CD Expresso 25, com os seus Arranjos e Reg\u00eancia e Pr\u00eamio A\u00e7orianos de M\u00fasica 2016 com sua comedia musical \u201cAs Tias do Vin\u00edcius\u201d na categoria Melhor Espet\u00e1culo do Ano.\u00a0 Ganhador do 2nd. Prize in The International Choral Composition Competition 2018, VocalEspoo Festival, Finl\u00e2ndia, com sua obra \u201cPasajes\u201d, para dois coros a capella.<\/p>\n<p style=\"font-weight: 400\"><strong>\u00a0<\/strong><strong>Servi\u00e7o:<\/strong><\/p>\n<p style=\"font-weight: 400\">Dia: 13 de agosto (ter\u00e7a-feira)<\/p>\n<p style=\"font-weight: 400\">Hora: a partir das 19h<\/p>\n<p style=\"font-weight: 400\">Local: Sal\u00e3o Mourisco da Biblioteca P\u00fablica do estado (Riachuelo, 1190) \u2013 Porto Alegre\/RS.<\/p>\n<p style=\"font-weight: 400\">\n<p style=\"font-weight: 400\">\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; A partir da obra de Vinicius de Moraes, a cantora Anaadi, a atriz Deborah Finocchiaro e o pianista Pablo Trindade falam do amor, exaltam a vida e traduzem quest\u00f5es cruciais dos nossos tempos, em \u201cBen\u00e7\u00e3o Poetinha\u201d. O show litero-musical ser\u00e1 atra\u00e7\u00e3o do projeto Chap\u00e9u Ac\u00fastico no dia 13 de agosto (ter\u00e7a-feira), a partir das [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":76204,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-76203","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-materiasecundaria"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"A partir da obra de Vinicius de Moraes, a cantora Anaadi, a atriz Deborah Finocchiaro e o pianista Pablo Trindade falam do amor, exaltam a vida e traduzem quest\u00f5es cruciais dos nossos tempos, em \u201cBen\u00e7\u00e3o Poetinha\u201d. O show litero-musical ser\u00e1 atra\u00e7\u00e3o do projeto Chap\u00e9u Ac\u00fastico no dia 13 de agosto (ter\u00e7a-feira), a partir das\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"da Reda\u00e7\u00e3o\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.jornalja.com.br\/cultura\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cultura\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"A m\u00fasica e a poesia de Vinicius de Moraes, no Chap\u00e9u Ac\u00fastico da BPE | Cultura\" \/>\n\t\t<meta property=\"og:description\" content=\"A partir da obra de Vinicius de Moraes, a cantora Anaadi, a atriz Deborah Finocchiaro e o pianista Pablo Trindade falam do amor, exaltam a vida e traduzem quest\u00f5es cruciais dos nossos tempos, em \u201cBen\u00e7\u00e3o Poetinha\u201d. O show litero-musical ser\u00e1 atra\u00e7\u00e3o do projeto Chap\u00e9u Ac\u00fastico no dia 13 de agosto (ter\u00e7a-feira), a partir das\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/2019\/08\/arte-Ben\u00e7\u00e3o-Poetinha-foto-Giovanna-Hagemann-291018GP016-450x300.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/2019\/08\/arte-Ben\u00e7\u00e3o-Poetinha-foto-Giovanna-Hagemann-291018GP016-450x300.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-08-11T22:07:38+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-08-11T22:07:38+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaljanaweb\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@jornal_ja\" \/>\n\t\t<meta name=\"twitter:title\" content=\"A m\u00fasica e a poesia de Vinicius de Moraes, no Chap\u00e9u Ac\u00fastico da BPE | Cultura\" \/>\n\t\t<meta name=\"twitter:description\" content=\"A partir da obra de Vinicius de Moraes, a cantora Anaadi, a atriz Deborah Finocchiaro e o pianista Pablo Trindade falam do amor, exaltam a vida e traduzem quest\u00f5es cruciais dos nossos tempos, em \u201cBen\u00e7\u00e3o Poetinha\u201d. O show litero-musical ser\u00e1 atra\u00e7\u00e3o do projeto Chap\u00e9u Ac\u00fastico no dia 13 de agosto (ter\u00e7a-feira), a partir das\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/2019\/08\/arte-Ben\u00e7\u00e3o-Poetinha-foto-Giovanna-Hagemann-291018GP016-450x300.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\\\/#article\",\"name\":\"A m\\u00fasica e a poesia de Vinicius de Moraes, no Chap\\u00e9u Ac\\u00fastico da BPE | Cultura\",\"headline\":\"A m\\u00fasica e a poesia de Vinicius de Moraes, no Chap\\u00e9u Ac\\u00fastico da BPE\",\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":76204},\"datePublished\":\"2019-08-11T19:07:38-03:00\",\"dateModified\":\"2019-08-11T19:07:38-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\\\/#webpage\"},\"articleSection\":\"Cultura-MAT\\u00c9RIA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"position\":2,\"name\":\"Cultura-MAT\\u00c9RIA\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\\\/#listItem\",\"name\":\"A m\\u00fasica e a poesia de Vinicius de Moraes, no Chap\\u00e9u Ac\\u00fastico da BPE\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\\\/#listItem\",\"position\":3,\"name\":\"A m\\u00fasica e a poesia de Vinicius de Moraes, no Chap\\u00e9u Ac\\u00fastico da BPE\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\",\"name\":\"Jornal J\\u00c1 Editora\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"telephone\":\"+555133307272\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/2020-logotipia-ja-35anos.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\\\/#organizationLogo\",\"width\":1067,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/jornaljapoa\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JornalJ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/\",\"name\":\"da Reda\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"da Reda\\u00e7\\u00e3o\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\\\/#webpage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\\\/\",\"name\":\"A m\\u00fasica e a poesia de Vinicius de Moraes, no Chap\\u00e9u Ac\\u00fastico da BPE | Cultura\",\"description\":\"A partir da obra de Vinicius de Moraes, a cantora Anaadi, a atriz Deborah Finocchiaro e o pianista Pablo Trindade falam do amor, exaltam a vida e traduzem quest\\u00f5es cruciais dos nossos tempos, em \\u201cBen\\u00e7\\u00e3o Poetinha\\u201d. O show litero-musical ser\\u00e1 atra\\u00e7\\u00e3o do projeto Chap\\u00e9u Ac\\u00fastico no dia 13 de agosto (ter\\u00e7a-feira), a partir das\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":76204,\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\\\/#mainImage\"},\"datePublished\":\"2019-08-11T19:07:38-03:00\",\"dateModified\":\"2019-08-11T19:07:38-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"name\":\"Cultura\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"A m\u00fasica e a poesia de Vinicius de Moraes, no Chap\u00e9u Ac\u00fastico da BPE | Cultura","description":"A partir da obra de Vinicius de Moraes, a cantora Anaadi, a atriz Deborah Finocchiaro e o pianista Pablo Trindade falam do amor, exaltam a vida e traduzem quest\u00f5es cruciais dos nossos tempos, em \u201cBen\u00e7\u00e3o Poetinha\u201d. O show litero-musical ser\u00e1 atra\u00e7\u00e3o do projeto Chap\u00e9u Ac\u00fastico no dia 13 de agosto (ter\u00e7a-feira), a partir das","canonical_url":"https:\/\/www.jornalja.com.br\/cultura\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornalja.com.br\/cultura\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\/#article","name":"A m\u00fasica e a poesia de Vinicius de Moraes, no Chap\u00e9u Ac\u00fastico da BPE | Cultura","headline":"A m\u00fasica e a poesia de Vinicius de Moraes, no Chap\u00e9u Ac\u00fastico da BPE","author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"},"image":{"@type":"ImageObject","url":76204},"datePublished":"2019-08-11T19:07:38-03:00","dateModified":"2019-08-11T19:07:38-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\/#webpage"},"isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\/#webpage"},"articleSection":"Cultura-MAT\u00c9RIA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornalja.com.br\/cultura\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","position":1,"name":"Home","item":"https:\/\/www.jornalja.com.br\/cultura","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","position":2,"name":"Cultura-MAT\u00c9RIA","item":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\/#listItem","name":"A m\u00fasica e a poesia de Vinicius de Moraes, no Chap\u00e9u Ac\u00fastico da BPE"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\/#listItem","position":3,"name":"A m\u00fasica e a poesia de Vinicius de Moraes, no Chap\u00e9u Ac\u00fastico da BPE","previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}}]},{"@type":"Organization","@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization","name":"Jornal J\u00c1 Editora","description":"Jornal J\u00c1 | Porto Alegre","url":"https:\/\/www.jornalja.com.br\/cultura\/","telephone":"+555133307272","logo":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/2020-logotipia-ja-35anos.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\/#organizationLogo","width":1067,"height":800},"image":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/jornaljapoa","https:\/\/www.youtube.com\/c\/JornalJ"]},{"@type":"Person","@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author","url":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/","name":"da Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.jornalja.com.br\/cultura\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g","width":96,"height":96,"caption":"da Reda\u00e7\u00e3o"}},{"@type":"WebPage","@id":"https:\/\/www.jornalja.com.br\/cultura\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\/#webpage","url":"https:\/\/www.jornalja.com.br\/cultura\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\/","name":"A m\u00fasica e a poesia de Vinicius de Moraes, no Chap\u00e9u Ac\u00fastico da BPE | Cultura","description":"A partir da obra de Vinicius de Moraes, a cantora Anaadi, a atriz Deborah Finocchiaro e o pianista Pablo Trindade falam do amor, exaltam a vida e traduzem quest\u00f5es cruciais dos nossos tempos, em \u201cBen\u00e7\u00e3o Poetinha\u201d. O show litero-musical ser\u00e1 atra\u00e7\u00e3o do projeto Chap\u00e9u Ac\u00fastico no dia 13 de agosto (ter\u00e7a-feira), a partir das","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#website"},"breadcrumb":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\/#breadcrumblist"},"author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"creator":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"image":{"@type":"ImageObject","url":76204,"@id":"https:\/\/www.jornalja.com.br\/cultura\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\/#mainImage"},"datePublished":"2019-08-11T19:07:38-03:00","dateModified":"2019-08-11T19:07:38-03:00"},{"@type":"WebSite","@id":"https:\/\/www.jornalja.com.br\/cultura\/#website","url":"https:\/\/www.jornalja.com.br\/cultura\/","name":"Cultura","description":"Jornal J\u00c1 | Porto Alegre","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Cultura","og:type":"article","og:title":"A m\u00fasica e a poesia de Vinicius de Moraes, no Chap\u00e9u Ac\u00fastico da BPE | Cultura","og:description":"A partir da obra de Vinicius de Moraes, a cantora Anaadi, a atriz Deborah Finocchiaro e o pianista Pablo Trindade falam do amor, exaltam a vida e traduzem quest\u00f5es cruciais dos nossos tempos, em \u201cBen\u00e7\u00e3o Poetinha\u201d. O show litero-musical ser\u00e1 atra\u00e7\u00e3o do projeto Chap\u00e9u Ac\u00fastico no dia 13 de agosto (ter\u00e7a-feira), a partir das","og:url":"https:\/\/www.jornalja.com.br\/cultura\/a-musica-e-a-poesia-de-vinicius-de-moraes-no-chapeu-acustico-da-bpe\/","og:image":"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/2019\/08\/arte-Ben\u00e7\u00e3o-Poetinha-foto-Giovanna-Hagemann-291018GP016-450x300.jpg","og:image:secure_url":"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/2019\/08\/arte-Ben\u00e7\u00e3o-Poetinha-foto-Giovanna-Hagemann-291018GP016-450x300.jpg","article:published_time":"2019-08-11T22:07:38+00:00","article:modified_time":"2019-08-11T22:07:38+00:00","article:publisher":"https:\/\/www.facebook.com\/jornaljanaweb","twitter:card":"summary","twitter:site":"@jornal_ja","twitter:title":"A m\u00fasica e a poesia de Vinicius de Moraes, no Chap\u00e9u Ac\u00fastico da BPE | Cultura","twitter:description":"A partir da obra de Vinicius de Moraes, a cantora Anaadi, a atriz Deborah Finocchiaro e o pianista Pablo Trindade falam do amor, exaltam a vida e traduzem quest\u00f5es cruciais dos nossos tempos, em \u201cBen\u00e7\u00e3o Poetinha\u201d. O show litero-musical ser\u00e1 atra\u00e7\u00e3o do projeto Chap\u00e9u Ac\u00fastico no dia 13 de agosto (ter\u00e7a-feira), a partir das","twitter:image":"https:\/\/www.jornalja.com.br\/wp-content\/uploads\/2019\/08\/arte-Ben\u00e7\u00e3o-Poetinha-foto-Giovanna-Hagemann-291018GP016-450x300.jpg"},"aioseo_meta_data":{"post_id":"76203","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-20 20:28:23","updated":"2025-06-04 11:36:25","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":72298,"url":"https:\/\/www.jornalja.com.br\/cultura\/sarau-voador-celebra-a-obra-de-vinicius-de-moraes-no-barco-cisne-branco\/","url_meta":{"origin":76203,"position":0},"title":"Sarau Voador celebra a obra de Vinicius de Moraes, no barco Cisne Branco","author":"da Reda\u00e7\u00e3o","date":"18 de janeiro de 2019","format":false,"excerpt":"O Sarau Voador \u2013 Literatura e Improvisos Transcriados realiza no dia 24 de janeiro (quinta-feira) uma edi\u00e7\u00e3o especial dentro da programa\u00e7\u00e3o do 20\u00ba Porto Ver\u00e3o Alegre em homenagem ao mestre Vinicius de Moraes.\u00a0Com o tema \u201cB\u00ean\u00e7\u00e3o, Poetinha\u201d,\u00a0a atriz\u00a0Deborah Finocchiaro e o jornalista Roger Lerina recebem a cantora Anaadi, o maestro\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":75808,"url":"https:\/\/www.jornalja.com.br\/cultura\/gil-jazz-trio-fecha-a-programacao-de-julho-do-chapeu-acustico\/","url_meta":{"origin":76203,"position":1},"title":"Gil Jazz Trio fecha a programa\u00e7\u00e3o de julho do Chap\u00e9u Ac\u00fastico","author":"da Reda\u00e7\u00e3o","date":"29 de julho de 2019","format":false,"excerpt":"Para fechar a programa\u00e7\u00e3o de julho do projeto Chap\u00e9u Ac\u00fastico, o Gil Jazz Trio levar\u00e1 o melhor da m\u00fasica instrumental \u00e0 Biblioteca P\u00fablica do Estado (Riachuelo, 1190), nessa ter\u00e7a-feira, dia 30, 19h, no show \u201cDo Jazz ao Samba\u201d. Formado em 2015, o trio liderado por Gilberto Oliveira conta com duas\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":77941,"url":"https:\/\/www.jornalja.com.br\/cultura\/chapeuzinho-acustico-apresenta-o-baile-do-gato-na-tuba-na-bpe\/","url_meta":{"origin":76203,"position":2},"title":"Chapeuzinho Ac\u00fastico apresenta &#039;O Baile do Gato na Tuba&#039;, na BPE","author":"da Reda\u00e7\u00e3o","date":"30 de setembro de 2019","format":false,"excerpt":"O Chapeuzinho Ac\u00fastico, vers\u00e3o infantil do projeto Chap\u00e9u Ac\u00fastico, tem como atra\u00e7\u00e3o neste ano, o \u201cBaile do Gato na Tuba\u201d, dia 6 de outubro (domingo), \u00e0s 16h, na Biblioteca P\u00fablica do Estado (Riachuelo, 1190). A Cia. Megamini promove um momento de festa, alegria, aprendizado e relaxamento, onde pais\/cuidadores e filhos\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/wp-content\/uploads\/2019\/09\/arte-Baile-d-Gato-na-Tuba-1-Gustavo-Ziegelmann--450x338.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":77869,"url":"https:\/\/www.jornalja.com.br\/cultura\/rafael-brasil-mostra-seu-canto-cancoes-de-amor-no-chapeu-acustico\/","url_meta":{"origin":76203,"position":3},"title":"Rafael Brasil mostra seu &quot;Canto Can\u00e7\u00f5es de Amor&quot; ,  no Chap\u00e9u Ac\u00fastico","author":"da Reda\u00e7\u00e3o","date":"28 de setembro de 2019","format":false,"excerpt":"Abrindo a programa\u00e7\u00e3o de outubro do projeto Chap\u00e9u Ac\u00fastico, na Biblioteca P\u00fablica do Estado do RS (Riachuelo, 1190), Rafael Brasil (viol\u00e3o e voz) apresenta \u201cCanto Can\u00e7\u00f5es de Amor\u201d, com onze m\u00fasicas do CD e DVD hom\u00f4nimos, todas autorais, acompanhado de M\u00e1rcio Bandeira (percuss\u00e3o). O show ser\u00e1 realizado no dia 1\u00ba\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/wp-content\/uploads\/2019\/09\/arte-Rafael-Brasil-foto-Rodrigo-Mattos-2-450x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":75864,"url":"https:\/\/www.jornalja.com.br\/cultura\/tribo-brasil-abre-a-agenda-de-agosto-do-projeto-chapeu-acustico\/","url_meta":{"origin":76203,"position":4},"title":"&quot;Tribo Brasil&quot; abre a agenda de agosto do projeto Chap\u00e9u Ac\u00fastico","author":"da Reda\u00e7\u00e3o","date":"31 de julho de 2019","format":false,"excerpt":"Uma das bandas de maior atua\u00e7\u00e3o e carisma no atual cen\u00e1rio musical porto-alegrense, a \"Tribo Brasil\", \u00e9 quem abre o projeto Chap\u00e9u Ac\u00fastico de agosto, no dia 6 (ter\u00e7a-feira), a partir das 19h, no Sal\u00e3o Mourisco. A entrada \u00e9 gratuita ou mediante contribui\u00e7\u00e3o espont\u00e2nea. Com a proposta de pesquisa e\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":78705,"url":"https:\/\/www.jornalja.com.br\/cultura\/leonardo-ribeiro-e-jefferson-max-sao-atracoes-no-ultimo-chapeu-acustico-do-mes-de-outubro\/","url_meta":{"origin":76203,"position":5},"title":"Leonardo Ribeiro e Jefferson Max, s\u00e3o atra\u00e7\u00f5es no \u00faltimo &quot;Chap\u00e9u Ac\u00fastico&quot; do m\u00eas de outubro","author":"da Reda\u00e7\u00e3o","date":"28 de outubro de 2019","format":false,"excerpt":"O violonista, cantor e compositor Leonardo Ribeiro e o guitarrista Jefferson Max apresentam um show que circula por v\u00e1rias tend\u00eancias da m\u00fasica universal e vai do Jazz \u00e0 MPB, passando pela m\u00fasica latina, no \u00faltimo Chap\u00e9u Ac\u00fastico de outubro, dia 29, a partir das 19h, na Biblioteca P\u00fablica do Estado\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKnZc-jP5","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/76203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/comments?post=76203"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/76203\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media?parent=76203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/categories?post=76203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/tags?post=76203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}