{"id":80432,"date":"2020-01-09T10:57:36","date_gmt":"2020-01-09T13:57:36","guid":{"rendered":"https:\/\/www.jornalja.com.br\/?p=80432"},"modified":"2020-01-09T10:57:36","modified_gmt":"2020-01-09T13:57:36","slug":"chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/cultura\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\/","title":{"rendered":"Chamada para ocupa\u00e7\u00e3o de teatros da Casa de Cultura M\u00e1rio Quintana"},"content":{"rendered":"<div>\nA Casa de Cultura Mario Quintana (CCMQ) abriu em dezembro, dia 17, e encerra no pr\u00f3ximo dia 15 de janeiro, as inscri\u00e7\u00f5es da <a href=\"http:\/\/www.ccmq.com.br\/site\/wp-content\/uploads\/2019\/12\/Chamada-P%C3%BAblica.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"http:\/\/www.google.com\/url?q=http:\/\/www.ccmq.com.br\/site\/wp-content\/uploads\/2019\/12\/Chamada-P%25C3%25BAblica.pdf&amp;source=gmail&amp;ust=1578662387758000&amp;usg=AFQjCNGpsFkL-7BsSK8X3iV1iJ-vtWJKBg\">Chamada P\u00fablica<\/a>\u00a0para a ocupa\u00e7\u00e3o do Teatro Bruno Kiefer e da Sala Carlos Carvalho, para temporadas de espet\u00e1culos nas modalidades artes c\u00eanicas (circo, dan\u00e7a e teatro) e m\u00fasica; e temporada livre (circo, dan\u00e7a, teatro e m\u00fasica), no primeiro semestre de 2020.<\/p>\n<div id=\"m_-3476518399545706717gmail-attachment_51049\">\n<span style=\"font-weight: 300\">Algumas temporadas ter\u00e3o uma data com int\u00e9rprete de Libras (L\u00edngua Brasileira de Sinais), com custos pagos pela CCMQ. J\u00e1 as temporadas de artes c\u00eanicas que contemplarem o teatro infantil ter\u00e3o o diferencial de serem duas datas semanais, aos s\u00e1bado e domingos, num total de 8 apresenta\u00e7\u00f5es.<\/span>\n<\/div>\n<p>As inscri\u00e7\u00f5es devem ser feitas at\u00e9 o dia 15 de janeiro pelo e-mail\u00a0<a href=\"mailto:chamadapublicaccmqteatros@gmail.com\" target=\"_blank\" rel=\"noopener noreferrer\">chamadapublicaccmqteatros@gmail.com<\/a>, para onde devem ser enviados os documentos:\u00a0<a href=\"http:\/\/www.ccmq.com.br\/site\/wp-content\/uploads\/2019\/12\/Anexo-I.doc\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"http:\/\/www.google.com\/url?q=http:\/\/www.ccmq.com.br\/site\/wp-content\/uploads\/2019\/12\/Anexo-I.doc&amp;source=gmail&amp;ust=1578662387758000&amp;usg=AFQjCNG2zDbJ9cJZ_a7MOPoBqboCVhVVkQ\">Anexo I<\/a>\u00a0(Of\u00edcio de Solicita\u00e7\u00e3o CCMQ)\u00a0e\u00a0<a href=\"http:\/\/www.ccmq.com.br\/site\/wp-content\/uploads\/2019\/12\/Anexo-II.doc\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"http:\/\/www.google.com\/url?q=http:\/\/www.ccmq.com.br\/site\/wp-content\/uploads\/2019\/12\/Anexo-II.doc&amp;source=gmail&amp;ust=1578662387758000&amp;usg=AFQjCNF09Bwvw6ftcUUFWoLMu2EpHF4ONQ\">Anexo II<\/a>\u00a0(Informa\u00e7\u00f5es espet\u00e1culo CCMQ), as solicita\u00e7\u00f5es de ocupa\u00e7\u00e3o e outras informa\u00e7\u00f5es que o proponente julgar pertinente. A divulga\u00e7\u00e3o dos projetos selecionados ocorre no dia 5 de fevereiro de 2020, pelo site da CCMQ:\u00a0<a href=\"http:\/\/www.ccmq.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"http:\/\/www.google.com\/url?q=http:\/\/www.ccmq.com.br&amp;source=gmail&amp;ust=1578662387758000&amp;usg=AFQjCNGwoq6q3FPN7wL95U6oryoMddhkFg\">www.ccmq.com.br<\/a>.<br \/>\n<strong>CRONOGRAMA<\/strong><br \/>\nAbertura: 17\/12\/2019<br \/>\nPer\u00edodo de recebimento das propostas: de 17\/12\/2019 a 15\/01\/2020<br \/>\nHabilita\u00e7\u00e3o das propostas: 16\/01 a 17\/01\/2020<br \/>\nDivulga\u00e7\u00e3o dos habilitados: 20\/01\/2020<br \/>\nRecursos: 21\/01 a 23\/01\/2020<br \/>\nDivulga\u00e7\u00e3o dos recursos: 27\/01\/2020<br \/>\nAn\u00e1lise e sele\u00e7\u00e3o das propostas: 31\/01 a 04\/02\/2020<br \/>\nDivulga\u00e7\u00e3o dos selecionados: 05\/02\/2020<br \/>\nOcupa\u00e7\u00e3o: a partir de 06\/03\/2020\n<\/div>\n<div>\n<div dir=\"ltr\" data-smartmail=\"gmail_signature\">\n<div dir=\"ltr\">\n<div>\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Casa de Cultura Mario Quintana (CCMQ) abriu em dezembro, dia 17, e encerra no pr\u00f3ximo dia 15 de janeiro, as inscri\u00e7\u00f5es da Chamada P\u00fablica\u00a0para a ocupa\u00e7\u00e3o do Teatro Bruno Kiefer e da Sala Carlos Carvalho, para temporadas de espet\u00e1culos nas modalidades artes c\u00eanicas (circo, dan\u00e7a e teatro) e m\u00fasica; e temporada livre (circo, dan\u00e7a, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":80433,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-80432","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-materiasecundaria"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"A Casa de Cultura Mario Quintana (CCMQ) abriu em dezembro, dia 17, e encerra no pr\u00f3ximo dia 15 de janeiro, as inscri\u00e7\u00f5es da Chamada P\u00fablica para a ocupa\u00e7\u00e3o do Teatro Bruno Kiefer e da Sala Carlos Carvalho, para temporadas de espet\u00e1culos nas modalidades artes c\u00eanicas (circo, dan\u00e7a e teatro) e m\u00fasica; e temporada livre (circo, dan\u00e7a,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"da Reda\u00e7\u00e3o\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.jornalja.com.br\/cultura\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cultura\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Chamada para ocupa\u00e7\u00e3o de teatros da Casa de Cultura M\u00e1rio Quintana | Cultura\" \/>\n\t\t<meta property=\"og:description\" content=\"A Casa de Cultura Mario Quintana (CCMQ) abriu em dezembro, dia 17, e encerra no pr\u00f3ximo dia 15 de janeiro, as inscri\u00e7\u00f5es da Chamada P\u00fablica para a ocupa\u00e7\u00e3o do Teatro Bruno Kiefer e da Sala Carlos Carvalho, para temporadas de espet\u00e1culos nas modalidades artes c\u00eanicas (circo, dan\u00e7a e teatro) e m\u00fasica; e temporada livre (circo, dan\u00e7a,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/01\/arte-teatro.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/01\/arte-teatro.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t\t<meta property=\"og:image:height\" content=\"143\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-01-09T13:57:36+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-01-09T13:57:36+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaljanaweb\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@jornal_ja\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Chamada para ocupa\u00e7\u00e3o de teatros da Casa de Cultura M\u00e1rio Quintana | Cultura\" \/>\n\t\t<meta name=\"twitter:description\" content=\"A Casa de Cultura Mario Quintana (CCMQ) abriu em dezembro, dia 17, e encerra no pr\u00f3ximo dia 15 de janeiro, as inscri\u00e7\u00f5es da Chamada P\u00fablica para a ocupa\u00e7\u00e3o do Teatro Bruno Kiefer e da Sala Carlos Carvalho, para temporadas de espet\u00e1culos nas modalidades artes c\u00eanicas (circo, dan\u00e7a e teatro) e m\u00fasica; e temporada livre (circo, dan\u00e7a,\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/01\/arte-teatro.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\\\/#article\",\"name\":\"Chamada para ocupa\\u00e7\\u00e3o de teatros da Casa de Cultura M\\u00e1rio Quintana | Cultura\",\"headline\":\"Chamada para ocupa\\u00e7\\u00e3o de teatros da Casa de Cultura M\\u00e1rio Quintana\",\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/01\\\/arte-teatro.jpg\",\"width\":300,\"height\":143,\"caption\":\"Espet\\u00e1culo Infantil \\u201cBandele\\u201d foi uma das pe\\u00e7as que ocupou o Teatro Bruno Kiefer no segundo semestre de 2019 \\u2013 Foto: Andr\\u00e9 Furtado\\\/ Divulga\\u00e7\\u00e3o\"},\"datePublished\":\"2020-01-09T10:57:36-03:00\",\"dateModified\":\"2020-01-09T10:57:36-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\\\/#webpage\"},\"articleSection\":\"Cultura-MAT\\u00c9RIA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"position\":2,\"name\":\"Cultura-MAT\\u00c9RIA\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\\\/#listItem\",\"name\":\"Chamada para ocupa\\u00e7\\u00e3o de teatros da Casa de Cultura M\\u00e1rio Quintana\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\\\/#listItem\",\"position\":3,\"name\":\"Chamada para ocupa\\u00e7\\u00e3o de teatros da Casa de Cultura M\\u00e1rio Quintana\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\",\"name\":\"Jornal J\\u00c1 Editora\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"telephone\":\"+555133307272\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/2020-logotipia-ja-35anos.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\\\/#organizationLogo\",\"width\":1067,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/jornaljapoa\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JornalJ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/\",\"name\":\"da Reda\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\\\/#authorImage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/litespeed\\\/avatar\\\/2\\\/d9cd863c234b5b6efee1c2d4e369043e.jpg?ver=1784090128\",\"width\":96,\"height\":96,\"caption\":\"da Reda\\u00e7\\u00e3o\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\\\/#webpage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\\\/\",\"name\":\"Chamada para ocupa\\u00e7\\u00e3o de teatros da Casa de Cultura M\\u00e1rio Quintana | Cultura\",\"description\":\"A Casa de Cultura Mario Quintana (CCMQ) abriu em dezembro, dia 17, e encerra no pr\\u00f3ximo dia 15 de janeiro, as inscri\\u00e7\\u00f5es da Chamada P\\u00fablica para a ocupa\\u00e7\\u00e3o do Teatro Bruno Kiefer e da Sala Carlos Carvalho, para temporadas de espet\\u00e1culos nas modalidades artes c\\u00eanicas (circo, dan\\u00e7a e teatro) e m\\u00fasica; e temporada livre (circo, dan\\u00e7a,\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/01\\\/arte-teatro.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\\\/#mainImage\",\"width\":300,\"height\":143,\"caption\":\"Espet\\u00e1culo Infantil \\u201cBandele\\u201d foi uma das pe\\u00e7as que ocupou o Teatro Bruno Kiefer no segundo semestre de 2019 \\u2013 Foto: Andr\\u00e9 Furtado\\\/ Divulga\\u00e7\\u00e3o\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\\\/#mainImage\"},\"datePublished\":\"2020-01-09T10:57:36-03:00\",\"dateModified\":\"2020-01-09T10:57:36-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"name\":\"Cultura\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Chamada para ocupa\u00e7\u00e3o de teatros da Casa de Cultura M\u00e1rio Quintana | Cultura","description":"A Casa de Cultura Mario Quintana (CCMQ) abriu em dezembro, dia 17, e encerra no pr\u00f3ximo dia 15 de janeiro, as inscri\u00e7\u00f5es da Chamada P\u00fablica para a ocupa\u00e7\u00e3o do Teatro Bruno Kiefer e da Sala Carlos Carvalho, para temporadas de espet\u00e1culos nas modalidades artes c\u00eanicas (circo, dan\u00e7a e teatro) e m\u00fasica; e temporada livre (circo, dan\u00e7a,","canonical_url":"https:\/\/www.jornalja.com.br\/cultura\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornalja.com.br\/cultura\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\/#article","name":"Chamada para ocupa\u00e7\u00e3o de teatros da Casa de Cultura M\u00e1rio Quintana | Cultura","headline":"Chamada para ocupa\u00e7\u00e3o de teatros da Casa de Cultura M\u00e1rio Quintana","author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/01\/arte-teatro.jpg","width":300,"height":143,"caption":"Espet\u00e1culo Infantil \u201cBandele\u201d foi uma das pe\u00e7as que ocupou o Teatro Bruno Kiefer no segundo semestre de 2019 \u2013 Foto: Andr\u00e9 Furtado\/ Divulga\u00e7\u00e3o"},"datePublished":"2020-01-09T10:57:36-03:00","dateModified":"2020-01-09T10:57:36-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\/#webpage"},"isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\/#webpage"},"articleSection":"Cultura-MAT\u00c9RIA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornalja.com.br\/cultura\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","position":1,"name":"Home","item":"https:\/\/www.jornalja.com.br\/cultura","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","position":2,"name":"Cultura-MAT\u00c9RIA","item":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\/#listItem","name":"Chamada para ocupa\u00e7\u00e3o de teatros da Casa de Cultura M\u00e1rio Quintana"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\/#listItem","position":3,"name":"Chamada para ocupa\u00e7\u00e3o de teatros da Casa de Cultura M\u00e1rio Quintana","previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}}]},{"@type":"Organization","@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization","name":"Jornal J\u00c1 Editora","description":"Jornal J\u00c1 | Porto Alegre","url":"https:\/\/www.jornalja.com.br\/cultura\/","telephone":"+555133307272","logo":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/2020-logotipia-ja-35anos.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\/#organizationLogo","width":1067,"height":800},"image":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/jornaljapoa","https:\/\/www.youtube.com\/c\/JornalJ"]},{"@type":"Person","@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author","url":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/","name":"da Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.jornalja.com.br\/cultura\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\/#authorImage","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/litespeed\/avatar\/2\/d9cd863c234b5b6efee1c2d4e369043e.jpg?ver=1784090128","width":96,"height":96,"caption":"da Reda\u00e7\u00e3o"}},{"@type":"WebPage","@id":"https:\/\/www.jornalja.com.br\/cultura\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\/#webpage","url":"https:\/\/www.jornalja.com.br\/cultura\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\/","name":"Chamada para ocupa\u00e7\u00e3o de teatros da Casa de Cultura M\u00e1rio Quintana | Cultura","description":"A Casa de Cultura Mario Quintana (CCMQ) abriu em dezembro, dia 17, e encerra no pr\u00f3ximo dia 15 de janeiro, as inscri\u00e7\u00f5es da Chamada P\u00fablica para a ocupa\u00e7\u00e3o do Teatro Bruno Kiefer e da Sala Carlos Carvalho, para temporadas de espet\u00e1culos nas modalidades artes c\u00eanicas (circo, dan\u00e7a e teatro) e m\u00fasica; e temporada livre (circo, dan\u00e7a,","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#website"},"breadcrumb":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\/#breadcrumblist"},"author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"creator":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/01\/arte-teatro.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\/#mainImage","width":300,"height":143,"caption":"Espet\u00e1culo Infantil \u201cBandele\u201d foi uma das pe\u00e7as que ocupou o Teatro Bruno Kiefer no segundo semestre de 2019 \u2013 Foto: Andr\u00e9 Furtado\/ Divulga\u00e7\u00e3o"},"primaryImageOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\/#mainImage"},"datePublished":"2020-01-09T10:57:36-03:00","dateModified":"2020-01-09T10:57:36-03:00"},{"@type":"WebSite","@id":"https:\/\/www.jornalja.com.br\/cultura\/#website","url":"https:\/\/www.jornalja.com.br\/cultura\/","name":"Cultura","description":"Jornal J\u00c1 | Porto Alegre","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Cultura","og:type":"article","og:title":"Chamada para ocupa\u00e7\u00e3o de teatros da Casa de Cultura M\u00e1rio Quintana | Cultura","og:description":"A Casa de Cultura Mario Quintana (CCMQ) abriu em dezembro, dia 17, e encerra no pr\u00f3ximo dia 15 de janeiro, as inscri\u00e7\u00f5es da Chamada P\u00fablica para a ocupa\u00e7\u00e3o do Teatro Bruno Kiefer e da Sala Carlos Carvalho, para temporadas de espet\u00e1culos nas modalidades artes c\u00eanicas (circo, dan\u00e7a e teatro) e m\u00fasica; e temporada livre (circo, dan\u00e7a,","og:url":"https:\/\/www.jornalja.com.br\/cultura\/chamada-para-ocupacao-de-teatros-da-casa-de-cultura-mario-quintana\/","og:image":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/01\/arte-teatro.jpg","og:image:secure_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/01\/arte-teatro.jpg","og:image:width":300,"og:image:height":143,"article:published_time":"2020-01-09T13:57:36+00:00","article:modified_time":"2020-01-09T13:57:36+00:00","article:publisher":"https:\/\/www.facebook.com\/jornaljanaweb","twitter:card":"summary","twitter:site":"@jornal_ja","twitter:title":"Chamada para ocupa\u00e7\u00e3o de teatros da Casa de Cultura M\u00e1rio Quintana | Cultura","twitter:description":"A Casa de Cultura Mario Quintana (CCMQ) abriu em dezembro, dia 17, e encerra no pr\u00f3ximo dia 15 de janeiro, as inscri\u00e7\u00f5es da Chamada P\u00fablica para a ocupa\u00e7\u00e3o do Teatro Bruno Kiefer e da Sala Carlos Carvalho, para temporadas de espet\u00e1culos nas modalidades artes c\u00eanicas (circo, dan\u00e7a e teatro) e m\u00fasica; e temporada livre (circo, dan\u00e7a,","twitter:image":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/01\/arte-teatro.jpg"},"aioseo_meta_data":{"post_id":"80432","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-20 20:39:24","updated":"2025-06-04 11:49:23","seo_analyzer_scan_date":null},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/01\/arte-teatro.jpg","jetpack-related-posts":[{"id":84944,"url":"https:\/\/www.jornalja.com.br\/cultura\/pata-de-elefante-abre-o-projeto-jazz-no-jardim-na-ccmq\/","url_meta":{"origin":80432,"position":0},"title":"Pata de Elefante abre o projeto Jazz no Jardim na CCMQ","author":"Higino Barros","date":"14 de outubro de 2021","format":false,"excerpt":"O rock instrumental com pegadas de blues, fusion jazz e psicodelismo da Pata de Elefante \u00e9 a atra\u00e7\u00e3o de abertura do projeto Jazz no Jardim, que acontece \u00e0s 19h deste s\u00e1bado, 16 de outubro, no Jardim Lutzenberger, 5\u00ba andar da Casa de Cultura Mario Quintana (CCMQ \u2013 Andradas, 736 \u2013\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/10\/patadeelefante-credito-raul-krebs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/10\/patadeelefante-credito-raul-krebs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/10\/patadeelefante-credito-raul-krebs.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/10\/patadeelefante-credito-raul-krebs.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/10\/patadeelefante-credito-raul-krebs.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/10\/patadeelefante-credito-raul-krebs.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":92266,"url":"https:\/\/www.jornalja.com.br\/cultura\/teatro-bruno-kiefer-reabre-apos-reforma-de-r-36-milhoes\/","url_meta":{"origin":80432,"position":1},"title":"Teatro Bruno Kiefer reabre ap\u00f3s reforma de R$ 3,6 milh\u00f5es","author":"da Reda\u00e7\u00e3o","date":"28 de maio de 2026","format":false,"excerpt":"Inteiramente reformado, ao custo de R$ 3,6 milh\u00f5es, reabriu na quarta-feira (27\/5), o Teatro Bruno Kiefer, no 6\u00ba andar da Casa de Cultura Mario Quintana (CCMQ), em Porto Alegre. O governador Eduardo Leite, do secret\u00e1rio da Cultura, Andr\u00e9 Kryszczun, e da diretora da CCMQ, Adriana Sperandir participaram da reinaugura\u00e7\u00e3o. A\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/05\/teatro-bruno-kiefer-reformado-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/05\/teatro-bruno-kiefer-reformado-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/05\/teatro-bruno-kiefer-reformado-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/05\/teatro-bruno-kiefer-reformado-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/05\/teatro-bruno-kiefer-reformado-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2026\/05\/teatro-bruno-kiefer-reformado-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":73552,"url":"https:\/\/www.jornalja.com.br\/cultura\/sobre-nos-revisita-classicos-de-tchekhov-no-teatro-carlos-carvalho\/","url_meta":{"origin":80432,"position":2},"title":"&quot;Sobre N\u00f3s\u201d revisita cl\u00e1ssicos de Tchekhov , no Teatro Carlos Carvalho","author":"da Reda\u00e7\u00e3o","date":"28 de mar\u00e7o de 2019","format":false,"excerpt":"O espet\u00e1culo\u00a0\u201cSobre N\u00f3s\u201d,\u00a0que traz uma vers\u00e3o contempor\u00e2nea dos cl\u00e1ssicos do dramaturgo russo\u00a0Anton Tchekhov, estreia na pr\u00f3xima semana no teatro Carlos Carvalho da\u00a0Casa de Cultura Mario Quintana (CCMQ). De 5 a 28 de abril, toda sexta, s\u00e1bado e domingo \u00e0s 20h, o p\u00fablico poder\u00e1 assistir a pe\u00e7a que \u00e9 inspirada nas\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/wp-content\/uploads\/2019\/03\/cinema-sobre-2-450x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":81727,"url":"https:\/\/www.jornalja.com.br\/cultura\/espetaculos-de-danca-e-circo-na-travessa-dos-cataventos-da-ccmq\/","url_meta":{"origin":80432,"position":3},"title":"Espet\u00e1culos de dan\u00e7a e circo na Travessa dos Cataventos da CCMQ","author":"da Reda\u00e7\u00e3o","date":"11 de mar\u00e7o de 2020","format":false,"excerpt":"\u00a0 A Travessa dos Cataventos, no cora\u00e7\u00e3o da Casa de Cultura Mario Quintana (CCMQ), recebe quatro espet\u00e1culos, entre os dias 17 e 27 de mar\u00e7o. Os eventos fazem parte dos projetos \u201cCirquintana\u201d e \u201cA Casa Dan\u00e7a\u201d, que integram o Plano Anual de Atividades da CCMQ. A programa\u00e7\u00e3o tem entrada gratuita\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/03\/arte-CCMQ_Capa_MAR20_sobretudo.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/03\/arte-CCMQ_Capa_MAR20_sobretudo.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/03\/arte-CCMQ_Capa_MAR20_sobretudo.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/03\/arte-CCMQ_Capa_MAR20_sobretudo.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":85496,"url":"https:\/\/www.jornalja.com.br\/cultura\/inscricoes-gratuitas-para-oficinas-de-teatro-musica-danca-e-artes-visuais-na-ccmq\/","url_meta":{"origin":80432,"position":4},"title":"Inscri\u00e7\u00f5es gratuitas para oficinas de teatro, m\u00fasica, dan\u00e7a e artes visuais, na CCMQ","author":"da Reda\u00e7\u00e3o","date":"21 de fevereiro de 2022","format":false,"excerpt":"O N\u00facleo Educativo da Casa de Cultura Mario Quintana (CCMQ), institui\u00e7\u00e3o da Secretaria de Estado da Cultura (Sedac), promove novas oficinas de teatro, m\u00fasica, dan\u00e7a e artes visuais, a partir de mar\u00e7o. As inscri\u00e7\u00f5es devem ser feitas mediante preenchimento de formul\u00e1rio online, nos links a seguir, espec\u00edficos para cada oficina.\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/02\/casa-oficina-pandeiro-popular5-foto-divulgacao-ccpa.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/02\/casa-oficina-pandeiro-popular5-foto-divulgacao-ccpa.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/02\/casa-oficina-pandeiro-popular5-foto-divulgacao-ccpa.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/02\/casa-oficina-pandeiro-popular5-foto-divulgacao-ccpa.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/02\/casa-oficina-pandeiro-popular5-foto-divulgacao-ccpa.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":85176,"url":"https:\/\/www.jornalja.com.br\/cultura\/espetaculo-infantil-marca-a-retomada-dos-teatros-da-casa-de-cultura-mario-quintana\/","url_meta":{"origin":80432,"position":5},"title":"Espet\u00e1culo infantil marca a retomada dos teatros da Casa de Cultura Mario Quintana","author":"da Reda\u00e7\u00e3o","date":"8 de novembro de 2021","format":false,"excerpt":"Os teatros da Casa de Cultura Mario Quintana (CCMQ), institui\u00e7\u00e3o da Secretaria de Estado da Cultura (Sedac), est\u00e3o retomando a agenda interrompida desde o in\u00edcio da pandemia. O Teatro Bruno Kiefer, no 6\u00ba andar, reabre para o p\u00fablico com o espet\u00e1culo infantil Peteca, Pi\u00e3o e Pique Pessoa. As sess\u00f5es acontecem\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/11\/teatro-foto5-andrea-seligman.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/11\/teatro-foto5-andrea-seligman.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/11\/teatro-foto5-andrea-seligman.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/11\/teatro-foto5-andrea-seligman.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/11\/teatro-foto5-andrea-seligman.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKnZc-kVi","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/80432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/comments?post=80432"}],"version-history":[{"count":0,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/80432\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media\/80433"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media?parent=80432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/categories?post=80432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/tags?post=80432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}