{"id":81901,"date":"2020-04-22T19:03:43","date_gmt":"2020-04-22T22:03:43","guid":{"rendered":"https:\/\/www.jornalja.com.br\/cultura\/?p=81901"},"modified":"2020-04-22T19:03:43","modified_gmt":"2020-04-22T22:03:43","slug":"o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/cultura\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\/","title":{"rendered":"O som do Bluegrass Porto-Alegrense no Mistura Fina virtual"},"content":{"rendered":"<p align=\"justify\"><span style=\"font-size: medium\"><span style=\"font-family: Arial, Helvetica, sans-serif\">As\u00a0apresenta\u00e7\u00f5es virtuais\u00a0do projeto\u00a0Mistura Fina &#8211; M\u00fasica para Fugir do Tr\u00e2nsito,\u00a0prosseguem nessa quinta-feira, dia 23 de abril,\u00a0tendo como atra\u00e7\u00e3o o\u00a0Conjunto Bluegrass Porto-Alegrense.\u00a0A transmiss\u00e3o \u00e9 feita pelas redes sociais do Mistura Fina, pelo link:\u00a0<a href=\"http:\/\/www.facebook.com\/misturafinamusica\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"http:\/\/www.google.com\/url?q=http:\/\/www.facebook.com\/misturafinamusica\/&amp;source=gmail&amp;ust=1587665952271000&amp;usg=AFQjCNFY7nutxBeJGHI7JdrLBEhOntPilg\">www.facebook.com\/misturafinamusica\/<\/a>, a partir das 18h30min. <\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: medium\"><span style=\"font-family: Arial, Helvetica, sans-serif\">Suspensas desde o dia 19 de mar\u00e7o, em acordo com as medidas tempor\u00e1rias de preven\u00e7\u00e3o ao cont\u00e1gio pela COVID-19 (novo Coronav\u00edrus), a programa\u00e7\u00e3o foi retomada no \u00faltimo dia 16, a fim de garantir a continuidade do projeto e o trabalho dos artistas participantes, bem como minimizar os efeitos do isolamento provocado pela crise sanit\u00e1ria no Brasil. A iniciativa leva a assinatura da\u00a0Funda\u00e7\u00e3o Theatro S\u00e3o Pedro, por meio da Associa\u00e7\u00e3o dos Amigos do Theatro S\u00e3o Pedro, produ\u00e7\u00e3o da Primeira Fila Produ\u00e7\u00f5es, financiamento do Pr\u00f3-Cultura RS e patroc\u00ednio da Companhia de G\u00e1s do Estado do Rio Grande do Sul &#8211; SULG\u00c1S.<\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: medium\"><span style=\"font-family: Arial, Helvetica, sans-serif\">A programa\u00e7\u00e3o do Mistura Fina &#8211; M\u00fasica para Fugir do Tr\u00e2nsito encontrava-se em plena execu\u00e7\u00e3o, desde agosto de 2019, cumprindo-se as 40 sess\u00f5es previstas, com apresenta\u00e7\u00f5es no Foyer Nobre do Theatro S\u00e3o Pedro, com muito sucesso. O recome\u00e7o das sess\u00f5es foi no dia 05 de mar\u00e7o, quando da reabertura do TSP. Neste mesmo m\u00eas, ocorreram os dois primeiros shows, restando ainda 20 a serem realizados. Entretanto, com o agravamento da situa\u00e7\u00e3o de controle da prolifera\u00e7\u00e3o do Covid-19, todas as atividades do Theatro S\u00e3o Pedro foram suspensas, ainda por tempo indeterminado, aguardando-se a evolu\u00e7\u00e3o da crise sanit\u00e1ria e seus desdobramentos.<\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: medium\"><span style=\"font-family: Arial, Helvetica, sans-serif\">Mais informa\u00e7\u00f5es:<\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: medium\"><span style=\"font-family: Arial, Helvetica, sans-serif\"><a href=\"http:\/\/www.teatrosaopedro.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"http:\/\/www.google.com\/url?q=http:\/\/www.teatrosaopedro.com.br\/&amp;source=gmail&amp;ust=1587665952271000&amp;usg=AFQjCNGOdGZqVhaBjtUsDV-JtGbgahJZwg\">http:\/\/www.teatrosaopedro.com.br\/<\/a><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: medium\"><span style=\"font-family: Arial, Helvetica, sans-serif\">(<a href=\"http:\/\/www.facebook.com\/misturafinamusica\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"http:\/\/www.google.com\/url?q=http:\/\/www.facebook.com\/misturafinamusica&amp;source=gmail&amp;ust=1587665952271000&amp;usg=AFQjCNGzo7WBAcUhJE-hhFDxl1CLQNx6dw\">http:\/\/www.facebook.com\/misturafinamusica<\/a>)<\/span><\/span><\/p>\n<p align=\"justify\">\n<p align=\"justify\"><span style=\"font-size: medium\"><span style=\"font-family: Arial, Helvetica, sans-serif\"><b>Mais sobre o Bluegrass:<\/b><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: medium\"><span style=\"font-family: Arial, Helvetica, sans-serif\">Influenciados pelo\u00a0<i>bluegrass music<\/i>, g\u00eanero musical oriundo dos Estados Unidos que utiliza somente instrumentos ac\u00fasticos, o\u00a0Conjunto Bluegrass Porto-Alegrensetem, em sua forma\u00e7\u00e3o, os m\u00fasicos Marcio Petracco (mandolin\/bandolim), Heine Wentz (fiddle\/violino), Ricardo Sabadini (guitar\/viol\u00e3o) e Jos\u00e9 Baronio (bass\/baixo).<\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: medium\"><span style=\"font-family: Arial, Helvetica, sans-serif\">Bluegrass \u00e9 o apelido do estado do Kentucky, &#8220;The Bluegrass State&#8221;, e \u00e9 de l\u00e1 que veio o grupo que deu nome ao estilo, &#8220;Bill Monroe and His Blue Grass Boys&#8221;. Bill Monroe \u00e9 considerado o pai da m\u00fasica bluegrass. &#8220;Nosso repert\u00f3rio \u00e9 exclusivamente de m\u00fasicas desse g\u00eanero. As ra\u00edzes dessa m\u00fasica remontam aos imigrantes irlandeses, escoceses e ingleses, fugidos da fome que passaram na Europa em meados do s\u00e9culo XVIII. Eles colonizaram a regi\u00e3o dos montes Apalaches, e junto com eles trouxeram sua cultura musical. O bluegrass tamb\u00e9m teve influ\u00eancia dos afro-americanos, que foram os respons\u00e1veis pela introdu\u00e7\u00e3o do banjo nos Estados Unidos&#8221;, conta Sabadini.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As\u00a0apresenta\u00e7\u00f5es virtuais\u00a0do projeto\u00a0Mistura Fina &#8211; M\u00fasica para Fugir do Tr\u00e2nsito,\u00a0prosseguem nessa quinta-feira, dia 23 de abril,\u00a0tendo como atra\u00e7\u00e3o o\u00a0Conjunto Bluegrass Porto-Alegrense.\u00a0A transmiss\u00e3o \u00e9 feita pelas redes sociais do Mistura Fina, pelo link:\u00a0www.facebook.com\/misturafinamusica\/, a partir das 18h30min. Suspensas desde o dia 19 de mar\u00e7o, em acordo com as medidas tempor\u00e1rias de preven\u00e7\u00e3o ao cont\u00e1gio pela COVID-19 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":81902,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-81901","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-materiasecundaria"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"As apresenta\u00e7\u00f5es virtuais do projeto Mistura Fina - M\u00fasica para Fugir do Tr\u00e2nsito, prosseguem nessa quinta-feira, dia 23 de abril, tendo como atra\u00e7\u00e3o o Conjunto Bluegrass Porto-Alegrense. A transmiss\u00e3o \u00e9 feita pelas redes sociais do Mistura Fina, pelo link: www.facebook.com\/misturafinamusica\/, a partir das 18h30min. Suspensas desde o dia 19 de mar\u00e7o, em acordo com as medidas tempor\u00e1rias de preven\u00e7\u00e3o ao cont\u00e1gio pela COVID-19\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"da Reda\u00e7\u00e3o\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.jornalja.com.br\/cultura\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cultura\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"O som do Bluegrass Porto-Alegrense no Mistura Fina virtual | Cultura\" \/>\n\t\t<meta property=\"og:description\" content=\"As apresenta\u00e7\u00f5es virtuais do projeto Mistura Fina - M\u00fasica para Fugir do Tr\u00e2nsito, prosseguem nessa quinta-feira, dia 23 de abril, tendo como atra\u00e7\u00e3o o Conjunto Bluegrass Porto-Alegrense. A transmiss\u00e3o \u00e9 feita pelas redes sociais do Mistura Fina, pelo link: www.facebook.com\/misturafinamusica\/, a partir das 18h30min. Suspensas desde o dia 19 de mar\u00e7o, em acordo com as medidas tempor\u00e1rias de preven\u00e7\u00e3o ao cont\u00e1gio pela COVID-19\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-04-22T22:03:43+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-04-22T22:03:43+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaljanaweb\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@jornal_ja\" \/>\n\t\t<meta name=\"twitter:title\" content=\"O som do Bluegrass Porto-Alegrense no Mistura Fina virtual | Cultura\" \/>\n\t\t<meta name=\"twitter:description\" content=\"As apresenta\u00e7\u00f5es virtuais do projeto Mistura Fina - M\u00fasica para Fugir do Tr\u00e2nsito, prosseguem nessa quinta-feira, dia 23 de abril, tendo como atra\u00e7\u00e3o o Conjunto Bluegrass Porto-Alegrense. A transmiss\u00e3o \u00e9 feita pelas redes sociais do Mistura Fina, pelo link: www.facebook.com\/misturafinamusica\/, a partir das 18h30min. Suspensas desde o dia 19 de mar\u00e7o, em acordo com as medidas tempor\u00e1rias de preven\u00e7\u00e3o ao cont\u00e1gio pela COVID-19\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\\\/#article\",\"name\":\"O som do Bluegrass Porto-Alegrense no Mistura Fina virtual | Cultura\",\"headline\":\"O som do Bluegrass Porto-Alegrense no Mistura Fina virtual\",\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/04\\\/arte-blue-grass.jpg\",\"width\":694,\"height\":463,\"caption\":\"Conjunto Bluegrass: virtual e usando somente instrumentos ac\\u00fasticos. Foto: Anderson Dorneles\\\/Divulga\\u00e7\\u00e3o\"},\"datePublished\":\"2020-04-22T19:03:43-03:00\",\"dateModified\":\"2020-04-22T19:03:43-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\\\/#webpage\"},\"articleSection\":\"Cultura-MAT\\u00c9RIA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"position\":2,\"name\":\"Cultura-MAT\\u00c9RIA\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\\\/#listItem\",\"name\":\"O som do Bluegrass Porto-Alegrense no Mistura Fina virtual\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\\\/#listItem\",\"position\":3,\"name\":\"O som do Bluegrass Porto-Alegrense no Mistura Fina virtual\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\",\"name\":\"Jornal J\\u00c1 Editora\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"telephone\":\"+555133307272\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/2020-logotipia-ja-35anos.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\\\/#organizationLogo\",\"width\":1067,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/jornaljapoa\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JornalJ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/\",\"name\":\"da Reda\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"da Reda\\u00e7\\u00e3o\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\\\/#webpage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\\\/\",\"name\":\"O som do Bluegrass Porto-Alegrense no Mistura Fina virtual | Cultura\",\"description\":\"As apresenta\\u00e7\\u00f5es virtuais do projeto Mistura Fina - M\\u00fasica para Fugir do Tr\\u00e2nsito, prosseguem nessa quinta-feira, dia 23 de abril, tendo como atra\\u00e7\\u00e3o o Conjunto Bluegrass Porto-Alegrense. A transmiss\\u00e3o \\u00e9 feita pelas redes sociais do Mistura Fina, pelo link: www.facebook.com\\\/misturafinamusica\\\/, a partir das 18h30min. Suspensas desde o dia 19 de mar\\u00e7o, em acordo com as medidas tempor\\u00e1rias de preven\\u00e7\\u00e3o ao cont\\u00e1gio pela COVID-19\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/04\\\/arte-blue-grass.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\\\/#mainImage\",\"width\":694,\"height\":463,\"caption\":\"Conjunto Bluegrass: virtual e usando somente instrumentos ac\\u00fasticos. Foto: Anderson Dorneles\\\/Divulga\\u00e7\\u00e3o\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\\\/#mainImage\"},\"datePublished\":\"2020-04-22T19:03:43-03:00\",\"dateModified\":\"2020-04-22T19:03:43-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"name\":\"Cultura\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"O som do Bluegrass Porto-Alegrense no Mistura Fina virtual | Cultura","description":"As apresenta\u00e7\u00f5es virtuais do projeto Mistura Fina - M\u00fasica para Fugir do Tr\u00e2nsito, prosseguem nessa quinta-feira, dia 23 de abril, tendo como atra\u00e7\u00e3o o Conjunto Bluegrass Porto-Alegrense. A transmiss\u00e3o \u00e9 feita pelas redes sociais do Mistura Fina, pelo link: www.facebook.com\/misturafinamusica\/, a partir das 18h30min. Suspensas desde o dia 19 de mar\u00e7o, em acordo com as medidas tempor\u00e1rias de preven\u00e7\u00e3o ao cont\u00e1gio pela COVID-19","canonical_url":"https:\/\/www.jornalja.com.br\/cultura\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornalja.com.br\/cultura\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\/#article","name":"O som do Bluegrass Porto-Alegrense no Mistura Fina virtual | Cultura","headline":"O som do Bluegrass Porto-Alegrense no Mistura Fina virtual","author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/04\/arte-blue-grass.jpg","width":694,"height":463,"caption":"Conjunto Bluegrass: virtual e usando somente instrumentos ac\u00fasticos. Foto: Anderson Dorneles\/Divulga\u00e7\u00e3o"},"datePublished":"2020-04-22T19:03:43-03:00","dateModified":"2020-04-22T19:03:43-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\/#webpage"},"isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\/#webpage"},"articleSection":"Cultura-MAT\u00c9RIA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornalja.com.br\/cultura\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","position":1,"name":"Home","item":"https:\/\/www.jornalja.com.br\/cultura","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","position":2,"name":"Cultura-MAT\u00c9RIA","item":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\/#listItem","name":"O som do Bluegrass Porto-Alegrense no Mistura Fina virtual"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\/#listItem","position":3,"name":"O som do Bluegrass Porto-Alegrense no Mistura Fina virtual","previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}}]},{"@type":"Organization","@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization","name":"Jornal J\u00c1 Editora","description":"Jornal J\u00c1 | Porto Alegre","url":"https:\/\/www.jornalja.com.br\/cultura\/","telephone":"+555133307272","logo":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/2020-logotipia-ja-35anos.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\/#organizationLogo","width":1067,"height":800},"image":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/jornaljapoa","https:\/\/www.youtube.com\/c\/JornalJ"]},{"@type":"Person","@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author","url":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/","name":"da Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.jornalja.com.br\/cultura\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g","width":96,"height":96,"caption":"da Reda\u00e7\u00e3o"}},{"@type":"WebPage","@id":"https:\/\/www.jornalja.com.br\/cultura\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\/#webpage","url":"https:\/\/www.jornalja.com.br\/cultura\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\/","name":"O som do Bluegrass Porto-Alegrense no Mistura Fina virtual | Cultura","description":"As apresenta\u00e7\u00f5es virtuais do projeto Mistura Fina - M\u00fasica para Fugir do Tr\u00e2nsito, prosseguem nessa quinta-feira, dia 23 de abril, tendo como atra\u00e7\u00e3o o Conjunto Bluegrass Porto-Alegrense. A transmiss\u00e3o \u00e9 feita pelas redes sociais do Mistura Fina, pelo link: www.facebook.com\/misturafinamusica\/, a partir das 18h30min. Suspensas desde o dia 19 de mar\u00e7o, em acordo com as medidas tempor\u00e1rias de preven\u00e7\u00e3o ao cont\u00e1gio pela COVID-19","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#website"},"breadcrumb":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\/#breadcrumblist"},"author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"creator":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/04\/arte-blue-grass.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\/#mainImage","width":694,"height":463,"caption":"Conjunto Bluegrass: virtual e usando somente instrumentos ac\u00fasticos. Foto: Anderson Dorneles\/Divulga\u00e7\u00e3o"},"primaryImageOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\/#mainImage"},"datePublished":"2020-04-22T19:03:43-03:00","dateModified":"2020-04-22T19:03:43-03:00"},{"@type":"WebSite","@id":"https:\/\/www.jornalja.com.br\/cultura\/#website","url":"https:\/\/www.jornalja.com.br\/cultura\/","name":"Cultura","description":"Jornal J\u00c1 | Porto Alegre","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Cultura","og:type":"article","og:title":"O som do Bluegrass Porto-Alegrense no Mistura Fina virtual | Cultura","og:description":"As apresenta\u00e7\u00f5es virtuais do projeto Mistura Fina - M\u00fasica para Fugir do Tr\u00e2nsito, prosseguem nessa quinta-feira, dia 23 de abril, tendo como atra\u00e7\u00e3o o Conjunto Bluegrass Porto-Alegrense. A transmiss\u00e3o \u00e9 feita pelas redes sociais do Mistura Fina, pelo link: www.facebook.com\/misturafinamusica\/, a partir das 18h30min. Suspensas desde o dia 19 de mar\u00e7o, em acordo com as medidas tempor\u00e1rias de preven\u00e7\u00e3o ao cont\u00e1gio pela COVID-19","og:url":"https:\/\/www.jornalja.com.br\/cultura\/o-som-do-bluegrass-porto-alegrense-no-mistura-fina-virtual\/","og:image":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg","og:image:secure_url":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg","article:published_time":"2020-04-22T22:03:43+00:00","article:modified_time":"2020-04-22T22:03:43+00:00","article:publisher":"https:\/\/www.facebook.com\/jornaljanaweb","twitter:card":"summary","twitter:site":"@jornal_ja","twitter:title":"O som do Bluegrass Porto-Alegrense no Mistura Fina virtual | Cultura","twitter:description":"As apresenta\u00e7\u00f5es virtuais do projeto Mistura Fina - M\u00fasica para Fugir do Tr\u00e2nsito, prosseguem nessa quinta-feira, dia 23 de abril, tendo como atra\u00e7\u00e3o o Conjunto Bluegrass Porto-Alegrense. A transmiss\u00e3o \u00e9 feita pelas redes sociais do Mistura Fina, pelo link: www.facebook.com\/misturafinamusica\/, a partir das 18h30min. Suspensas desde o dia 19 de mar\u00e7o, em acordo com as medidas tempor\u00e1rias de preven\u00e7\u00e3o ao cont\u00e1gio pela COVID-19","twitter:image":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg"},"aioseo_meta_data":{"post_id":"81901","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-20 20:33:32","updated":"2025-06-04 12:01:23","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":91081,"url":"https:\/\/www.jornalja.com.br\/cultura\/voz-violao-e-poesia-ian-ramil-e-atracao-no-mistura-fina-em-porto-alegre\/","url_meta":{"origin":81901,"position":0},"title":"Voz, viol\u00e3o e poesia: Ian Ramil \u00e9 atra\u00e7\u00e3o no Mistura Fina em Porto Alegre","author":"Higino Barros","date":"20 de junho de 2025","format":false,"excerpt":"Show em formato voz e viol\u00e3o percorre diferentes fases da carreira do artista, com composi\u00e7\u00f5es autorais e releituras afetivas O cantor e compositor\u00a0Ian Ramil\u00a0apresenta, no dia\u00a026 de junho, \u00e0s\u00a019h, um show em formato voz e viol\u00e3o no\u00a0Teatro Oficina Olga Reverbel \u2013 Multipalco Eva Sopher. A apresenta\u00e7\u00e3o integra a programa\u00e7\u00e3o da\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/06\/ramil.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/06\/ramil.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/06\/ramil.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2025\/06\/ramil.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":81997,"url":"https:\/\/www.jornalja.com.br\/cultura\/o-novo-trabalho-de-adriana-deffenti-em-controversa4-no-mistura-fina-virtual\/","url_meta":{"origin":81901,"position":1},"title":"O novo trabalho de Adriana Deffenti em &#8220;Controversa4&#8221;, no Mistura Fina virtual","author":"da Reda\u00e7\u00e3o","date":"18 de maio de 2020","format":false,"excerpt":"A apresenta\u00e7\u00e3o em ambiente virtual de\u00a0Adriana Deffenti\u00a0d\u00e1 continuidade \u00e0 programa\u00e7\u00e3o do projeto\u00a0Mistura\u00a0Fina\u00a0- M\u00fasica para Fugir do Tr\u00e2nsito, nesta\u00a0quinta-feira,\u00a021 de maio. A transmiss\u00e3o \u00e9 feita pelas redes sociais do Mistura Fina, pelo link:\u00a0www.facebook.com\/misturafinamusica\/, a partir das\u00a018h30min.\u00a0Para este projeto, a cantora e compositora apresenta \"Controversa4\",\u00a0t\u00edtulo do seu novo \u00e1lbum e show. A\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/05\/adriana-defenti.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/05\/adriana-defenti.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/05\/adriana-defenti.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":82035,"url":"https:\/\/www.jornalja.com.br\/cultura\/a-vez-de-chanson-blues-com-luana-pacheco-e-luciano-leaes-no-mistura-fina-virtual\/","url_meta":{"origin":81901,"position":2},"title":"A vez de  &#8220;Chanson &amp; Blues&#8221;, com\u00a0Luana Pacheco e Luciano Le\u00e3es, no Mistura Fina virtual","author":"da Reda\u00e7\u00e3o","date":"25 de maio de 2020","format":false,"excerpt":"O show \"Chanson & Blues\", com\u00a0Luana Pacheco e Luciano Le\u00e3es, d\u00e1 continuidade \u00e0 s\u00e9rie de\u00a0show virtuais\u00a0que integram a programa\u00e7\u00e3o do projeto\u00a0Mistura\u00a0Fina\u00a0- M\u00fasica para Fugir do Tr\u00e2nsito, no pr\u00f3ximo dia\u00a028 de maio,\u00a0quinta-feira. A transmiss\u00e3o \u00e9 feita pelas redes sociais do Mistura Fina, pelo link:\u00a0www.facebook.com\/misturafinamusica\/, a partir das\u00a018h30min. O casal prop\u00f5e uma\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/05\/arte-luciano.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/05\/arte-luciano.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/05\/arte-luciano.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":81858,"url":"https:\/\/www.jornalja.com.br\/cultura\/projeto-mistura-fina-do-tsp-abre-serie-de-shows-virtuais-com-simone-rasslan\/","url_meta":{"origin":81901,"position":3},"title":"Projeto Mistura Fina, do TSP, abre s\u00e9rie de shows virtuais com Simone Rasslan","author":"da Reda\u00e7\u00e3o","date":"13 de abril de 2020","format":false,"excerpt":"Suspensas desde o dia 19 de mar\u00e7o, em acordo com as medidas tempor\u00e1rias de preven\u00e7\u00e3o ao cont\u00e1gio pela COVID-19 (novo Coronav\u00edrus), as apresenta\u00e7\u00f5es do projeto\u00a0Mistura Fina - M\u00fasica para Fugir do Tr\u00e2nsito\u00a0ter\u00e3o continuidade no m\u00eas de abril, de\u00a0forma virtual, com transmiss\u00e3o pelas redes sociais do projeto Mistura Fina pelo link\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/04\/arte-Simone-Rasslan-abre-a-s%C3%A9rie-de-shows-virtuais-com-repert%C3%B3rio-autoral.-Foto-Vanessa-Schwartzhaupt.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/04\/arte-Simone-Rasslan-abre-a-s%C3%A9rie-de-shows-virtuais-com-repert%C3%B3rio-autoral.-Foto-Vanessa-Schwartzhaupt.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/04\/arte-Simone-Rasslan-abre-a-s%C3%A9rie-de-shows-virtuais-com-repert%C3%B3rio-autoral.-Foto-Vanessa-Schwartzhaupt.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":81909,"url":"https:\/\/www.jornalja.com.br\/cultura\/pedrinho-figueiredo-e-handyer-borba-duas-geracoes-de-instrumentistas-se-encontram-no-mistura-fina-virtual\/","url_meta":{"origin":81901,"position":4},"title":"Pedrinho Figueiredo e Handyer Borba, duas gera\u00e7\u00f5es de instrumentistas, se encontram no Mistura Fina virtual","author":"da Reda\u00e7\u00e3o","date":"26 de abril de 2020","format":false,"excerpt":"Duas gera\u00e7\u00f5es de instrumentistas se encontram em ambiente virtual para dar continuidade \u00e0 programa\u00e7\u00e3o do projeto\u00a0Mistura\u00a0Fina\u00a0- M\u00fasica para Fugir do Tr\u00e2nsito. O show virtual de\u00a0Pedrinho Figueiredo\u00a0e\u00a0Handyer Borba\u00a0vai ao ar no pr\u00f3ximo dia\u00a030 de abril,\u00a0quinta-feira. A transmiss\u00e3o \u00e9 feita pelas redes sociais do Mistura Fina, pelo link:\u00a0www.facebook.com\/misturafinamusica\/, a partir das\u00a018h30min. A\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/04\/arte-Handyer-Borba-e-Pedrinho-Figueiredo-encontro-de-talentos-e-gera%C3%A7%C3%B5es.-Foto-Carol-Rossi.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/04\/arte-Handyer-Borba-e-Pedrinho-Figueiredo-encontro-de-talentos-e-gera%C3%A7%C3%B5es.-Foto-Carol-Rossi.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/04\/arte-Handyer-Borba-e-Pedrinho-Figueiredo-encontro-de-talentos-e-gera%C3%A7%C3%B5es.-Foto-Carol-Rossi.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":82053,"url":"https:\/\/www.jornalja.com.br\/cultura\/novas-cancoes-de-pablo-vanzoni-no-mistura-fina-virtual\/","url_meta":{"origin":81901,"position":5},"title":"Novas can\u00e7\u00f5es de Pablo Vanzoni, no Mistura Fina virtual","author":"da Reda\u00e7\u00e3o","date":"1 de junho de 2020","format":false,"excerpt":"\u00a0 A apresenta\u00e7\u00e3o em ambiente virtual de\u00a0Pablo Lanzoni\u00a0d\u00e1 continuidade \u00e0 programa\u00e7\u00e3o do projeto\u00a0Mistura\u00a0Fina\u00a0- M\u00fasica para Fugir do Tr\u00e2nsito, no pr\u00f3ximo dia\u00a004 de junho,\u00a0quinta-feira. A transmiss\u00e3o \u00e9 feita pelas redes sociais do Mistura Fina, pelo link:\u00a0www.facebook.com\/misturafinamusica\/, a partir das\u00a018h30min. Para este projeto, o cantor e compositor apresenta um repert\u00f3rio que mescla\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/06\/arte-pablo-vanzoni.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/06\/arte-pablo-vanzoni.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/06\/arte-pablo-vanzoni.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKnZc-liZ","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/04\/arte-blue-grass.jpg","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/81901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/comments?post=81901"}],"version-history":[{"count":1,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/81901\/revisions"}],"predecessor-version":[{"id":81903,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/81901\/revisions\/81903"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media\/81902"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media?parent=81901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/categories?post=81901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/tags?post=81901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}