{"id":82106,"date":"2020-06-10T11:35:18","date_gmt":"2020-06-10T14:35:18","guid":{"rendered":"https:\/\/www.jornalja.com.br\/cultura\/?p=82106"},"modified":"2020-06-10T11:38:28","modified_gmt":"2020-06-10T14:38:28","slug":"festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro","status":"publish","type":"post","link":"https:\/\/www.jornalja.com.br\/cultura\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\/","title":{"rendered":"Festival de Cinema de Gramado \u00e9 transferido para metade de setembro"},"content":{"rendered":"<p>A organiza\u00e7\u00e3o do\u00a0\u00a0Festival de Cinema de Gramado\u00a0comunica a transfer\u00eancia do evento, inicialmente programado para agosto, para o per\u00edodo de\u00a018 a 26 setembro.\u00a0 A nova data foi fixada a partir da an\u00e1lise do cen\u00e1rio nacional em fun\u00e7\u00e3o da pandemia.<\/p>\n<p>Dia a dia, a organiza\u00e7\u00e3o e as equipes de conte\u00fado e produ\u00e7\u00e3o observam e avaliam as altera\u00e7\u00f5es no cen\u00e1rio enquanto constroem a edi\u00e7\u00e3o 2020.<\/p>\n<p>\u201cO Festival de Gramado re\u00fane, aproxima equipes de produ\u00e7\u00e3o, elencos, diretores e realizadores. S\u00e3o nove dias de celebra\u00e7\u00e3o ao cinema, de reconhecimento \u00e0s produ\u00e7\u00f5es concorrentes, mas tamb\u00e9m de fomento e incentivo \u00e0s novas produ\u00e7\u00f5es. Os festivais mant\u00eam o cinema vivo e Gramado tem muita honra de contribuir com o fortalecimento da ind\u00fastria do audiovisual. Esse \u00e9 o nosso compromisso e ser\u00e1 mantido ainda que n\u00e3o sejam descartadas altera\u00e7\u00f5es ou adequa\u00e7\u00f5es no formato\u201d, avalia Diego Scariot, gerente de projetos da Gramadotur.<\/p>\n<p>No atual cronograma, a sele\u00e7\u00e3o dos filmes para as mostras competitivas \u2013 curtas ga\u00fachos e nacionais, longas brasileiros e estrangeiros \u2013 deve estar conclu\u00edda at\u00e9 final de julho.<\/p>\n<p>Segundo informa\u00e7\u00f5es de 2019, no Brasil, a ind\u00fastria do audiovisual emprega cerca de 300 mil pessoas. Dados da Ag\u00eancia Nacional do Cinema (Ancine) apontam que o pa\u00eds conta com 12,7 mil empresas de todos os elos da cadeia. A arrecada\u00e7\u00e3o anual do setor em impostos diretos e indiretos chega a R$ 3,4 bilh\u00f5es. \u201cA produ\u00e7\u00e3o audiovisual tem uma import\u00e2ncia social, cultural e econ\u00f4mica inestim\u00e1vel\u201d, conclui Diego.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A organiza\u00e7\u00e3o do\u00a0\u00a0Festival de Cinema de Gramado\u00a0comunica a transfer\u00eancia do evento, inicialmente programado para agosto, para o per\u00edodo de\u00a018 a 26 setembro.\u00a0 A nova data foi fixada a partir da an\u00e1lise do cen\u00e1rio nacional em fun\u00e7\u00e3o da pandemia. Dia a dia, a organiza\u00e7\u00e3o e as equipes de conte\u00fado e produ\u00e7\u00e3o observam e avaliam as altera\u00e7\u00f5es [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":82107,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-82106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-materiasecundaria"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"A organiza\u00e7\u00e3o do Festival de Cinema de Gramado comunica a transfer\u00eancia do evento, inicialmente programado para agosto, para o per\u00edodo de 18 a 26 setembro. A nova data foi fixada a partir da an\u00e1lise do cen\u00e1rio nacional em fun\u00e7\u00e3o da pandemia. Dia a dia, a organiza\u00e7\u00e3o e as equipes de conte\u00fado e produ\u00e7\u00e3o observam e avaliam as altera\u00e7\u00f5es\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"da Reda\u00e7\u00e3o\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.jornalja.com.br\/cultura\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cultura\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Festival de Cinema de Gramado \u00e9 transferido para metade de setembro | Cultura\" \/>\n\t\t<meta property=\"og:description\" content=\"A organiza\u00e7\u00e3o do Festival de Cinema de Gramado comunica a transfer\u00eancia do evento, inicialmente programado para agosto, para o per\u00edodo de 18 a 26 setembro. A nova data foi fixada a partir da an\u00e1lise do cen\u00e1rio nacional em fun\u00e7\u00e3o da pandemia. Dia a dia, a organiza\u00e7\u00e3o e as equipes de conte\u00fado e produ\u00e7\u00e3o observam e avaliam as altera\u00e7\u00f5es\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.jornalja.com.br\/cultura\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-06-10T14:35:18+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-06-10T14:38:28+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaljanaweb\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@jornal_ja\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Festival de Cinema de Gramado \u00e9 transferido para metade de setembro | Cultura\" \/>\n\t\t<meta name=\"twitter:description\" content=\"A organiza\u00e7\u00e3o do Festival de Cinema de Gramado comunica a transfer\u00eancia do evento, inicialmente programado para agosto, para o per\u00edodo de 18 a 26 setembro. A nova data foi fixada a partir da an\u00e1lise do cen\u00e1rio nacional em fun\u00e7\u00e3o da pandemia. Dia a dia, a organiza\u00e7\u00e3o e as equipes de conte\u00fado e produ\u00e7\u00e3o observam e avaliam as altera\u00e7\u00f5es\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\\\/#article\",\"name\":\"Festival de Cinema de Gramado \\u00e9 transferido para metade de setembro | Cultura\",\"headline\":\"Festival de Cinema de Gramado \\u00e9 transferido para metade de setembro\",\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/Foto-Cleiton-Thiele_Pressphoto-scaled.jpg\",\"width\":1024,\"height\":683,\"caption\":\"Gramado - RS 12\\\/08\\\/2019 - 47\\u00ba Festival de Cinema de Gramado - Preparativos - Foto: Cleiton Thiele \\\/ Pressphoto\"},\"datePublished\":\"2020-06-10T11:35:18-03:00\",\"dateModified\":\"2020-06-10T11:38:28-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\\\/#webpage\"},\"articleSection\":\"Cultura-MAT\\u00c9RIA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"position\":2,\"name\":\"Cultura-MAT\\u00c9RIA\",\"item\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\\\/#listItem\",\"name\":\"Festival de Cinema de Gramado \\u00e9 transferido para metade de setembro\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\\\/#listItem\",\"position\":3,\"name\":\"Festival de Cinema de Gramado \\u00e9 transferido para metade de setembro\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/category\\\/materiasecundaria\\\/#listItem\",\"name\":\"Cultura-MAT\\u00c9RIA\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\",\"name\":\"Jornal J\\u00c1 Editora\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"telephone\":\"+555133307272\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/2020-logotipia-ja-35anos.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\\\/#organizationLogo\",\"width\":1067,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/jornaljapoa\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JornalJ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/\",\"name\":\"da Reda\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"da Reda\\u00e7\\u00e3o\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\\\/#webpage\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\\\/\",\"name\":\"Festival de Cinema de Gramado \\u00e9 transferido para metade de setembro | Cultura\",\"description\":\"A organiza\\u00e7\\u00e3o do Festival de Cinema de Gramado comunica a transfer\\u00eancia do evento, inicialmente programado para agosto, para o per\\u00edodo de 18 a 26 setembro. A nova data foi fixada a partir da an\\u00e1lise do cen\\u00e1rio nacional em fun\\u00e7\\u00e3o da pandemia. Dia a dia, a organiza\\u00e7\\u00e3o e as equipes de conte\\u00fado e produ\\u00e7\\u00e3o observam e avaliam as altera\\u00e7\\u00f5es\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/author\\\/daredacao\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/Foto-Cleiton-Thiele_Pressphoto-scaled.jpg\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\\\/#mainImage\",\"width\":1024,\"height\":683,\"caption\":\"Gramado - RS 12\\\/08\\\/2019 - 47\\u00ba Festival de Cinema de Gramado - Preparativos - Foto: Cleiton Thiele \\\/ Pressphoto\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\\\/#mainImage\"},\"datePublished\":\"2020-06-10T11:35:18-03:00\",\"dateModified\":\"2020-06-10T11:38:28-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#website\",\"url\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/\",\"name\":\"Cultura\",\"description\":\"Jornal J\\u00c1 | Porto Alegre\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jornalja.com.br\\\/cultura\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Festival de Cinema de Gramado \u00e9 transferido para metade de setembro | Cultura","description":"A organiza\u00e7\u00e3o do Festival de Cinema de Gramado comunica a transfer\u00eancia do evento, inicialmente programado para agosto, para o per\u00edodo de 18 a 26 setembro. A nova data foi fixada a partir da an\u00e1lise do cen\u00e1rio nacional em fun\u00e7\u00e3o da pandemia. Dia a dia, a organiza\u00e7\u00e3o e as equipes de conte\u00fado e produ\u00e7\u00e3o observam e avaliam as altera\u00e7\u00f5es","canonical_url":"https:\/\/www.jornalja.com.br\/cultura\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornalja.com.br\/cultura\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\/#article","name":"Festival de Cinema de Gramado \u00e9 transferido para metade de setembro | Cultura","headline":"Festival de Cinema de Gramado \u00e9 transferido para metade de setembro","author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/06\/Foto-Cleiton-Thiele_Pressphoto-scaled.jpg","width":1024,"height":683,"caption":"Gramado - RS 12\/08\/2019 - 47\u00ba Festival de Cinema de Gramado - Preparativos - Foto: Cleiton Thiele \/ Pressphoto"},"datePublished":"2020-06-10T11:35:18-03:00","dateModified":"2020-06-10T11:38:28-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\/#webpage"},"isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\/#webpage"},"articleSection":"Cultura-MAT\u00c9RIA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornalja.com.br\/cultura\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","position":1,"name":"Home","item":"https:\/\/www.jornalja.com.br\/cultura","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","position":2,"name":"Cultura-MAT\u00c9RIA","item":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\/#listItem","name":"Festival de Cinema de Gramado \u00e9 transferido para metade de setembro"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\/#listItem","position":3,"name":"Festival de Cinema de Gramado \u00e9 transferido para metade de setembro","previousItem":{"@type":"ListItem","@id":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/#listItem","name":"Cultura-MAT\u00c9RIA"}}]},{"@type":"Organization","@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization","name":"Jornal J\u00c1 Editora","description":"Jornal J\u00c1 | Porto Alegre","url":"https:\/\/www.jornalja.com.br\/cultura\/","telephone":"+555133307272","logo":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/05\/2020-logotipia-ja-35anos.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\/#organizationLogo","width":1067,"height":800},"image":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/jornaljapoa","https:\/\/www.youtube.com\/c\/JornalJ"]},{"@type":"Person","@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author","url":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/","name":"da Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.jornalja.com.br\/cultura\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/469fd857d6605ad19919d27ed29d35a968a25f6e8fd9318356bbb7f57aae9c65?s=96&d=mm&r=g","width":96,"height":96,"caption":"da Reda\u00e7\u00e3o"}},{"@type":"WebPage","@id":"https:\/\/www.jornalja.com.br\/cultura\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\/#webpage","url":"https:\/\/www.jornalja.com.br\/cultura\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\/","name":"Festival de Cinema de Gramado \u00e9 transferido para metade de setembro | Cultura","description":"A organiza\u00e7\u00e3o do Festival de Cinema de Gramado comunica a transfer\u00eancia do evento, inicialmente programado para agosto, para o per\u00edodo de 18 a 26 setembro. A nova data foi fixada a partir da an\u00e1lise do cen\u00e1rio nacional em fun\u00e7\u00e3o da pandemia. Dia a dia, a organiza\u00e7\u00e3o e as equipes de conte\u00fado e produ\u00e7\u00e3o observam e avaliam as altera\u00e7\u00f5es","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#website"},"breadcrumb":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\/#breadcrumblist"},"author":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"creator":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/author\/daredacao\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/06\/Foto-Cleiton-Thiele_Pressphoto-scaled.jpg","@id":"https:\/\/www.jornalja.com.br\/cultura\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\/#mainImage","width":1024,"height":683,"caption":"Gramado - RS 12\/08\/2019 - 47\u00ba Festival de Cinema de Gramado - Preparativos - Foto: Cleiton Thiele \/ Pressphoto"},"primaryImageOfPage":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\/#mainImage"},"datePublished":"2020-06-10T11:35:18-03:00","dateModified":"2020-06-10T11:38:28-03:00"},{"@type":"WebSite","@id":"https:\/\/www.jornalja.com.br\/cultura\/#website","url":"https:\/\/www.jornalja.com.br\/cultura\/","name":"Cultura","description":"Jornal J\u00c1 | Porto Alegre","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.jornalja.com.br\/cultura\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Cultura","og:type":"article","og:title":"Festival de Cinema de Gramado \u00e9 transferido para metade de setembro | Cultura","og:description":"A organiza\u00e7\u00e3o do Festival de Cinema de Gramado comunica a transfer\u00eancia do evento, inicialmente programado para agosto, para o per\u00edodo de 18 a 26 setembro. A nova data foi fixada a partir da an\u00e1lise do cen\u00e1rio nacional em fun\u00e7\u00e3o da pandemia. Dia a dia, a organiza\u00e7\u00e3o e as equipes de conte\u00fado e produ\u00e7\u00e3o observam e avaliam as altera\u00e7\u00f5es","og:url":"https:\/\/www.jornalja.com.br\/cultura\/festival-de-cinema-de-gramado-e-transferido-para-metade-de-setembro\/","og:image":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg","og:image:secure_url":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg","article:published_time":"2020-06-10T14:35:18+00:00","article:modified_time":"2020-06-10T14:38:28+00:00","article:publisher":"https:\/\/www.facebook.com\/jornaljanaweb","twitter:card":"summary","twitter:site":"@jornal_ja","twitter:title":"Festival de Cinema de Gramado \u00e9 transferido para metade de setembro | Cultura","twitter:description":"A organiza\u00e7\u00e3o do Festival de Cinema de Gramado comunica a transfer\u00eancia do evento, inicialmente programado para agosto, para o per\u00edodo de 18 a 26 setembro. A nova data foi fixada a partir da an\u00e1lise do cen\u00e1rio nacional em fun\u00e7\u00e3o da pandemia. Dia a dia, a organiza\u00e7\u00e3o e as equipes de conte\u00fado e produ\u00e7\u00e3o observam e avaliam as altera\u00e7\u00f5es","twitter:image":"https:\/\/www.jornalja.com.br\/economics\/wp-content\/uploads\/sites\/11\/2026\/08\/ja-folhaderosto-facebook.jpg"},"aioseo_meta_data":{"post_id":"82106","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-20 20:28:24","updated":"2025-06-04 12:09:24","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":87653,"url":"https:\/\/www.jornalja.com.br\/cultura\/hebe-tabachnik-ministra-master-class-sobre-festivais-do-setor-audiovisual-em-tempos-pos-pandemicos\/","url_meta":{"origin":82106,"position":0},"title":"Hebe Tabachnik ministra master class sobre festivais do setor audiovisual em tempos p\u00f3s-pand\u00eamicos\u00a0","author":"da Reda\u00e7\u00e3o","date":"20 de mar\u00e7o de 2023","format":false,"excerpt":"\u00a0 Evento ocorre durante o Encontro dos Festivais Ibero-americanos de Cinema, promovido pela Fundacine em parceria com a Cinemateca Capit\u00f3lio, entre os dias 23 e 27 de mar\u00e7o, em Porto Alegre A demanda por conte\u00fado, ferramentas criativas revolucion\u00e1rias e formas h\u00edbridas de entregar\u00a0 hist\u00f3rias se expandiram exponencialmente ap\u00f3s o per\u00edodo\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/03\/hebe-tabachnik-headshot-square-photo-credit-juan-tallo.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/03\/hebe-tabachnik-headshot-square-photo-credit-juan-tallo.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2023\/03\/hebe-tabachnik-headshot-square-photo-credit-juan-tallo.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":86541,"url":"https:\/\/www.jornalja.com.br\/cultura\/na-programacao-do-festival-internacional-literario-de-gramado-mais-de-150-atividades-gratuitas\/","url_meta":{"origin":82106,"position":1},"title":"Na programa\u00e7\u00e3o do Festival Internacional Liter\u00e1rio de Gramado, mais de 150 atividades gratuitas","author":"da Reda\u00e7\u00e3o","date":"28 de agosto de 2022","format":false,"excerpt":"A serra ga\u00facha receber\u00e1, a partir da pr\u00f3xima semana, a primeira edi\u00e7\u00e3o do Festival Internacional Liter\u00e1rio de Gramado. Com o tema\u00a0\u201cO livro est\u00e1 na mesa: o papel da literatura em momentos de transforma\u00e7\u00e3o\u201d, o\u00a0FiliGram\u00a0ser\u00e1 realizado de\u00a002 a 11 de setembro\u00a0no\u00a0Lago Joaquina Rita Bier. Durante 10 dias est\u00e3o previstas mais de\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/08\/filigram-oliveira-silveira-cred-tania-meinerz.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/08\/filigram-oliveira-silveira-cred-tania-meinerz.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/08\/filigram-oliveira-silveira-cred-tania-meinerz.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/08\/filigram-oliveira-silveira-cred-tania-meinerz.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/08\/filigram-oliveira-silveira-cred-tania-meinerz.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84467,"url":"https:\/\/www.jornalja.com.br\/cultura\/a-nuvem-rosa-filme-de-iuli-gerbase-tera-pre-estreia-no-cine-farol-santander\/","url_meta":{"origin":82106,"position":2},"title":"&#8220;A Nuvem Rosa&#8221;, filme de Iuli Gerbase, ter\u00e1 pr\u00e9-estreia no Cine Farol Santander","author":"da Reda\u00e7\u00e3o","date":"24 de agosto de 2021","format":false,"excerpt":"\u00a0Numa mescla de cl\u00e1ssicos e novidades, o Cine Farol Santander traz de volta uma personalidade para o cinema, atrav\u00e9s das parcerias com consulados e embaixadas, al\u00e9m das mostras tem\u00e1ticas, como a que est\u00e1 em cartaz atualmente, das diretoras francesas, em parceria com a embaixada da cinemateca da Fran\u00e7a, e parcerias\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/a-nuvem-rosa-06-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/a-nuvem-rosa-06-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/a-nuvem-rosa-06-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/a-nuvem-rosa-06-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/a-nuvem-rosa-06-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2021\/08\/a-nuvem-rosa-06-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":86579,"url":"https:\/\/www.jornalja.com.br\/cultura\/a-poesia-e-arte-visual-de-liana-timm-no-festival-internaciomal-literario-de-gramado\/","url_meta":{"origin":82106,"position":3},"title":"A poesia e a arte visual de Liana Timm, no Festival Internaciomal Liter\u00e1rio de Gramado","author":"da Reda\u00e7\u00e3o","date":"31 de agosto de 2022","format":false,"excerpt":"Artista lan\u00e7a antologia de 35 anos de poesia e exposi\u00e7\u00e3o \"Recortes de uma Trajet\u00f3ria\". Vernissage ser\u00e1 no s\u00e1bado, 3 de setembro, no Centro Municipal de Cultura Arno Michaelsen Gramado \u00e9 o templo da cultura. E a arte de Liana Timm vai estar presente no Festival Internacional Liter\u00e1rio de Gramado (Filigram),\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/08\/liana-4-o-olhar-divergente-serie-o-traco-sensivel-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/08\/liana-4-o-olhar-divergente-serie-o-traco-sensivel-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/08\/liana-4-o-olhar-divergente-serie-o-traco-sensivel-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/08\/liana-4-o-olhar-divergente-serie-o-traco-sensivel-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/08\/liana-4-o-olhar-divergente-serie-o-traco-sensivel-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2022\/08\/liana-4-o-olhar-divergente-serie-o-traco-sensivel-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":75017,"url":"https:\/\/www.jornalja.com.br\/cultura\/1o-gramado-jazz-blues-festival-abre-inscricoes-para-musicos-gauchos\/","url_meta":{"origin":82106,"position":4},"title":"1\u00ba Gramado Jazz &amp; Blues Festival abre inscri\u00e7\u00f5es para m\u00fasicos ga\u00fachos","author":"da Reda\u00e7\u00e3o","date":"21 de junho de 2019","format":false,"excerpt":"Dois dias com muitos shows gratuitos de jazz e blues na Serra Ga\u00facha. Essa \u00e9 a proposta do 1\u00ba Gramado Jazz & Blues Festival, que acontece nos dias 26 e 27 de julho, em diferentes pontos da cidade de Gramado, tendo como palco principal a Rua Coberta.\u00a0 Al\u00e9m de atra\u00e7\u00f5es\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":77231,"url":"https:\/\/www.jornalja.com.br\/cultura\/rogerio-soares-celebra-30-anos-de-fotografia-com-a-exposicao-dossie\/","url_meta":{"origin":82106,"position":5},"title":"Rog\u00e9rio Soares celebra 30 anos de fotografia com a exposi\u00e7\u00e3o &quot;Dossi\u00ea&quot;","author":"da Reda\u00e7\u00e3o","date":"9 de setembro de 2019","format":false,"excerpt":"Completando 30 anos de trajet\u00f3ria profissional na fotografia, Rog\u00e9rio Soares prepara a exposi\u00e7\u00e3o que \u00e9 um verdadeiro dossi\u00ea de sua carreira, incluindo registros jornal\u00edsticos, da cena cultural e do cotidiano. \u2018Dossi\u00ea - 30 anos, fotografias de Rog\u00e9rio Soares\u2019 re\u00fane imagens que demonstram a diversidade de interesses do fotojornalista, professor e\u2026","rel":"","context":"Em &quot;Cultura-MAT\u00c9RIA&quot;","block_context":{"text":"Cultura-MAT\u00c9RIA","link":"https:\/\/www.jornalja.com.br\/cultura\/category\/materiasecundaria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jornalja.com.br\/wp-content\/uploads\/2019\/09\/arte-expo-Nei-Lisboa_por-Rog%C3%A9rio-Soares-293x450.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pbKnZc-lmi","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.jornalja.com.br\/cultura\/wp-content\/uploads\/sites\/2\/2020\/06\/Foto-Cleiton-Thiele_Pressphoto-scaled.jpg","_links":{"self":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/82106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/comments?post=82106"}],"version-history":[{"count":1,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/82106\/revisions"}],"predecessor-version":[{"id":82109,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/posts\/82106\/revisions\/82109"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media\/82107"}],"wp:attachment":[{"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/media?parent=82106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/categories?post=82106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalja.com.br\/cultura\/wp-json\/wp\/v2\/tags?post=82106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}